{"id":1031,"date":"2019-06-19T10:18:37","date_gmt":"2019-06-19T08:18:37","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=1031"},"modified":"2019-06-19T10:18:37","modified_gmt":"2019-06-19T08:18:37","slug":"istat-ad-aprile-in-crescita-i-flussi-commerciali-con-lestero","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/istat-ad-aprile-in-crescita-i-flussi-commerciali-con-lestero\/","title":{"rendered":"Istat: ad aprile in crescita i flussi commerciali con l&#8217;estero"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">A<\/span>d aprile 2019 si stima una crescita congiunturale per entrambi i flussi commerciali con l\u2019estero, pi\u00f9 intensa per le importazioni (+0,9%) che per le esportazioni (+0,3%).<\/p>\n<p>L\u2019aumento congiunturale dell\u2019export \u00e8 da ascrivere all\u2019incremento delle vendite sia verso i mercati extra Ue (+0,4%) sia verso l\u2019area Ue (+0,2%).<\/p>\n<p>Nel trimestre febbraio-aprile 2019, rispetto al precedente, si registra un contenuto incremento delle esportazioni (+0,4%) e una pi\u00f9 marcata diminuzione delle importazioni (-1,3%).<\/p>\n<p>Ad aprile 2019 la crescita dell\u2019export su base annua \u00e8 pari a +5,8% ed \u00e8 determinata dall\u2019aumento delle vendite registrato sia per l\u2019area extra Ue (+6,7%) sia per quella Ue (+5,2%). Analogamente le importazioni sono in aumento (+6,7%) sia dai mercati extra Ue (+7,4%) sia dall\u2019area Ue (+6,1%).<\/p>\n<p>Tra i settori che contribuiscono positivamente alla variazione tendenziale dell\u2019export nel mese di aprile 2019, si segnalano articoli farmaceutici, chimico-medicinali e botanici (+39,1%), prodotti alimentari, bevande e tabacco (+13,3%) e macchinari e apparecchi n.c.a. (+4,8%). Diminuiscono su base annua gli autoveicoli (-10,2%) e i prodotti petroliferi raffinati (-12,5%).<\/p>\n<p><strong>Su base annua<\/strong>, i paesi che contribuiscono maggiormente all\u2019incremento delle esportazioni sono Svizzera (+24,8%), Stati Uniti (+6,1%), Francia (+3,9%) e Germania (+3,0%) mentre si registra una flessione delle vendite verso la Turchia (-15,5%) e i paesi OPEC (-5,1%).<\/p>\n<p>Nei primi quattro mesi del 2019, l\u2019aumento su base annua dell\u2019export (+2,9%) \u00e8 determinato principalmente dalle vendite di prodotti tessili e dell&#8217;abbigliamento, pelli e accessori (+7,2%), metalli di base e prodotti in metallo, esclusi macchine e impianti (+4,4%), prodotti alimentari, bevande e tabacco (+8,0%) e articoli farmaceutici, chimico-medicinali e botanici (+20,5%).Si stima che il surplus commerciale diminuisca di 101 milioni di euro (da +2.985 milioni ad aprile 2018 a +2.885 milioni ad aprile 2019).<\/p>\n<p>Nei primi quattro mesi dell\u2019anno l\u2019avanzo commerciale raggiunge +11.027 milioni (+24.718 milioni al netto dei prodotti energetici).<\/p>\n<p>Nel mese di aprile 2019, si stima una lieve crescita congiunturale dei prezzi all\u2019importazione (+0,5%); su base annua, l\u2019incremento \u00e8 pari all\u20191,2%.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ad aprile 2019 si stima una crescita congiunturale per entrambi i flussi commerciali con l\u2019estero, pi\u00f9 intensa per le importazioni (+0,9%) che per le esportazioni (+0,3%). L\u2019aumento congiunturale dell\u2019export \u00e8 da ascrivere all\u2019incremento delle vendite sia verso i mercati extra Ue (+0,4%) sia verso l\u2019area Ue (+0,2%). Nel trimestre febbraio-aprile 2019, rispetto al precedente, si [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1032,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56],"tags":[102],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Istat: ad aprile in crescita i flussi commerciali con l&#039;estero -<\/title>\n<meta name=\"description\" content=\"Ad aprile 2019 si stima una crescita congiunturale per entrambi i flussi commerciali con l\u2019estero, pi\u00f9 intensa per le importazioni\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/istat-ad-aprile-in-crescita-i-flussi-commerciali-con-lestero\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Istat: ad aprile in crescita i flussi commerciali con l&#039;estero -\" \/>\n<meta property=\"og:description\" content=\"Ad aprile 2019 si stima una crescita congiunturale per entrambi i flussi commerciali con l\u2019estero, pi\u00f9 intensa per le importazioni\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/istat-ad-aprile-in-crescita-i-flussi-commerciali-con-lestero\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-19T08:18:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/commercio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"678\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/istat-ad-aprile-in-crescita-i-flussi-commerciali-con-lestero\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/istat-ad-aprile-in-crescita-i-flussi-commerciali-con-lestero\/\",\"name\":\"Istat: ad aprile in crescita i flussi commerciali con l'estero -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/istat-ad-aprile-in-crescita-i-flussi-commerciali-con-lestero\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/istat-ad-aprile-in-crescita-i-flussi-commerciali-con-lestero\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/commercio.jpg\",\"datePublished\":\"2019-06-19T08:18:37+00:00\",\"dateModified\":\"2019-06-19T08:18:37+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"description\":\"Ad aprile 2019 si stima una crescita congiunturale per entrambi i flussi commerciali con l\u2019estero, pi\u00f9 intensa per le importazioni\",\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/istat-ad-aprile-in-crescita-i-flussi-commerciali-con-lestero\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/istat-ad-aprile-in-crescita-i-flussi-commerciali-con-lestero\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/istat-ad-aprile-in-crescita-i-flussi-commerciali-con-lestero\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/commercio.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/commercio.jpg\",\"width\":960,\"height\":678},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/istat-ad-aprile-in-crescita-i-flussi-commerciali-con-lestero\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Istat: ad aprile in crescita i flussi commerciali con l&#8217;estero\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Istat: ad aprile in crescita i flussi commerciali con l'estero -","description":"Ad aprile 2019 si stima una crescita congiunturale per entrambi i flussi commerciali con l\u2019estero, pi\u00f9 intensa per le importazioni","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/istat-ad-aprile-in-crescita-i-flussi-commerciali-con-lestero\/","og_locale":"it_IT","og_type":"article","og_title":"Istat: ad aprile in crescita i flussi commerciali con l'estero -","og_description":"Ad aprile 2019 si stima una crescita congiunturale per entrambi i flussi commerciali con l\u2019estero, pi\u00f9 intensa per le importazioni","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/istat-ad-aprile-in-crescita-i-flussi-commerciali-con-lestero\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2019-06-19T08:18:37+00:00","og_image":[{"width":960,"height":678,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/commercio.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/istat-ad-aprile-in-crescita-i-flussi-commerciali-con-lestero\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/istat-ad-aprile-in-crescita-i-flussi-commerciali-con-lestero\/","name":"Istat: ad aprile in crescita i flussi commerciali con l'estero -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/istat-ad-aprile-in-crescita-i-flussi-commerciali-con-lestero\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/istat-ad-aprile-in-crescita-i-flussi-commerciali-con-lestero\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/commercio.jpg","datePublished":"2019-06-19T08:18:37+00:00","dateModified":"2019-06-19T08:18:37+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"description":"Ad aprile 2019 si stima una crescita congiunturale per entrambi i flussi commerciali con l\u2019estero, pi\u00f9 intensa per le importazioni","breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/istat-ad-aprile-in-crescita-i-flussi-commerciali-con-lestero\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/istat-ad-aprile-in-crescita-i-flussi-commerciali-con-lestero\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/istat-ad-aprile-in-crescita-i-flussi-commerciali-con-lestero\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/commercio.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/commercio.jpg","width":960,"height":678},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/istat-ad-aprile-in-crescita-i-flussi-commerciali-con-lestero\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Istat: ad aprile in crescita i flussi commerciali con l&#8217;estero"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/1031"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=1031"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/1031\/revisions"}],"predecessor-version":[{"id":1033,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/1031\/revisions\/1033"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/1032"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=1031"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=1031"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=1031"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}