{"id":1041,"date":"2019-06-19T15:54:57","date_gmt":"2019-06-19T13:54:57","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=1041"},"modified":"2019-06-19T16:11:47","modified_gmt":"2019-06-19T14:11:47","slug":"nel-primo-trimestre-207mila-posti-stabili","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/nel-primo-trimestre-207mila-posti-stabili\/","title":{"rendered":"Nel primo trimestre +207mila posti stabili"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">N<\/span>el <strong>primo<\/strong> <strong>trimestre 2019<\/strong> si osserva un contenuto <strong>aumento dell\u2019occupazione <\/strong>sia rispetto al quarto trimestre 2018 sia su base annua .<\/p>\n<p>Queste dinamiche si sono sviluppate in un contesto di lieve <strong>aumento congiunturale del Pil<\/strong> (+0,1%) dopo due trimestri di leggero calo (-0,1%); l\u2019input di lavoro misurato in termini di Ula (Unit\u00e0 di lavoro equivalenti a tempo pieno) registra una dinamica significativamente pi\u00f9 accelerata rispetto a quella del Pil (+0,4 sotto il profilo congiunturale e +1,1% in termini tendenziali).<\/p>\n<blockquote class=\"td_quote_box td_box_left\"><p>E&#8217; quanto emerge dalla nota congiunta sull&#8217;occupazione di ministero del Lavoro, Istat, Inps, Inail e Anpal.<\/p><\/blockquote>\n<p><strong>Il tasso di occupazione destagionalizzato<\/strong> si porta al 58,7% (+0,1 punti in confronto al trimestre precedente) come sintesi dell\u2019aumento di quello femminile e della stabilit\u00e0 di quello maschile. L\u2019indicatore supera di oltre tre punti il valore minimo del terzo trimestre 2013 (55,4%) tornando ai livelli pre-crisi e sfiorando il livello massimo del secondo trimestre del 2008 (58,8%).<\/p>\n<p>In questo contesto, l\u2019insieme dei dati provenienti dalle diverse fonti consente di evidenziare i seguenti aspetti.<\/p>\n<p><strong>Prosegue la crescita tendenziale dell\u2019occupazione<\/strong> <strong>dipendente <\/strong>in termini sia di occupati (+0,5%, Istat, Rilevazione sulle forze di lavoro) sia di posizioni lavorative riferite ai settori dell\u2019industria e dei servizi (+1,7%, Istat, Rilevazione Oros).<\/p>\n<p>Lo stesso andamento si riscontra nei dati del Ministero del lavoro e delle politiche sociali tratti dalle Comunicazioni obbligatorie (CO) rielaborate (+376 mila posizioni lavorative nel primo trimestre 2019 rispetto al primo del 2018, ) e nei dati dell\u2019Inps-Uniemens riferiti alle sole imprese private (+351 mila posizioni lavorative al 31 marzo 2019 rispetto al 31 marzo 2018).<\/p>\n<p>L\u2019aumento tendenziale delle posizioni lavorative dipendenti interessa tutte le classi dimensionali d\u2019impresa .<\/p>\n<p><strong>Il lavoro indipendente, <\/strong>secondo la Rilevazione sulle forze di lavoro dell\u2019Istat, <strong>mostra una crescita<\/strong> sia congiunturale (+7 mila occupati, +0,1%), dopo un calo quasi ininterrotto dal primo trimestre 2017, sia su base annua (+52 mila occupati, +1,0%) per il quarto trimestre consecutivo.<\/p>\n<p><strong>Le posizioni lavorative dipendenti<\/strong>, nei dati destagionalizzati, presentano<strong> un incremento congiunturale.<\/strong><\/p>\n<p>Nel primo trimestre 2019, in base alle CO, le attivazioni sono state 2 milioni 580 mila e le cessazioni 2 milioni 443 mila, determinando un saldo positivo di 138 mila posizioni di lavoro dipendente .<\/p>\n<p>La crescita riguarda tutti i settori di attivit\u00e0 economica: oltre l\u2019industria in senso stretto (+24 mila) e i servizi (+79 mila), incrementi rilevanti tornano a manifestarsi anche in agricoltura (+17 mila) e nelle costruzioni (+18 mila).<\/p>\n<p>Andamenti analoghi si riscontrano nelle posizioni lavorative dei dipendenti del settore privato extra-agricolo (Istat, Rilevazione Oros), dove la variazione congiunturale di +0,6% (+74 mila posizioni) \u00e8 dovuta ad aumenti di simile entit\u00e0 nell\u2019industria in senso stretto (+0,5%, +20 mila posizioni) e nei servizi (+0,6%, +47 mila) e lievemente pi\u00f9 ampi nelle costruzioni (+0,9%, +7 mila).<\/p>\n<p>La crescita congiunturale delle posizioni lavorative dipendenti sulla base delle CO riguarda le <strong>posizioni a tempo indeterminato <\/strong>(+207 mila) mentre quelle<strong> a tempo determinato <\/strong>subiscono una<strong> riduzione<\/strong> (-69 mila)<strong>.<\/strong><\/p>\n<p>Entrambe queste tendenze sono influenzate dal notevole aumento delle <strong>trasformazioni a tempo indeterminato <\/strong>(+223 mila, +55%) che raggiungono il livello massimo della serie storica contribuendo in modo complementare ad accrescere il numero di posizioni a tempo indeterminato e a diminuire quello delle posizioni a termine, in calo per la prima volta dal secondo trimestre 2016.<\/p>\n<p>L\u2019incidenza delle trasformazioni sul totale degli ingressi a tempo indeterminato (attivazioni e trasformazioni) raggiunge il 28,5% con un incremento di 6,5 punti percentuali rispetto al trimestre precedente.<\/p>\n<p>Su<strong> base annua <\/strong>la<strong> dinamica <\/strong>delle<strong> posizioni a tempo determinato<\/strong> risulta <strong>negativa<\/strong> nei dati CO (-24 mila; Tavola 2), dopo undici trimestri di crescita, sebbene in progressivo rallentamento nei tre trimestri precedenti (+155 mila, +277 mila, +378 mila rispettivamente nel quarto, terzo e secondo trimestre 2018).<\/p>\n<p>Tale andamento si accentua nei dati Inps-Uniemens (-99 mila nel primo trimestre 2019 rispetto a +117 mila, +247 mila e +376 mila) che comprendono anche il lavoro in somministrazione e a chiamata.<\/p>\n<p>Le <strong>posizioni lavorative a tempo indeterminato<\/strong> <strong>presentano un aumento<\/strong> nei dati delle CO (+401 mila) in accelerazione rispetto ai tre trimestri precedenti<br \/>\n(+230 mila, +124 mila e +74 mila); del tutto analogo l\u2019andamento registrato dai dati Inps (+450 mila) in confronto ai tre trimestri precedenti (+297 mila, +158 mila e +67 mila).<\/p>\n<p>Secondo i dati Istat della Rilevazione sulle forze di lavoro prosegue l\u2019<strong>aumento tendenziale dell\u2019occupazione <\/strong>(+144 mila unit\u00e0; ) a cui si associa una <strong>diminuzione delle persone in cerca di lavoro<\/strong> (-138 mila) <strong>e degli inattivi<\/strong> (-130 mila).<\/p>\n<p>Tra i giovani di 15-34 anni tornano a crescere, in termini sia congiunturali sia tendenziali, l\u2019occupazione e il relativo tasso.<\/p>\n<p>Rimane significativo l\u2019impatto dell\u2019invecchiamento della popolazione, che contribuisce a spiegare la crescita del numero degli occupati ultracinquantenni , indotta anche dall\u2019allungamento dell\u2019et\u00e0 pensionabile.<\/p>\n<p>Dopo quasi sei anni di continua crescita e aver raggiunto nel terzo trimestre 2018 la massima espansione (418 mila unit\u00e0; ), <strong>il numero dei lavoratori in somministrazione<\/strong> nel primo trimestre 2019 <strong>subisce una significativa riduzione tendenziale<\/strong> (-20 mila unit\u00e0 corrispondenti a -5,1% nei dati Inps-Uniemens).<\/p>\n<p>Nel primo trimestre 2019 <strong>prosegue l\u2019aumento tendenziale <\/strong>del numero <strong>dei lavoratori a chiamata o intermittenti<\/strong> sulla base dei dati Inps-Uniemens (+15 mila unit\u00e0 rispetto all\u2019analogo trimestre del 2018; ), anche se rallenta ulteriormente il tasso di crescita (+7,3% nel primo trimestre 2019 rispetto al +8,3%, al +8,8% e il +15,9% rispettivamente nel quarto, terzo e secondo 2018; ).<\/p>\n<p>Il numero dei lavoratori impiegati con il <strong>Contratto di Prestazione Occasionale<\/strong> e quelli pagati con i titoli del <strong>Libretto Famiglia<\/strong> \u2013 le due nuove forme contrattuali di lavoro occasionale introdotte operativamente da luglio 2017 in sostituzione del lavoro accessorio (voucher) \u2013 nel primo trimestre 2019, in termini di valori medi mensili, hanno raggiunto rispettivamente le 19 mila e le 10 mila unit\u00e0.<\/p>\n<p>Gli <strong>infortuni sul lavoro<\/strong> accaduti e denunciati all&#8217;Inail nel primo trimestre del 2019 sono stati 131 mila (109 mila in occasione di lavoro e 22 mila in itinere), in aumento dell\u20191,7% (+2 mila denunce) rispetto al primo trimestre del 2018 . Gli infortuni sul lavoro con esito mortale accaduti e denunciati all&#8217;Inail nel primo trimestre del 2019 sono stati 212 (144 in occasione di lavoro e 68 in itinere), lo stesso numero del primo trimestre del 2018 .<\/p>\n<p>Le <strong>malattie professionali<\/strong> denunciate all&#8217;Inail e protocollate nel primo trimestre del 2019 sono state 15.900, in diminuzione (-1,4%, 224 casi in meno) rispetto all&#8217;analogo trimestre dell&#8217;anno precedente<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nel primo trimestre 2019 si osserva un contenuto aumento dell\u2019occupazione sia rispetto al quarto trimestre 2018 sia su base annua . Queste dinamiche si sono sviluppate in un contesto di lieve aumento congiunturale del Pil (+0,1%) dopo due trimestri di leggero calo (-0,1%); l\u2019input di lavoro misurato in termini di Ula (Unit\u00e0 di lavoro equivalenti [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1042,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[102,88,437],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Nel primo trimestre +207mila posti stabili -<\/title>\n<meta name=\"description\" content=\"Nel primo trimestre 2019 si osserva un contenuto aumento dell\u2019occupazione sia rispetto al quarto trimestre 2018 sia su base annua .\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/nel-primo-trimestre-207mila-posti-stabili\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nel primo trimestre +207mila posti stabili -\" \/>\n<meta property=\"og:description\" content=\"Nel primo trimestre 2019 si osserva un contenuto aumento dell\u2019occupazione sia rispetto al quarto trimestre 2018 sia su base annua .\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/nel-primo-trimestre-207mila-posti-stabili\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-19T13:54:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-06-19T14:11:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/laptop-3196481_960_720.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/nel-primo-trimestre-207mila-posti-stabili\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/nel-primo-trimestre-207mila-posti-stabili\/\",\"name\":\"Nel primo trimestre +207mila posti stabili -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/nel-primo-trimestre-207mila-posti-stabili\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/nel-primo-trimestre-207mila-posti-stabili\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/laptop-3196481_960_720.jpg\",\"datePublished\":\"2019-06-19T13:54:57+00:00\",\"dateModified\":\"2019-06-19T14:11:47+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"description\":\"Nel primo trimestre 2019 si osserva un contenuto aumento dell\u2019occupazione sia rispetto al quarto trimestre 2018 sia su base annua .\",\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/nel-primo-trimestre-207mila-posti-stabili\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/nel-primo-trimestre-207mila-posti-stabili\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/nel-primo-trimestre-207mila-posti-stabili\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/laptop-3196481_960_720.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/laptop-3196481_960_720.jpg\",\"width\":960,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/nel-primo-trimestre-207mila-posti-stabili\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nel primo trimestre +207mila posti stabili\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nel primo trimestre +207mila posti stabili -","description":"Nel primo trimestre 2019 si osserva un contenuto aumento dell\u2019occupazione sia rispetto al quarto trimestre 2018 sia su base annua .","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/nel-primo-trimestre-207mila-posti-stabili\/","og_locale":"it_IT","og_type":"article","og_title":"Nel primo trimestre +207mila posti stabili -","og_description":"Nel primo trimestre 2019 si osserva un contenuto aumento dell\u2019occupazione sia rispetto al quarto trimestre 2018 sia su base annua .","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/nel-primo-trimestre-207mila-posti-stabili\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2019-06-19T13:54:57+00:00","article_modified_time":"2019-06-19T14:11:47+00:00","og_image":[{"width":960,"height":640,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/laptop-3196481_960_720.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/nel-primo-trimestre-207mila-posti-stabili\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/nel-primo-trimestre-207mila-posti-stabili\/","name":"Nel primo trimestre +207mila posti stabili -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/nel-primo-trimestre-207mila-posti-stabili\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/nel-primo-trimestre-207mila-posti-stabili\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/laptop-3196481_960_720.jpg","datePublished":"2019-06-19T13:54:57+00:00","dateModified":"2019-06-19T14:11:47+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"description":"Nel primo trimestre 2019 si osserva un contenuto aumento dell\u2019occupazione sia rispetto al quarto trimestre 2018 sia su base annua .","breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/nel-primo-trimestre-207mila-posti-stabili\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/nel-primo-trimestre-207mila-posti-stabili\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/nel-primo-trimestre-207mila-posti-stabili\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/laptop-3196481_960_720.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/laptop-3196481_960_720.jpg","width":960,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/nel-primo-trimestre-207mila-posti-stabili\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Nel primo trimestre +207mila posti stabili"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/1041"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=1041"}],"version-history":[{"count":3,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/1041\/revisions"}],"predecessor-version":[{"id":1045,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/1041\/revisions\/1045"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/1042"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=1041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=1041"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=1041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}