{"id":1256,"date":"2019-07-17T18:43:40","date_gmt":"2019-07-17T16:43:40","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=1256"},"modified":"2019-07-17T18:43:40","modified_gmt":"2019-07-17T16:43:40","slug":"sisma-centro-italia-domande-per-le-agevolazioni-dal-18-giugno","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/sisma-centro-italia-domande-per-le-agevolazioni-dal-18-giugno\/","title":{"rendered":"Sisma centro Italia, domande per le agevolazioni dal 18 giugno"},"content":{"rendered":"<p>Il Ministero dello Sviluppo Economico rende noto che dal 18 giugno 2019 potranno essere presentate le domande per le agevolazioni in favore delle imprese e dei lavoratori autonomi localizzati nella\u00a0<strong>Zona Franca Urbana<\/strong>\u00a0istituita nei Comuni delle Regioni del Lazio, dell\u2019Umbria, delle Marche e dell\u2019Abruzzo, colpiti dagli\u00a0<strong>eventi sismici<\/strong>\u00a0che si sono susseguiti dal 24 agosto 2016.<\/p>\n<p>Le risorse disponibili per le esenzioni fiscali e contributive sono circa\u00a0<strong>142 milioni di euro<\/strong>.<\/p>\n<p>Con la circolare del Ministero dello Sviluppo Economico pubblicata sono, infatti, definiti i requisiti, le modalit\u00e0 e i termini di accesso alle agevolazioni, alla luce delle modifiche introdotte con la legge di bilancio 2019.<\/p>\n<p>Per consultare la circolare clicca sul seguente link:\u00a0<a href=\"https:\/\/www.mise.gov.it\/index.php\/it\/normativa\/circolari-note-direttive-e-atti-di-indirizzo\/2039805-circolare-direttoriale-6-giugno-2019-n-243317-zfu-sisma-centro-italia-chiarimenti-in-merito-alle-modalita-e-ai-termini-di-presentazione-delle-istanze-di-accesso-alle-agevolazioni\" target=\"_blank\" rel=\"noopener noreferrer\">circolare direttoriale 6 giugno 2019, n. 243317<\/a><\/p>\n<p>Per maggiori informazioni sulla\u00a0<a title=\"Zona Franca Urbana Sisma Centro Italia\" href=\"https:\/\/www.mise.gov.it\/index.php\/it\/incentivi\/impresa\/zone-franche-urbane\/sisma-centro-italia\" target=\"_blank\" rel=\"noopener noreferrer\">Zona Franca Urbana Sisma Centro Italia<\/a>\u00a0clicca il relativo link<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Ministero dello Sviluppo Economico rende noto che dal 18 giugno 2019 potranno essere presentate le domande per le agevolazioni in favore delle imprese e dei lavoratori autonomi localizzati nella\u00a0Zona Franca Urbana\u00a0istituita nei Comuni delle Regioni del Lazio, dell\u2019Umbria, delle Marche e dell\u2019Abruzzo, colpiti dagli\u00a0eventi sismici\u00a0che si sono susseguiti dal 24 agosto 2016. Le risorse [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1257,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sisma centro Italia, domande per le agevolazioni dal 18 giugno -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/sisma-centro-italia-domande-per-le-agevolazioni-dal-18-giugno\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sisma centro Italia, domande per le agevolazioni dal 18 giugno -\" \/>\n<meta property=\"og:description\" content=\"Il Ministero dello Sviluppo Economico rende noto che dal 18 giugno 2019 potranno essere presentate le domande per le agevolazioni in favore delle imprese e dei lavoratori autonomi localizzati nella\u00a0Zona Franca Urbana\u00a0istituita nei Comuni delle Regioni del Lazio, dell\u2019Umbria, delle Marche e dell\u2019Abruzzo, colpiti dagli\u00a0eventi sismici\u00a0che si sono susseguiti dal 24 agosto 2016. Le risorse [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/sisma-centro-italia-domande-per-le-agevolazioni-dal-18-giugno\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-17T16:43:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/07\/earthquake-1665870_1280.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"849\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/sisma-centro-italia-domande-per-le-agevolazioni-dal-18-giugno\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/sisma-centro-italia-domande-per-le-agevolazioni-dal-18-giugno\/\",\"name\":\"Sisma centro Italia, domande per le agevolazioni dal 18 giugno -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/sisma-centro-italia-domande-per-le-agevolazioni-dal-18-giugno\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/sisma-centro-italia-domande-per-le-agevolazioni-dal-18-giugno\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/07\/earthquake-1665870_1280.jpg\",\"datePublished\":\"2019-07-17T16:43:40+00:00\",\"dateModified\":\"2019-07-17T16:43:40+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/sisma-centro-italia-domande-per-le-agevolazioni-dal-18-giugno\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/sisma-centro-italia-domande-per-le-agevolazioni-dal-18-giugno\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/sisma-centro-italia-domande-per-le-agevolazioni-dal-18-giugno\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/07\/earthquake-1665870_1280.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/07\/earthquake-1665870_1280.jpg\",\"width\":1280,\"height\":849},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/sisma-centro-italia-domande-per-le-agevolazioni-dal-18-giugno\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sisma centro Italia, domande per le agevolazioni dal 18 giugno\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sisma centro Italia, domande per le agevolazioni dal 18 giugno -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/sisma-centro-italia-domande-per-le-agevolazioni-dal-18-giugno\/","og_locale":"it_IT","og_type":"article","og_title":"Sisma centro Italia, domande per le agevolazioni dal 18 giugno -","og_description":"Il Ministero dello Sviluppo Economico rende noto che dal 18 giugno 2019 potranno essere presentate le domande per le agevolazioni in favore delle imprese e dei lavoratori autonomi localizzati nella\u00a0Zona Franca Urbana\u00a0istituita nei Comuni delle Regioni del Lazio, dell\u2019Umbria, delle Marche e dell\u2019Abruzzo, colpiti dagli\u00a0eventi sismici\u00a0che si sono susseguiti dal 24 agosto 2016. Le risorse [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/sisma-centro-italia-domande-per-le-agevolazioni-dal-18-giugno\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2019-07-17T16:43:40+00:00","og_image":[{"width":1280,"height":849,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/07\/earthquake-1665870_1280.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/sisma-centro-italia-domande-per-le-agevolazioni-dal-18-giugno\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/sisma-centro-italia-domande-per-le-agevolazioni-dal-18-giugno\/","name":"Sisma centro Italia, domande per le agevolazioni dal 18 giugno -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/sisma-centro-italia-domande-per-le-agevolazioni-dal-18-giugno\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/sisma-centro-italia-domande-per-le-agevolazioni-dal-18-giugno\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/07\/earthquake-1665870_1280.jpg","datePublished":"2019-07-17T16:43:40+00:00","dateModified":"2019-07-17T16:43:40+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/sisma-centro-italia-domande-per-le-agevolazioni-dal-18-giugno\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/sisma-centro-italia-domande-per-le-agevolazioni-dal-18-giugno\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/sisma-centro-italia-domande-per-le-agevolazioni-dal-18-giugno\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/07\/earthquake-1665870_1280.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/07\/earthquake-1665870_1280.jpg","width":1280,"height":849},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/sisma-centro-italia-domande-per-le-agevolazioni-dal-18-giugno\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Sisma centro Italia, domande per le agevolazioni dal 18 giugno"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/1256"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=1256"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/1256\/revisions"}],"predecessor-version":[{"id":1258,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/1256\/revisions\/1258"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/1257"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=1256"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=1256"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=1256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}