{"id":1368,"date":"2019-07-24T16:26:25","date_gmt":"2019-07-24T14:26:25","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=1368"},"modified":"2019-07-24T16:48:44","modified_gmt":"2019-07-24T14:48:44","slug":"un-milione-di-addetti-nelle-imprese-femminili-del-mezzogiorno","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/un-milione-di-addetti-nelle-imprese-femminili-del-mezzogiorno\/","title":{"rendered":"Un milione di addetti nelle imprese femminili del Mezzogiorno"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\"> L<\/span>e imprese femminili del Sud danno lavoro a quasi un milione di persone.<\/p>\n<p>E\u2019 quanto emerge dalla lettura dei dati sulle aziende guidate da donne al 31 marzo scorso, elaborati dall\u2019<strong>Osservatorio per l\u2019imprenditorialit\u00e0 femminile di Unioncamere e InfoCamere<\/strong>.<\/p>\n<p>I 3 milioni di addetti presenti nelle imprese femminili (che sono pi\u00f9 di un milione e 330mila a fine marzo scorso) incidono per meno del 15% sull\u2019occupazione del settore privato.<\/p>\n<p>Ma, in Molise e in Sardegna, nelle imprese guidate da donne trovano lavoro oltre il 20% degli addetti delle imprese presenti sul territorio, in Calabria quasi il 20%, in Sicilia, in Umbria e in Abruzzo quasi il 19%, pi\u00f9 del 18% in Basilicata.<\/p>\n<p>Nel complesso nel Mezzogiorno alle 483mila attivit\u00e0 a trazione femminile si deve il 17% dell\u2019occupazione generata dal settore privato.<\/p>\n<p>Alle spalle del Meridione si incontra il Nord Ovest, dove nelle 314mila imprese femminili lavorano pi\u00f9 di 800mila persone, l\u201911,8% degli addetti delle imprese presenti in quest\u2019area.<\/p>\n<p>A seguire il Centro, con 302mila imprese femminili e 710mila addetti e un\u2019incidenza sul totale che arriva al 15%. Quindi il Nord Est, con 232mila attivit\u00e0 guidate da donne e 627mila addetti, pari al 13,5% del totale riferito al settore privato.<\/p>\n<p>I numeri pi\u00f9 elevati dell\u2019occupazione nelle imprese femminili si registrano ovviamente nelle regioni in cui queste attivit\u00e0 sono maggiormente diffuse: la Lombardia, con 179mila imprese femminili e oltre 500mila addetti, il Lazio, in cui le 145mila attivit\u00e0 d\u2019impresa guidate da donne vantano oltre 325mila addetti.<\/p>\n<p>Ma, in questi casi, il \u201cpeso\u201d specifico sul totale degli occupati di quanti nelle aziende femminili hanno trovato un lavoro \u00e8 inferiore alla media nazionale.<\/p>\n<p>A fronte di un apporto importante all\u2019occupazione, l\u2019analisi degli addetti delle imprese femminili mette in evidenza anche la maggior fragilit\u00e0 strutturale di questo universo rispetto al complesso del mondo produttivo nazionale.<\/p>\n<p>Nelle attivit\u00e0 guidate da donne, che rappresentano quasi il 22% delle imprese totali italiane, operano mediamente 2,32 persone, mentre nel totale delle imprese il numero medio di addetti \u00e8 quasi di 4.<\/p>\n<p>La piccola dimensione delle attivit\u00e0 d\u2019impresa al femminile emerge anche guardando alle forme giuridiche, con un\u2019incidenza di imprese individuali di oltre 10 punti percentuali superiore a quella che si registra nel totale delle imprese (quasi il 63% a fronte di poco meno del 52%).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le imprese femminili del Sud danno lavoro a quasi un milione di persone. E\u2019 quanto emerge dalla lettura dei dati sulle aziende guidate da donne al 31 marzo scorso, elaborati dall\u2019Osservatorio per l\u2019imprenditorialit\u00e0 femminile di Unioncamere e InfoCamere. I 3 milioni di addetti presenti nelle imprese femminili (che sono pi\u00f9 di un milione e 330mila [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1369,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[58,601,602,68],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Un milione di addetti nelle imprese femminili del Mezzogiorno -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/un-milione-di-addetti-nelle-imprese-femminili-del-mezzogiorno\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un milione di addetti nelle imprese femminili del Mezzogiorno -\" \/>\n<meta property=\"og:description\" content=\"Le imprese femminili del Sud danno lavoro a quasi un milione di persone. E\u2019 quanto emerge dalla lettura dei dati sulle aziende guidate da donne al 31 marzo scorso, elaborati dall\u2019Osservatorio per l\u2019imprenditorialit\u00e0 femminile di Unioncamere e InfoCamere. I 3 milioni di addetti presenti nelle imprese femminili (che sono pi\u00f9 di un milione e 330mila [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/un-milione-di-addetti-nelle-imprese-femminili-del-mezzogiorno\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-24T14:26:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-24T14:48:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/07\/impfemminile.png\" \/>\n\t<meta property=\"og:image:width\" content=\"440\" \/>\n\t<meta property=\"og:image:height\" content=\"302\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/un-milione-di-addetti-nelle-imprese-femminili-del-mezzogiorno\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/un-milione-di-addetti-nelle-imprese-femminili-del-mezzogiorno\/\",\"name\":\"Un milione di addetti nelle imprese femminili del Mezzogiorno -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/un-milione-di-addetti-nelle-imprese-femminili-del-mezzogiorno\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/un-milione-di-addetti-nelle-imprese-femminili-del-mezzogiorno\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/07\/impfemminile.png\",\"datePublished\":\"2019-07-24T14:26:25+00:00\",\"dateModified\":\"2019-07-24T14:48:44+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/un-milione-di-addetti-nelle-imprese-femminili-del-mezzogiorno\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/un-milione-di-addetti-nelle-imprese-femminili-del-mezzogiorno\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/un-milione-di-addetti-nelle-imprese-femminili-del-mezzogiorno\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/07\/impfemminile.png\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/07\/impfemminile.png\",\"width\":440,\"height\":302},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/un-milione-di-addetti-nelle-imprese-femminili-del-mezzogiorno\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un milione di addetti nelle imprese femminili del Mezzogiorno\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un milione di addetti nelle imprese femminili del Mezzogiorno -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/un-milione-di-addetti-nelle-imprese-femminili-del-mezzogiorno\/","og_locale":"it_IT","og_type":"article","og_title":"Un milione di addetti nelle imprese femminili del Mezzogiorno -","og_description":"Le imprese femminili del Sud danno lavoro a quasi un milione di persone. E\u2019 quanto emerge dalla lettura dei dati sulle aziende guidate da donne al 31 marzo scorso, elaborati dall\u2019Osservatorio per l\u2019imprenditorialit\u00e0 femminile di Unioncamere e InfoCamere. I 3 milioni di addetti presenti nelle imprese femminili (che sono pi\u00f9 di un milione e 330mila [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/un-milione-di-addetti-nelle-imprese-femminili-del-mezzogiorno\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2019-07-24T14:26:25+00:00","article_modified_time":"2019-07-24T14:48:44+00:00","og_image":[{"width":440,"height":302,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/07\/impfemminile.png","type":"image\/png"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/un-milione-di-addetti-nelle-imprese-femminili-del-mezzogiorno\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/un-milione-di-addetti-nelle-imprese-femminili-del-mezzogiorno\/","name":"Un milione di addetti nelle imprese femminili del Mezzogiorno -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/un-milione-di-addetti-nelle-imprese-femminili-del-mezzogiorno\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/un-milione-di-addetti-nelle-imprese-femminili-del-mezzogiorno\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/07\/impfemminile.png","datePublished":"2019-07-24T14:26:25+00:00","dateModified":"2019-07-24T14:48:44+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/un-milione-di-addetti-nelle-imprese-femminili-del-mezzogiorno\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/un-milione-di-addetti-nelle-imprese-femminili-del-mezzogiorno\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/un-milione-di-addetti-nelle-imprese-femminili-del-mezzogiorno\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/07\/impfemminile.png","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/07\/impfemminile.png","width":440,"height":302},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/un-milione-di-addetti-nelle-imprese-femminili-del-mezzogiorno\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Un milione di addetti nelle imprese femminili del Mezzogiorno"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/1368"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=1368"}],"version-history":[{"count":4,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/1368\/revisions"}],"predecessor-version":[{"id":1373,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/1368\/revisions\/1373"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/1369"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=1368"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=1368"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=1368"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}