{"id":1380,"date":"2019-07-25T15:33:00","date_gmt":"2019-07-25T13:33:00","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=1380"},"modified":"2019-07-25T15:39:19","modified_gmt":"2019-07-25T13:39:19","slug":"inpsfalse-comunicazioni-di-addebito-alle-aziende-attraverso-la-pec","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/inpsfalse-comunicazioni-di-addebito-alle-aziende-attraverso-la-pec\/","title":{"rendered":"Inps: false comunicazioni di addebito alle aziende attraverso la PEC"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">S<\/span>ono pervenute segnalazioni da parte di numerose aziende che ricevono attraverso la Posta Elettronica Certificata contestazioni di addebiti relativi a mancati versamenti contributivi. Le email hanno lo scopo di far accedere ad un collegamento, \u201c<em>DETTAGLIO DEGLI ADDEBITI E DEGLI IMPORTI DOVUTI<\/em>\u201d, attraverso il quale viene scaricato un virus informatico.<\/p>\n<p>L\u2019Inps \u00e8 del tutto estraneo a tali PEC e le segnalazioni pervenute all\u2019Istituto sono state inviate alle autorit\u00e0 competenti.<\/p>\n<p>Si ricorda a tutti gli utenti di non dare seguito a richieste ambigue che arrivino via email e che l\u2019unico link per accedere alle informazioni, ai servizi e alle prestazioni dell\u2019Istituto \u00e8 quello del portale istituzionale: <a href=\"http:\/\/www.inps.it\">www.inps.it<\/a><\/p>\n<p>I <a href=\"https:\/\/www.inps.it\/nuovoportaleinps\/default.aspx?iMenu=24\">contatti<\/a> ufficiali sono disponibili sulla home page del sito internet cos\u00ec come gli elenchi degli <a href=\"https:\/\/www.inps.it\/nuovoportaleinps\/default.aspx?sPathID=0%3b50446%3b&amp;lastMenu=50446&amp;iMenu=1\">indirizzi di PEC<\/a> utilizzati dalle strutture INPS.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sono pervenute segnalazioni da parte di numerose aziende che ricevono attraverso la Posta Elettronica Certificata contestazioni di addebiti relativi a mancati versamenti contributivi. Le email hanno lo scopo di far accedere ad un collegamento, \u201cDETTAGLIO DEGLI ADDEBITI E DEGLI IMPORTI DOVUTI\u201d, attraverso il quale viene scaricato un virus informatico. L\u2019Inps \u00e8 del tutto estraneo a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":952,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[490],"tags":[608,247,607,491],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Inps: false comunicazioni di addebito alle aziende attraverso la PEC -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/inpsfalse-comunicazioni-di-addebito-alle-aziende-attraverso-la-pec\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Inps: false comunicazioni di addebito alle aziende attraverso la PEC -\" \/>\n<meta property=\"og:description\" content=\"Sono pervenute segnalazioni da parte di numerose aziende che ricevono attraverso la Posta Elettronica Certificata contestazioni di addebiti relativi a mancati versamenti contributivi. Le email hanno lo scopo di far accedere ad un collegamento, \u201cDETTAGLIO DEGLI ADDEBITI E DEGLI IMPORTI DOVUTI\u201d, attraverso il quale viene scaricato un virus informatico. L\u2019Inps \u00e8 del tutto estraneo a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/inpsfalse-comunicazioni-di-addebito-alle-aziende-attraverso-la-pec\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-25T13:33:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-25T13:39:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/lavoro-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/inpsfalse-comunicazioni-di-addebito-alle-aziende-attraverso-la-pec\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/inpsfalse-comunicazioni-di-addebito-alle-aziende-attraverso-la-pec\/\",\"name\":\"Inps: false comunicazioni di addebito alle aziende attraverso la PEC -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/inpsfalse-comunicazioni-di-addebito-alle-aziende-attraverso-la-pec\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/inpsfalse-comunicazioni-di-addebito-alle-aziende-attraverso-la-pec\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/lavoro-1.jpg\",\"datePublished\":\"2019-07-25T13:33:00+00:00\",\"dateModified\":\"2019-07-25T13:39:19+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/inpsfalse-comunicazioni-di-addebito-alle-aziende-attraverso-la-pec\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/inpsfalse-comunicazioni-di-addebito-alle-aziende-attraverso-la-pec\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/inpsfalse-comunicazioni-di-addebito-alle-aziende-attraverso-la-pec\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/lavoro-1.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/lavoro-1.jpg\",\"width\":960,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/inpsfalse-comunicazioni-di-addebito-alle-aziende-attraverso-la-pec\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Inps: false comunicazioni di addebito alle aziende attraverso la PEC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Inps: false comunicazioni di addebito alle aziende attraverso la PEC -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/inpsfalse-comunicazioni-di-addebito-alle-aziende-attraverso-la-pec\/","og_locale":"it_IT","og_type":"article","og_title":"Inps: false comunicazioni di addebito alle aziende attraverso la PEC -","og_description":"Sono pervenute segnalazioni da parte di numerose aziende che ricevono attraverso la Posta Elettronica Certificata contestazioni di addebiti relativi a mancati versamenti contributivi. Le email hanno lo scopo di far accedere ad un collegamento, \u201cDETTAGLIO DEGLI ADDEBITI E DEGLI IMPORTI DOVUTI\u201d, attraverso il quale viene scaricato un virus informatico. L\u2019Inps \u00e8 del tutto estraneo a [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/inpsfalse-comunicazioni-di-addebito-alle-aziende-attraverso-la-pec\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2019-07-25T13:33:00+00:00","article_modified_time":"2019-07-25T13:39:19+00:00","og_image":[{"width":960,"height":640,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/lavoro-1.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/inpsfalse-comunicazioni-di-addebito-alle-aziende-attraverso-la-pec\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/inpsfalse-comunicazioni-di-addebito-alle-aziende-attraverso-la-pec\/","name":"Inps: false comunicazioni di addebito alle aziende attraverso la PEC -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/inpsfalse-comunicazioni-di-addebito-alle-aziende-attraverso-la-pec\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/inpsfalse-comunicazioni-di-addebito-alle-aziende-attraverso-la-pec\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/lavoro-1.jpg","datePublished":"2019-07-25T13:33:00+00:00","dateModified":"2019-07-25T13:39:19+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/inpsfalse-comunicazioni-di-addebito-alle-aziende-attraverso-la-pec\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/inpsfalse-comunicazioni-di-addebito-alle-aziende-attraverso-la-pec\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/inpsfalse-comunicazioni-di-addebito-alle-aziende-attraverso-la-pec\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/lavoro-1.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/lavoro-1.jpg","width":960,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/inpsfalse-comunicazioni-di-addebito-alle-aziende-attraverso-la-pec\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Inps: false comunicazioni di addebito alle aziende attraverso la PEC"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/1380"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=1380"}],"version-history":[{"count":2,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/1380\/revisions"}],"predecessor-version":[{"id":1386,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/1380\/revisions\/1386"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/952"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=1380"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=1380"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=1380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}