{"id":1403,"date":"2019-07-26T17:02:43","date_gmt":"2019-07-26T15:02:43","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=1403"},"modified":"2019-07-26T17:03:34","modified_gmt":"2019-07-26T15:03:34","slug":"startup-innovative-ecco-tutti-i-dati-al-30-giugno-2019","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/startup-innovative-ecco-tutti-i-dati-al-30-giugno-2019\/","title":{"rendered":"Startup innovative: ecco tutti i dati al 30 giugno 2019"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">\u00c8<\/span> online la nuova edizione del rapporto di monitoraggio trimestrale dedicato ai trend demografici e alle performance economiche delle startup innovative.<\/p>\n<p>L\u2019analisi, che presenta dati aggiornati al 30 giugno 2019, \u00e8 frutto della collaborazione tra <strong>MiSE<\/strong> (DG per la Politica Industriale) e <strong>InfoCamere<\/strong>, con il supporto del sistema delle <strong>Camere di Commercio<\/strong> (Unioncamere).<\/p>\n<p>Il rapporto offre una vasta panoramica sul mondo delle startup, a quasi sette anni dall\u2019introduzione della policy dedicata (d.l. 179\/2012), e costituisce uno dei pilastri dell\u2019esteso sistema di monitoraggio curato dal MISE (archivio reportistica).<br \/>\nTra le principali informazioni contenute nel rapporto:<\/p>\n<ul>\n<li>Crescita della popolazione: le startup iscritte si assestano ormai stabilmente sopra quota 10mila. Al 30 giugno 2019 se ne contano 10.426, il 2,8% di tutte le societ\u00e0 di capitali di recente costituzione;<\/li>\n<li>Distribuzione territoriale: la Lombardia ospita poco pi\u00f9 di un quarto di tutte le startup italiane (25,5%). La sola provincia di Milano, con 1.860, rappresenta il 17,8% della popolazione, pi\u00f9 di qualsiasi altra regione: solo il Lazio supera quota mille, in gran parte localizzate a Roma (1.012, 10% nazionale). Tuttavia, la regione con la maggiore densit\u00e0 di imprese innovative \u00e8 il Trentino-Alto Adige, dove il 5,5% di tutte le societ\u00e0 costituite negli ultimi 5 anni \u00e8 una startup;<\/li>\n<li>Forza lavoro: le startup innovative impiegano complessivamente 60mila persone, almeno 45mila delle quali sono soci di capitale dell\u2019azienda. Elevata la rappresentazione di imprese fondate da under-35 (circa il 20% del totale), mentre risultano sottorappresentate le imprese femminili: 13,5%, contro un 22% registrato nel complesso delle societ\u00e0 di capitali;<\/li>\n<li>Fatturato: le startup innovative sono soprattutto micro-imprese, registrando un valore della produzione medio inferiore ai 150mila euro. Ci\u00f2 \u00e8 anche dovuto al ricambio costante cui \u00e8 soggetta questa popolazione: per definizione, le imprese \u201cbest-performer\u201d, pi\u00f9 consolidate per et\u00e0 e fatturato, tendono progressivamente a perdere lo status di startup innovativa;<\/li>\n<li>Investimenti e redditivit\u00e0: come fisiologico, le startup innovative mostrano un\u2019incidenza pi\u00f9 elevata della media di societ\u00e0 in perdita (55% contro 34% complessivo). Tuttavia, le societ\u00e0 in utile mostrano valori particolarmente positivi in termini di redditivit\u00e0 (ROI, ROE) e valore aggiunto.<\/li>\n<\/ul>\n<p>Inoltre, le startup innovative presentano un tasso di immobilizzazioni \u2013 uno dei principali indicatori della propensione a investire delle aziende \u2013 di ben sei volte pi\u00f9 elevato rispetto alle altre aziende comparabili.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c8 online la nuova edizione del rapporto di monitoraggio trimestrale dedicato ai trend demografici e alle performance economiche delle startup innovative. L\u2019analisi, che presenta dati aggiornati al 30 giugno 2019, \u00e8 frutto della collaborazione tra MiSE (DG per la Politica Industriale) e InfoCamere, con il supporto del sistema delle Camere di Commercio (Unioncamere). Il rapporto [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1052,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[53],"tags":[31,615,614],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Startup innovative: ecco tutti i dati al 30 giugno 2019 -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/startup-innovative-ecco-tutti-i-dati-al-30-giugno-2019\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Startup innovative: ecco tutti i dati al 30 giugno 2019 -\" \/>\n<meta property=\"og:description\" content=\"\u00c8 online la nuova edizione del rapporto di monitoraggio trimestrale dedicato ai trend demografici e alle performance economiche delle startup innovative. L\u2019analisi, che presenta dati aggiornati al 30 giugno 2019, \u00e8 frutto della collaborazione tra MiSE (DG per la Politica Industriale) e InfoCamere, con il supporto del sistema delle Camere di Commercio (Unioncamere). Il rapporto [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/startup-innovative-ecco-tutti-i-dati-al-30-giugno-2019\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-26T15:02:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-26T15:03:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/fattura.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/startup-innovative-ecco-tutti-i-dati-al-30-giugno-2019\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/startup-innovative-ecco-tutti-i-dati-al-30-giugno-2019\/\",\"name\":\"Startup innovative: ecco tutti i dati al 30 giugno 2019 -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/startup-innovative-ecco-tutti-i-dati-al-30-giugno-2019\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/startup-innovative-ecco-tutti-i-dati-al-30-giugno-2019\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/fattura.jpg\",\"datePublished\":\"2019-07-26T15:02:43+00:00\",\"dateModified\":\"2019-07-26T15:03:34+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/startup-innovative-ecco-tutti-i-dati-al-30-giugno-2019\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/startup-innovative-ecco-tutti-i-dati-al-30-giugno-2019\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/startup-innovative-ecco-tutti-i-dati-al-30-giugno-2019\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/fattura.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/fattura.jpg\",\"width\":960,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/startup-innovative-ecco-tutti-i-dati-al-30-giugno-2019\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Startup innovative: ecco tutti i dati al 30 giugno 2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Startup innovative: ecco tutti i dati al 30 giugno 2019 -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/startup-innovative-ecco-tutti-i-dati-al-30-giugno-2019\/","og_locale":"it_IT","og_type":"article","og_title":"Startup innovative: ecco tutti i dati al 30 giugno 2019 -","og_description":"\u00c8 online la nuova edizione del rapporto di monitoraggio trimestrale dedicato ai trend demografici e alle performance economiche delle startup innovative. L\u2019analisi, che presenta dati aggiornati al 30 giugno 2019, \u00e8 frutto della collaborazione tra MiSE (DG per la Politica Industriale) e InfoCamere, con il supporto del sistema delle Camere di Commercio (Unioncamere). Il rapporto [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/startup-innovative-ecco-tutti-i-dati-al-30-giugno-2019\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2019-07-26T15:02:43+00:00","article_modified_time":"2019-07-26T15:03:34+00:00","og_image":[{"width":960,"height":640,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/fattura.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/startup-innovative-ecco-tutti-i-dati-al-30-giugno-2019\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/startup-innovative-ecco-tutti-i-dati-al-30-giugno-2019\/","name":"Startup innovative: ecco tutti i dati al 30 giugno 2019 -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/startup-innovative-ecco-tutti-i-dati-al-30-giugno-2019\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/startup-innovative-ecco-tutti-i-dati-al-30-giugno-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/fattura.jpg","datePublished":"2019-07-26T15:02:43+00:00","dateModified":"2019-07-26T15:03:34+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/startup-innovative-ecco-tutti-i-dati-al-30-giugno-2019\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/startup-innovative-ecco-tutti-i-dati-al-30-giugno-2019\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/startup-innovative-ecco-tutti-i-dati-al-30-giugno-2019\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/fattura.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/fattura.jpg","width":960,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/startup-innovative-ecco-tutti-i-dati-al-30-giugno-2019\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Startup innovative: ecco tutti i dati al 30 giugno 2019"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/1403"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=1403"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/1403\/revisions"}],"predecessor-version":[{"id":1404,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/1403\/revisions\/1404"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/1052"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=1403"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=1403"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=1403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}