{"id":1410,"date":"2019-07-27T07:40:41","date_gmt":"2019-07-27T05:40:41","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=1410"},"modified":"2019-07-26T17:43:27","modified_gmt":"2019-07-26T15:43:27","slug":"ecobonus-cna-labrogazione-dello-sconto-in-fattura-e-lunica-strada-percorribile","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/ecobonus-cna-labrogazione-dello-sconto-in-fattura-e-lunica-strada-percorribile\/","title":{"rendered":"Ecobonus, CNA: \u201cL\u2019abrogazione dello sconto in fattura \u00e8 l\u2019unica strada percorribile\u201d"},"content":{"rendered":"<p>\u201cFinalmente ci si \u00e8 accorti che l\u2019articolo 10 del Decreto Crescita, che ha introdotto lo sconto in fattura per l\u2019Ecobonus e il Sisma-bonus, rappresenta una jattura per artigiani e piccole imprese. Non esistono scorciatoie: l\u2019unica soluzione \u00e8 l\u2019abrogazione della misura.<\/p>\n<p>Sulla base delle anticipazioni del testo, neanche il Ddl presentato in Senato dal M5S per modificare il meccanismo di utilizzo dello sconto appare adeguato a evitare che le imprese siano costrette ad anticipare un contributo pubblico, facendo da bancomat allo Stato. La CNA chiede al Parlamento di imboccare la strada dell\u2019abrogazione al pi\u00f9 presto\u201d.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cFinalmente ci si \u00e8 accorti che l\u2019articolo 10 del Decreto Crescita, che ha introdotto lo sconto in fattura per l\u2019Ecobonus e il Sisma-bonus, rappresenta una jattura per artigiani e piccole imprese. Non esistono scorciatoie: l\u2019unica soluzione \u00e8 l\u2019abrogazione della misura. Sulla base delle anticipazioni del testo, neanche il Ddl presentato in Senato dal M5S per [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":497,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[166],"tags":[425,426,168],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ecobonus, CNA: \u201cL\u2019abrogazione dello sconto in fattura \u00e8 l\u2019unica strada percorribile\u201d -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/ecobonus-cna-labrogazione-dello-sconto-in-fattura-e-lunica-strada-percorribile\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ecobonus, CNA: \u201cL\u2019abrogazione dello sconto in fattura \u00e8 l\u2019unica strada percorribile\u201d -\" \/>\n<meta property=\"og:description\" content=\"\u201cFinalmente ci si \u00e8 accorti che l\u2019articolo 10 del Decreto Crescita, che ha introdotto lo sconto in fattura per l\u2019Ecobonus e il Sisma-bonus, rappresenta una jattura per artigiani e piccole imprese. Non esistono scorciatoie: l\u2019unica soluzione \u00e8 l\u2019abrogazione della misura. Sulla base delle anticipazioni del testo, neanche il Ddl presentato in Senato dal M5S per [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/ecobonus-cna-labrogazione-dello-sconto-in-fattura-e-lunica-strada-percorribile\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-27T05:40:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-26T15:43:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/04\/cantieri.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"638\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/ecobonus-cna-labrogazione-dello-sconto-in-fattura-e-lunica-strada-percorribile\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/ecobonus-cna-labrogazione-dello-sconto-in-fattura-e-lunica-strada-percorribile\/\",\"name\":\"Ecobonus, CNA: \u201cL\u2019abrogazione dello sconto in fattura \u00e8 l\u2019unica strada percorribile\u201d -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/ecobonus-cna-labrogazione-dello-sconto-in-fattura-e-lunica-strada-percorribile\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/ecobonus-cna-labrogazione-dello-sconto-in-fattura-e-lunica-strada-percorribile\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/04\/cantieri.jpg\",\"datePublished\":\"2019-07-27T05:40:41+00:00\",\"dateModified\":\"2019-07-26T15:43:27+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/ecobonus-cna-labrogazione-dello-sconto-in-fattura-e-lunica-strada-percorribile\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/ecobonus-cna-labrogazione-dello-sconto-in-fattura-e-lunica-strada-percorribile\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/ecobonus-cna-labrogazione-dello-sconto-in-fattura-e-lunica-strada-percorribile\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/04\/cantieri.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/04\/cantieri.jpg\",\"width\":960,\"height\":638},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/ecobonus-cna-labrogazione-dello-sconto-in-fattura-e-lunica-strada-percorribile\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ecobonus, CNA: \u201cL\u2019abrogazione dello sconto in fattura \u00e8 l\u2019unica strada percorribile\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ecobonus, CNA: \u201cL\u2019abrogazione dello sconto in fattura \u00e8 l\u2019unica strada percorribile\u201d -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/ecobonus-cna-labrogazione-dello-sconto-in-fattura-e-lunica-strada-percorribile\/","og_locale":"it_IT","og_type":"article","og_title":"Ecobonus, CNA: \u201cL\u2019abrogazione dello sconto in fattura \u00e8 l\u2019unica strada percorribile\u201d -","og_description":"\u201cFinalmente ci si \u00e8 accorti che l\u2019articolo 10 del Decreto Crescita, che ha introdotto lo sconto in fattura per l\u2019Ecobonus e il Sisma-bonus, rappresenta una jattura per artigiani e piccole imprese. Non esistono scorciatoie: l\u2019unica soluzione \u00e8 l\u2019abrogazione della misura. Sulla base delle anticipazioni del testo, neanche il Ddl presentato in Senato dal M5S per [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/ecobonus-cna-labrogazione-dello-sconto-in-fattura-e-lunica-strada-percorribile\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2019-07-27T05:40:41+00:00","article_modified_time":"2019-07-26T15:43:27+00:00","og_image":[{"width":960,"height":638,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/04\/cantieri.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/ecobonus-cna-labrogazione-dello-sconto-in-fattura-e-lunica-strada-percorribile\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/ecobonus-cna-labrogazione-dello-sconto-in-fattura-e-lunica-strada-percorribile\/","name":"Ecobonus, CNA: \u201cL\u2019abrogazione dello sconto in fattura \u00e8 l\u2019unica strada percorribile\u201d -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/ecobonus-cna-labrogazione-dello-sconto-in-fattura-e-lunica-strada-percorribile\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/ecobonus-cna-labrogazione-dello-sconto-in-fattura-e-lunica-strada-percorribile\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/04\/cantieri.jpg","datePublished":"2019-07-27T05:40:41+00:00","dateModified":"2019-07-26T15:43:27+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/ecobonus-cna-labrogazione-dello-sconto-in-fattura-e-lunica-strada-percorribile\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/ecobonus-cna-labrogazione-dello-sconto-in-fattura-e-lunica-strada-percorribile\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/ecobonus-cna-labrogazione-dello-sconto-in-fattura-e-lunica-strada-percorribile\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/04\/cantieri.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/04\/cantieri.jpg","width":960,"height":638},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/ecobonus-cna-labrogazione-dello-sconto-in-fattura-e-lunica-strada-percorribile\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Ecobonus, CNA: \u201cL\u2019abrogazione dello sconto in fattura \u00e8 l\u2019unica strada percorribile\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/1410"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=1410"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/1410\/revisions"}],"predecessor-version":[{"id":1411,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/1410\/revisions\/1411"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/497"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=1410"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=1410"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=1410"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}