{"id":1454,"date":"2019-07-30T18:55:01","date_gmt":"2019-07-30T16:55:01","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=1454"},"modified":"2019-07-30T18:55:40","modified_gmt":"2019-07-30T16:55:40","slug":"il-gruppo-ebano-consolida-la-sua-crescita-e-punta-sul-piano-di-acquisizioni","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/il-gruppo-ebano-consolida-la-sua-crescita-e-punta-sul-piano-di-acquisizioni\/","title":{"rendered":"Il Gruppo Ebano consolida la sua crescita e punta sul piano di acquisizioni"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">C<\/span>irca 18 milioni di fatturato aggregato con una crescita negli ultimi 6 anni dell\u2019800%, 8 societ\u00e0 controllate, 15 partnership produttive, pi\u00f9 di 250 dipendenti e collaboratori, una clientela media annuale che ormai supera le seimila unit\u00e0 per il solo business della formazione a distanza e un piano di crescita per linee interne ed esterne con investimenti nel solo 2018 di 700 mila euro.<\/p>\n<blockquote class=\"td_quote_box td_box_left\"><p>Sono questi alcuni dei numeri dell&#8217;andamento del Gruppo Ebano che lancia il piano triennale di acquisizioni.<\/p><\/blockquote>\n<p>L&#8217;azienda fondata e presieduta dall&#8217;imprenditore <strong>Carlo Robiglio<\/strong> \u00e8 tra i leader in Italia sulla formazione a distanza ed opera anche nell&#8217;editoria, nella comunicazione e nel marketing caratterizzando tutta l&#8217;offerta per il suo approccio innovativo. Tra i punti di forza c\u2019\u00e8 la controllata Cef Publishing, realt\u00e0 che opera nella progettazione, realizzazione ed erogazione di corsi professionali attraverso modalit\u00e0 Fad (formazione a distanza) ed e-learning, in ambiti come il socio assistenziale, l\u2019animal care, il food, l\u2019estetica e il benessere.<\/p>\n<p>Docenti dei suoi corsi sono tra gli altri lo Chef stellato Antonino Cannavacciuolo per il corso \u201cCuoco professionista CHEFuoriclasse\u201d e il truccatore e imprenditore nel mondo della cosmetica Diego Dalla Palma per il corso &#8220;Professionista della Bellezza e del Benessere. Percorso Immagine&#8221;.<\/p>\n<p>L&#8217;azienda \u00e8 stata premiata da Deloitte a maggio a Milano nella sede di Borsa Italiana \u00a0con il Premio \u201cDeloitte Best Managed Companies\u201d (BMC): il riconoscimento rivolto alle aziende che si sono distinte per strategia, competenze, impegno verso le persone e performance realizzato da Deloitte in collaborazione con ALTIS Universit\u00e0 Cattolica, da ELITE &#8211; il progetto del London Stock Exchange Group che supporta lo sviluppo e la crescita delle imprese ad alto potenziale &#8211; e da Confindustria.<\/p>\n<p>\u201cLa storia di Ebano- dichiara Carlo Robiglio &#8211; \u00a0ha radici profonde e ha inizio con l\u2019idea, nata intorno ai primi anni novanta, di dar vita ad una iniziativa imprenditoriale nel mondo dell\u2019editoria e della cultura che potesse, in primo luogo, valorizzare la storia, le tradizioni e i valori di un territorio. La formazione continua insieme agli investimenti in ricerca e innovazione rappresentano i pilastri strategici per la nostra crescita.<br \/>\nPuntiamo a crescere sia per linee interne, rafforzando le competenze del gruppo, che per linee esterne attraverso uno strutturato piano di acquisizioni.&#8221;<\/p>\n<p>&#8220;L&#8217;andamento operativo del Gruppo dall&#8217;acquisizione di Cef- dichiara il direttore generale Silvano Mottura- \u00e8 in costante crescita.<br \/>\nIl Gruppo Ebano tramite Cef Publishing \u00e8 anche in Elite, il programma internazionale nato in Borsa Italiana nel 2012 in collaborazione con Confindustria e dedicato alle aziende pi\u00f9 ambiziose, con un modello di business solido ed una chiara strategia di crescita ed \u00e8 un&#8217;azienda fortemente impegnata nel sociale e nella sostenibilit\u00e0. La politica aziendale del Gruppo Ebano, volta a perseguire alti standard in termini\u2028di sostenibilit\u00e0 e impatto sociale, ha permesso, attraverso la partecipata Cef Publishing, di ottenere la Certificazione b Corp\u00ae, rilasciata dall\u2019ente non-profit americano B Corporation.&#8221;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Circa 18 milioni di fatturato aggregato con una crescita negli ultimi 6 anni dell\u2019800%, 8 societ\u00e0 controllate, 15 partnership produttive, pi\u00f9 di 250 dipendenti e collaboratori, una clientela media annuale che ormai supera le seimila unit\u00e0 per il solo business della formazione a distanza e un piano di crescita per linee interne ed esterne con [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":564,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[133],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Il Gruppo Ebano consolida la sua crescita e punta sul piano di acquisizioni -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/il-gruppo-ebano-consolida-la-sua-crescita-e-punta-sul-piano-di-acquisizioni\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il Gruppo Ebano consolida la sua crescita e punta sul piano di acquisizioni -\" \/>\n<meta property=\"og:description\" content=\"Circa 18 milioni di fatturato aggregato con una crescita negli ultimi 6 anni dell\u2019800%, 8 societ\u00e0 controllate, 15 partnership produttive, pi\u00f9 di 250 dipendenti e collaboratori, una clientela media annuale che ormai supera le seimila unit\u00e0 per il solo business della formazione a distanza e un piano di crescita per linee interne ed esterne con [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/il-gruppo-ebano-consolida-la-sua-crescita-e-punta-sul-piano-di-acquisizioni\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-30T16:55:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-30T16:55:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/04\/Robiglio1-1024x683.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/il-gruppo-ebano-consolida-la-sua-crescita-e-punta-sul-piano-di-acquisizioni\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/il-gruppo-ebano-consolida-la-sua-crescita-e-punta-sul-piano-di-acquisizioni\/\",\"name\":\"Il Gruppo Ebano consolida la sua crescita e punta sul piano di acquisizioni -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/il-gruppo-ebano-consolida-la-sua-crescita-e-punta-sul-piano-di-acquisizioni\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/il-gruppo-ebano-consolida-la-sua-crescita-e-punta-sul-piano-di-acquisizioni\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/04\/Robiglio1.jpg\",\"datePublished\":\"2019-07-30T16:55:01+00:00\",\"dateModified\":\"2019-07-30T16:55:40+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/il-gruppo-ebano-consolida-la-sua-crescita-e-punta-sul-piano-di-acquisizioni\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/il-gruppo-ebano-consolida-la-sua-crescita-e-punta-sul-piano-di-acquisizioni\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/il-gruppo-ebano-consolida-la-sua-crescita-e-punta-sul-piano-di-acquisizioni\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/04\/Robiglio1.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/04\/Robiglio1.jpg\",\"width\":2449,\"height\":1633,\"caption\":\"Carlo Robiglio\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/il-gruppo-ebano-consolida-la-sua-crescita-e-punta-sul-piano-di-acquisizioni\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il Gruppo Ebano consolida la sua crescita e punta sul piano di acquisizioni\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il Gruppo Ebano consolida la sua crescita e punta sul piano di acquisizioni -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/il-gruppo-ebano-consolida-la-sua-crescita-e-punta-sul-piano-di-acquisizioni\/","og_locale":"it_IT","og_type":"article","og_title":"Il Gruppo Ebano consolida la sua crescita e punta sul piano di acquisizioni -","og_description":"Circa 18 milioni di fatturato aggregato con una crescita negli ultimi 6 anni dell\u2019800%, 8 societ\u00e0 controllate, 15 partnership produttive, pi\u00f9 di 250 dipendenti e collaboratori, una clientela media annuale che ormai supera le seimila unit\u00e0 per il solo business della formazione a distanza e un piano di crescita per linee interne ed esterne con [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/il-gruppo-ebano-consolida-la-sua-crescita-e-punta-sul-piano-di-acquisizioni\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2019-07-30T16:55:01+00:00","article_modified_time":"2019-07-30T16:55:40+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/04\/Robiglio1-1024x683.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/il-gruppo-ebano-consolida-la-sua-crescita-e-punta-sul-piano-di-acquisizioni\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/il-gruppo-ebano-consolida-la-sua-crescita-e-punta-sul-piano-di-acquisizioni\/","name":"Il Gruppo Ebano consolida la sua crescita e punta sul piano di acquisizioni -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/il-gruppo-ebano-consolida-la-sua-crescita-e-punta-sul-piano-di-acquisizioni\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/il-gruppo-ebano-consolida-la-sua-crescita-e-punta-sul-piano-di-acquisizioni\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/04\/Robiglio1.jpg","datePublished":"2019-07-30T16:55:01+00:00","dateModified":"2019-07-30T16:55:40+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/il-gruppo-ebano-consolida-la-sua-crescita-e-punta-sul-piano-di-acquisizioni\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/il-gruppo-ebano-consolida-la-sua-crescita-e-punta-sul-piano-di-acquisizioni\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/il-gruppo-ebano-consolida-la-sua-crescita-e-punta-sul-piano-di-acquisizioni\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/04\/Robiglio1.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/04\/Robiglio1.jpg","width":2449,"height":1633,"caption":"Carlo Robiglio"},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/il-gruppo-ebano-consolida-la-sua-crescita-e-punta-sul-piano-di-acquisizioni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Il Gruppo Ebano consolida la sua crescita e punta sul piano di acquisizioni"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/1454"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=1454"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/1454\/revisions"}],"predecessor-version":[{"id":1455,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/1454\/revisions\/1455"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/564"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=1454"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=1454"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=1454"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}