{"id":1495,"date":"2019-08-07T18:55:42","date_gmt":"2019-08-07T16:55:42","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=1495"},"modified":"2019-08-07T18:55:42","modified_gmt":"2019-08-07T16:55:42","slug":"paghiamo-334-miliardi-di-tasse-in-piu-rispetto-alla-media-europea","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/paghiamo-334-miliardi-di-tasse-in-piu-rispetto-alla-media-europea\/","title":{"rendered":"Paghiamo 33,4 miliardi di tasse in pi\u00f9 rispetto alla media Europea"},"content":{"rendered":"<div class=\"page\" title=\"Page 1\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p><span class=\"dropcap dropcap3\">N<\/span>el 2018 gli italiani hanno pagato 33,4 miliardi di euro di tasse in piu\u0300 rispetto all\u2019ammontare complessivo medio versato dai cittadini dell\u2019Unione Europea.<\/p>\n<p>Si tratta di un differenziale che \u201cpesa\u201d quasi 2 punti di Pil.<\/p>\n<p>In termini pro capite, invece, abbiamo corrisposto al fisco 552 euro in piu\u0300 rispetto alla media dei cittadini europei.<\/p>\n<p>A dirlo e\u0300 l\u2019Ufficio studi della CGIA che ha comparato la pressione fiscale dei 28 Paesi dell\u2019UE e, successivamente, ha calcolato il gap esistente tra l\u2019Italia e ciascun Paese appartenente all\u2019Unione (vedi Tab. 1). Denuncia il coordinatore dell\u2019Ufficio studi, Paolo Zabeo:<\/p>\n<p>\u201cIl tempo degli slogan e delle promesse e\u0300 terminato. Con la prossima manovra di Bilancio e\u0300 necessario uno scossone che nel giro di qualche anno riduca di 3-4 punti percentuali il peso delle tasse.<\/p>\n<p>Considerata la delicata situazione dei nostri conti pubblici, tale intervento sara\u0300 praticabile solo ed esclusivamente se si riuscira\u0300 ad abbassare, di pari importo, la spesa pubblica improduttiva e una parte dei bonus fiscali.<\/p>\n<p>Operazione, quest\u2019ultima, che appare difficilmente perseguibile. A confermarlo sono i risultati ottenuti in questi ultimi 10 anni.<\/p>\n<p>Tutti gli esecutivi che si sono succeduti si sono cimentati con grande determinazione sul versante della spending review; gli esiti, pero\u0300, sono stati insoddisfacenti. L\u2019auspicio e\u0300 che il Governo Conte abbia maggiore fortuna\u201d.<\/p>\n<p>Le troppe tasse, comunque, sono un problema non solo perche\u0301 mettono a repentaglio la tenuta finanziaria di tante famiglie e altrettante imprese, ma anche poiche\u0301 hanno innescato nel sistema economico dei processi viziosi molto pericolosi. Afferma il segretario della CGIA, Renato Mason:<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"page\" title=\"Page 2\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>\u201cCon un peso fiscale opprimente e una platea di servizi erogati dall\u2019Amministrazione pubblica che negli ultimi anni e\u0300 diminuita sia in termini di qualita\u0300 che di quantita\u0300, la domanda interna e gli investimenti hanno subito una caduta verticale.<\/p>\n<p>Inoltre, e\u0300 diventato sempre piu\u0300 difficile fare impresa, creare nuovi posti di lavoro e redistribuire la ricchezza.<\/p>\n<p>Alle piccole e piccolissime imprese, altresi\u0300, l\u2019effetto combinato tra il calo dei consumi delle famiglie e la contrazione dei prestiti bancari ha provocato molti squilibri finanziari, costringendo tantissimi lavoratori autonomi a chiudere l\u2019attivita\u0300 e a cambiare mestiere\u201d.<\/p>\n<p>E in attesa che la manovra di Bilancio 2020 chiarisca come verranno \u201crecuperati\u201d i 23,1 miliardi di euro necessari per evitare che dal prossimo 1\u00b0 gennaio l\u2019Iva torni ad aumentare, la CGIA ricorda che la pressione fiscale \u201creale\u201d presente nel nostro Paese e\u0300 di ben 6 punti superiore al dato \u201cufficiale\u201d.<\/p>\n<p>Il nostro Pil, infatti, come del resto quello di altri Paesi dell\u2019Ue, include anche gli effetti dell\u2019economia non osservata che, secondo le ultime stime dell\u2019Istat, ammontano a 209 miliardi di euro all\u2019anno.<\/p>\n<p>Questa \u201cricchezza\u201d, generata dalle attivita\u0300 irregolari e illegali, se da un lato non fornisce alcun contributo all\u2019incremento delle entrate fiscali, dall\u2019altro accresce la dimensione del Pil.<\/p>\n<p>Rammentando che la pressione fiscale si ottiene dal rapporto tra le entrate fiscali e il Pil, se dalla ricchezza prodotta (ovvero dal denominatore) togliamo la componente riconducibile all\u2019economia \u201cin nero\u201d, il risultato del rapporto (vale a dire la pressione fiscale) in capo ai contribuenti onesti aumenta, consegnandoci un carico fiscale \u201creale\u201d molto superiore a quello \u201cufficiale\u201d (48 per cento anziche\u0301 42,1 per cento).<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"page\" title=\"Page 3\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Tornando ai dati della comparazione, sempre nel 2018 e\u0300 emerso che in Europa solo Francia, Belgio, Danimarca, Svezia, Austria e Finlandia hanno pagato mediamente piu\u0300 tasse di noi.<\/p>\n<p>La \u201csorpresa\u201d viene da Parigi: ogni cittadino d\u2019Oltralpe ha versato al fisco 1.830 euro in piu\u0300 rispetto a noi. In termini assoluti il divario fiscale e\u0300 a noi favorevole e ammonta a 110,7 miliardi di euro.<\/p>\n<p>Rispetto agli altri principali competitori, invece, \u201csoccombiamo\u201d sempre.<\/p>\n<p>Se avessimo la pressione fiscale della Germania verseremmo 24,6 miliardi di tasse in meno (407 euro pro capite), dell\u2019Olanda 56,2 (930 euro pro capite), del Regno Unito 114,2 (1.888 euro pro capite) e della Spagna 119,5 (1.975 euro pro capite).<\/p>\n<p>La flat tax puo\u0300 costituire la medicina che consentira\u0300 alla pressione fiscale italiana di scendere ad un livello accettabile? Premesso che qualsiasi misura che riduca il peso delle tasse non puo\u0300 che essere salutata positivamente, bisogna fare molta attenzione.<\/p>\n<p>Se i numeri in circolazione in queste settimane saranno confermati, pare che gia\u0300 oggi sulla maggior parte dei contribuenti Irpef gravi un\u2019aliquota effettiva inferiore al 15 per cento.<\/p>\n<p>Pertanto, l\u2019applicazione della tassa piatta rischia di interessare un numero ristretto di soggetti con redditi medio-alti.<\/p>\n<p>Tuttavia, la vera questione sara\u0300 dove trovare le risorse per realizzare questa decisa riduzione delle imposte.<\/p>\n<p>Se difficilmente saranno compensate da un risparmio della spesa, il ministro Tria, seppur critico sulla flat tax, pare abbia in mente la soluzione: il taglio dell\u2019Irpef potrebbe essere in parte coperto da un aumento dell\u2019Iva, anche in forma selettiva.<\/p>\n<p>Operazione che, secondo la CGIA, favorirebbe sicuramente le esportazioni, come sostengono i tecnici di via Venti Settembre, ma penalizzerebbe i consumi interni.<\/p>\n<p>E a pagare il conto non sarebbero solo le famiglie, in particolar modo quelle meno abbienti, ma anche gli artigiani, i piccoli commercianti e i lavoratori autonomi che vivono quasi esclusivamente di domanda interna.<\/p>\n<p>Gli artigiani mestrini, infine, ricordano che, nell\u2019ipotesi peggiore, se non verranno recuperati entro la fine di quest\u2019anno 23,1 miliardi di euro, l\u2019aliquota ordinaria passera\u0300 dal 22 al 25,2 per cento, mentre quella ridotta salira\u0300 dal 10 al 13 per cento.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Nel 2018 gli italiani hanno pagato 33,4 miliardi di euro di tasse in piu\u0300 rispetto all\u2019ammontare complessivo medio versato dai cittadini dell\u2019Unione Europea. Si tratta di un differenziale che \u201cpesa\u201d quasi 2 punti di Pil. In termini pro capite, invece, abbiamo corrisposto al fisco 552 euro in piu\u0300 rispetto alla media dei cittadini europei. A [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":201,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41],"tags":[44,221,189],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Paghiamo 33,4 miliardi di tasse in pi\u00f9 rispetto alla media Europea -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/paghiamo-334-miliardi-di-tasse-in-piu-rispetto-alla-media-europea\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Paghiamo 33,4 miliardi di tasse in pi\u00f9 rispetto alla media Europea -\" \/>\n<meta property=\"og:description\" content=\"Nel 2018 gli italiani hanno pagato 33,4 miliardi di euro di tasse in piu\u0300 rispetto all\u2019ammontare complessivo medio versato dai cittadini dell\u2019Unione Europea. Si tratta di un differenziale che \u201cpesa\u201d quasi 2 punti di Pil. In termini pro capite, invece, abbiamo corrisposto al fisco 552 euro in piu\u0300 rispetto alla media dei cittadini europei. A [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/paghiamo-334-miliardi-di-tasse-in-piu-rispetto-alla-media-europea\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-07T16:55:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/08\/tax.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"340\" \/>\n\t<meta property=\"og:image:height\" content=\"340\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/paghiamo-334-miliardi-di-tasse-in-piu-rispetto-alla-media-europea\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/paghiamo-334-miliardi-di-tasse-in-piu-rispetto-alla-media-europea\/\",\"name\":\"Paghiamo 33,4 miliardi di tasse in pi\u00f9 rispetto alla media Europea -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/paghiamo-334-miliardi-di-tasse-in-piu-rispetto-alla-media-europea\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/paghiamo-334-miliardi-di-tasse-in-piu-rispetto-alla-media-europea\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/08\/tax.jpg\",\"datePublished\":\"2019-08-07T16:55:42+00:00\",\"dateModified\":\"2019-08-07T16:55:42+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/paghiamo-334-miliardi-di-tasse-in-piu-rispetto-alla-media-europea\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/paghiamo-334-miliardi-di-tasse-in-piu-rispetto-alla-media-europea\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/paghiamo-334-miliardi-di-tasse-in-piu-rispetto-alla-media-europea\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/08\/tax.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/08\/tax.jpg\",\"width\":340,\"height\":340},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/paghiamo-334-miliardi-di-tasse-in-piu-rispetto-alla-media-europea\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Paghiamo 33,4 miliardi di tasse in pi\u00f9 rispetto alla media Europea\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Paghiamo 33,4 miliardi di tasse in pi\u00f9 rispetto alla media Europea -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/paghiamo-334-miliardi-di-tasse-in-piu-rispetto-alla-media-europea\/","og_locale":"it_IT","og_type":"article","og_title":"Paghiamo 33,4 miliardi di tasse in pi\u00f9 rispetto alla media Europea -","og_description":"Nel 2018 gli italiani hanno pagato 33,4 miliardi di euro di tasse in piu\u0300 rispetto all\u2019ammontare complessivo medio versato dai cittadini dell\u2019Unione Europea. Si tratta di un differenziale che \u201cpesa\u201d quasi 2 punti di Pil. In termini pro capite, invece, abbiamo corrisposto al fisco 552 euro in piu\u0300 rispetto alla media dei cittadini europei. A [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/paghiamo-334-miliardi-di-tasse-in-piu-rispetto-alla-media-europea\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2019-08-07T16:55:42+00:00","og_image":[{"width":340,"height":340,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/08\/tax.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/paghiamo-334-miliardi-di-tasse-in-piu-rispetto-alla-media-europea\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/paghiamo-334-miliardi-di-tasse-in-piu-rispetto-alla-media-europea\/","name":"Paghiamo 33,4 miliardi di tasse in pi\u00f9 rispetto alla media Europea -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/paghiamo-334-miliardi-di-tasse-in-piu-rispetto-alla-media-europea\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/paghiamo-334-miliardi-di-tasse-in-piu-rispetto-alla-media-europea\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/08\/tax.jpg","datePublished":"2019-08-07T16:55:42+00:00","dateModified":"2019-08-07T16:55:42+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/paghiamo-334-miliardi-di-tasse-in-piu-rispetto-alla-media-europea\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/paghiamo-334-miliardi-di-tasse-in-piu-rispetto-alla-media-europea\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/paghiamo-334-miliardi-di-tasse-in-piu-rispetto-alla-media-europea\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/08\/tax.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/08\/tax.jpg","width":340,"height":340},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/paghiamo-334-miliardi-di-tasse-in-piu-rispetto-alla-media-europea\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Paghiamo 33,4 miliardi di tasse in pi\u00f9 rispetto alla media Europea"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/1495"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=1495"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/1495\/revisions"}],"predecessor-version":[{"id":1496,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/1495\/revisions\/1496"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/201"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=1495"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=1495"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=1495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}