{"id":1505,"date":"2019-08-13T15:51:00","date_gmt":"2019-08-13T13:51:00","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=1505"},"modified":"2019-08-13T15:51:00","modified_gmt":"2019-08-13T13:51:00","slug":"un-terzo-dellindustria-della-vacanza-e-donna-quasi-150mila-le-imprese-femminili","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/un-terzo-dellindustria-della-vacanza-e-donna-quasi-150mila-le-imprese-femminili\/","title":{"rendered":"Un terzo dell\u2019industria della vacanza \u00e8 donna: quasi 150mila le imprese femminili"},"content":{"rendered":"<p><strong>Quasi un terzo dell\u2019industria della vacanza \u00e8 in mano alle donne d\u2019impresa<\/strong>. Sono infatti oltre <strong>148mila <\/strong>le imprese femminili che si occupano di attivit\u00e0 di ristorazione e alloggio, di servizi turistici o legati all\u2019intrattenimento e al divertimento, il 29,5% del totale. Sensibile la crescita di questo insieme in 4 anni: <strong>+8,7% e quasi 12mila imprese in pi\u00f9.<\/strong><\/p>\n<p>Dall\u2019elaborazione effettuata dall\u2019Osservatorio sull\u2019imprenditorialit\u00e0 femminile di <strong>Unioncamere<\/strong> e <strong>InfoCamere<\/strong>, sulla base dei dati al 30 giugno scorso, emergono con chiarezza i settori turistici a maggior vocazione femminile, ma anche quelli che in questi ultimi anni hanno attratto maggiormente le donne.<\/p>\n<p>Come mostrano i tassi di femminilizzazione di questi settori (dati dal rapporto tra imprese totali e imprese femminili), nell\u2019avviare una attivit\u00e0 dedicata alla vacanza e al divertimento, le donne puntano di pi\u00f9 sui bed and breakfast e sulle case vacanza piuttosto che sugli alberghi, sui bar piuttosto che su ristoranti, sui parchi divertimento e sui parchi tematici piuttosto che sugli stabilimenti balneari o sulle palestre.<\/p>\n<p>E diventano quasi decisive, \u201cpesando\u201d oltre il 40% del totale, in tutti quegli ambiti in cui probabilmente la capacit\u00e0 organizzativa o un pi\u00f9 elevato titolo di studi fanno la differenza: quasi il 42% delle agenzie di viaggio \u00e8 al femminile, lo sono anche il 40% delle imprese che forniscono servizi su prenotazione e guide turistiche, e, sebbene con numeri complessivamente pi\u00f9 contenuti, al femminile \u00e8 anche il 41% delle attivit\u00e0 di biblioteche ed archivi, cos\u00ec come lo \u00e8 il 30% circa dei musei.<\/p>\n<p>Il confronto con il 2015, poi, mostra una vera \u201cimpennata\u201d di imprese guidate da donne nel settore dei bed and breakfast e delle case vacanze (+4.258 imprese) e in quello dei servizi di prenotazione e guide turistiche (+517). Oltre 5mila in pi\u00f9, inoltre, i ristoranti gestiti da donne rispetto a 4 anni fa e circa 1.300 i bar al femminile aggiuntivi rispetto alla fotografia scattata a fine giugno 2015.<\/p>\n<p>Il settore dell\u2019alloggio e della ristorazione, comparto fondamentale dell\u2019industria turistica nazionale, rappresenta del resto uno degli ambiti in cui <strong>il milione e 338mila imprese<\/strong> femminili sono pi\u00f9 diffuse: 133.531 quelle registrate a fine giugno scorso, pari al 29,37% del totale. In termini di numerosit\u00e0, comunque, i primi settori per partecipazione femminile all\u2019impresa sono il commercio, con oltre 356mila imprese guidate da donne, e l\u2019agricoltura, con pi\u00f9 di 211mila.<\/p>\n<p>Anche l\u2019elevata presenza di imprese femminili nel commercio e nel turismo \u00e8 probabilmente tra le ragioni per cui <strong>pi\u00f9 di un terzo delle attivit\u00e0 guidate da donne si concentra nella citt\u00e0 metropolitane<\/strong>, a partire da Roma, Milano e Napoli. In termini di incidenza percentuale sul totale delle imprese registrate, invece, sono alcune piccole province, molte delle quali del Mezzogiorno, a trainare la classifica nazionale, a cominciare da Benevento, Avellino e Chieti, in cui le donne di impresa sfiorano il 30% delle attivit\u00e0 totali.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quasi un terzo dell\u2019industria della vacanza \u00e8 in mano alle donne d\u2019impresa. Sono infatti oltre 148mila le imprese femminili che si occupano di attivit\u00e0 di ristorazione e alloggio, di servizi turistici o legati all\u2019intrattenimento e al divertimento, il 29,5% del totale. Sensibile la crescita di questo insieme in 4 anni: +8,7% e quasi 12mila imprese [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1506,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56],"tags":[648,68],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Un terzo dell\u2019industria della vacanza \u00e8 donna: quasi 150mila le imprese femminili -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/un-terzo-dellindustria-della-vacanza-e-donna-quasi-150mila-le-imprese-femminili\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un terzo dell\u2019industria della vacanza \u00e8 donna: quasi 150mila le imprese femminili -\" \/>\n<meta property=\"og:description\" content=\"Quasi un terzo dell\u2019industria della vacanza \u00e8 in mano alle donne d\u2019impresa. Sono infatti oltre 148mila le imprese femminili che si occupano di attivit\u00e0 di ristorazione e alloggio, di servizi turistici o legati all\u2019intrattenimento e al divertimento, il 29,5% del totale. Sensibile la crescita di questo insieme in 4 anni: +8,7% e quasi 12mila imprese [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/un-terzo-dellindustria-della-vacanza-e-donna-quasi-150mila-le-imprese-femminili\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-13T13:51:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/UN-TERZO-DELLINDUSTRIA-DELLA-VACANZA-DONNA1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"440\" \/>\n\t<meta property=\"og:image:height\" content=\"369\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/un-terzo-dellindustria-della-vacanza-e-donna-quasi-150mila-le-imprese-femminili\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/un-terzo-dellindustria-della-vacanza-e-donna-quasi-150mila-le-imprese-femminili\/\",\"name\":\"Un terzo dell\u2019industria della vacanza \u00e8 donna: quasi 150mila le imprese femminili -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/un-terzo-dellindustria-della-vacanza-e-donna-quasi-150mila-le-imprese-femminili\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/un-terzo-dellindustria-della-vacanza-e-donna-quasi-150mila-le-imprese-femminili\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/UN-TERZO-DELLINDUSTRIA-DELLA-VACANZA-DONNA1.png\",\"datePublished\":\"2019-08-13T13:51:00+00:00\",\"dateModified\":\"2019-08-13T13:51:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/un-terzo-dellindustria-della-vacanza-e-donna-quasi-150mila-le-imprese-femminili\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/un-terzo-dellindustria-della-vacanza-e-donna-quasi-150mila-le-imprese-femminili\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/un-terzo-dellindustria-della-vacanza-e-donna-quasi-150mila-le-imprese-femminili\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/UN-TERZO-DELLINDUSTRIA-DELLA-VACANZA-DONNA1.png\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/UN-TERZO-DELLINDUSTRIA-DELLA-VACANZA-DONNA1.png\",\"width\":440,\"height\":369},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/un-terzo-dellindustria-della-vacanza-e-donna-quasi-150mila-le-imprese-femminili\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un terzo dell\u2019industria della vacanza \u00e8 donna: quasi 150mila le imprese femminili\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un terzo dell\u2019industria della vacanza \u00e8 donna: quasi 150mila le imprese femminili -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/un-terzo-dellindustria-della-vacanza-e-donna-quasi-150mila-le-imprese-femminili\/","og_locale":"it_IT","og_type":"article","og_title":"Un terzo dell\u2019industria della vacanza \u00e8 donna: quasi 150mila le imprese femminili -","og_description":"Quasi un terzo dell\u2019industria della vacanza \u00e8 in mano alle donne d\u2019impresa. Sono infatti oltre 148mila le imprese femminili che si occupano di attivit\u00e0 di ristorazione e alloggio, di servizi turistici o legati all\u2019intrattenimento e al divertimento, il 29,5% del totale. Sensibile la crescita di questo insieme in 4 anni: +8,7% e quasi 12mila imprese [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/un-terzo-dellindustria-della-vacanza-e-donna-quasi-150mila-le-imprese-femminili\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2019-08-13T13:51:00+00:00","og_image":[{"width":440,"height":369,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/UN-TERZO-DELLINDUSTRIA-DELLA-VACANZA-DONNA1.png","type":"image\/png"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/un-terzo-dellindustria-della-vacanza-e-donna-quasi-150mila-le-imprese-femminili\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/un-terzo-dellindustria-della-vacanza-e-donna-quasi-150mila-le-imprese-femminili\/","name":"Un terzo dell\u2019industria della vacanza \u00e8 donna: quasi 150mila le imprese femminili -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/un-terzo-dellindustria-della-vacanza-e-donna-quasi-150mila-le-imprese-femminili\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/un-terzo-dellindustria-della-vacanza-e-donna-quasi-150mila-le-imprese-femminili\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/UN-TERZO-DELLINDUSTRIA-DELLA-VACANZA-DONNA1.png","datePublished":"2019-08-13T13:51:00+00:00","dateModified":"2019-08-13T13:51:00+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/un-terzo-dellindustria-della-vacanza-e-donna-quasi-150mila-le-imprese-femminili\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/un-terzo-dellindustria-della-vacanza-e-donna-quasi-150mila-le-imprese-femminili\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/un-terzo-dellindustria-della-vacanza-e-donna-quasi-150mila-le-imprese-femminili\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/UN-TERZO-DELLINDUSTRIA-DELLA-VACANZA-DONNA1.png","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/UN-TERZO-DELLINDUSTRIA-DELLA-VACANZA-DONNA1.png","width":440,"height":369},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/un-terzo-dellindustria-della-vacanza-e-donna-quasi-150mila-le-imprese-femminili\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Un terzo dell\u2019industria della vacanza \u00e8 donna: quasi 150mila le imprese femminili"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/1505"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=1505"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/1505\/revisions"}],"predecessor-version":[{"id":1507,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/1505\/revisions\/1507"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/1506"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=1505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=1505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=1505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}