{"id":1586,"date":"2019-08-27T11:15:08","date_gmt":"2019-08-27T09:15:08","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=1586"},"modified":"2019-08-27T11:33:58","modified_gmt":"2019-08-27T09:33:58","slug":"universita-per-gli-italiani-costa-di-piu","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/universita-per-gli-italiani-costa-di-piu\/","title":{"rendered":"Universit\u00e0, per gli italiani costa di pi\u00f9"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">Q<\/span>uanto costa andare all&#8217;universit\u00e0? Sono tanti gli s\u00adtudenti che richiedono finanziamenti sul web per affrontare percorsi formativi e accademici.<\/p>\n<p>&nbsp;<\/p>\n<p>Quest&#8217;anno, come rivela l&#8217;ultimo osservatorio SosTariffe in materia finanziaria, la cifra richiesta per far fronte alle esigenze di studio \u00e8 decollata (del <strong>13,56%<\/strong>), passando da un importo medio di <strong>67.600 euro<\/strong> del 2018, ai <strong>76.750 euro del 2019<\/strong>.<\/p>\n<p>E anche la durata media del finanziamento \u00e8 cresciuta, passando da <strong>quattro a cinque anni<\/strong> (con un incremento del 22%).<\/p>\n<p><strong><u>Prestiti agli universitari: pi\u00f9 lunghi e cospicui <\/u><\/strong><\/p>\n<p>L&#8217;indagine \u00e8 stata condotta ad agosto 2019, esaminando le richieste di finanziamento online pervenute al <a href=\"https:\/\/www.sostariffe.it\/prestiti\/\">comparatore prestiti<\/a> e finanziamenti di SosTariffe.<\/p>\n<p>L\u2019osservatorio ha paragonato le cifre medie inserite dagli italiani nelle richieste di preventivi nel corso del 2018 e del 2019. In particolare \u00e8 stato considerato il lasso di tempo gennaio &#8211; agosto 2018, e lo stesso periodo di quest\u2019anno.<\/p>\n<p><strong>Se nel 2018 l&#8217;importo medio necessario per sostenere le proprie esigenze di studio era di 67.587 euro, quest&#8217;anno <\/strong>chi cerca di risparmiare confrontando i preventivi online punta a ottenere una somma pi\u00f9 alta, pari a<strong> euro 67.755 (circa il 13,56% in pi\u00f9). <\/strong><\/p>\n<p><strong>Si ha bisogno di pi\u00f9 liquidit\u00e0 ma anche di pi\u00f9 tempo per restituirla.<\/strong> Anche la durata media del finanziamento-tipo infatti, si \u00e8 allungata. Mentre i finanziamenti richiesti alle porte del precedente anno accademico erano da rimborsare in media entro 50 mesi (circa in quattro anni) i prestiti di quest&#8217;anno hanno una scadenza di rimborso prevista a 61 mesi, pi\u00f9 o meno pari a cinque anni. <strong>Si registra pertanto anche una variazione della durata media del prestito (pari al 22% in pi\u00f9).<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quanto costa andare all&#8217;universit\u00e0? Sono tanti gli s\u00adtudenti che richiedono finanziamenti sul web per affrontare percorsi formativi e accademici. &nbsp; Quest&#8217;anno, come rivela l&#8217;ultimo osservatorio SosTariffe in materia finanziaria, la cifra richiesta per far fronte alle esigenze di studio \u00e8 decollata (del 13,56%), passando da un importo medio di 67.600 euro del 2018, ai 76.750 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1587,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[133],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Universit\u00e0, per gli italiani costa di pi\u00f9 -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/universita-per-gli-italiani-costa-di-piu\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Universit\u00e0, per gli italiani costa di pi\u00f9 -\" \/>\n<meta property=\"og:description\" content=\"Quanto costa andare all&#8217;universit\u00e0? Sono tanti gli s\u00adtudenti che richiedono finanziamenti sul web per affrontare percorsi formativi e accademici. &nbsp; Quest&#8217;anno, come rivela l&#8217;ultimo osservatorio SosTariffe in materia finanziaria, la cifra richiesta per far fronte alle esigenze di studio \u00e8 decollata (del 13,56%), passando da un importo medio di 67.600 euro del 2018, ai 76.750 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/universita-per-gli-italiani-costa-di-piu\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-27T09:15:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-08-27T09:33:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/prestiti.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/universita-per-gli-italiani-costa-di-piu\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/universita-per-gli-italiani-costa-di-piu\/\",\"name\":\"Universit\u00e0, per gli italiani costa di pi\u00f9 -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/universita-per-gli-italiani-costa-di-piu\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/universita-per-gli-italiani-costa-di-piu\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/prestiti.jpg\",\"datePublished\":\"2019-08-27T09:15:08+00:00\",\"dateModified\":\"2019-08-27T09:33:58+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/universita-per-gli-italiani-costa-di-piu\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/universita-per-gli-italiani-costa-di-piu\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/universita-per-gli-italiani-costa-di-piu\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/prestiti.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/prestiti.jpg\",\"width\":960,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/universita-per-gli-italiani-costa-di-piu\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Universit\u00e0, per gli italiani costa di pi\u00f9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Universit\u00e0, per gli italiani costa di pi\u00f9 -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/universita-per-gli-italiani-costa-di-piu\/","og_locale":"it_IT","og_type":"article","og_title":"Universit\u00e0, per gli italiani costa di pi\u00f9 -","og_description":"Quanto costa andare all&#8217;universit\u00e0? Sono tanti gli s\u00adtudenti che richiedono finanziamenti sul web per affrontare percorsi formativi e accademici. &nbsp; Quest&#8217;anno, come rivela l&#8217;ultimo osservatorio SosTariffe in materia finanziaria, la cifra richiesta per far fronte alle esigenze di studio \u00e8 decollata (del 13,56%), passando da un importo medio di 67.600 euro del 2018, ai 76.750 [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/universita-per-gli-italiani-costa-di-piu\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2019-08-27T09:15:08+00:00","article_modified_time":"2019-08-27T09:33:58+00:00","og_image":[{"width":960,"height":640,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/prestiti.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/universita-per-gli-italiani-costa-di-piu\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/universita-per-gli-italiani-costa-di-piu\/","name":"Universit\u00e0, per gli italiani costa di pi\u00f9 -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/universita-per-gli-italiani-costa-di-piu\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/universita-per-gli-italiani-costa-di-piu\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/prestiti.jpg","datePublished":"2019-08-27T09:15:08+00:00","dateModified":"2019-08-27T09:33:58+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/universita-per-gli-italiani-costa-di-piu\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/universita-per-gli-italiani-costa-di-piu\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/universita-per-gli-italiani-costa-di-piu\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/prestiti.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/prestiti.jpg","width":960,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/universita-per-gli-italiani-costa-di-piu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Universit\u00e0, per gli italiani costa di pi\u00f9"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/1586"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=1586"}],"version-history":[{"count":4,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/1586\/revisions"}],"predecessor-version":[{"id":1591,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/1586\/revisions\/1591"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/1587"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=1586"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=1586"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=1586"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}