{"id":1622,"date":"2019-08-30T10:18:54","date_gmt":"2019-08-30T08:18:54","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=1622"},"modified":"2019-08-30T10:18:54","modified_gmt":"2019-08-30T08:18:54","slug":"lavoratori-anziani-e-infortuni-sul-lavoro-in-agricoltura-la-frequenza-piu-alta","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/lavoratori-anziani-e-infortuni-sul-lavoro-in-agricoltura-la-frequenza-piu-alta\/","title":{"rendered":"Lavoratori anziani e infortuni sul lavoro, in agricoltura la frequenza pi\u00f9 alta"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">N<\/span>ei paesi occidentali l\u2019invecchiamento della popolazione anziana in et\u00e0 lavorativa appare da tempo sempre pi\u00f9 evidente. Secondo l\u2019Organizzazione mondiale della Sanit\u00e0, la definizione di \u201clavoratore che invecchia\u201d \u00e8 quella di un addetto che supera l\u2019et\u00e0 di 45 anni, mentre \u00e8 denominato \u201clavoratore anziano\u201d chi ha oltre 55 anni. Nell\u2019Unione Europea si stima che nel 2025 i lavoratori di et\u00e0 compresa tra i 50 e i 64 anni saranno il 35%, ponendo problemi di sostenibilit\u00e0 economica anche sotto il profilo sanitario e pensionistico, con un incremento della durata della vita lavorativa.<\/p>\n<p><strong>L\u2019invecchiamento attivo dei lavoratori gi\u00e0 al centro della campagna Eu-Osha 2016-2017.<\/strong> Il tema dell\u2019anzianit\u00e0 della popolazione lavorativa \u00e8 divenuto centrale nelle analisi di esperti e osservatori per l\u2019impatto che esso ha sulle dinamiche occupazionali e sociali. Su di esso si \u00e8 ampiamente riflettuto proprio di recente con la campagna 2016-2017 dell\u2019Agenzia europea per la sicurezza e la salute sul lavoro (Eu-Osha), dedicata all\u2019invecchiamento attivo dei lavoratori e alla sensibilizzazione sull\u2019importanza del lavoro sostenibile nel corso dell\u2019intera vita professionale.<\/p>\n<p><strong>Le informazioni sugli infortuni degli anziani tratte dalla banca dati Infor.MO.<\/strong> A rioccuparsi delle conseguenze dell\u2019invecchiamento e delle loro ripercussioni sull\u2019andamento infortunistico in Italia \u00e8 ora un report redatto dal Dipartimento di medicina, epidemiologia, igiene del lavoro e ambientale (Dimeila) dell\u2019Inail, consultabile nell\u2019area \u201ccomunicazione\u201d del sito dell\u2019Istituto. Nel documento vengono analizzati, dal 2011 al 2015, i dati infortunistici dei lavoratori anziani, di et\u00e0 pari o superiore ai 55 anni, presenti nella banca dati Infor.MO, ed esaminati secondo i seguenti criteri: attivit\u00e0 svolte dall\u2019infortunato; attivit\u00e0 compiute da soggetti terzi; utilizzo di utensili, macchine, impianti; uso di materiali; fattori ambientali; utilizzazione di dispositivi di protezione ambientale. Nel repertorio Infor.MO, che \u00e8 il sistema nazionale di sorveglianza degli infortuni mortali e gravi sul lavoro, sono riportati dati sintetici e analisi delle dinamiche correlate in un flusso temporale che va dall\u2019inizio dell\u2019incidente fino alle sue fasi definitive.<\/p>\n<p><strong>In agricoltura la percentuale maggiore di incidenti mortali.<\/strong> Sul totale dei 1.256 casi registrati nel quinquennio preso in esame, nell\u2019archivio sono segnalati 442 infortuni mortali di lavoratori anziani, avvenuti principalmente nel settore agricolo (44%) e nelle costruzioni (24%), seguiti dal comparto manifatturiero, dal terziario e dai trasporti. Per quanto riguarda la tipologia di impresa, gli infortuni sono accaduti essenzialmente nelle micro imprese (80%), mentre risulta bassa (7%) la quota di casi avvenuti in aziende medio grandi, cio\u00e8 da cinquanta addetti in su.<\/p>\n<p><strong>Frequenti i ribaltamenti da trattore.<\/strong> La scheda poi passa ad analizzare i fattori di rischio presenti nei cinque comparti esaminati. Le modalit\u00e0 di accadimento pi\u00f9 frequenti negli infortuni mortali risultano essere le cadute dall\u2019alto (34%) e la perdita di controllo dei mezzi utilizzati (25%), molto spesso con il loro ribaltamento. Un dato, quest\u2019ultimo, che le cronache registrano di frequente in agricoltura, in particolare con la segnalazione di incidenti con l\u2019uso di trattori. L\u2019attivit\u00e0 svolta dal lavoratore agricolo nel cagionare l\u2019incidente \u00e8 presente nel 59% dei casi, ed \u00e8 dovuta ad azioni estemporanee o a pratiche abituali non corrette, legate al cosiddetto \u2018fattore dell\u2019esperienza\u2019 che caratterizza il settore agricolo, nel quale \u00e8 pi\u00f9 difficile mutare comportamenti tramandati per tradizione nonostante la loro pericolosit\u00e0.<\/p>\n<p><strong>Nelle attivit\u00e0 manifatturiere segnalate carenze formative e di addestramento.<\/strong> Nel comparto edilizio le cadute dall\u2019alto (71%) si confermano come la causa pi\u00f9 ricorrente, con l\u2019attivit\u00e0 dell\u2019infortunato presente al 42% e il contesto ambientale al 20%. Nel settore manifatturiero, gli eventi mortali pi\u00f9 frequenti tra i lavoratori over 55 sono dovuti a caduta dall\u2019alto dei gravi (29%) e a caduta dall\u2019alto degli infortunati stessi (21%). Anche in questo settore le attivit\u00e0 svolte dalla persona mostrano il loro peso nel verificarsi dell\u2019evento incidentale, causato specificamente per il compimento di azioni estemporanee (38%), pratiche abituali non idonee (33%), carenze nella formazione o nell\u2019addestramento (26%). Le stesse osservazioni possono dirsi anche per il terziario e per il settore dei trasporti.<\/p>\n<p><strong>Necessario un approccio biopsicosociale nella valutazione dei rischi.<\/strong> \u201cDalle analisi riportate \u2013 scrivono gli autori nelle considerazioni conclusive \u2013 emerge che i lavoratori anziani sono una parte crescente della forza lavoro, dal momento che si lavora pi\u00f9 a lungo, per cui la gestione della salute e sicurezza sul lavoro per la forza lavoro in et\u00e0 avanzata \u00e8 divenuta una priorit\u00e0\u201d. E\u2019 necessario quindi \u2013 proseguono i ricercatori del Dimeila \u2013 avviare \u201cun approccio biopsicosociale nella valutazione dei rischi e nella connotazione sociale della popolazione lavorativa\u201d, in grado di riequilibrare la prestazione professionale con le capacit\u00e0 individuali del lavoratore anziano.<\/p>\n<p><strong>Da incrementare corsi di formazione e servizi sanitari.<\/strong> Nella scia di quanto gi\u00e0 affermato dalla campagna Eu-Osha, va quindi cambiato l\u2019atteggiamento verso l\u2019invecchiamento, introducendo aggiornamenti periodici e permanenti, adattando il lavoro all\u2019et\u00e0 e rendendolo pi\u00f9 flessibile. E\u2019 necessario infine rimodulare i servizi sanitari alle esigenze di una popolazione che avanza nell\u2019et\u00e0 coinvolgendo di pi\u00f9 la figura del medico competente nella definizione dei compiti lavorativi e dei rischi correlati.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nei paesi occidentali l\u2019invecchiamento della popolazione anziana in et\u00e0 lavorativa appare da tempo sempre pi\u00f9 evidente. Secondo l\u2019Organizzazione mondiale della Sanit\u00e0, la definizione di \u201clavoratore che invecchia\u201d \u00e8 quella di un addetto che supera l\u2019et\u00e0 di 45 anni, mentre \u00e8 denominato \u201clavoratore anziano\u201d chi ha oltre 55 anni. Nell\u2019Unione Europea si stima che nel 2025 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1623,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[258],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Lavoratori anziani e infortuni sul lavoro, in agricoltura la frequenza pi\u00f9 alta -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/lavoratori-anziani-e-infortuni-sul-lavoro-in-agricoltura-la-frequenza-piu-alta\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lavoratori anziani e infortuni sul lavoro, in agricoltura la frequenza pi\u00f9 alta -\" \/>\n<meta property=\"og:description\" content=\"Nei paesi occidentali l\u2019invecchiamento della popolazione anziana in et\u00e0 lavorativa appare da tempo sempre pi\u00f9 evidente. Secondo l\u2019Organizzazione mondiale della Sanit\u00e0, la definizione di \u201clavoratore che invecchia\u201d \u00e8 quella di un addetto che supera l\u2019et\u00e0 di 45 anni, mentre \u00e8 denominato \u201clavoratore anziano\u201d chi ha oltre 55 anni. Nell\u2019Unione Europea si stima che nel 2025 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/lavoratori-anziani-e-infortuni-sul-lavoro-in-agricoltura-la-frequenza-piu-alta\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-30T08:18:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/incidenti-sul-lavoro.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"594\" \/>\n\t<meta property=\"og:image:height\" content=\"340\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/lavoratori-anziani-e-infortuni-sul-lavoro-in-agricoltura-la-frequenza-piu-alta\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/lavoratori-anziani-e-infortuni-sul-lavoro-in-agricoltura-la-frequenza-piu-alta\/\",\"name\":\"Lavoratori anziani e infortuni sul lavoro, in agricoltura la frequenza pi\u00f9 alta -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/lavoratori-anziani-e-infortuni-sul-lavoro-in-agricoltura-la-frequenza-piu-alta\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/lavoratori-anziani-e-infortuni-sul-lavoro-in-agricoltura-la-frequenza-piu-alta\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/incidenti-sul-lavoro.jpg\",\"datePublished\":\"2019-08-30T08:18:54+00:00\",\"dateModified\":\"2019-08-30T08:18:54+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/lavoratori-anziani-e-infortuni-sul-lavoro-in-agricoltura-la-frequenza-piu-alta\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/lavoratori-anziani-e-infortuni-sul-lavoro-in-agricoltura-la-frequenza-piu-alta\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/lavoratori-anziani-e-infortuni-sul-lavoro-in-agricoltura-la-frequenza-piu-alta\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/incidenti-sul-lavoro.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/incidenti-sul-lavoro.jpg\",\"width\":594,\"height\":340},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/lavoratori-anziani-e-infortuni-sul-lavoro-in-agricoltura-la-frequenza-piu-alta\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lavoratori anziani e infortuni sul lavoro, in agricoltura la frequenza pi\u00f9 alta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lavoratori anziani e infortuni sul lavoro, in agricoltura la frequenza pi\u00f9 alta -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/lavoratori-anziani-e-infortuni-sul-lavoro-in-agricoltura-la-frequenza-piu-alta\/","og_locale":"it_IT","og_type":"article","og_title":"Lavoratori anziani e infortuni sul lavoro, in agricoltura la frequenza pi\u00f9 alta -","og_description":"Nei paesi occidentali l\u2019invecchiamento della popolazione anziana in et\u00e0 lavorativa appare da tempo sempre pi\u00f9 evidente. Secondo l\u2019Organizzazione mondiale della Sanit\u00e0, la definizione di \u201clavoratore che invecchia\u201d \u00e8 quella di un addetto che supera l\u2019et\u00e0 di 45 anni, mentre \u00e8 denominato \u201clavoratore anziano\u201d chi ha oltre 55 anni. Nell\u2019Unione Europea si stima che nel 2025 [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/lavoratori-anziani-e-infortuni-sul-lavoro-in-agricoltura-la-frequenza-piu-alta\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2019-08-30T08:18:54+00:00","og_image":[{"width":594,"height":340,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/incidenti-sul-lavoro.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/lavoratori-anziani-e-infortuni-sul-lavoro-in-agricoltura-la-frequenza-piu-alta\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/lavoratori-anziani-e-infortuni-sul-lavoro-in-agricoltura-la-frequenza-piu-alta\/","name":"Lavoratori anziani e infortuni sul lavoro, in agricoltura la frequenza pi\u00f9 alta -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/lavoratori-anziani-e-infortuni-sul-lavoro-in-agricoltura-la-frequenza-piu-alta\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/lavoratori-anziani-e-infortuni-sul-lavoro-in-agricoltura-la-frequenza-piu-alta\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/incidenti-sul-lavoro.jpg","datePublished":"2019-08-30T08:18:54+00:00","dateModified":"2019-08-30T08:18:54+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/lavoratori-anziani-e-infortuni-sul-lavoro-in-agricoltura-la-frequenza-piu-alta\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/lavoratori-anziani-e-infortuni-sul-lavoro-in-agricoltura-la-frequenza-piu-alta\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/lavoratori-anziani-e-infortuni-sul-lavoro-in-agricoltura-la-frequenza-piu-alta\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/incidenti-sul-lavoro.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/incidenti-sul-lavoro.jpg","width":594,"height":340},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/lavoratori-anziani-e-infortuni-sul-lavoro-in-agricoltura-la-frequenza-piu-alta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Lavoratori anziani e infortuni sul lavoro, in agricoltura la frequenza pi\u00f9 alta"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/1622"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=1622"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/1622\/revisions"}],"predecessor-version":[{"id":1624,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/1622\/revisions\/1624"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/1623"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=1622"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=1622"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=1622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}