{"id":1636,"date":"2019-09-04T09:50:36","date_gmt":"2019-09-04T07:50:36","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=1636"},"modified":"2019-09-04T09:50:36","modified_gmt":"2019-09-04T07:50:36","slug":"utenze-rc-auto-banche-e-telefonia-mobile-a-settembre-pioggia-di-rincari","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/utenze-rc-auto-banche-e-telefonia-mobile-a-settembre-pioggia-di-rincari\/","title":{"rendered":"Utenze, rc auto, banche e telefonia mobile: a settembre pioggia di rincari"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">S<\/span>ettembre prende il via con una pioggia di rincari: i settori pi\u00f9 colpiti sono la telefonia mobile, con prezzi dei pacchetti alle stelle (+28,07%) e l\u2019Rc auto. Ma salgono anche i costi bancari, l\u2019abbonamento alla pay tv e le bollette della luce. Uniche voci leggere sono le fatture del gas e la connessione internet di casa.<\/p>\n<p>L\u2019ultimo studio SosTariffe ha analizzato l\u2019oscillazione del costo medio annuo di tutti i servizi presi in esame dal comparatore, ponendo a confronto i prezzi di gennaio con quelli attuali<strong><em>\u00a0<\/em><\/strong><\/p>\n<p>\u00c8 un ritorno dalle vacanze &#8220;faticoso&#8221; per le tasche di milioni di italiani che a settembre vedranno impennarsi i costi medi annui delle utenze domestiche ma anche di molti altri servizi di uso quotidiano: dall&#8217;energia al gas, dalla connessione internet domestica alla telefonia mobile, passando per RC auto, pay-tv e prezzi di conto corrente.<\/p>\n<p>\u00c8 quanto emerge dall&#8217;ultimo Osservatorio <a href=\"https:\/\/www.sostariffe.it\/\">SosTariffe,<\/a> secondo il quale i rincari colpiranno nel complesso soprattutto le coppie (+7,94%) e meno le famiglie (+ 4,29%) e single (+ 4,05%). La stangata riguarda in primis telefonia mobile (+ 28,08%) ed RC auto (+14,81%). Mentre i prezzi sono in lieve calo per bollette del gas e connessione internet domestica.<\/p>\n<p><strong><u>Coppie, le pi\u00f9 colpite dagli aumenti<\/u><\/strong><\/p>\n<p>L&#8217;indagine \u00e8 stata condotta ad agosto 2019 sulla base di preventivi e richieste pervenute a SosTariffe.it nella rispettiva sezione di comparazione. Lo studio ha tenuto conto delle migliori offerte di servizi pubblicate sul portale. Per ogni servizio sono stati presi in esame tre profili di consumo diversi: il single, la coppia, la famiglia, ed \u00e8 stata posta a confronto la variazione della spesa media annua sostenuta a gennaio 2019 con le previsioni per questo mese di settembre.<\/p>\n<p>Ne \u00e8 venuto fuori che <strong>le coppie sono le pi\u00f9 colpite dagli aumenti autunnali: la loro spesa annua media complessiva, tenuto conto di tutti i servizi esaminati dall\u2019indagine (ovvero luce, gas, internet domestico, telefonia mobile, Rc auto, pay tv e conti correnti)<\/strong> <strong>\u00e8 salita infatti del 7,94%,<\/strong> passando dai 3803,78 euro stimati a gennaio a 4105,66 euro. <strong>A seguire, sul podio dei pi\u00f9 esposti ai rincari troviamo le famiglie<\/strong>, che salgono da 6225,72 euro di spesa annuale preventivata a gennaio a 6492,86 euro di settembre (pari al 4,29% in pi\u00f9). <strong>Infine il carovita si abbatte, anche se in misura minore, sui single<\/strong>, i quali da spendere 2409 euro per tutti i servizi considerati, a settembre si trovano a ricalcolare il budget necessario che schizza a 2506,54 euro (+4,05%).<\/p>\n<p><strong><u>Luce e gas: le bollette dell&#8217;energia salgono, ma si risparmia sul gas<\/u><\/strong><\/p>\n<p>Le fatture della luce al rientro dalle ferie diventano lievemente pi\u00f9 pesanti per tutti. <strong>I rincari pesano di pi\u00f9 sui single <\/strong>(con un fabbisogno annuo ipotizzato di 1400 kWh): per loro mentre a gennaio la spesa media annua si attestava intorno ai 319 euro, a settembre \u00e8 salita a 331,14 euro (con un aumento del 3,81%). <strong>Sulle coppie<\/strong> (due persone con un fabbisogno annuo ipotizzato di 2700 kWh) <strong>gli aumenti si fanno sentire meno<\/strong>: in questo caso si passa dai 558 euro di gennaio ai 569,83 euro di settembre (con un rincaro del 2,12%). <strong>Infine le famiglie<\/strong>: per lo studio si \u00e8 tenuto conto di un nucleo familiare- tipo con un fabbisogno di 3900 kWh annui. <strong>Su di loro gli aumenti sono quasi impercettibili.<\/strong> Si passa dalla spesa media annua di 832 euro stimati a gennaio, ogni 845, 30 attuali (circa l&#8217;1,60% in pi\u00f9).<\/p>\n<p><strong>Per fortuna le bollette del gas diventano pi\u00f9 leggere.<\/strong> I single (con un fabbisogno annuo stimato di 800 metri cubi di gas) passano da 679 euro di gennaio a 635,85 euro di settembre, con un calo del -6,35%. Fatture pi\u00f9 economiche anche per le coppie (con un fabbisogno annuo stimato di 1000 metri cubi), che passano da una spesa media di 837 euro calcolata a gennaio ai 781,17 di settembre (spendendo il 6,67% in meno). <strong>Chi se la cava meglio sono le famiglie. I nuclei familiari infatti<\/strong> (con un fabbisogno annuo stimato di 1500 metri cubi di gas) <strong>passano da 1231 euro stimati a gennaio, ai 1144,39 euro di settembre, pari al -7,04 %. Un bel risparmio insomma.<\/strong><\/p>\n<p><strong><u>Internet di casa: aumenti per coppie e famiglie, i single risparmiano<\/u><\/strong><\/p>\n<p><strong>Per quanto riguarda la connessione internet domestica, settembre non sar\u00e0 un mese di rincari per tutti. Spenderanno meno per navigare ad esempio i single<\/strong> (ipotizzando che usufruiscano di un abbonamento solo internet) le cui bollette caleranno dai 360 euro di spesa media annua stimata a gennaio 2019 ai 330 euro di settembre (- 8, 33%). <strong>Non possono cantare vittoria invece le coppie<\/strong>, con un abbonamento stimato di internet pi\u00f9 telefonate con scatto alla risposta. <strong>In questo caso gli aumenti si faranno davvero sentire<\/strong>: mentre a gennaio la spesa media annua prevista per le coppie era di 302,50 euro, a settembre le tariffe sono salite a 330, 35 euro (con aumenti significativi pari al 9,21%). Chi risente di pi\u00f9 degli aumenti internet sono pi\u00f9 delle coppie, dunque. <strong>Per le famiglie infatti le bollette di internet saranno appena pi\u00f9 lievi<\/strong>. Si va infatti dai 408 euro annui stimati a gennaio, ai 407,76 di settembre (-0,06 %).<\/p>\n<p><strong><u>Telefonia mobile vero salasso dell&#8217;autunno: mega rincari all\u2019orizzonte<\/u><\/strong><\/p>\n<p><strong>Le bollette dei cellulari peseranno moltissimo (+28,08%) su single, coppie e famiglie.<\/strong><br \/>\nPrendiamo in considerazione i single ad esempio. Lo studio ipotizza il caso di un single con un pacchetto di 1000 minuti, 300 sms e 8 GB mensili: se a gennaio la spesa annua ipotizzata per lui era di 243,50 euro, a settembre dovr\u00e0 rivedere la spesa annuale in 311,88 euro (pari appunto al 28,8% in pi\u00f9). <strong>Stessa stangata per le coppie<\/strong>, l&#8217;indagine prende in esame due persone con due offerte da 400 minuti, 200 sms e 5 GB mensili. in questo caso la spesa media annua stimata gennaio di 487 euro rincara, fino ad arrivare a 623, 76 euro (con un incremento sempre del 28,08%). Non sono al riparo dagli aumenti neanche le famiglie. I nuclei familiari tipo ipotizzati dallo studio, sono composti da 3 persone, con un identica tariffa che comprende 1000 minuti, 300 sms e 10 GB al mese. Se le previsioni annuali di gennaio nel loro caso parlavano di 730,50 euro, a settembre la cifra va rivalutata in aumento passando a 935,64 euro (anche in questo caso il 28,08% in pi\u00f9).<\/p>\n<p><strong><u>RC auto: stangata in arrivo per single e coppie<\/u><\/strong><\/p>\n<p><strong>Anche sul versante assicurativo sar\u00e0 un autunno &#8220;caldo&#8221;. Lo studio SosTariffe.it ha previsto rincari sui costi medi annui dell&#8217;RC auto soprattutto per single e coppie.<\/strong> Il single preso in considerazione dallo studio, \u00e8 un trentenne, alla guida una Fiat Panda. Per lui, la spesa media annua assicurativa \u00e8 salita dai 544, 50 euro di gennaio a 623,50 euro di settembre (pari al 14,51% in pi\u00f9). Gli aumenti si faranno sentire anche sulle coppie. L&#8217;indagine del comparatore a considerato una coppia tipo con due veicoli, un uomo 35enne alla guida di una Fiat Panda e una donna trentenne al volante di una Smart ForTwo. Se per loro la previsione di spesa inizio anno era di 1112 euro, ora il premio assicurativo da corrispondere \u00e8 salito a 1276,66 (circa il 14,81% di aumento). Se la caveranno con meno invece le famiglie. Lo studio in questo caso ha preso in considerazione tre veicoli familiari: un Audi A4 guidata da un uomo di 55 anni, una Fiat Panda guidata da una donna di 50 anni, e una Smart ForTwo, il cui conducente \u00e8 un ragazzo diciottenne. In questo caso la spesa annua media assicurativa sale dai 2242 euro complessivi stimati a gennaio, a 2369,72 euro di settembre (in questo caso gli aumenti, pi\u00f9 contenuti, sono pari al 5,70%).<\/p>\n<p><strong><u>Pay TV: i rincari quasi impercettibili<\/u><\/strong><\/p>\n<p><strong>Tra tutti i servizi presi in esame dall&#8217;indagine, la pay tv \u00e8 quella che subisce i rincari minori. <\/strong>Se consideriamo un single, ad esempio, con un abbonamento a una piattaforma streaming tv per vedere serie tv &#8211; cinema o calcio, nel suo caso i prezzi saliranno da 189,46 euro di gennaio a 191,88 di settembre (con un aumento, lieve, dell&#8217;1,28%). Stesso rincaro per una coppia che abbia due distinti abbonamenti, uno per serie tv &#8211; cinema e l&#8217;altro per il calcio. Qui il costo complessivo sale da 378,91 euro di gennaio a 383,76 euro di settembre (anche in questo caso il 1,28% di aumento). <strong>Quasi non si accorgeranno della variazione invece, le famiglie.<\/strong> L&#8217;indagine ipotizza un nucleo familiare con un abbonamento pay tv tradizionale per serie tv, intrattenimento, sport e calcio. La famiglia passa dai 598,80 euro di inizio anno a 603,60 euro stimati al rientro dalle ferie (&#8220;solo&#8221; lo 0,80% in pi\u00f9).<\/p>\n<p><strong><u>Conti correnti: tenere i soldi in banca costa soprattutto ai single<\/u><\/strong><\/p>\n<p>Nel caso dei costi bancari, i rincari di settembre colpiscono soprattutto i single, a seguire le coppie, e in misura lievissima le famiglie.<\/p>\n<p><strong>Partiamo con i single, i pi\u00f9 colpiti<\/strong>: se ipotizziamo il caso di una persona con molti movimenti online e nessuna operazione allo sportello, i costi annuali legati al conto corrente sono saliti da 73,62 euro di gennaio a 82,29 euro (circa l&#8217;11, 78% in pi\u00f9).<\/p>\n<p><strong>Settembre peser\u00e0 meno sulle tasche delle coppie. <\/strong>In questo caso i costi bancari per due persone con molti movimenti online e nessuno allo sportello salgono da 128,37 euro di inizio anno a 140,13 euro di settembre (con un incremento del 9,16 %). Infine, <strong>rincari piuma sui costi bancari per le famiglie<\/strong> (il nucleo ipotizzato dello studio compie pi\u00f9 operazioni allo sportello e poche online). Nel loro caso, i costi bancari da 183, 42 euro di gennaio salgono a 186,45 euro di settembre (pari al 1,65% in pi\u00f9).<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Settembre prende il via con una pioggia di rincari: i settori pi\u00f9 colpiti sono la telefonia mobile, con prezzi dei pacchetti alle stelle (+28,07%) e l\u2019Rc auto. Ma salgono anche i costi bancari, l\u2019abbonamento alla pay tv e le bollette della luce. Uniche voci leggere sono le fatture del gas e la connessione internet di [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1478,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Utenze, rc auto, banche e telefonia mobile: a settembre pioggia di rincari -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/utenze-rc-auto-banche-e-telefonia-mobile-a-settembre-pioggia-di-rincari\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Utenze, rc auto, banche e telefonia mobile: a settembre pioggia di rincari -\" \/>\n<meta property=\"og:description\" content=\"Settembre prende il via con una pioggia di rincari: i settori pi\u00f9 colpiti sono la telefonia mobile, con prezzi dei pacchetti alle stelle (+28,07%) e l\u2019Rc auto. Ma salgono anche i costi bancari, l\u2019abbonamento alla pay tv e le bollette della luce. Uniche voci leggere sono le fatture del gas e la connessione internet di [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/utenze-rc-auto-banche-e-telefonia-mobile-a-settembre-pioggia-di-rincari\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-04T07:50:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/crisi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"944\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/utenze-rc-auto-banche-e-telefonia-mobile-a-settembre-pioggia-di-rincari\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/utenze-rc-auto-banche-e-telefonia-mobile-a-settembre-pioggia-di-rincari\/\",\"name\":\"Utenze, rc auto, banche e telefonia mobile: a settembre pioggia di rincari -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/utenze-rc-auto-banche-e-telefonia-mobile-a-settembre-pioggia-di-rincari\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/utenze-rc-auto-banche-e-telefonia-mobile-a-settembre-pioggia-di-rincari\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/crisi.jpg\",\"datePublished\":\"2019-09-04T07:50:36+00:00\",\"dateModified\":\"2019-09-04T07:50:36+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/utenze-rc-auto-banche-e-telefonia-mobile-a-settembre-pioggia-di-rincari\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/utenze-rc-auto-banche-e-telefonia-mobile-a-settembre-pioggia-di-rincari\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/utenze-rc-auto-banche-e-telefonia-mobile-a-settembre-pioggia-di-rincari\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/crisi.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/crisi.jpg\",\"width\":944,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/utenze-rc-auto-banche-e-telefonia-mobile-a-settembre-pioggia-di-rincari\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Utenze, rc auto, banche e telefonia mobile: a settembre pioggia di rincari\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Utenze, rc auto, banche e telefonia mobile: a settembre pioggia di rincari -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/utenze-rc-auto-banche-e-telefonia-mobile-a-settembre-pioggia-di-rincari\/","og_locale":"it_IT","og_type":"article","og_title":"Utenze, rc auto, banche e telefonia mobile: a settembre pioggia di rincari -","og_description":"Settembre prende il via con una pioggia di rincari: i settori pi\u00f9 colpiti sono la telefonia mobile, con prezzi dei pacchetti alle stelle (+28,07%) e l\u2019Rc auto. Ma salgono anche i costi bancari, l\u2019abbonamento alla pay tv e le bollette della luce. Uniche voci leggere sono le fatture del gas e la connessione internet di [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/utenze-rc-auto-banche-e-telefonia-mobile-a-settembre-pioggia-di-rincari\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2019-09-04T07:50:36+00:00","og_image":[{"width":944,"height":720,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/crisi.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/utenze-rc-auto-banche-e-telefonia-mobile-a-settembre-pioggia-di-rincari\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/utenze-rc-auto-banche-e-telefonia-mobile-a-settembre-pioggia-di-rincari\/","name":"Utenze, rc auto, banche e telefonia mobile: a settembre pioggia di rincari -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/utenze-rc-auto-banche-e-telefonia-mobile-a-settembre-pioggia-di-rincari\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/utenze-rc-auto-banche-e-telefonia-mobile-a-settembre-pioggia-di-rincari\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/crisi.jpg","datePublished":"2019-09-04T07:50:36+00:00","dateModified":"2019-09-04T07:50:36+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/utenze-rc-auto-banche-e-telefonia-mobile-a-settembre-pioggia-di-rincari\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/utenze-rc-auto-banche-e-telefonia-mobile-a-settembre-pioggia-di-rincari\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/utenze-rc-auto-banche-e-telefonia-mobile-a-settembre-pioggia-di-rincari\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/crisi.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/crisi.jpg","width":944,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/utenze-rc-auto-banche-e-telefonia-mobile-a-settembre-pioggia-di-rincari\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Utenze, rc auto, banche e telefonia mobile: a settembre pioggia di rincari"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/1636"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=1636"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/1636\/revisions"}],"predecessor-version":[{"id":1637,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/1636\/revisions\/1637"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/1478"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=1636"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=1636"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=1636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}