{"id":1654,"date":"2019-09-07T09:46:46","date_gmt":"2019-09-07T07:46:46","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=1654"},"modified":"2019-09-07T09:46:46","modified_gmt":"2019-09-07T07:46:46","slug":"il-gruppo-ebano-acquisisce-masterfood-e-sichef","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/il-gruppo-ebano-acquisisce-masterfood-e-sichef\/","title":{"rendered":"Il Gruppo Ebano acquisisce Masterfood e SiChef"},"content":{"rendered":"<div>\n<div><span style=\"font-family: garamond, times new roman, serif; font-size: large;\">Valorizzare e diffondere con metodi innovativi la cultura gastronomica italiana su scala nazionale e internazionale. E\u2019 questa la mission di Masterfood srl, societ\u00e0 di Bari acquisita al 100% dal Gruppo Ebano, che amplia cos\u00ec la propria offerta di contenuti nel settore \u201cFood\u201d e incrementa il business \u201cdell\u2019online\u201d.\u00a0<\/span><\/div>\n<div><\/div>\n<p><span style=\"font-family: garamond, times new roman, serif; font-size: large;\">A Masterfood fa capo SiChef, la prima Accademia che parla di cultura del cibo italiano con didattica 2.0, avallata dal Ministero dello Sviluppo Economico. Attraverso lo strumento dell\u2019e-learning, realizzato con l\u2019apporto di docenti chef qualificati e innovative video lezioni, chi si accosta al mondo SiChef viene introdotto all\u2019alta formazione culinaria Made in Italy, anche grazie a corsi in Lis (Lingua Italiana dei Segni).<\/p>\n<p>Masterfood entra quindi nella galassia del Gruppo Ebano, realt\u00e0 fondata e presieduta dall&#8217;imprenditore e Presidente della Piccola Industria e Vice Presidente di Confindustria Carlo Robiglio \u00e8 tra i leader in Italia sulla formazione a distanza ed opera anche nell&#8217;editoria, nella comunicazione e nel marketing caratterizzando tutta l&#8217;offerta per il suo approccio innovativo.\u00a0<\/span><\/div>\n<div><span style=\"font-family: garamond, times new roman, serif; font-size: large;\"><br \/>\nCirca 18 milioni di fatturato nel 2018 e una crescita negli ultimi 6 anni dell\u2019800%, 8 societ\u00e0 controllate, 15 partnership produttive, pi\u00f9 di 250 dipendenti e collaboratori, una clientela media annuale che ormai supera le seimila unit\u00e0 per il solo business della Formazione a distanza e un piano di crescita per linee interne ed esterne con investimenti nel solo 2018 di 700 mila euro.\u00a0Sono questi alcuni dei numeri che sottolineano la costante crescita del Gruppo Ebano negli ultimi anni.<\/p>\n<p>\u201cL\u2019obiettivo che ci poniamo a breve termine \u00e8 il rilancio della piattaforma e-commerce di Masterfood\u201d, spiega Carlo Robiglio, fondatore e presidente del Gruppo Ebano. \u201cAffideremo questo compito alla nostra societ\u00e0 E-Development, anche questa pugliese e di recentissima acquisizione. <\/span><\/div>\n<div><\/div>\n<blockquote class=\"td_pull_quote td_pull_center\">\n<div><span class=\"td_btn td_btn_md td_default_btn\" style=\"font-family: garamond, times new roman, serif; font-size: large;\">E\u2019 la dimostrazione che si pu\u00f2 puntare sul Mezzogiorno coniugando il ruolo sociale dell\u2019impresa con l\u2019investimento in realt\u00e0 qualificate, come ad esempio tante dinamiche startup e Pmi innovative che operano nell\u2019area<\/span><\/div>\n<\/blockquote>\n<div><span style=\"font-family: garamond, times new roman, serif; font-size: large;\"><br \/>\nQuelli in Masterfood e SiChef oggi e con Zampando nel 2018 e E-Development ad agosto sono i nostri primi investimenti al Sud e non \u00e8 un caso che siano in Puglia. Una regione ricca di opportunit\u00e0 e di giovani con grandi competenze nel digitale e nell&#8217;informatica e molto attente ai temi della sostenibilit\u00e0. Un ecosistema nel quale vogliamo attingere competenze per tutto il Gruppo Ebano.&#8221;<\/p>\n<p>Tra i punti di forza del Gruppo Ebano c\u2019\u00e8 la controllata Cef Publishing, realt\u00e0 che opera nella progettazione, realizzazione ed erogazione di corsi professionali attraverso modalit\u00e0 Fad (formazione a distanza) ed e-learning, in ambiti come il socio assistenziale, l\u2019animal care, il food, l\u2019estetica e il benessere.<\/span><\/div>\n<div><span style=\"font-family: garamond, times new roman, serif; font-size: large;\"><br \/>\nL&#8217;azienda \u00e8 stata premiata da Deloitte a maggio a Milano nella sede di Borsa Italiana con il Premio \u201cDeloitte Best Managed Companies\u201d (BMC): il riconoscimento rivolto alle aziende che si sono distinte per strategia, competenze, impegno verso le persone e performance realizzato da Deloitte in collaborazione con ALTIS Universit\u00e0 Cattolica,\u00a0<\/span>Confindustria e\u00a0ELITE, il progetto del London Stock Exchange Group che supporta lo sviluppo e la crescita delle imprese ad alto potenziale.<\/div>\n<div>\n<span style=\"font-family: garamond, times new roman, serif; font-size: large;\">Il Gruppo Ebano tramite Cef Publishing \u00e8 anche in Elite, il programma internazionale nato in Borsa Italiana nel 2012 in collaborazione con Confindustria e dedicato alle aziende pi\u00f9 ambiziose, con un modello di business solido ed una chiara strategia di crescita ed \u00e8 un&#8217;azienda fortemente impegnata nel sociale e nella sostenibilit\u00e0. <\/span><\/div>\n<div><\/div>\n<div><span style=\"font-family: garamond, times new roman, serif; font-size: large;\">La politica aziendale del Gruppo Ebano, volta a perseguire alti standard in termini\u2028di sostenibilit\u00e0 e impatto sociale, ha permesso, attraverso la partecipata Cef Publishing, di ottenere la Certificazione b Corp\u00ae, rilasciata dalla B Corporation, l\u2019ente non-profit americano.\u00a0<\/span><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Valorizzare e diffondere con metodi innovativi la cultura gastronomica italiana su scala nazionale e internazionale. E\u2019 questa la mission di Masterfood srl, societ\u00e0 di Bari acquisita al 100% dal Gruppo Ebano, che amplia cos\u00ec la propria offerta di contenuti nel settore \u201cFood\u201d e incrementa il business \u201cdell\u2019online\u201d.\u00a0 A Masterfood fa capo SiChef, la prima Accademia [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":564,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[251,250,697,698],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Il Gruppo Ebano acquisisce Masterfood e SiChef -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/il-gruppo-ebano-acquisisce-masterfood-e-sichef\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il Gruppo Ebano acquisisce Masterfood e SiChef -\" \/>\n<meta property=\"og:description\" content=\"Valorizzare e diffondere con metodi innovativi la cultura gastronomica italiana su scala nazionale e internazionale. E\u2019 questa la mission di Masterfood srl, societ\u00e0 di Bari acquisita al 100% dal Gruppo Ebano, che amplia cos\u00ec la propria offerta di contenuti nel settore \u201cFood\u201d e incrementa il business \u201cdell\u2019online\u201d.\u00a0 A Masterfood fa capo SiChef, la prima Accademia [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/il-gruppo-ebano-acquisisce-masterfood-e-sichef\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-07T07:46:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/04\/Robiglio1-1024x683.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/il-gruppo-ebano-acquisisce-masterfood-e-sichef\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/il-gruppo-ebano-acquisisce-masterfood-e-sichef\/\",\"name\":\"Il Gruppo Ebano acquisisce Masterfood e SiChef -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/il-gruppo-ebano-acquisisce-masterfood-e-sichef\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/il-gruppo-ebano-acquisisce-masterfood-e-sichef\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/04\/Robiglio1.jpg\",\"datePublished\":\"2019-09-07T07:46:46+00:00\",\"dateModified\":\"2019-09-07T07:46:46+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/il-gruppo-ebano-acquisisce-masterfood-e-sichef\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/il-gruppo-ebano-acquisisce-masterfood-e-sichef\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/il-gruppo-ebano-acquisisce-masterfood-e-sichef\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/04\/Robiglio1.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/04\/Robiglio1.jpg\",\"width\":2449,\"height\":1633,\"caption\":\"Carlo Robiglio\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/il-gruppo-ebano-acquisisce-masterfood-e-sichef\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il Gruppo Ebano acquisisce Masterfood e SiChef\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il Gruppo Ebano acquisisce Masterfood e SiChef -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/il-gruppo-ebano-acquisisce-masterfood-e-sichef\/","og_locale":"it_IT","og_type":"article","og_title":"Il Gruppo Ebano acquisisce Masterfood e SiChef -","og_description":"Valorizzare e diffondere con metodi innovativi la cultura gastronomica italiana su scala nazionale e internazionale. E\u2019 questa la mission di Masterfood srl, societ\u00e0 di Bari acquisita al 100% dal Gruppo Ebano, che amplia cos\u00ec la propria offerta di contenuti nel settore \u201cFood\u201d e incrementa il business \u201cdell\u2019online\u201d.\u00a0 A Masterfood fa capo SiChef, la prima Accademia [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/il-gruppo-ebano-acquisisce-masterfood-e-sichef\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2019-09-07T07:46:46+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/04\/Robiglio1-1024x683.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/il-gruppo-ebano-acquisisce-masterfood-e-sichef\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/il-gruppo-ebano-acquisisce-masterfood-e-sichef\/","name":"Il Gruppo Ebano acquisisce Masterfood e SiChef -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/il-gruppo-ebano-acquisisce-masterfood-e-sichef\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/il-gruppo-ebano-acquisisce-masterfood-e-sichef\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/04\/Robiglio1.jpg","datePublished":"2019-09-07T07:46:46+00:00","dateModified":"2019-09-07T07:46:46+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/il-gruppo-ebano-acquisisce-masterfood-e-sichef\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/il-gruppo-ebano-acquisisce-masterfood-e-sichef\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/il-gruppo-ebano-acquisisce-masterfood-e-sichef\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/04\/Robiglio1.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/04\/Robiglio1.jpg","width":2449,"height":1633,"caption":"Carlo Robiglio"},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/il-gruppo-ebano-acquisisce-masterfood-e-sichef\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Il Gruppo Ebano acquisisce Masterfood e SiChef"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/1654"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=1654"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/1654\/revisions"}],"predecessor-version":[{"id":1655,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/1654\/revisions\/1655"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/564"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=1654"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=1654"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=1654"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}