{"id":169,"date":"2018-07-26T10:29:32","date_gmt":"2018-07-26T08:29:32","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=169"},"modified":"2018-07-26T10:29:32","modified_gmt":"2018-07-26T08:29:32","slug":"compravendite-on-line-piu-sicure-grazie-ad-un-app","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/compravendite-on-line-piu-sicure-grazie-ad-un-app\/","title":{"rendered":"Compravendite on line pi\u00f9 sicure grazie ad un App"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">U<\/span>na applicazione innovativa per il controllo e il pagamento nell\u2019ambito delle compravendite on line.<\/p>\n<p>\u00c8 Weldpay, uno dei progetti finanziabili all\u2019interno di <strong>PostepayCrowd 2.0<\/strong>, l\u2019iniziativa di <strong>Poste Italiane <\/strong>in collaborazione con<strong> MasterCard<\/strong>, con la partnership della piattaforma Eppela, per il sostegno ai progetti di innovazione, fintech e trasformazione digitale.<br \/>\nSi tratta di una applicazione che propone una soluzione che tuteli dalle truffe on line, in particolar modo nel campo degli anticipi di denaro per affitto di case vacanza, acquisto di auto\/moto e nel mondo dell\u2019e-commerce per oggetti usati e nuovi.<\/p>\n<p>Con Weldpay, infatti, \u00e8 possibile acquistare o vendere in sicurezza attraverso sei fasi: acquisto del prodotto sul web conferma dell\u2019acquisto, pagamento in sicurezza, controllo e monitoraggio dell\u2019acquisto prima che, nell\u2019ultima fase, Weldpay paghi direttamente il venditore del prodotto acquistato. L\u2019applicazione, in sostanza, si fa da intermediaria fra acquirente e venditore per per garantire a entrambi che l\u2019acquisto possa andare a buon fine.<\/p>\n<p>Le risorse raccolte tramite crowdfunding verranno impiegate per il perfezionamento della piattaforma, per il potenziamento delle campagne marketing on line e off line e per la definizione e lo sviluppo della strategia commerciale. Per chi decider\u00e0 di finanziare il progetto sono previste delle ricompense. Con una donazione di 10 euro il finanziatore verr\u00e0 ricompensato con un ventilatore usb alimentabile tramite telefono. Uno speaker bluetooth per coloro che decideranno di donare 30 euro mentre con donazioni pi\u00f9 cospicue, come 50 e 100 euro, i donatori potranno ricevere rispettivamente un caricabatterie a induzione pieghevole per smartphone e un paio di occhiali per la realt\u00e0 aumentata.<\/p>\n<blockquote class=\"td_quote_box td_box_left\"><p>\nLa campagna di crowdfunding per sostenere questo progetto rimarr\u00e0 attiva fino all\u201911 agosto.<\/p><\/blockquote>\n<p>A capo del progetto Weldpay c\u2019\u00e8 il presidente del cda di <strong>Safepay Italia Srl,<\/strong> Dimitri Belardo, che pu\u00f2 vantare un\u2019esperienza ventennale nello sviluppo di attivit\u00e0 imprenditoriali di successo in vari settori. <strong>Federico Breda<\/strong>, tributarista con studio a Brescia, \u00e8 invece al vertice della Holdinvest Srl ed \u00e8 un esperto contabilit\u00e0. Nel progetto ha il compito di presidiare l\u2019attivit\u00e0 amministrativa, gestionale e la supervisione del processo aziendale dell\u2019attivit\u00e0.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una applicazione innovativa per il controllo e il pagamento nell\u2019ambito delle compravendite on line. \u00c8 Weldpay, uno dei progetti finanziabili all\u2019interno di PostepayCrowd 2.0, l\u2019iniziativa di Poste Italiane in collaborazione con MasterCard, con la partnership della piattaforma Eppela, per il sostegno ai progetti di innovazione, fintech e trasformazione digitale. Si tratta di una applicazione che [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":170,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[53],"tags":[55,54],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Compravendite on line pi\u00f9 sicure grazie ad un App -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.italiaeconomiaonline.it\/web\/compravendite-on-line-piu-sicure-grazie-ad-un-app\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Compravendite on line pi\u00f9 sicure grazie ad un App -\" \/>\n<meta property=\"og:description\" content=\"Una applicazione innovativa per il controllo e il pagamento nell\u2019ambito delle compravendite on line. \u00c8 Weldpay, uno dei progetti finanziabili all\u2019interno di PostepayCrowd 2.0, l\u2019iniziativa di Poste Italiane in collaborazione con MasterCard, con la partnership della piattaforma Eppela, per il sostegno ai progetti di innovazione, fintech e trasformazione digitale. Si tratta di una applicazione che [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.italiaeconomiaonline.it\/web\/compravendite-on-line-piu-sicure-grazie-ad-un-app\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-26T08:29:32+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/07\/weldpay1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.italiaeconomiaonline.it\/web\/compravendite-on-line-piu-sicure-grazie-ad-un-app\/\",\"url\":\"http:\/\/www.italiaeconomiaonline.it\/web\/compravendite-on-line-piu-sicure-grazie-ad-un-app\/\",\"name\":\"Compravendite on line pi\u00f9 sicure grazie ad un App -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/www.italiaeconomiaonline.it\/web\/compravendite-on-line-piu-sicure-grazie-ad-un-app\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/www.italiaeconomiaonline.it\/web\/compravendite-on-line-piu-sicure-grazie-ad-un-app\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/07\/weldpay1.jpg\",\"datePublished\":\"2018-07-26T08:29:32+00:00\",\"dateModified\":\"2018-07-26T08:29:32+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"http:\/\/www.italiaeconomiaonline.it\/web\/compravendite-on-line-piu-sicure-grazie-ad-un-app\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.italiaeconomiaonline.it\/web\/compravendite-on-line-piu-sicure-grazie-ad-un-app\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\/\/www.italiaeconomiaonline.it\/web\/compravendite-on-line-piu-sicure-grazie-ad-un-app\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/07\/weldpay1.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/07\/weldpay1.jpg\",\"width\":900,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/www.italiaeconomiaonline.it\/web\/compravendite-on-line-piu-sicure-grazie-ad-un-app\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Compravendite on line pi\u00f9 sicure grazie ad un App\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Compravendite on line pi\u00f9 sicure grazie ad un App -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.italiaeconomiaonline.it\/web\/compravendite-on-line-piu-sicure-grazie-ad-un-app\/","og_locale":"it_IT","og_type":"article","og_title":"Compravendite on line pi\u00f9 sicure grazie ad un App -","og_description":"Una applicazione innovativa per il controllo e il pagamento nell\u2019ambito delle compravendite on line. \u00c8 Weldpay, uno dei progetti finanziabili all\u2019interno di PostepayCrowd 2.0, l\u2019iniziativa di Poste Italiane in collaborazione con MasterCard, con la partnership della piattaforma Eppela, per il sostegno ai progetti di innovazione, fintech e trasformazione digitale. Si tratta di una applicazione che [&hellip;]","og_url":"http:\/\/www.italiaeconomiaonline.it\/web\/compravendite-on-line-piu-sicure-grazie-ad-un-app\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2018-07-26T08:29:32+00:00","og_image":[{"width":900,"height":600,"url":"http:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/07\/weldpay1.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/www.italiaeconomiaonline.it\/web\/compravendite-on-line-piu-sicure-grazie-ad-un-app\/","url":"http:\/\/www.italiaeconomiaonline.it\/web\/compravendite-on-line-piu-sicure-grazie-ad-un-app\/","name":"Compravendite on line pi\u00f9 sicure grazie ad un App -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.italiaeconomiaonline.it\/web\/compravendite-on-line-piu-sicure-grazie-ad-un-app\/#primaryimage"},"image":{"@id":"http:\/\/www.italiaeconomiaonline.it\/web\/compravendite-on-line-piu-sicure-grazie-ad-un-app\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/07\/weldpay1.jpg","datePublished":"2018-07-26T08:29:32+00:00","dateModified":"2018-07-26T08:29:32+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"http:\/\/www.italiaeconomiaonline.it\/web\/compravendite-on-line-piu-sicure-grazie-ad-un-app\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.italiaeconomiaonline.it\/web\/compravendite-on-line-piu-sicure-grazie-ad-un-app\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/www.italiaeconomiaonline.it\/web\/compravendite-on-line-piu-sicure-grazie-ad-un-app\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/07\/weldpay1.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/07\/weldpay1.jpg","width":900,"height":600},{"@type":"BreadcrumbList","@id":"http:\/\/www.italiaeconomiaonline.it\/web\/compravendite-on-line-piu-sicure-grazie-ad-un-app\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Compravendite on line pi\u00f9 sicure grazie ad un App"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/169"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=169"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/169\/revisions"}],"predecessor-version":[{"id":171,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/169\/revisions\/171"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/170"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=169"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=169"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}