{"id":1697,"date":"2019-09-10T11:38:54","date_gmt":"2019-09-10T09:38:54","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=1697"},"modified":"2019-09-10T11:38:54","modified_gmt":"2019-09-10T09:38:54","slug":"privacy-violazioni-di-dati-personali-in-base-al-regolamento-ue-2016-679","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/privacy-violazioni-di-dati-personali-in-base-al-regolamento-ue-2016-679\/","title":{"rendered":"Privacy: violazioni di dati personali in base al Regolamento UE 2016\/679"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">U<\/span>na violazione di sicurezza che comporta &#8211; accidentalmente o in modo illecito &#8211; la distruzione, la perdita, la modifica, la divulgazione non autorizzata o l\u2019accesso ai dati personali trasmessi, conservati o comunque trattati.<\/p>\n<p>Una violazione dei dati personali pu\u00f2 compromettere la riservatezza, l\u2019integrit\u00e0 o la disponibilit\u00e0 di dati personali.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Alcuni possibili esempi:<\/strong><\/p>\n<p>&#8211; l\u2019accesso o l\u2019acquisizione dei dati da parte di terzi non autorizzati;<\/p>\n<p>&#8211; il furto o la perdita di dispositivi informatici contenenti dati personali;<\/p>\n<p>&#8211; la deliberata alterazione di dati personali;<\/p>\n<p>&#8211; l\u2019impossibilit\u00e0 di accedere ai dati per cause accidentali o per attacchi esterni, virus, malware, ecc.;<\/p>\n<p>&#8211; la perdita o la distruzione di dati personali a causa di incidenti, eventi avversi, incendi o altre calamit\u00e0;<\/p>\n<p>&#8211; la divulgazione non autorizzata dei dati personali.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>COSA FARE IN CASO DI VIOLAZIONE DEI DATI PERSONALI?<\/strong><\/p>\n<p>Il titolare del trattamento (soggetto pubblico, impresa, associazione, partito, professionista, ecc.)\u00a0<strong>senza ingiustificato ritardo<\/strong>\u00a0e, ove possibile,\u00a0<strong>entro 72 ore dal momento in cui ne \u00e8 venuto a conoscenza<\/strong>, deve notificare la violazione al Garante per la protezione dei dati personali a meno che sia\u00a0<strong>improbabile\u00a0<\/strong>che la violazione dei dati personali comporti un\u00a0<strong>rischio\u00a0<\/strong>per i diritti e le libert\u00e0 delle persone fisiche.<\/p>\n<p>&nbsp;<\/p>\n<p>Il responsabile del trattamento che viene a conoscenza di una eventuale violazione \u00e8 tenuto a informare tempestivamente il titolare in modo che possa attivarsi.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Le notifiche al Garante effettuate oltre il termine delle 72 ore\u00a0devono essere\u00a0accompagnate dai motivi del ritardo.\u00a0<\/strong><\/p>\n<p>Inoltre, se la violazione comporta un rischio elevato per i diritti delle persone, il titolare deve comunicarla a tutti gli interessati, utilizzando i canali pi\u00f9 idonei, a meno che abbia gi\u00e0 preso misure tali da ridurne l\u2019impatto.<\/p>\n<p>Il titolare del trattamento, a prescindere dalla notifica al Garante,\u00a0documenta\u00a0tutte le violazioni dei dati personali, ad esempio predisponendo un apposito registro. Tale documentazione consente all\u2019Autorit\u00e0 di effettuare eventuali verifiche sul rispetto della normativa.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>CHE TIPO DI VIOLAZIONI \u00a0DI DATI PERSONALI VANNO NOTIFICATE?<\/strong><\/p>\n<p>Vanno notificate unicamente le violazioni di dati personali che possono avere\u00a0effetti avversi significativi\u00a0sugli individui, causando danni fisici, materiali \u00a0o immateriali.<\/p>\n<p>Ci\u00f2 pu\u00f2 includere, ad esempio, la perdita del controllo sui propri dati personali, la limitazione di alcuni diritti, la discriminazione, il furto d&#8217;identit\u00e0 o il rischio di frode, la perdita di riservatezza dei dati personali protetti dal segreto professionale, una perdita finanziaria, un danno alla reputazione \u00a0e qualsiasi altro significativo svantaggio economico o sociale.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>CHE INFORMAZIONI DEVE CONTENERE LA NOTIFICA AL GARANTE?<\/strong><strong><a href=\"https:\/\/www.garanteprivacy.it\/regolamentoue\/databreach\">**<\/a><\/strong><br \/>\nLa notifica deve contenere le informazioni previste all\u2019art. 33, par. 3 del Regolamento (UE) 2016\/679 e indicate nell\u2019allegato al\u00a0<a href=\"https:\/\/www.garanteprivacy.it\/garante\/doc.jsp?ID=9126951\">Provvedimento del Garante del 30 luglio 2019 sulla notifica delle violazioni dei dati personali (doc. web n. 9126951<\/a><a href=\"https:\/\/www.garanteprivacy.it\/garante\/doc.jsp?ID=9126951\">)<\/a>.<\/p>\n<p>Qualora si utilizzi per la notifica il\u00a0<a href=\"https:\/\/www.garanteprivacy.it\/garante\/document?ID=9128501\">modello allegato al provvedimento<\/a>, \u00e8 necessario scaricarlo sul proprio dispositivo e successivamente procedere alla sua compilazione.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>COME INVIARE LA NOTIFICA AL GARANTE?<\/strong><\/p>\n<p>La notifica deve essere inviata al Garante tramite <a href=\"protocollo@pec.gpdp.it\">posta elettronica<\/a>\u00a0 e deve essere sottoscritta digitalmente (con firma elettronica qualificata\/firma digitale) ovvero con firma autografa. In quest&#8217;ultimo caso la notifica deve essere presentata unitamente alla copia del documento d&#8217;identit\u00e0 del firmatario.<\/p>\n<p>&nbsp;<\/p>\n<p>L&#8217;oggetto del messaggio deve contenere obbligatoriamente la dicitura\u00a0<strong>\u201cNOTIFICA VIOLAZIONE DATI PERSONALI\u201d<\/strong>\u00a0e opzionalmente la denominazione del titolare del trattamento.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>LE AZIONI DEL GARANTE<\/strong><\/p>\n<p>Il Garante pu\u00f2 prescrivere misure correttive (v. art. 58, paragrafo 2, del Regolamento UE 2016\/679) nel caso sia rilevata una violazione delle disposizioni del Regolamento stesso, anche per quanto riguarda l\u2019adeguatezza delle misure di sicurezza tecniche e organizzative applicate ai dati oggetto di violazione. Sono previste sanzioni pecuniarie che possono arrivare\u00a0<strong>fino a 10 milioni di Euro<\/strong>\u00a0o, nel caso di imprese,<strong>\u00a0fino al 2% del fatturato totale annuo mondiale<\/strong> <a id=\"*\" name=\"*\"><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>* La scheda ha mero valore divulgativo ed \u00e8 in continuo aggiornamento in base all\u2019evoluzione delle indicazioni applicative del Regolamento (UE) 2016\/679.<\/p>\n<p><a id=\"**\" name=\"**\"><\/a><\/p>\n<p>** Il Garante render\u00e0 prossimamente disponibile una procedura online.<br \/>\n<strong id=\"aui_3_2_0_1999\">LINEE GUIDA<\/strong><\/p>\n<p><a href=\"http:\/\/ec.europa.eu\/newsroom\/article29\/item-detail.cfm?item_id=612052\">Linee guida in materia di notifica delle violazioni di dati personali (data breach notification) &#8211; WP250, definite in base alle previsioni del Regolamento (UE) 2016\/679<\/a><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p id=\"aui_3_2_0_1954\">\n<p>Fonte: Garante Privacy, comunicato del 3.9.2019<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una violazione di sicurezza che comporta &#8211; accidentalmente o in modo illecito &#8211; la distruzione, la perdita, la modifica, la divulgazione non autorizzata o l\u2019accesso ai dati personali trasmessi, conservati o comunque trattati. Una violazione dei dati personali pu\u00f2 compromettere la riservatezza, l\u2019integrit\u00e0 o la disponibilit\u00e0 di dati personali. &nbsp; Alcuni possibili esempi: &#8211; l\u2019accesso [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1446,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[35],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Privacy: violazioni di dati personali in base al Regolamento UE 2016\/679 -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/privacy-violazioni-di-dati-personali-in-base-al-regolamento-ue-2016-679\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Privacy: violazioni di dati personali in base al Regolamento UE 2016\/679 -\" \/>\n<meta property=\"og:description\" content=\"Una violazione di sicurezza che comporta &#8211; accidentalmente o in modo illecito &#8211; la distruzione, la perdita, la modifica, la divulgazione non autorizzata o l\u2019accesso ai dati personali trasmessi, conservati o comunque trattati. Una violazione dei dati personali pu\u00f2 compromettere la riservatezza, l\u2019integrit\u00e0 o la disponibilit\u00e0 di dati personali. &nbsp; Alcuni possibili esempi: &#8211; l\u2019accesso [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/privacy-violazioni-di-dati-personali-in-base-al-regolamento-ue-2016-679\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-10T09:38:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/07\/Sicurezza.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"510\" \/>\n\t<meta property=\"og:image:height\" content=\"340\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/privacy-violazioni-di-dati-personali-in-base-al-regolamento-ue-2016-679\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/privacy-violazioni-di-dati-personali-in-base-al-regolamento-ue-2016-679\/\",\"name\":\"Privacy: violazioni di dati personali in base al Regolamento UE 2016\/679 -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/privacy-violazioni-di-dati-personali-in-base-al-regolamento-ue-2016-679\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/privacy-violazioni-di-dati-personali-in-base-al-regolamento-ue-2016-679\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/07\/Sicurezza.jpg\",\"datePublished\":\"2019-09-10T09:38:54+00:00\",\"dateModified\":\"2019-09-10T09:38:54+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/privacy-violazioni-di-dati-personali-in-base-al-regolamento-ue-2016-679\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/privacy-violazioni-di-dati-personali-in-base-al-regolamento-ue-2016-679\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/privacy-violazioni-di-dati-personali-in-base-al-regolamento-ue-2016-679\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/07\/Sicurezza.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/07\/Sicurezza.jpg\",\"width\":510,\"height\":340},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/privacy-violazioni-di-dati-personali-in-base-al-regolamento-ue-2016-679\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Privacy: violazioni di dati personali in base al Regolamento UE 2016\/679\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Privacy: violazioni di dati personali in base al Regolamento UE 2016\/679 -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/privacy-violazioni-di-dati-personali-in-base-al-regolamento-ue-2016-679\/","og_locale":"it_IT","og_type":"article","og_title":"Privacy: violazioni di dati personali in base al Regolamento UE 2016\/679 -","og_description":"Una violazione di sicurezza che comporta &#8211; accidentalmente o in modo illecito &#8211; la distruzione, la perdita, la modifica, la divulgazione non autorizzata o l\u2019accesso ai dati personali trasmessi, conservati o comunque trattati. Una violazione dei dati personali pu\u00f2 compromettere la riservatezza, l\u2019integrit\u00e0 o la disponibilit\u00e0 di dati personali. &nbsp; Alcuni possibili esempi: &#8211; l\u2019accesso [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/privacy-violazioni-di-dati-personali-in-base-al-regolamento-ue-2016-679\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2019-09-10T09:38:54+00:00","og_image":[{"width":510,"height":340,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/07\/Sicurezza.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/privacy-violazioni-di-dati-personali-in-base-al-regolamento-ue-2016-679\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/privacy-violazioni-di-dati-personali-in-base-al-regolamento-ue-2016-679\/","name":"Privacy: violazioni di dati personali in base al Regolamento UE 2016\/679 -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/privacy-violazioni-di-dati-personali-in-base-al-regolamento-ue-2016-679\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/privacy-violazioni-di-dati-personali-in-base-al-regolamento-ue-2016-679\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/07\/Sicurezza.jpg","datePublished":"2019-09-10T09:38:54+00:00","dateModified":"2019-09-10T09:38:54+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/privacy-violazioni-di-dati-personali-in-base-al-regolamento-ue-2016-679\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/privacy-violazioni-di-dati-personali-in-base-al-regolamento-ue-2016-679\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/privacy-violazioni-di-dati-personali-in-base-al-regolamento-ue-2016-679\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/07\/Sicurezza.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/07\/Sicurezza.jpg","width":510,"height":340},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/privacy-violazioni-di-dati-personali-in-base-al-regolamento-ue-2016-679\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Privacy: violazioni di dati personali in base al Regolamento UE 2016\/679"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/1697"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=1697"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/1697\/revisions"}],"predecessor-version":[{"id":1698,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/1697\/revisions\/1698"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/1446"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=1697"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=1697"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=1697"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}