{"id":1721,"date":"2019-09-17T11:59:19","date_gmt":"2019-09-17T09:59:19","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=1721"},"modified":"2019-09-17T11:59:20","modified_gmt":"2019-09-17T09:59:20","slug":"piu-sprechi-che-evasione-linefficienza-della-nostra-pa-e-un-freno-allo-sviluppo","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/piu-sprechi-che-evasione-linefficienza-della-nostra-pa-e-un-freno-allo-sviluppo\/","title":{"rendered":"Pi\u00f9 sprechi che evasione. L&#8217;inefficienza della nostra PA \u00e8 un freno allo sviluppo"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">C<\/span>i sono ragionevoli certezze nel ritenere che nel rapporto \u201cdare avere\u201d tra lo Stato e il contribuente italiano, il soggetto maggiormente leso non sia il primo, bens\u00ec il secondo.<\/p>\n<p>Considerando tutta una serie di caveat, che saranno sviluppati successivamente, la tesi \u00e8 la seguente: la dimensione economica dell\u2019evasione fiscale presente in Italia (110 miliardi) \u00e8 poco pi\u00f9 della met\u00e0 dei costi a carico di cittadini e imprese relativi a sprechi, sperperi e inefficienze generate dalla Pubblica amministrazione (almeno 200 miliardi di euro).<\/p>\n<p>L\u2019Ufficio studi della CGIA \u00e8 pervenuto a questa conclusione partendo dall\u2019analisi di alcuni dati di contesto e rammentando che uno Stato di diritto si basa, tra le altre cose, sul principio della legalit\u00e0.<\/p>\n<p>Sia chiaro, chi evade commette un reato e va perseguito ovunque esso si annidi; tuttavia, la legalit\u00e0 deve essere rispettata da tutti: sia dai soggetti pubblici sia da quelli privati. Il record di infrazioni europee subite dal nostro Paese fino ad oggi, ad esempio, dimostra che le nostre istituzioni pubbliche devono migliorare tantissimo.<\/p>\n<p>Segnaliamo che tra le procedure in corso nei confronti dell\u2019Italia figurano quelle sulla pessima qualit\u00e0 dell\u2019aria presente in molte citt\u00e0, la presenza dell\u2019arsenico nell\u2019acqua potabile, il mancato rispetto dei tempi di pagamento da parte della nostra Pubblica Amministrazione (PA) e i livelli di inquinamento presenti nell\u2019area dell\u2019ex Ilva di Taranto.<\/p>\n<p>Gli sprechi sono quasi il doppio dell\u2019evasione Torniamo al rapporto \u201cdare-avere\u201d tra lo Stato e il contribuente italiano. Secondo una stima del ministero dell\u2019Economia, l\u2019ammontare complessivo dell\u2019evasione in Italia si attesterebbe attorno ai 110 miliardi di euro all\u2019anno.<\/p>\n<p>Una cifra, quella dovuta all\u2019infedelt\u00e0 fiscale degli italiani, spaventosamente elevata che, secondo gli artigiani veneti, sarebbe comunque molto inferiore al costo che i cittadini e le imprese sopportano in ragione del cattivo funzionamento della PA e degli effetti negativi procurati dal mancato rispetto della norme e dei regolamenti vigenti da parte di un pubblico ufficiale o di un incaricato al pubblico servizio.<\/p>\n<p>Mettendo in fila i risultati di alcune analisi condotte da una mezza dozzina di istituzioni molto autorevoli, il danno economico per i contribuenti italiani sarebbe di almeno 200 miliardi di euro all\u2019anno. Si tratta di una dimensione economica quasi doppia a quella dell\u2019evasione.<\/p>\n<p><a href=\"http:\/\/www.italiaeconomiaonline.it\/web\/piu-sprechi-che-evasione-linefficienza-della-nostra-pa-e-un-freno-allo-sviluppo\/sprechipa-2\/\" rel=\"attachment wp-att-1723\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-1723\" src=\"http:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/09\/sprechipa-1.png\" alt=\"\" width=\"609\" height=\"265\" srcset=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/09\/sprechipa-1.png 609w, https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/09\/sprechipa-1-300x131.png 300w\" sizes=\"(max-width: 609px) 100vw, 609px\" \/><\/a><\/p>\n<p>E\u2019 una comparazione, quella appena evocata, che ovviamente non ha alcun rigore scientifico: infatti, gli effetti economici delle inefficienze pubbliche che si \u201cscaricano\u201d sui privati sono di fonte diversa, gli ambiti in molti casi si sovrappongono e, per tali ragioni, non sono addizionabili.<\/p>\n<p>Tuttavia, il ragionamento ha una sua fondatezza: nonostante ci sia tanta evasione, una PA poco efficiente causa ai privati dei danni economici nettamente superiori. Una conclusione, a cui \u00e8 pervenuta la CGIA, che non appare per nulla scontata, visto che c\u2019\u00e8 una buona parte dell\u2019opinione pubblica che se da un lato ha una forte sensibilit\u00e0 verso il tema dell\u2019evasione, dall\u2019altro lato avverte in misura meno preoccupante gli effetti degli sprechi, degli sperperi e delle inefficienze della PA. Afferma il coordinatore dell\u2019Ufficio studi Paolo Zabeo:<\/p>\n<p>\u201cE\u2019 verosimile ritenere che se recuperassimo una buona parte delle risorse nascoste al fisco, la nostra macchina pubblica avrebbe pi\u00f9 risorse, funzionerebbe meglio e, forse, si potrebbe ridurre il carico fiscale. Tuttavia, \u00e8 altrettanto plausibile supporre che se si riuscisse a tagliare sensibilmente le inefficienze presenti nella spesa pubblica, il Paese reale ne trarrebbe beneficio e, molto probabilmente, l\u2019evasione e la pressione fiscale sarebbero pi\u00f9 contenute. Non a caso molti affermano che la fedelt\u00e0 fiscale di un Paese sia direttamente proporzionale al livello delle tasse a cui sono sottoposti i propri contribuenti\u201d.<\/p>\n<p>Dalla CGIA tengono comunque a precisare che sarebbe sbagliato generalizzare e non riconoscere anche i livelli di eccellenza che caratterizzano molti settori della nostra PA, come, ad esempio, la sanit\u00e0 nelle regioni centro-settentrionali, il livello di insegnamento e di professionalit\u00e0 presenti in molte Universit\u00e0\/enti di ricerca e la qualit\u00e0 del lavoro effettuato dalle forze dell\u2019ordine.<\/p>\n<p>\u201cEppure &#8211; dichiara il Segretario Renato Mason \u2013 le imprese italiane, essendo prevalentemente di piccolissima dimensione, hanno bisogno di un servizio pubblico efficiente, economicamente vantaggioso e di alta qualit\u00e0, in cui le decisioni vengano prese senza ritardi e vi sia certezza per quanto riguarda le leggi e la durata delle procedure. Se, invece, la farraginosit\u00e0 della nostra legislazione continuer\u00e0 a lasciare una grande discrezione interpretativa ai dirigenti e ai funzionari pubblici, \u00e8 evidente che le distorsioni presenti nel pubblico impiego avranno ricadute negative sul nostro sistema economico privato\u201d.<\/p>\n<p>\uf0b7 I costi del cattivo funzionamento della nostra PA L\u2019Ufficio studi della CGIA ha raccolto ed allineato i risultati di una serie di analisi sulle inefficienze e gli sprechi che caratterizzano la nostra Pubblica Amministrazione. In sintesi si evidenzia che:<\/p>\n<ul>\n<li>\u00a0il costo annuo sostenuto dalle imprese per la gestione dei rapporti con la PA (burocrazia) \u00e8 pari a 57 miliardi di euro (Fonte: The European House Ambrosetti);<\/li>\n<li>i debiti commerciali della PA nei confronti dei propri fornitori ammontano a 53 miliardi di euro (Fonte: Banca d\u2019Italia);<\/li>\n<li>il deficit logistico-infrastrutturale penalizza il nostro sistema economico per un importo di 40 miliardi di euro all\u2019anno (Fonte: Ministero delle Infrastrutture e dei Trasporti);<\/li>\n<li>se la giustizia civile italiana avesse gli stessi tempi di quella tedesca, il guadagno in termini di Pil sarebbe di 40 miliardi di euro all\u2019anno (Fonte: CER-Eures);<\/li>\n<li>sono 24 i miliardi di euro di spesa pubblica in eccesso che non ci consentono di abbassare la nostra pressione fiscale alla media UE (Fonte: Discussion paper 23 Commissione Europea);<\/li>\n<li>gli sprechi e la corruzione presenti nella sanit\u00e0 costano alla collettivit\u00e0 23,5 miliardi di euro ogni anno (Fonte: ISPE);<\/li>\n<li>gli sprechi e le inefficienze presenti nel settore del trasporto pubblico locale ammontano a 12,5 miliardi di euro all\u2019anno (Fonte: The European House Ambrosetti-Ferrovie dello Stato).\n<p>Come abbiamo gi\u00e0 evidenziato in precedenza, questi malfunzionamenti, tratti da fonti diverse, non si possono sommare, anche perch\u00e9 in molti casi le aree di influenza di queste analisi si accavallano. Tuttavia, queste avvertenze non pregiudicano la correttezza della riflessione espressa pi\u00f9 sopra.<\/p>\n<p>In buona sostanza, possiamo affermare che l\u2019ammontare dell\u2019evasione fiscale sia molto inferiore degli effetti negativi generati dal cattivo funzionamento della nostra PA che, spesso, si manifestano a seguito di una palese violazione delle norme di legge e dei regolamenti compiuta da dirigenti e funzionari pubblici poco solerti.<\/li>\n<\/ul>\n<p><a href=\"http:\/\/www.italiaeconomiaonline.it\/web\/piu-sprechi-che-evasione-linefficienza-della-nostra-pa-e-un-freno-allo-sviluppo\/sprechipa\/\" rel=\"attachment wp-att-1722\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-1722\" src=\"http:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/09\/sprechipa.png\" alt=\"\" width=\"694\" height=\"495\" srcset=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/09\/sprechipa.png 694w, https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/09\/sprechipa-300x214.png 300w, https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/09\/sprechipa-100x70.png 100w, https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/09\/sprechipa-589x420.png 589w\" sizes=\"(max-width: 694px) 100vw, 694px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ci sono ragionevoli certezze nel ritenere che nel rapporto \u201cdare avere\u201d tra lo Stato e il contribuente italiano, il soggetto maggiormente leso non sia il primo, bens\u00ec il secondo. Considerando tutta una serie di caveat, che saranno sviluppati successivamente, la tesi \u00e8 la seguente: la dimensione economica dell\u2019evasione fiscale presente in Italia (110 miliardi) \u00e8 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1724,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56],"tags":[190,718,719],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pi\u00f9 sprechi che evasione. L&#039;inefficienza della nostra PA \u00e8 un freno allo sviluppo -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/piu-sprechi-che-evasione-linefficienza-della-nostra-pa-e-un-freno-allo-sviluppo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pi\u00f9 sprechi che evasione. L&#039;inefficienza della nostra PA \u00e8 un freno allo sviluppo -\" \/>\n<meta property=\"og:description\" content=\"Ci sono ragionevoli certezze nel ritenere che nel rapporto \u201cdare avere\u201d tra lo Stato e il contribuente italiano, il soggetto maggiormente leso non sia il primo, bens\u00ec il secondo. Considerando tutta una serie di caveat, che saranno sviluppati successivamente, la tesi \u00e8 la seguente: la dimensione economica dell\u2019evasione fiscale presente in Italia (110 miliardi) \u00e8 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/piu-sprechi-che-evasione-linefficienza-della-nostra-pa-e-un-freno-allo-sviluppo\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-17T09:59:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-09-17T09:59:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/09\/soldi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"486\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/piu-sprechi-che-evasione-linefficienza-della-nostra-pa-e-un-freno-allo-sviluppo\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/piu-sprechi-che-evasione-linefficienza-della-nostra-pa-e-un-freno-allo-sviluppo\/\",\"name\":\"Pi\u00f9 sprechi che evasione. L'inefficienza della nostra PA \u00e8 un freno allo sviluppo -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/piu-sprechi-che-evasione-linefficienza-della-nostra-pa-e-un-freno-allo-sviluppo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/piu-sprechi-che-evasione-linefficienza-della-nostra-pa-e-un-freno-allo-sviluppo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/09\/soldi.jpg\",\"datePublished\":\"2019-09-17T09:59:19+00:00\",\"dateModified\":\"2019-09-17T09:59:20+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/piu-sprechi-che-evasione-linefficienza-della-nostra-pa-e-un-freno-allo-sviluppo\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/piu-sprechi-che-evasione-linefficienza-della-nostra-pa-e-un-freno-allo-sviluppo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/piu-sprechi-che-evasione-linefficienza-della-nostra-pa-e-un-freno-allo-sviluppo\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/09\/soldi.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/09\/soldi.jpg\",\"width\":960,\"height\":486},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/piu-sprechi-che-evasione-linefficienza-della-nostra-pa-e-un-freno-allo-sviluppo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pi\u00f9 sprechi che evasione. L&#8217;inefficienza della nostra PA \u00e8 un freno allo sviluppo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pi\u00f9 sprechi che evasione. L'inefficienza della nostra PA \u00e8 un freno allo sviluppo -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/piu-sprechi-che-evasione-linefficienza-della-nostra-pa-e-un-freno-allo-sviluppo\/","og_locale":"it_IT","og_type":"article","og_title":"Pi\u00f9 sprechi che evasione. L'inefficienza della nostra PA \u00e8 un freno allo sviluppo -","og_description":"Ci sono ragionevoli certezze nel ritenere che nel rapporto \u201cdare avere\u201d tra lo Stato e il contribuente italiano, il soggetto maggiormente leso non sia il primo, bens\u00ec il secondo. Considerando tutta una serie di caveat, che saranno sviluppati successivamente, la tesi \u00e8 la seguente: la dimensione economica dell\u2019evasione fiscale presente in Italia (110 miliardi) \u00e8 [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/piu-sprechi-che-evasione-linefficienza-della-nostra-pa-e-un-freno-allo-sviluppo\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2019-09-17T09:59:19+00:00","article_modified_time":"2019-09-17T09:59:20+00:00","og_image":[{"width":960,"height":486,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/09\/soldi.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/piu-sprechi-che-evasione-linefficienza-della-nostra-pa-e-un-freno-allo-sviluppo\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/piu-sprechi-che-evasione-linefficienza-della-nostra-pa-e-un-freno-allo-sviluppo\/","name":"Pi\u00f9 sprechi che evasione. L'inefficienza della nostra PA \u00e8 un freno allo sviluppo -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/piu-sprechi-che-evasione-linefficienza-della-nostra-pa-e-un-freno-allo-sviluppo\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/piu-sprechi-che-evasione-linefficienza-della-nostra-pa-e-un-freno-allo-sviluppo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/09\/soldi.jpg","datePublished":"2019-09-17T09:59:19+00:00","dateModified":"2019-09-17T09:59:20+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/piu-sprechi-che-evasione-linefficienza-della-nostra-pa-e-un-freno-allo-sviluppo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/piu-sprechi-che-evasione-linefficienza-della-nostra-pa-e-un-freno-allo-sviluppo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/piu-sprechi-che-evasione-linefficienza-della-nostra-pa-e-un-freno-allo-sviluppo\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/09\/soldi.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/09\/soldi.jpg","width":960,"height":486},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/piu-sprechi-che-evasione-linefficienza-della-nostra-pa-e-un-freno-allo-sviluppo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Pi\u00f9 sprechi che evasione. L&#8217;inefficienza della nostra PA \u00e8 un freno allo sviluppo"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/1721"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=1721"}],"version-history":[{"count":2,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/1721\/revisions"}],"predecessor-version":[{"id":1726,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/1721\/revisions\/1726"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/1724"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=1721"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=1721"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=1721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}