{"id":181,"date":"2018-08-01T11:52:05","date_gmt":"2018-08-01T09:52:05","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=181"},"modified":"2018-08-01T12:00:32","modified_gmt":"2018-08-01T10:00:32","slug":"acqua-e-cambiamenti-climatici-premiato-dalla-ue-il-progetto-life-wstore2","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/acqua-e-cambiamenti-climatici-premiato-dalla-ue-il-progetto-life-wstore2\/","title":{"rendered":"Acqua e cambiamenti climatici, premiato dalla UE il progetto Life &#8220;Wstore2&#8221;"},"content":{"rendered":"<p><strong><span class=\"dropcap dropcap3\">V<\/span><\/strong><span class=\"dropcap dropcap3\"><br \/>\n<\/span><strong>eneto Agricoltura<\/strong> sulla pedana dei premiati dall\u2019<strong>Unione Europea<\/strong>. Un Comitato ad hoc ha infatti riconosciuto la <strong>qualit\u00e0<\/strong> e l\u2019importanza di un <strong>progetto LIFE<\/strong> (il pi\u00f9 importante Programma europeo per l\u2019Ambiente) realizzato dall\u2019Agenzia regionale a <strong>ValleVecchia-Caorle<\/strong> (Ve).<\/p>\n<p>Pi\u00f9 specificatamente, il Comitato europeo LIFE ha selezionato tra le centinaia di progetti LIFE conclusi negli anni 2016-2017 i <strong>62 progetti migliori<\/strong>, conferendo loro il titolo di \u201c<strong>Best Life Project<\/strong>\u201d.<\/p>\n<p>Tra questi \u201c<strong><em>WSTORE2<\/em><\/strong><em> &#8211; Conciliare l\u2019agricoltura con l\u2019ambiente attraverso nuove forme di governance dell\u2019acqua nelle zone costiere salmastre<\/em>\u201d, che tra il 2012 e il 2015 \u00e8 stato coordinato da <strong>Veneto Agricoltura<\/strong> e realizzato nella sua azienda pilota e dimostrativa<strong> ValleVecchia<\/strong> di Caorle (Ve).<\/p>\n<p>Il \u201c<strong>Best Life Project<\/strong>\u201d \u00e8, come detto, una selezione che premia i <strong>progetti LIFE<\/strong> realizzati nei <strong>28 Stati Membri<\/strong> dell\u2019UE che maggiormente si sono distinti per il loro grado di <strong>innovazione e trasferibilit\u00e0<\/strong>, la loro rilevanza per la <strong>politica ambientale<\/strong> e la loro <strong>efficacia<\/strong> in termini di costi.<\/p>\n<p>Il progetto <strong>WSTORE2<\/strong>, realizzato da <strong>Veneto Agricoltura<\/strong> in partenariato con il <strong>Consorzio <\/strong>di Bonifica per il Canale<strong> emiliano romagnolo<\/strong>, il <strong>GAL Venezia Orientale<\/strong> e il Dipartimento di <strong>Ingegneria<\/strong> industriale<strong> dell\u2019Universit\u00e0 di Padova<\/strong>, ha dimostrato come sia <strong>possibile<\/strong> adottare <strong>tecniche innovative<\/strong> per conciliare l\u2019agricoltura con l\u2019ambiente attraverso nuove forme di <strong>governance dell\u2019acqua<\/strong> con particolare riferimento alle aree costiere che sono particolarmente sensibili ai cambiamenti climatici.<\/p>\n<p>A <strong>ValleVecchia <\/strong>\u00e8 stato progettato, realizzato e positivamente valutato un <strong>sistema automatizzato<\/strong> di <strong>gestione delle acque<\/strong> che, in seguito alla variazione dei parametri chimico-fisici delle acque della rete di scolo e del suolo (in particolare, la salinit\u00e0), consente l\u2019<strong>accumulo di acqua di qualit\u00e0<\/strong> (a ridotto contenuto di sali) in un bacino dedicato o l\u2019allontanamento dal reticolo idraulico se l\u2019acqua presenta alta concentrazione salina.<\/p>\n<p>Il sistema, che si basa su <strong>chiaviche<\/strong> dotate di sensori tele-controllate da uno specifico <strong>software<\/strong>, consente che l\u2019acqua immagazzinata nel bacino possa essere utilizzata per tutta una serie di funzioni, quali: il lavaggio dei terreni, creare\/consolidare una falda di acqua dolce sopra quella salata pi\u00f9 profonda, ravvivare l\u2019acqua nella rete di scolo, il ristoro irriguo delle aree naturali, micro-irrigazione delle colture.<\/p>\n<p>In altre parole, <strong>WSTORE2<\/strong> ha mostrato <strong>concrete soluzioni<\/strong> per mantenere importanti valenze naturalistiche, anche di elevato pregio, l\u2019agricoltura e le altre attivit\u00e0 economiche, in sintesi la presenza dell\u2019uomo, in zone costiere minacciate dal cambiamento climatico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>V eneto Agricoltura sulla pedana dei premiati dall\u2019Unione Europea. Un Comitato ad hoc ha infatti riconosciuto la qualit\u00e0 e l\u2019importanza di un progetto LIFE (il pi\u00f9 importante Programma europeo per l\u2019Ambiente) realizzato dall\u2019Agenzia regionale a ValleVecchia-Caorle (Ve). Pi\u00f9 specificatamente, il Comitato europeo LIFE ha selezionato tra le centinaia di progetti LIFE conclusi negli anni 2016-2017 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":182,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[53],"tags":[65,63,64],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Acqua e cambiamenti climatici, premiato dalla UE il progetto Life &quot;Wstore2&quot; -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/acqua-e-cambiamenti-climatici-premiato-dalla-ue-il-progetto-life-wstore2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Acqua e cambiamenti climatici, premiato dalla UE il progetto Life &quot;Wstore2&quot; -\" \/>\n<meta property=\"og:description\" content=\"V eneto Agricoltura sulla pedana dei premiati dall\u2019Unione Europea. Un Comitato ad hoc ha infatti riconosciuto la qualit\u00e0 e l\u2019importanza di un progetto LIFE (il pi\u00f9 importante Programma europeo per l\u2019Ambiente) realizzato dall\u2019Agenzia regionale a ValleVecchia-Caorle (Ve). Pi\u00f9 specificatamente, il Comitato europeo LIFE ha selezionato tra le centinaia di progetti LIFE conclusi negli anni 2016-2017 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/acqua-e-cambiamenti-climatici-premiato-dalla-ue-il-progetto-life-wstore2\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2018-08-01T09:52:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-08-01T10:00:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/08\/acqua.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/acqua-e-cambiamenti-climatici-premiato-dalla-ue-il-progetto-life-wstore2\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/acqua-e-cambiamenti-climatici-premiato-dalla-ue-il-progetto-life-wstore2\/\",\"name\":\"Acqua e cambiamenti climatici, premiato dalla UE il progetto Life \\\"Wstore2\\\" -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/acqua-e-cambiamenti-climatici-premiato-dalla-ue-il-progetto-life-wstore2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/acqua-e-cambiamenti-climatici-premiato-dalla-ue-il-progetto-life-wstore2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/08\/acqua.jpg\",\"datePublished\":\"2018-08-01T09:52:05+00:00\",\"dateModified\":\"2018-08-01T10:00:32+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/acqua-e-cambiamenti-climatici-premiato-dalla-ue-il-progetto-life-wstore2\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/acqua-e-cambiamenti-climatici-premiato-dalla-ue-il-progetto-life-wstore2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/acqua-e-cambiamenti-climatici-premiato-dalla-ue-il-progetto-life-wstore2\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/08\/acqua.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/08\/acqua.jpg\",\"width\":960,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/acqua-e-cambiamenti-climatici-premiato-dalla-ue-il-progetto-life-wstore2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Acqua e cambiamenti climatici, premiato dalla UE il progetto Life &#8220;Wstore2&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Acqua e cambiamenti climatici, premiato dalla UE il progetto Life \"Wstore2\" -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/acqua-e-cambiamenti-climatici-premiato-dalla-ue-il-progetto-life-wstore2\/","og_locale":"it_IT","og_type":"article","og_title":"Acqua e cambiamenti climatici, premiato dalla UE il progetto Life \"Wstore2\" -","og_description":"V eneto Agricoltura sulla pedana dei premiati dall\u2019Unione Europea. Un Comitato ad hoc ha infatti riconosciuto la qualit\u00e0 e l\u2019importanza di un progetto LIFE (il pi\u00f9 importante Programma europeo per l\u2019Ambiente) realizzato dall\u2019Agenzia regionale a ValleVecchia-Caorle (Ve). Pi\u00f9 specificatamente, il Comitato europeo LIFE ha selezionato tra le centinaia di progetti LIFE conclusi negli anni 2016-2017 [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/acqua-e-cambiamenti-climatici-premiato-dalla-ue-il-progetto-life-wstore2\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2018-08-01T09:52:05+00:00","article_modified_time":"2018-08-01T10:00:32+00:00","og_image":[{"width":960,"height":640,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/08\/acqua.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/acqua-e-cambiamenti-climatici-premiato-dalla-ue-il-progetto-life-wstore2\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/acqua-e-cambiamenti-climatici-premiato-dalla-ue-il-progetto-life-wstore2\/","name":"Acqua e cambiamenti climatici, premiato dalla UE il progetto Life \"Wstore2\" -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/acqua-e-cambiamenti-climatici-premiato-dalla-ue-il-progetto-life-wstore2\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/acqua-e-cambiamenti-climatici-premiato-dalla-ue-il-progetto-life-wstore2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/08\/acqua.jpg","datePublished":"2018-08-01T09:52:05+00:00","dateModified":"2018-08-01T10:00:32+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/acqua-e-cambiamenti-climatici-premiato-dalla-ue-il-progetto-life-wstore2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/acqua-e-cambiamenti-climatici-premiato-dalla-ue-il-progetto-life-wstore2\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/acqua-e-cambiamenti-climatici-premiato-dalla-ue-il-progetto-life-wstore2\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/08\/acqua.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/08\/acqua.jpg","width":960,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/acqua-e-cambiamenti-climatici-premiato-dalla-ue-il-progetto-life-wstore2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Acqua e cambiamenti climatici, premiato dalla UE il progetto Life &#8220;Wstore2&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/181"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=181"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/181\/revisions"}],"predecessor-version":[{"id":183,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/181\/revisions\/183"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/182"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=181"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=181"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}