{"id":1813,"date":"2019-09-30T12:49:34","date_gmt":"2019-09-30T10:49:34","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=1813"},"modified":"2019-09-30T12:49:56","modified_gmt":"2019-09-30T10:49:56","slug":"record-di-pratiche-amministrative-gestite-dallo-sportello-unico-digitale","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/record-di-pratiche-amministrative-gestite-dallo-sportello-unico-digitale\/","title":{"rendered":"Record di pratiche amministrative gestite  dallo Sportello unico digitale"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">N<\/span>uovo record dello Sportello unico per le attivit\u00e0 produttive (Suap) digitale gestito da 3.830 Comuni in collaborazione con le Camere di commercio.<\/p>\n<p>Nei primi nove mesi dell\u2019anno, le pratiche amministrative per l\u2019avvio e l\u2019esercizio di impresa, completate interamente online attraverso il<a href=\"http:\/\/www.impresainungiorno.gov.it\"> portale<\/a> , sono cresciute di quasi un terzo rispetto allo stesso periodo dell\u2019anno scorso, arrivando a quota 411.600 (+31% rispetto a gennaio-agosto 2018).<\/p>\n<p>A luglio, in particolare, si \u00e8 sperimentato un vero e proprio picco di attivit\u00e0, con quasi 60mila pratiche pervenute ed un aumento del 36% rispetto a luglio 2018.<\/p>\n<p>Il Suap supera cos\u00ec la soglia dei 2 milioni di procedure digitali in otto anni di attivit\u00e0, semplificando la vita amministrativa di quasi 3 milioni di imprese italiane.<\/p>\n<p>Ad utilizzare con sempre maggior frequenza la piattaforma realizzata dal sistema delle Camere di commercio sono state soprattutto le imprese lombarde (quasi 4mila le pratiche in pi\u00f9 nell\u2019ultimo mese rispetto a un anno fa), seguite dalle pugliesi (+2.988), venete (+2.782) e siciliane (+1.286). A Milano, in particolare, sono state inviate e ricevute 2.770 procedure a luglio, pi\u00f9 di 1.800 quelle di Venezia. Tra i Comuni pi\u00f9 attivi ci sono anche Taranto (701), Vicenza (583) e Treviso (531).<\/p>\n<p>L\u2019incremento delle pratiche e dei documenti inviati dalle imprese ai Suap arricchisce automaticamente anche la raccolta dei Fascicoli d\u2019impresa, il servizio delle Camere di Commercio che consente a tutte le Pubbliche Amministrazioni di accedere direttamente a documenti ed atti relativi alle imprese, senza doverne richiedere ulteriore copia agli operatori economici. Attualmente sono oltre un milione i fascicoli d\u2019impresa consultabili dalla Pa, 107mila in pi\u00f9 di dicembre 2018.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nuovo record dello Sportello unico per le attivit\u00e0 produttive (Suap) digitale gestito da 3.830 Comuni in collaborazione con le Camere di commercio. Nei primi nove mesi dell\u2019anno, le pratiche amministrative per l\u2019avvio e l\u2019esercizio di impresa, completate interamente online attraverso il portale , sono cresciute di quasi un terzo rispetto allo stesso periodo dell\u2019anno scorso, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1360,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56],"tags":[264,755,68],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Record di pratiche amministrative gestite dallo Sportello unico digitale -<\/title>\n<meta name=\"description\" content=\"Nuovo record dello Sportello unico per le attivit\u00e0 produttive (Suap) digitale gestito da 3.830 Comuni in collaborazione con le Camere di commercio.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/record-di-pratiche-amministrative-gestite-dallo-sportello-unico-digitale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Record di pratiche amministrative gestite dallo Sportello unico digitale -\" \/>\n<meta property=\"og:description\" content=\"Nuovo record dello Sportello unico per le attivit\u00e0 produttive (Suap) digitale gestito da 3.830 Comuni in collaborazione con le Camere di commercio.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/record-di-pratiche-amministrative-gestite-dallo-sportello-unico-digitale\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-30T10:49:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-09-30T10:49:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/07\/Telelavoro.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"682\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/record-di-pratiche-amministrative-gestite-dallo-sportello-unico-digitale\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/record-di-pratiche-amministrative-gestite-dallo-sportello-unico-digitale\/\",\"name\":\"Record di pratiche amministrative gestite dallo Sportello unico digitale -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/record-di-pratiche-amministrative-gestite-dallo-sportello-unico-digitale\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/record-di-pratiche-amministrative-gestite-dallo-sportello-unico-digitale\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/07\/Telelavoro.jpg\",\"datePublished\":\"2019-09-30T10:49:34+00:00\",\"dateModified\":\"2019-09-30T10:49:56+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"description\":\"Nuovo record dello Sportello unico per le attivit\u00e0 produttive (Suap) digitale gestito da 3.830 Comuni in collaborazione con le Camere di commercio.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/record-di-pratiche-amministrative-gestite-dallo-sportello-unico-digitale\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/record-di-pratiche-amministrative-gestite-dallo-sportello-unico-digitale\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/record-di-pratiche-amministrative-gestite-dallo-sportello-unico-digitale\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/07\/Telelavoro.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/07\/Telelavoro.jpg\",\"width\":1024,\"height\":682},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/record-di-pratiche-amministrative-gestite-dallo-sportello-unico-digitale\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Record di pratiche amministrative gestite dallo Sportello unico digitale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Record di pratiche amministrative gestite dallo Sportello unico digitale -","description":"Nuovo record dello Sportello unico per le attivit\u00e0 produttive (Suap) digitale gestito da 3.830 Comuni in collaborazione con le Camere di commercio.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/record-di-pratiche-amministrative-gestite-dallo-sportello-unico-digitale\/","og_locale":"it_IT","og_type":"article","og_title":"Record di pratiche amministrative gestite dallo Sportello unico digitale -","og_description":"Nuovo record dello Sportello unico per le attivit\u00e0 produttive (Suap) digitale gestito da 3.830 Comuni in collaborazione con le Camere di commercio.","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/record-di-pratiche-amministrative-gestite-dallo-sportello-unico-digitale\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2019-09-30T10:49:34+00:00","article_modified_time":"2019-09-30T10:49:56+00:00","og_image":[{"width":1024,"height":682,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/07\/Telelavoro.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/record-di-pratiche-amministrative-gestite-dallo-sportello-unico-digitale\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/record-di-pratiche-amministrative-gestite-dallo-sportello-unico-digitale\/","name":"Record di pratiche amministrative gestite dallo Sportello unico digitale -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/record-di-pratiche-amministrative-gestite-dallo-sportello-unico-digitale\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/record-di-pratiche-amministrative-gestite-dallo-sportello-unico-digitale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/07\/Telelavoro.jpg","datePublished":"2019-09-30T10:49:34+00:00","dateModified":"2019-09-30T10:49:56+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"description":"Nuovo record dello Sportello unico per le attivit\u00e0 produttive (Suap) digitale gestito da 3.830 Comuni in collaborazione con le Camere di commercio.","breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/record-di-pratiche-amministrative-gestite-dallo-sportello-unico-digitale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/record-di-pratiche-amministrative-gestite-dallo-sportello-unico-digitale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/record-di-pratiche-amministrative-gestite-dallo-sportello-unico-digitale\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/07\/Telelavoro.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/07\/Telelavoro.jpg","width":1024,"height":682},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/record-di-pratiche-amministrative-gestite-dallo-sportello-unico-digitale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Record di pratiche amministrative gestite dallo Sportello unico digitale"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/1813"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=1813"}],"version-history":[{"count":2,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/1813\/revisions"}],"predecessor-version":[{"id":1815,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/1813\/revisions\/1815"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/1360"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=1813"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=1813"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=1813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}