{"id":185,"date":"2018-08-23T11:57:50","date_gmt":"2018-08-23T09:57:50","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=185"},"modified":"2018-08-23T11:57:50","modified_gmt":"2018-08-23T09:57:50","slug":"prezzi-allingrosso-carni-di-pollo-e-burro-in-calo-a-luglio-risalgono-olio-di-oliva-e-semola-di-grano-duro","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/prezzi-allingrosso-carni-di-pollo-e-burro-in-calo-a-luglio-risalgono-olio-di-oliva-e-semola-di-grano-duro\/","title":{"rendered":"Prezzi all\u2019ingrosso: carni di pollo e burro in calo a luglio. Risalgono olio di oliva e semola di grano duro"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">T<\/span>ornano a scendere a luglio i prezzi all\u2019ingrosso delle carni (-1,8% rispetto a giugno), spinti al ribasso dal forte ridimensionamento osservato per le carni di pollo.<\/p>\n<p>L\u2019indice dei prezzi all\u2019ingrosso elaborato da <strong>Unioncamere e BMTI<\/strong> ha mostrato infatti a luglio una caduta del 14,6% per le carni di pollo, dipesa dalla forte contrazione della domanda avvenuta nella prima parte del mese.<\/p>\n<blockquote class=\"td_quote_box td_box_left\"><p>Una flessione che ha riportato in negativo anche la variazione rispetto allo scorso anno (dal +10,6% di giugno al -7,8% di luglio).<\/p><\/blockquote>\n<p>Il segno \u201cmeno\u201d ha interessato a luglio anche le carni di coniglio (-3,3% rispetto a giugno), che hanno dunque proseguito la congiuntura negativa in atto dal mese di aprile. I prezzi attuali si mantengono comunque in linea con lo scorso anno. Variazione rispetto a dodici mesi fa che rimane negativa invece per le carni suine (-4,7%), sebbene luglio abbia registrato un nuovo aumento mensile (+4,5%).<\/p>\n<p>Tra le carni rosse, leggero rialzo per le carni bovine, i cui prezzi si confermano peraltro pi\u00f9 alti rispetto allo scorso anno (+3,5%).<\/p>\n<p>Prezzi in lieve discesa nel comparto di latte e formaggi (-1,6% rispetto a giugno), all\u2019interno del quale \u00e8 spiccato il robusto calo per la panna (-10,1%), dettato soprattutto dalla domanda limitata.<\/p>\n<p>A monte della filiera, dopo i rialzi osservati nel secondo trimestre dell\u2019anno, i prezzi del latte spot hanno mostrato segnali di stabilit\u00e0 a luglio (-0,3% su base mensile).<\/p>\n<blockquote class=\"td_quote_box td_box_right\"><p>Un quadro che per il comparto lattiero-caseario appare tutt\u2019altro che roseo anche rispetto a dodici mesi fa, con i prezzi che cedono il 4,1% nel complesso.<\/p><\/blockquote>\n<p>Significativa la diminuzione osservata per il latte e la panna, in entrambi i casi superiore ai dieci punti percentuali. Segno \u201cmeno\u201d rispetto allo scorso anno che permane per i formaggi a lunga stagionatura (-3,6%).Nel comparto degli oli e grassi, dopo una serie di ribassi in atto sin dall\u2019inizio della campagna commerciale, i listini all\u2019ingrosso degli oli di oliva sono tornati a mostrare un deciso rialzo a luglio (+5%).<\/p>\n<p>Crescita imputabile ai timori che si riscontrano per la prossima campagna, in particolare nelle aree produttive pi\u00f9 importanti, a causa delle avversit\u00e0 climatiche delle passate settimane.<\/p>\n<p>Tra le materie grasse, pesante battuta d\u2019arresto, invece, per il burro (-9% rispetto a giugno), il cui mercato anche a livello comunitario \u00e8 stato interessato da forti ribassi. Pur a fronte di dinamiche mensili contrapposte, olio di oliva e burro accusano una pesante riduzione rispetto allo scorso anno, superiore al 20%.<\/p>\n<p>Prezzi all\u2019ingrosso in crescita nel comparto di riso e cereali (+1,8% su base mensile), grazie all\u2019incremento riscontrato per la semola di grano duro (+2,9%) e per il riso. In particolare, il mercato della semola &#8211; la materia prima utilizzata per la produzione della pasta &#8211; ha mostrato una maggiore vivacit\u00e0 rispetto ai mesi scorsi, in coincidenza con l\u2019avvio della nuova campagna del grano duro.<\/p>\n<p>Segnali di aumento, ancorch\u00e8 di lieve entit\u00e0, per le farine di grano tenero, in un mercato che a luglio ha invece registrato crescenti tensioni per i prezzi dei grani, a causa dei timori su una possibile forte contrazione dei raccolti in Europa Settentrionale, nell\u2019area del Mar Nero e in Australia.<\/p>\n<p>Unioncamere con la societ\u00e0 BMTI scpa pubblica mensilmente l\u2019indice del prezzi all\u2019ingrosso dell\u2019agroalimentare\u00a0 aggregando i dati ufficiali rilevati dalle Camere di Commercio nelle rispettive piazze attraverso i listini sui prezzi all\u2019ingrosso all\u2019agroalimentare. La nota di Unioncamere riporta il dato congiunturale e tendenziale mostrando la dinamica nazionale nei 4 comparti: Riso e Cereali, Carni, Latte formaggi e uova, Oli e grassi .<\/p>\n<p><a href=\"http:\/\/www.italiaeconomiaonline.it\/web\/2018\/08\/23\/prezzi-allingrosso-carni-di-pollo-e-burro-in-calo-a-luglio-risalgono-olio-di-oliva-e-semola-di-grano-duro\/dati_unioncamere\/\" rel=\"attachment wp-att-186\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-186\" src=\"http:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/08\/dati_unioncamere.png\" alt=\"\" width=\"586\" height=\"378\" srcset=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/08\/dati_unioncamere.png 586w, https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/08\/dati_unioncamere-300x194.png 300w\" sizes=\"(max-width: 586px) 100vw, 586px\" \/><\/a><\/p>\n<h6><i>Fonte: L\u2019Indice dei Prezzi Ufficiali all\u2019ingrosso viene elaborato da Unioncamere e da BMTI Scpa e si basa sui prezzi ufficiali all\u2019ingrosso rilevati e pubblicati dal Sistema Camerale. <\/i><\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Tornano a scendere a luglio i prezzi all\u2019ingrosso delle carni (-1,8% rispetto a giugno), spinti al ribasso dal forte ridimensionamento osservato per le carni di pollo. L\u2019indice dei prezzi all\u2019ingrosso elaborato da Unioncamere e BMTI ha mostrato infatti a luglio una caduta del 14,6% per le carni di pollo, dipesa dalla forte contrazione della domanda [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":187,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56],"tags":[69,66,67,68],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Prezzi all\u2019ingrosso: carni di pollo e burro in calo a luglio. Risalgono olio di oliva e semola di grano duro -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/prezzi-allingrosso-carni-di-pollo-e-burro-in-calo-a-luglio-risalgono-olio-di-oliva-e-semola-di-grano-duro\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prezzi all\u2019ingrosso: carni di pollo e burro in calo a luglio. Risalgono olio di oliva e semola di grano duro -\" \/>\n<meta property=\"og:description\" content=\"Tornano a scendere a luglio i prezzi all\u2019ingrosso delle carni (-1,8% rispetto a giugno), spinti al ribasso dal forte ridimensionamento osservato per le carni di pollo. L\u2019indice dei prezzi all\u2019ingrosso elaborato da Unioncamere e BMTI ha mostrato infatti a luglio una caduta del 14,6% per le carni di pollo, dipesa dalla forte contrazione della domanda [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/prezzi-allingrosso-carni-di-pollo-e-burro-in-calo-a-luglio-risalgono-olio-di-oliva-e-semola-di-grano-duro\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2018-08-23T09:57:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/08\/olio_di_oliva.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/prezzi-allingrosso-carni-di-pollo-e-burro-in-calo-a-luglio-risalgono-olio-di-oliva-e-semola-di-grano-duro\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/prezzi-allingrosso-carni-di-pollo-e-burro-in-calo-a-luglio-risalgono-olio-di-oliva-e-semola-di-grano-duro\/\",\"name\":\"Prezzi all\u2019ingrosso: carni di pollo e burro in calo a luglio. Risalgono olio di oliva e semola di grano duro -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/prezzi-allingrosso-carni-di-pollo-e-burro-in-calo-a-luglio-risalgono-olio-di-oliva-e-semola-di-grano-duro\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/prezzi-allingrosso-carni-di-pollo-e-burro-in-calo-a-luglio-risalgono-olio-di-oliva-e-semola-di-grano-duro\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/08\/olio_di_oliva.jpg\",\"datePublished\":\"2018-08-23T09:57:50+00:00\",\"dateModified\":\"2018-08-23T09:57:50+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/prezzi-allingrosso-carni-di-pollo-e-burro-in-calo-a-luglio-risalgono-olio-di-oliva-e-semola-di-grano-duro\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/prezzi-allingrosso-carni-di-pollo-e-burro-in-calo-a-luglio-risalgono-olio-di-oliva-e-semola-di-grano-duro\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/prezzi-allingrosso-carni-di-pollo-e-burro-in-calo-a-luglio-risalgono-olio-di-oliva-e-semola-di-grano-duro\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/08\/olio_di_oliva.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/08\/olio_di_oliva.jpg\",\"width\":960,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/prezzi-allingrosso-carni-di-pollo-e-burro-in-calo-a-luglio-risalgono-olio-di-oliva-e-semola-di-grano-duro\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prezzi all\u2019ingrosso: carni di pollo e burro in calo a luglio. Risalgono olio di oliva e semola di grano duro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prezzi all\u2019ingrosso: carni di pollo e burro in calo a luglio. Risalgono olio di oliva e semola di grano duro -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/prezzi-allingrosso-carni-di-pollo-e-burro-in-calo-a-luglio-risalgono-olio-di-oliva-e-semola-di-grano-duro\/","og_locale":"it_IT","og_type":"article","og_title":"Prezzi all\u2019ingrosso: carni di pollo e burro in calo a luglio. Risalgono olio di oliva e semola di grano duro -","og_description":"Tornano a scendere a luglio i prezzi all\u2019ingrosso delle carni (-1,8% rispetto a giugno), spinti al ribasso dal forte ridimensionamento osservato per le carni di pollo. L\u2019indice dei prezzi all\u2019ingrosso elaborato da Unioncamere e BMTI ha mostrato infatti a luglio una caduta del 14,6% per le carni di pollo, dipesa dalla forte contrazione della domanda [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/prezzi-allingrosso-carni-di-pollo-e-burro-in-calo-a-luglio-risalgono-olio-di-oliva-e-semola-di-grano-duro\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2018-08-23T09:57:50+00:00","og_image":[{"width":960,"height":640,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/08\/olio_di_oliva.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/prezzi-allingrosso-carni-di-pollo-e-burro-in-calo-a-luglio-risalgono-olio-di-oliva-e-semola-di-grano-duro\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/prezzi-allingrosso-carni-di-pollo-e-burro-in-calo-a-luglio-risalgono-olio-di-oliva-e-semola-di-grano-duro\/","name":"Prezzi all\u2019ingrosso: carni di pollo e burro in calo a luglio. Risalgono olio di oliva e semola di grano duro -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/prezzi-allingrosso-carni-di-pollo-e-burro-in-calo-a-luglio-risalgono-olio-di-oliva-e-semola-di-grano-duro\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/prezzi-allingrosso-carni-di-pollo-e-burro-in-calo-a-luglio-risalgono-olio-di-oliva-e-semola-di-grano-duro\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/08\/olio_di_oliva.jpg","datePublished":"2018-08-23T09:57:50+00:00","dateModified":"2018-08-23T09:57:50+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/prezzi-allingrosso-carni-di-pollo-e-burro-in-calo-a-luglio-risalgono-olio-di-oliva-e-semola-di-grano-duro\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/prezzi-allingrosso-carni-di-pollo-e-burro-in-calo-a-luglio-risalgono-olio-di-oliva-e-semola-di-grano-duro\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/prezzi-allingrosso-carni-di-pollo-e-burro-in-calo-a-luglio-risalgono-olio-di-oliva-e-semola-di-grano-duro\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/08\/olio_di_oliva.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/08\/olio_di_oliva.jpg","width":960,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/prezzi-allingrosso-carni-di-pollo-e-burro-in-calo-a-luglio-risalgono-olio-di-oliva-e-semola-di-grano-duro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Prezzi all\u2019ingrosso: carni di pollo e burro in calo a luglio. Risalgono olio di oliva e semola di grano duro"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/185"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=185"}],"version-history":[{"count":2,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/185\/revisions"}],"predecessor-version":[{"id":189,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/185\/revisions\/189"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/187"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=185"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=185"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}