{"id":1900,"date":"2019-10-15T12:39:20","date_gmt":"2019-10-15T10:39:20","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=1900"},"modified":"2019-10-15T12:49:40","modified_gmt":"2019-10-15T10:49:40","slug":"ricerca-e-innovazione-la-situazione-migliora-ma-troppo-lentamente","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/ricerca-e-innovazione-la-situazione-migliora-ma-troppo-lentamente\/","title":{"rendered":"Ricerca e innovazione: la situazione migliora ma troppo lentamente"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">P<\/span>resentata oggi la Relazione 2019 del Consiglio nazionale delle ricerche, alla presenza del premier Conte e del ministro Fioramonti. Migliorano, in misura per\u00f2 insufficiente, i dati della spesa per Ricerca e Sviluppo in rapporto al Pil, degli stanziamenti pubblici, dei ricercatori in rapporto alla forza lavoro, del divario di genere, del saldo commerciale tecnologico e dei brevetti.<\/p>\n<p>Si conferma il quadro positivo della produzione scientifica dei nostri ricercatori. Anche se l\u2019Italia \u00e8 fermamente integrata nei Programmi Quadro dell\u2019Unione Europea, il contributo da noi versato continua ad essere superiore a quanto riusciamo ad ottenere con i progetti di ricerca aggiudicati.<\/p>\n<p>Non ci sono invece segni di miglioramento per quanto riguarda l\u2019et\u00e0 media dei ricercatori italiani. Nel complesso, la posizione italiana resta quindi lontana dalla media Ue e dai competitor europei. \u201cOccorre una politica di reclutamento regolare, programmata, garantita\u201d, osserva il presidente del Cnr, Inguscio<\/p>\n<p>Il Consiglio nazionale delle ricerche presenta oggi\u00a0 la <em>Relazione sulla ricerca e l\u2019innovazione in Italia 2019<\/em>, un rapporto contenente analisi e dati di politica della scienza e della tecnologia, che l\u2019Ente mette a disposizione di Governo, Parlamento e opinione pubblica.<\/p>\n<p>All\u2019evento, che si \u00e8 svolto presso la sede centrale dell\u2019Ente, hanno partecipato tra gli altri il presidente del Consiglio, Giuseppe Conte, il ministro dell\u2019Istruzione, universit\u00e0 e ricerca scientifica (Miur) Lorenzo Fioramonti, il presidente della Crui, Gaetano Manfredi, il presidente del Cnr Massimo Inguscio e i curatori della Relazione, Daniele Archibugi e Fabrizio Tuzi.<\/p>\n<p>Tra le autorit\u00e0 presenti: le ministre Elena Bonetti, Pari opportunit\u00e0, e Paola Pisano, Innovazione tecnologica, e numerosi Rettori e Presidenti degli Enti di Ricerca. La Relazione e i contenuti multimediali sono disponibili <a href=\"https:\/\/www.cnr.it\/it\/comunicato-stampa\/8975\">on line<\/a><\/p>\n<p>In Italia, la <strong>spesa<\/strong> <strong>per Ricerca e Sviluppo<\/strong> (R&amp;S) in rapporto al Prodotto interno lordo (Pil) \u00e8 in lieve ripresa, passando dall\u20191,0% del 2000 a circa l\u20191,4% del 2016, grazie anche all\u2019interruzione del trend di diminuzione degli stanziamenti pubblici. Restiamo tuttavia posizionati in fondo alla classifica dei paesi europei, dove il rapporto tra investimenti in R&amp;S e Pil \u00e8 quasi del 2%. Dopo la flessione del biennio 2014-15, sono in ripresa anche gli stanziamenti del Miur agli Enti pubblici di ricerca (Epr), passati da 1.572 milioni nel 2016 a 1.670 milioni nel 2018: il Cnr, in particolare, ha ottenuto nel biennio un incremento da 555 milioni a 602 milioni.<\/p>\n<p><strong>La quota dei ricercatori<\/strong> in rapporto alla forza lavoro, pur rimanendo ben al di sotto di quella degli altri paesi europei e distanziandosi ancora di pi\u00f9 dalla media Ue, \u00e8 costantemente cresciuta nell\u2019ultimo decennio. Dal 2005 al 2016 i ricercatori sono aumentati di circa 60.000 unit\u00e0.<\/p>\n<p>Tra i settori istituzionali, la crescita pi\u00f9 rilevante si \u00e8 registrata nelle imprese private: i dati pi\u00f9 recenti mostrano una tendenza in atto che avvicina questo settore per numero di ricercatori all\u2019universit\u00e0: quest\u2019ultima rimane ancora l\u2019area maggiore, con 78.000 addetti contro i 72.000 delle imprese, ma nell\u2019universit\u00e0 il numero complessivo \u00e8 pressoch\u00e9 stazionario nel tempo. Anche gli Epr hanno registrato una crescita sensibile nel corso degli ultimi 10 anni, giungendo a circa 29.000 ricercatori, oltre il 15% del totale. Molto rilevante la quota di assegnisti: sono pi\u00f9 del 20% dei ricercatori nelle universit\u00e0, e addirittura il 25% negli Enti.<\/p>\n<p>Si rileva un progressivo aumento delle ricercatrici e, secondo le proiezioni, entro il 2025 il <strong>divario di rappresentanza di genere<\/strong> potrebbe pressoch\u00e9 scomparire nelle istituzioni pubbliche e ridursi drasticamente nelle universit\u00e0, mentre nelle imprese sembra rimanere sostanzialmente immutato. Tuttavia, queste proiezioni non considerano la progressione di carriera, che tuttora penalizza le donne.<\/p>\n<p>Confrontando l\u2019<strong>et\u00e0 dei ricercatori<\/strong>, la Relazione evidenzia come nell\u2019universit\u00e0 italiana gli over 50 superano la met\u00e0 dei docenti, mentre nel Regno Unito e in Francia sono, rispettivamente, il 40% e il 37%. L\u2019et\u00e0 media dei docenti italiani \u00e8 di quasi 49 anni e quella dei ricercatori negli Epr \u00e8 di 46. I ricercatori nelle imprese private hanno un\u2019et\u00e0 inferiore, pari a 43 anni. Il fenomeno \u00e8 correlato al generale invecchiamento della popolazione italiana, ma testimonia anche la difficolt\u00e0 di effettuare nel settore pubblico un reclutamento ordinario basato su una programmazione di lungo periodo. Secondo le proiezioni, in assenza di politiche strategiche di lungo periodo, l\u2019et\u00e0 media dei ricercatori continuer\u00e0 ad aumentare in tutti i comparti.<\/p>\n<p>\u201cLa sfida della scienza passa anche per politiche orientate ad un futuro, che \u00e8\u00a0gi\u00e0 presente, in cui si realizzino le necessarie sinergie tra ricerca, tecnica, ambiente, patrimonio culturale: rafforzando cos\u00ec un patto che \u00e8 iscritto nella nostra stessa Costituzione e che cerca di produrre, senza discriminazioni, benefici per le donne e per gli uomini\u201d, osserva il presidente del Cnr, Massimo Inguscio.<\/p>\n<p>\u201cLe donne e gli uomini che lavorano nella ricerca devono anche essere protagonisti di una politica di reclutamento adeguata. Siamo riusciti a non disperdere le competenze sviluppatesi negli anni, stabilizzando in modo molto significativo il lavoro precario, a far ripartire un nuovo reclutamento con concorsi nazionali competitivi organizzati per aree strategiche, a realizzare promozioni meritocratiche. Centrale sar\u00e0 d\u2019ora in poi una politica di investimento che consenta un reclutamento regolare e programmato ed eviti il prodursi di nuovo precariato\u201d.<\/p>\n<p>Per quanto riguarda la <strong>produzione scientifica<\/strong>, si conferma il quadro positivo della precedente Relazione: la comunit\u00e0 dei ricercatori italiani produce una quantit\u00e0 di pubblicazioni significativa e in crescita: sia come quota mondiale (quasi il 5% nel 2018), sia per qualit\u00e0, attestata dalle citazioni medie ricevute per pubblicazione, che nel biennio 2017-18 sfiorano l\u20191,4. Una produzione scientifica analoga a quella della Francia, la quale per\u00f2 conta su un numero di ricercatori pi\u00f9 elevato rispetto al nostro paese. La Relazione presenta anche una metodologia per identificare i punti di forza e di debolezza dei diversi settori della Ricerca accademica.<\/p>\n<p>L\u2019Italia continua a essere un partecipante attivo dei <strong>Programmi Quadro Europei<\/strong>, compreso Horizon 2020, conseguendo nel primo triennio del programma europeo settennale in corso l\u20198,7% dei finanziamenti: una quota per\u00f2 distante da quella dei finanziamenti ottenuti dai maggiori paesi europei quali Germania (16,4%), Regno Unito (14,0%) e Francia (10,5%).<\/p>\n<p>Il saldo tra quanto il Paese contribuisce per i Programmi Quadro dell\u2019Ue a 28 e quanto riesce ad ottenere \u00e8 purtroppo negativo: l&#8217;Italia, infatti, concorre con il 12,5% al bilancio complessivo e intercetta lo 8,7% delle erogazioni. Il risultato \u00e8 dovuto in parte al minor numero di ricercatori presenti in Italia e in parte al tasso di successo dei progetti coordinati dal nostro Paese, pari al 7,5% a fronte di una media di Horizon 2020 del 13,0%.<\/p>\n<p>\u201cCi sono margini di miglioramento che rendono necessario perseguire politiche strategiche. Per aumentare il tasso di ritorno dell\u2019investimento europeo, occorre pensare a sostegni amministrativi, ad incentivi per chi presenta domande, favorendo la collaborazione pubblico-privato e l\u2019innovazione, e coinvolgendo maggiormente idee e proposte dei giovani ricercatori\u201d, osservano Daniele Archibugi e Fabrizio Tuzi, ricercatori Cnr tra gli autori della Relazione.<\/p>\n<p>Per quanto riguarda l\u2019entit\u00e0 del <em>public procurement<\/em>, cio\u00e8 gli <strong>appalti pubblici<\/strong>, i dati evidenziano effetti marginali: gli avvisi relativi al settore Ricerca e Sviluppo sono 6 ogni mille gare bandite, mentre nel Regno Unito sono 10 su mille e in Germania 8. Il procurement di R&amp;S nel 2018 ha raggiunto i 176 milioni di euro, appena lo 0,15% del totale dei beni e servizi acquistati dalla pubblica amministrazione. Basterebbe un moderato aumento di questi numeri per incrementare notevolmente l\u2019investimento totale in R&amp;S: se, ad esempio, il valore arrivasse all\u20191% degli appalti pubblici nazionali, con un incremento di circa 6 volte rispetto alla spesa attuale, si genererebbe un significativo strumento per promuovere l\u2019innovazione industriale.<\/p>\n<p>Gli indicatori relativi alle prestazioni tecnologiche continuano a mostrare minimi segnali di miglioramento. Per quanto riguarda il <strong>saldo commerciale nell\u2019alta tecnologia<\/strong>, nell\u2019ultimo decennio il deficit registrato dall\u2019Italia \u00e8 diventato meno rilevante, attestandosi nel 2018 su -4 miliardi di dollari. I settori high-tech dove si riscontrano le maggiori quote esportate si confermano l\u2019Automazione industriale, con il 7% delle esportazioni mondiali, e la Farmaceutica, con circa il 4,5%. Anche i <strong>brevetti<\/strong> depositati ogni 100.000 abitanti hanno mostrato un incoraggiante miglioramento: 6,7% nel 2016; 7,2% nel 2018. I brevetti italiani continuano, tuttavia, ad essere solo il 2,52% sul totale mondiale.<\/p>\n<p>&nbsp;<\/p>\n<p>R<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Presentata oggi la Relazione 2019 del Consiglio nazionale delle ricerche, alla presenza del premier Conte e del ministro Fioramonti. Migliorano, in misura per\u00f2 insufficiente, i dati della spesa per Ricerca e Sviluppo in rapporto al Pil, degli stanziamenti pubblici, dei ricercatori in rapporto alla forza lavoro, del divario di genere, del saldo commerciale tecnologico e [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1801,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[53],"tags":[786,446,785,210],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ricerca e innovazione: la situazione migliora ma troppo lentamente -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/ricerca-e-innovazione-la-situazione-migliora-ma-troppo-lentamente\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ricerca e innovazione: la situazione migliora ma troppo lentamente -\" \/>\n<meta property=\"og:description\" content=\"Presentata oggi la Relazione 2019 del Consiglio nazionale delle ricerche, alla presenza del premier Conte e del ministro Fioramonti. Migliorano, in misura per\u00f2 insufficiente, i dati della spesa per Ricerca e Sviluppo in rapporto al Pil, degli stanziamenti pubblici, dei ricercatori in rapporto alla forza lavoro, del divario di genere, del saldo commerciale tecnologico e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/ricerca-e-innovazione-la-situazione-migliora-ma-troppo-lentamente\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-15T10:39:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-10-15T10:49:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/09\/mondo1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/ricerca-e-innovazione-la-situazione-migliora-ma-troppo-lentamente\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/ricerca-e-innovazione-la-situazione-migliora-ma-troppo-lentamente\/\",\"name\":\"Ricerca e innovazione: la situazione migliora ma troppo lentamente -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/ricerca-e-innovazione-la-situazione-migliora-ma-troppo-lentamente\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/ricerca-e-innovazione-la-situazione-migliora-ma-troppo-lentamente\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/09\/mondo1.jpg\",\"datePublished\":\"2019-10-15T10:39:20+00:00\",\"dateModified\":\"2019-10-15T10:49:40+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/ricerca-e-innovazione-la-situazione-migliora-ma-troppo-lentamente\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/ricerca-e-innovazione-la-situazione-migliora-ma-troppo-lentamente\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/ricerca-e-innovazione-la-situazione-migliora-ma-troppo-lentamente\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/09\/mondo1.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/09\/mondo1.jpg\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/ricerca-e-innovazione-la-situazione-migliora-ma-troppo-lentamente\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ricerca e innovazione: la situazione migliora ma troppo lentamente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ricerca e innovazione: la situazione migliora ma troppo lentamente -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/ricerca-e-innovazione-la-situazione-migliora-ma-troppo-lentamente\/","og_locale":"it_IT","og_type":"article","og_title":"Ricerca e innovazione: la situazione migliora ma troppo lentamente -","og_description":"Presentata oggi la Relazione 2019 del Consiglio nazionale delle ricerche, alla presenza del premier Conte e del ministro Fioramonti. Migliorano, in misura per\u00f2 insufficiente, i dati della spesa per Ricerca e Sviluppo in rapporto al Pil, degli stanziamenti pubblici, dei ricercatori in rapporto alla forza lavoro, del divario di genere, del saldo commerciale tecnologico e [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/ricerca-e-innovazione-la-situazione-migliora-ma-troppo-lentamente\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2019-10-15T10:39:20+00:00","article_modified_time":"2019-10-15T10:49:40+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/09\/mondo1.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/ricerca-e-innovazione-la-situazione-migliora-ma-troppo-lentamente\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/ricerca-e-innovazione-la-situazione-migliora-ma-troppo-lentamente\/","name":"Ricerca e innovazione: la situazione migliora ma troppo lentamente -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/ricerca-e-innovazione-la-situazione-migliora-ma-troppo-lentamente\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/ricerca-e-innovazione-la-situazione-migliora-ma-troppo-lentamente\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/09\/mondo1.jpg","datePublished":"2019-10-15T10:39:20+00:00","dateModified":"2019-10-15T10:49:40+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/ricerca-e-innovazione-la-situazione-migliora-ma-troppo-lentamente\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/ricerca-e-innovazione-la-situazione-migliora-ma-troppo-lentamente\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/ricerca-e-innovazione-la-situazione-migliora-ma-troppo-lentamente\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/09\/mondo1.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/09\/mondo1.jpg","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/ricerca-e-innovazione-la-situazione-migliora-ma-troppo-lentamente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Ricerca e innovazione: la situazione migliora ma troppo lentamente"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/1900"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=1900"}],"version-history":[{"count":3,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/1900\/revisions"}],"predecessor-version":[{"id":1903,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/1900\/revisions\/1903"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/1801"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=1900"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=1900"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=1900"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}