{"id":1976,"date":"2019-11-03T16:07:43","date_gmt":"2019-11-03T15:07:43","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=1976"},"modified":"2019-11-03T16:07:43","modified_gmt":"2019-11-03T15:07:43","slug":"ecomondo-in-fiera-i-laboratori-didattici-di-apicoltura","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/ecomondo-in-fiera-i-laboratori-didattici-di-apicoltura\/","title":{"rendered":"Ecomondo, in fiera i laboratori didattici di apicoltura"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">A<\/span>llo stand di Confagricoltura ad Ecomondo, a Rimini, ci saranno anche le api. Gli alveari didattici della FAI \u2013 Federazione degli Apicoltori Italiani mostreranno ai visitatori la vita dell\u2019insetto amico dell\u2019uomo, ambasciatore e sentinella della biodiversit\u00e0.<\/p>\n<p>Presso la sala dibattiti dello spazio fieristico di Confagricoltura, tutte le mattine &#8211; dal 5 all\u20198 novembre (dalle ore 10 alle ore 12) &#8211; si terranno una serie di laboratori apistici organizzati dalla FAI pensati per le scuole, gli agricoltori e tutti i visitatori. Un suggestivo viaggio nell\u2019 \u2018ecomondo delle api\u2019, supportato anche da un docufilm di grande impatto.<\/p>\n<p>Nei laboratori si approfondiranno: la vita delle api ed il ruolo che svolgono in natura; il rapporto con l\u2019agricoltura; le azioni concrete per la tutela e la salvaguardia delle api; i fiori utili da diffondere negli ambienti urbani e nelle aree incolte; il riconoscimento dei vari colori del miele; la degustazione e l\u2019esplorazione sensoriale dei suoni, degli odori e dei gusti dell\u2019alveare.<\/p>\n<p>\u201cSaremo a Rimini \u2013 sottolinea il presidente della Federazione degli Apicoltori Italiani, Raffaele Cirone \u2013 per spiegare i segreti di una goccia di miele: dal fiore al vasetto cosa succede e come si arriva a trarre un alimento di grande qualit\u00e0 scavando in quella miniera a cielo aperto che sono i fiori presenti sui nostri territori, nelle nostre zone rurali, naturali, urbane persino\u201d.<\/p>\n<p>Il presidente della FAI pone in evidenza come sia fondamentale immettere negli agrosistemi una quantit\u00e0 sufficiente di alveari, quindi di api che, fiore dopo fiore, impollinano e incrementano sensibilmente le rese economiche. \u201cCi\u00f2 che scientificamente \u00e8 noto e misurabile come \u2018apporto ecosistemico\u2019, noi apicoltori lo chiamiamo semplicemente \u2018servizio di impollinazione\u2019\u201d.<\/p>\n<p>I prodotti dell\u2019alveare tutti messi insieme valgono 150 di milioni di euro \u2013 concludono Confagricoltura e FAI -. Mentre il valore aggiunto che l\u2019agricoltura conquista, grazie alla presenza delle api nelle nostre campagne, supera il fatturato di 2 miliardi di euro all\u2019anno\u201d.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Allo stand di Confagricoltura ad Ecomondo, a Rimini, ci saranno anche le api. Gli alveari didattici della FAI \u2013 Federazione degli Apicoltori Italiani mostreranno ai visitatori la vita dell\u2019insetto amico dell\u2019uomo, ambasciatore e sentinella della biodiversit\u00e0. Presso la sala dibattiti dello spazio fieristico di Confagricoltura, tutte le mattine &#8211; dal 5 all\u20198 novembre (dalle ore [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1977,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ecomondo, in fiera i laboratori didattici di apicoltura -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/ecomondo-in-fiera-i-laboratori-didattici-di-apicoltura\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ecomondo, in fiera i laboratori didattici di apicoltura -\" \/>\n<meta property=\"og:description\" content=\"Allo stand di Confagricoltura ad Ecomondo, a Rimini, ci saranno anche le api. Gli alveari didattici della FAI \u2013 Federazione degli Apicoltori Italiani mostreranno ai visitatori la vita dell\u2019insetto amico dell\u2019uomo, ambasciatore e sentinella della biodiversit\u00e0. Presso la sala dibattiti dello spazio fieristico di Confagricoltura, tutte le mattine &#8211; dal 5 all\u20198 novembre (dalle ore [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/ecomondo-in-fiera-i-laboratori-didattici-di-apicoltura\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-03T15:07:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/api-apicoltura.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/ecomondo-in-fiera-i-laboratori-didattici-di-apicoltura\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/ecomondo-in-fiera-i-laboratori-didattici-di-apicoltura\/\",\"name\":\"Ecomondo, in fiera i laboratori didattici di apicoltura -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/ecomondo-in-fiera-i-laboratori-didattici-di-apicoltura\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/ecomondo-in-fiera-i-laboratori-didattici-di-apicoltura\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/api-apicoltura.jpg\",\"datePublished\":\"2019-11-03T15:07:43+00:00\",\"dateModified\":\"2019-11-03T15:07:43+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/ecomondo-in-fiera-i-laboratori-didattici-di-apicoltura\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/ecomondo-in-fiera-i-laboratori-didattici-di-apicoltura\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/ecomondo-in-fiera-i-laboratori-didattici-di-apicoltura\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/api-apicoltura.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/api-apicoltura.jpg\",\"width\":960,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/ecomondo-in-fiera-i-laboratori-didattici-di-apicoltura\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ecomondo, in fiera i laboratori didattici di apicoltura\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ecomondo, in fiera i laboratori didattici di apicoltura -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/ecomondo-in-fiera-i-laboratori-didattici-di-apicoltura\/","og_locale":"it_IT","og_type":"article","og_title":"Ecomondo, in fiera i laboratori didattici di apicoltura -","og_description":"Allo stand di Confagricoltura ad Ecomondo, a Rimini, ci saranno anche le api. Gli alveari didattici della FAI \u2013 Federazione degli Apicoltori Italiani mostreranno ai visitatori la vita dell\u2019insetto amico dell\u2019uomo, ambasciatore e sentinella della biodiversit\u00e0. Presso la sala dibattiti dello spazio fieristico di Confagricoltura, tutte le mattine &#8211; dal 5 all\u20198 novembre (dalle ore [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/ecomondo-in-fiera-i-laboratori-didattici-di-apicoltura\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2019-11-03T15:07:43+00:00","og_image":[{"width":960,"height":720,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/api-apicoltura.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/ecomondo-in-fiera-i-laboratori-didattici-di-apicoltura\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/ecomondo-in-fiera-i-laboratori-didattici-di-apicoltura\/","name":"Ecomondo, in fiera i laboratori didattici di apicoltura -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/ecomondo-in-fiera-i-laboratori-didattici-di-apicoltura\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/ecomondo-in-fiera-i-laboratori-didattici-di-apicoltura\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/api-apicoltura.jpg","datePublished":"2019-11-03T15:07:43+00:00","dateModified":"2019-11-03T15:07:43+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/ecomondo-in-fiera-i-laboratori-didattici-di-apicoltura\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/ecomondo-in-fiera-i-laboratori-didattici-di-apicoltura\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/ecomondo-in-fiera-i-laboratori-didattici-di-apicoltura\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/api-apicoltura.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/api-apicoltura.jpg","width":960,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/ecomondo-in-fiera-i-laboratori-didattici-di-apicoltura\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Ecomondo, in fiera i laboratori didattici di apicoltura"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/1976"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=1976"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/1976\/revisions"}],"predecessor-version":[{"id":1978,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/1976\/revisions\/1978"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/1977"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=1976"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=1976"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=1976"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}