{"id":1981,"date":"2019-11-03T16:33:27","date_gmt":"2019-11-03T15:33:27","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=1981"},"modified":"2019-11-03T16:39:28","modified_gmt":"2019-11-03T15:39:28","slug":"mese-delleducazione-finanziaria-2019-ecco-i-numeri","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/mese-delleducazione-finanziaria-2019-ecco-i-numeri\/","title":{"rendered":"Mese dell&#8217;educazione finanziaria 2019, ecco i numeri"},"content":{"rendered":"<p>La seconda edizione del <strong>\u201cMese dell\u2019Educazione Finanziaria\u201d<\/strong>, organizzato dall\u20191 al 31 Ottobre dal Comitato per la programmazione e il coordinamento delle attivit\u00e0 di educazione finanziaria, si chiude con numeri da record: 602 appuntamenti all\u2019attivo e la partecipazione di tutte le Regioni d\u2019Italia. Un risultato notevole, che testimonia il crescente interesse sia da parte dei cittadini che dei tanti soggetti, pubblici e privati, che quest\u2019anno hanno organizzato eventi per contribuire a far crescere e diffondere l\u2019educazione finanziaria, assicurativa e previdenziale nel nostro Paese.<\/p>\n<p>Il \u2018Mese\u2019 &#8211; che ha visto il debutto della prima Giornata Nazionale sull\u2019Educazione Assicurativa, il 9 ottobre e che diventer\u00e0 un appuntamento fisso dei prossimi anni &#8211; si chiuder\u00e0 oggi, in occasione della <strong>Giornata Mondiale del Risparmio<\/strong>.<\/p>\n<p>Nel dettaglio, il calendario 2019 del \u2018Mese\u2019 ha fatto registrare ben 252 appuntamenti in pi\u00f9 rispetto ai 350 dello scorso anno (+72%), organizzati in tutte le Regioni d\u2019Italia, anche se Lombardia (143), Lazio (89) e Veneto (42) da sole hanno fatto registrare quasi la met\u00e0 degli eventi.<\/p>\n<p>La gran parte degli appuntamenti ha riguardato l\u2019<strong>educazione finanziaria<\/strong> (510), seguita da quella <strong>previdenziale<\/strong> (64) e <strong>assicurativa<\/strong> (28).<\/p>\n<p>Tante le modalit\u00e0 con cui si \u00e8 fatta informazione: incontri, workshop, seminari, lezioni, ma anche giochi, quiz, cacce al tesoro, cineforum, rappresentazioni teatrali. E tante sono state anche le categorie coinvolte. Il maggior numero di eventi \u00e8 stato pensato per gli studenti delle scuole superiori di primo e secondo grado e delle universit\u00e0 (310), seguiti dagli adulti (120). Non sono mancati per\u00f2 appuntamenti rivolti alle famiglie, ai professionisti ed alle imprese, ai bambini, alle donne e ai migranti.<\/p>\n<p>Il successo dell\u2019edizione 2019 del Mese dell\u2019educazione finanziaria si misura, quest\u2019anno, anche sulla base della partecipazione e del coinvolgimento dei cittadini attraverso le campagne informative messe in campo sui media tradizionali e sui social network. La neonata pagina Facebook del Comitato \u2013 a poche settimane dal debutto &#8211; conta oltre 18.000 nuovi fan; ottimi risultati arrivano anche dal canale YouTube del Comitato.<\/p>\n<p><em>\u201cVoglio ringraziare tutte le persone che hanno lavorato in queste settimane per organizzare ogni singolo appuntamento del calendario 2019 del Mese dell\u2019educazione finanziaria. Insieme<\/em> \u2013 dice <strong>Annamaria Lusardi<\/strong>, direttore del Comitato per la programmazione e il coordinamento delle attivit\u00e0 di educazione finanziaria \u2013 <em>abbiamo trasformato l\u2019Italia in un grande laboratorio, pieno di eventi creativi e innovativi. Insieme &#8211; <\/em>continua<em> &#8211; abbiamo raggiunto ogni angolo del Paese con tantissimi eventi, soprattutto per i giovani. Ora dobbiamo fare tesoro del lavoro fatto, delle esperienze sui territori, dei bisogni dei cittadini\u201d.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La seconda edizione del \u201cMese dell\u2019Educazione Finanziaria\u201d, organizzato dall\u20191 al 31 Ottobre dal Comitato per la programmazione e il coordinamento delle attivit\u00e0 di educazione finanziaria, si chiude con numeri da record: 602 appuntamenti all\u2019attivo e la partecipazione di tutte le Regioni d\u2019Italia. Un risultato notevole, che testimonia il crescente interesse sia da parte dei cittadini [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1982,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[162],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mese dell&#039;educazione finanziaria 2019, ecco i numeri -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/mese-delleducazione-finanziaria-2019-ecco-i-numeri\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mese dell&#039;educazione finanziaria 2019, ecco i numeri -\" \/>\n<meta property=\"og:description\" content=\"La seconda edizione del \u201cMese dell\u2019Educazione Finanziaria\u201d, organizzato dall\u20191 al 31 Ottobre dal Comitato per la programmazione e il coordinamento delle attivit\u00e0 di educazione finanziaria, si chiude con numeri da record: 602 appuntamenti all\u2019attivo e la partecipazione di tutte le Regioni d\u2019Italia. Un risultato notevole, che testimonia il crescente interesse sia da parte dei cittadini [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/mese-delleducazione-finanziaria-2019-ecco-i-numeri\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-03T15:33:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-11-03T15:39:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/salvadanaio-soldi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/mese-delleducazione-finanziaria-2019-ecco-i-numeri\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/mese-delleducazione-finanziaria-2019-ecco-i-numeri\/\",\"name\":\"Mese dell'educazione finanziaria 2019, ecco i numeri -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/mese-delleducazione-finanziaria-2019-ecco-i-numeri\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/mese-delleducazione-finanziaria-2019-ecco-i-numeri\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/salvadanaio-soldi.jpg\",\"datePublished\":\"2019-11-03T15:33:27+00:00\",\"dateModified\":\"2019-11-03T15:39:28+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/mese-delleducazione-finanziaria-2019-ecco-i-numeri\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/mese-delleducazione-finanziaria-2019-ecco-i-numeri\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/mese-delleducazione-finanziaria-2019-ecco-i-numeri\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/salvadanaio-soldi.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/salvadanaio-soldi.jpg\",\"width\":960,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/mese-delleducazione-finanziaria-2019-ecco-i-numeri\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mese dell&#8217;educazione finanziaria 2019, ecco i numeri\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mese dell'educazione finanziaria 2019, ecco i numeri -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/mese-delleducazione-finanziaria-2019-ecco-i-numeri\/","og_locale":"it_IT","og_type":"article","og_title":"Mese dell'educazione finanziaria 2019, ecco i numeri -","og_description":"La seconda edizione del \u201cMese dell\u2019Educazione Finanziaria\u201d, organizzato dall\u20191 al 31 Ottobre dal Comitato per la programmazione e il coordinamento delle attivit\u00e0 di educazione finanziaria, si chiude con numeri da record: 602 appuntamenti all\u2019attivo e la partecipazione di tutte le Regioni d\u2019Italia. Un risultato notevole, che testimonia il crescente interesse sia da parte dei cittadini [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/mese-delleducazione-finanziaria-2019-ecco-i-numeri\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2019-11-03T15:33:27+00:00","article_modified_time":"2019-11-03T15:39:28+00:00","og_image":[{"width":960,"height":640,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/salvadanaio-soldi.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/mese-delleducazione-finanziaria-2019-ecco-i-numeri\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/mese-delleducazione-finanziaria-2019-ecco-i-numeri\/","name":"Mese dell'educazione finanziaria 2019, ecco i numeri -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/mese-delleducazione-finanziaria-2019-ecco-i-numeri\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/mese-delleducazione-finanziaria-2019-ecco-i-numeri\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/salvadanaio-soldi.jpg","datePublished":"2019-11-03T15:33:27+00:00","dateModified":"2019-11-03T15:39:28+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/mese-delleducazione-finanziaria-2019-ecco-i-numeri\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/mese-delleducazione-finanziaria-2019-ecco-i-numeri\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/mese-delleducazione-finanziaria-2019-ecco-i-numeri\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/salvadanaio-soldi.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/salvadanaio-soldi.jpg","width":960,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/mese-delleducazione-finanziaria-2019-ecco-i-numeri\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Mese dell&#8217;educazione finanziaria 2019, ecco i numeri"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/1981"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=1981"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/1981\/revisions"}],"predecessor-version":[{"id":1983,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/1981\/revisions\/1983"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/1982"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=1981"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=1981"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=1981"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}