{"id":2003,"date":"2019-11-06T11:06:13","date_gmt":"2019-11-06T10:06:13","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=2003"},"modified":"2019-11-06T11:06:13","modified_gmt":"2019-11-06T10:06:13","slug":"svimez-dispersione-scolastica-nel-mezzogiorno-fenomeno-allarmante","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/svimez-dispersione-scolastica-nel-mezzogiorno-fenomeno-allarmante\/","title":{"rendered":"Svimez, dispersione scolastica nel Mezzogiorno fenomeno allarmante"},"content":{"rendered":"<div align=\"left\"><span style=\"color: #000000; font-family: Arial;\"><span class=\"dropcap dropcap3\">I<\/span> <em>dati diffusi ieri alla Camera dal rapporto<strong> Svimez<\/strong> sulla dispersione scolastica nelle regioni del Mezzogiorno confermano un fenomeno allarmante che purtroppo nessuno degli interventi adottati fino ad ora ha in alcun modo scalfito: il dato nazionale parla di una dispersione scolastica al 14,5% nel 2018 in crescita dello 0,5% sul 2017 con punte del 18,8% nel Mezzogiorno anche in questo caso in preoccupante crescita. <\/em><\/span><\/div>\n<div align=\"left\"><\/div>\n<div align=\"left\"><span style=\"color: #000000; font-family: Arial;\"><em>Se le percentuali non scendono vuol dire che dobbiamo tutti interrogarci, le istituzioni per prime ma anche le parti sociali, su quali siano gli interventi urgenti da mettere in atto per invertire la tendenza.<\/em> <\/span><\/div>\n<div align=\"left\"><\/div>\n<div align=\"left\"><span style=\"color: #000000; font-family: Arial;\">Lo dichiara il Segretario confederale della <strong>Cisl,<\/strong> <strong>Angelo Colombini.<\/strong> &#8220;I ragazzi che abbandonano il sistema di istruzione e formazione andranno a rinforzare le fila dei NEET, cio\u00e8 i ragazzi che non studiano, non lavorano e non sono impegnati in corsi di formazione con una spreco inaccettabile di risorse preziose per la crescita e lo sviluppo del nostro paese. <\/span><\/div>\n<div align=\"left\"><\/div>\n<div align=\"left\"><span style=\"color: #000000; font-family: Arial;\">E\u2019 necessario intervenire urgentemente per prima cosa stanziando risorse aggiuntive nella legge di bilancio per il 2020 per investire nel sistema nazionale di istruzione e formazione dallo 0-6 fino al livello terziario, a partire dalla valorizzazione dei lavoratori del comparto, per rafforzare il raccordo tra scuola e lavoro potenziando l\u2019alternanza scuola lavoro e l\u2019apprendistato di primo e terzo livello, sostenere gli ITS ed attuare un sistema nazionale di apprendimento permanente che aiuti giovani ed adulti a valorizzare, elevare e perfezionare le proprie competenze lungo tutto il corso della loro vita. <\/span><\/div>\n<div align=\"left\"><\/div>\n<div align=\"left\"><span style=\"color: #000000; font-family: Arial;\">E\u2019 necessario che i finanziamenti nazionali, regionali e quelli dei fondi strutturali siano orientati tutti verso obiettivi condivisi e partecipati dalle istituzioni a tutti i livelli e dalle parti sociali per fare finalmente massa critica con interventi che possano impattare concretamente sulla vita dei cittadini. <\/span><\/div>\n<div align=\"left\"><\/div>\n<div align=\"left\"><span style=\"color: #000000; font-family: Arial;\">Anche i sindacati devono fare la loro parte ed infatti stiamo lavorando con <strong>Confindustria<\/strong> per dare attuazione alla parte dell\u2019accordo \u00a0interconfederale del 9 marzo 2018 su educazione e formazione dettagliando cosa le parti sociali possono fare per impedire la dispersione di competenze, abilit\u00e0, professionalit\u00e0 preziose per la crescita civile, sociale, economica ed occupazionale del nostro paese&#8221;.<\/span><\/div>\n","protected":false},"excerpt":{"rendered":"<p>I dati diffusi ieri alla Camera dal rapporto Svimez sulla dispersione scolastica nelle regioni del Mezzogiorno confermano un fenomeno allarmante che purtroppo nessuno degli interventi adottati fino ad ora ha in alcun modo scalfito: il dato nazionale parla di una dispersione scolastica al 14,5% nel 2018 in crescita dello 0,5% sul 2017 con punte del [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":703,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Svimez, dispersione scolastica nel Mezzogiorno fenomeno allarmante -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.italiaeconomiaonline.it\/web\/svimez-dispersione-scolastica-nel-mezzogiorno-fenomeno-allarmante\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Svimez, dispersione scolastica nel Mezzogiorno fenomeno allarmante -\" \/>\n<meta property=\"og:description\" content=\"I dati diffusi ieri alla Camera dal rapporto Svimez sulla dispersione scolastica nelle regioni del Mezzogiorno confermano un fenomeno allarmante che purtroppo nessuno degli interventi adottati fino ad ora ha in alcun modo scalfito: il dato nazionale parla di una dispersione scolastica al 14,5% nel 2018 in crescita dello 0,5% sul 2017 con punte del [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.italiaeconomiaonline.it\/web\/svimez-dispersione-scolastica-nel-mezzogiorno-fenomeno-allarmante\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-06T10:06:13+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/05\/lavoro.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"606\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.italiaeconomiaonline.it\/web\/svimez-dispersione-scolastica-nel-mezzogiorno-fenomeno-allarmante\/\",\"url\":\"http:\/\/www.italiaeconomiaonline.it\/web\/svimez-dispersione-scolastica-nel-mezzogiorno-fenomeno-allarmante\/\",\"name\":\"Svimez, dispersione scolastica nel Mezzogiorno fenomeno allarmante -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/www.italiaeconomiaonline.it\/web\/svimez-dispersione-scolastica-nel-mezzogiorno-fenomeno-allarmante\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/www.italiaeconomiaonline.it\/web\/svimez-dispersione-scolastica-nel-mezzogiorno-fenomeno-allarmante\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/05\/lavoro.jpg\",\"datePublished\":\"2019-11-06T10:06:13+00:00\",\"dateModified\":\"2019-11-06T10:06:13+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"http:\/\/www.italiaeconomiaonline.it\/web\/svimez-dispersione-scolastica-nel-mezzogiorno-fenomeno-allarmante\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.italiaeconomiaonline.it\/web\/svimez-dispersione-scolastica-nel-mezzogiorno-fenomeno-allarmante\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\/\/www.italiaeconomiaonline.it\/web\/svimez-dispersione-scolastica-nel-mezzogiorno-fenomeno-allarmante\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/05\/lavoro.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/05\/lavoro.jpg\",\"width\":960,\"height\":606},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/www.italiaeconomiaonline.it\/web\/svimez-dispersione-scolastica-nel-mezzogiorno-fenomeno-allarmante\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Svimez, dispersione scolastica nel Mezzogiorno fenomeno allarmante\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Svimez, dispersione scolastica nel Mezzogiorno fenomeno allarmante -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.italiaeconomiaonline.it\/web\/svimez-dispersione-scolastica-nel-mezzogiorno-fenomeno-allarmante\/","og_locale":"it_IT","og_type":"article","og_title":"Svimez, dispersione scolastica nel Mezzogiorno fenomeno allarmante -","og_description":"I dati diffusi ieri alla Camera dal rapporto Svimez sulla dispersione scolastica nelle regioni del Mezzogiorno confermano un fenomeno allarmante che purtroppo nessuno degli interventi adottati fino ad ora ha in alcun modo scalfito: il dato nazionale parla di una dispersione scolastica al 14,5% nel 2018 in crescita dello 0,5% sul 2017 con punte del [&hellip;]","og_url":"http:\/\/www.italiaeconomiaonline.it\/web\/svimez-dispersione-scolastica-nel-mezzogiorno-fenomeno-allarmante\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2019-11-06T10:06:13+00:00","og_image":[{"width":960,"height":606,"url":"http:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/05\/lavoro.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/www.italiaeconomiaonline.it\/web\/svimez-dispersione-scolastica-nel-mezzogiorno-fenomeno-allarmante\/","url":"http:\/\/www.italiaeconomiaonline.it\/web\/svimez-dispersione-scolastica-nel-mezzogiorno-fenomeno-allarmante\/","name":"Svimez, dispersione scolastica nel Mezzogiorno fenomeno allarmante -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.italiaeconomiaonline.it\/web\/svimez-dispersione-scolastica-nel-mezzogiorno-fenomeno-allarmante\/#primaryimage"},"image":{"@id":"http:\/\/www.italiaeconomiaonline.it\/web\/svimez-dispersione-scolastica-nel-mezzogiorno-fenomeno-allarmante\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/05\/lavoro.jpg","datePublished":"2019-11-06T10:06:13+00:00","dateModified":"2019-11-06T10:06:13+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"http:\/\/www.italiaeconomiaonline.it\/web\/svimez-dispersione-scolastica-nel-mezzogiorno-fenomeno-allarmante\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.italiaeconomiaonline.it\/web\/svimez-dispersione-scolastica-nel-mezzogiorno-fenomeno-allarmante\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/www.italiaeconomiaonline.it\/web\/svimez-dispersione-scolastica-nel-mezzogiorno-fenomeno-allarmante\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/05\/lavoro.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/05\/lavoro.jpg","width":960,"height":606},{"@type":"BreadcrumbList","@id":"http:\/\/www.italiaeconomiaonline.it\/web\/svimez-dispersione-scolastica-nel-mezzogiorno-fenomeno-allarmante\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Svimez, dispersione scolastica nel Mezzogiorno fenomeno allarmante"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/2003"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=2003"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/2003\/revisions"}],"predecessor-version":[{"id":2004,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/2003\/revisions\/2004"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/703"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=2003"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=2003"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=2003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}