{"id":2013,"date":"2019-11-06T11:47:49","date_gmt":"2019-11-06T10:47:49","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=2013"},"modified":"2019-11-06T11:47:49","modified_gmt":"2019-11-06T10:47:49","slug":"reddito-e-pensione-di-cittadinanza-superata-la-soglia-di-un-milione-di-domande-accolte","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/reddito-e-pensione-di-cittadinanza-superata-la-soglia-di-un-milione-di-domande-accolte\/","title":{"rendered":"Reddito e Pensione di cittadinanza: superata la soglia di un milione di domande accolte"},"content":{"rendered":"<div class=\"page\" title=\"Page 1\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Al 31 ottobre 2019 sono state accolte 900.283 domande di Reddito di cittadinanza e 120.327 domande di Pensione di cittadinanza, per un totale di 1.020.610 nuclei familiari.<\/p>\n<p>Sono invece 1.555.588 le domande presentate.<\/p>\n<p><a href=\"http:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/Schermata-2019-11-06-alle-11.39.13.png\"><img decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-2014 aligncenter\" src=\"http:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/Schermata-2019-11-06-alle-11.39.13.png\" alt=\"\" width=\"654\" height=\"492\" srcset=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/Schermata-2019-11-06-alle-11.39.13.png 654w, https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/Schermata-2019-11-06-alle-11.39.13-300x226.png 300w, https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/Schermata-2019-11-06-alle-11.39.13-80x60.png 80w, https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/Schermata-2019-11-06-alle-11.39.13-265x198.png 265w, https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/Schermata-2019-11-06-alle-11.39.13-558x420.png 558w\" sizes=\"(max-width: 654px) 100vw, 654px\" \/><\/a> <a href=\"http:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/Schermata-2019-11-06-alle-11.39.28.png\"><img decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-2015 aligncenter\" src=\"http:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/Schermata-2019-11-06-alle-11.39.28.png\" alt=\"\" width=\"656\" height=\"256\" srcset=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/Schermata-2019-11-06-alle-11.39.28.png 656w, https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/Schermata-2019-11-06-alle-11.39.28-300x117.png 300w\" sizes=\"(max-width: 656px) 100vw, 656px\" \/><\/a><\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Al 31 ottobre 2019 sono state accolte 900.283 domande di Reddito di cittadinanza e 120.327 domande di Pensione di cittadinanza, per un totale di 1.020.610 nuclei familiari. Sono invece 1.555.588 le domande presentate.<\/p>\n","protected":false},"author":1,"featured_media":2016,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[162],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Reddito e Pensione di cittadinanza: superata la soglia di un milione di domande accolte -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/reddito-e-pensione-di-cittadinanza-superata-la-soglia-di-un-milione-di-domande-accolte\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reddito e Pensione di cittadinanza: superata la soglia di un milione di domande accolte -\" \/>\n<meta property=\"og:description\" content=\"Al 31 ottobre 2019 sono state accolte 900.283 domande di Reddito di cittadinanza e 120.327 domande di Pensione di cittadinanza, per un totale di 1.020.610 nuclei familiari. Sono invece 1.555.588 le domande presentate.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/reddito-e-pensione-di-cittadinanza-superata-la-soglia-di-un-milione-di-domande-accolte\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-06T10:47:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/soldi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/reddito-e-pensione-di-cittadinanza-superata-la-soglia-di-un-milione-di-domande-accolte\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/reddito-e-pensione-di-cittadinanza-superata-la-soglia-di-un-milione-di-domande-accolte\/\",\"name\":\"Reddito e Pensione di cittadinanza: superata la soglia di un milione di domande accolte -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/reddito-e-pensione-di-cittadinanza-superata-la-soglia-di-un-milione-di-domande-accolte\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/reddito-e-pensione-di-cittadinanza-superata-la-soglia-di-un-milione-di-domande-accolte\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/soldi.jpg\",\"datePublished\":\"2019-11-06T10:47:49+00:00\",\"dateModified\":\"2019-11-06T10:47:49+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/reddito-e-pensione-di-cittadinanza-superata-la-soglia-di-un-milione-di-domande-accolte\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/reddito-e-pensione-di-cittadinanza-superata-la-soglia-di-un-milione-di-domande-accolte\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/reddito-e-pensione-di-cittadinanza-superata-la-soglia-di-un-milione-di-domande-accolte\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/soldi.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/soldi.jpg\",\"width\":960,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/reddito-e-pensione-di-cittadinanza-superata-la-soglia-di-un-milione-di-domande-accolte\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reddito e Pensione di cittadinanza: superata la soglia di un milione di domande accolte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reddito e Pensione di cittadinanza: superata la soglia di un milione di domande accolte -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/reddito-e-pensione-di-cittadinanza-superata-la-soglia-di-un-milione-di-domande-accolte\/","og_locale":"it_IT","og_type":"article","og_title":"Reddito e Pensione di cittadinanza: superata la soglia di un milione di domande accolte -","og_description":"Al 31 ottobre 2019 sono state accolte 900.283 domande di Reddito di cittadinanza e 120.327 domande di Pensione di cittadinanza, per un totale di 1.020.610 nuclei familiari. Sono invece 1.555.588 le domande presentate.","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/reddito-e-pensione-di-cittadinanza-superata-la-soglia-di-un-milione-di-domande-accolte\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2019-11-06T10:47:49+00:00","og_image":[{"width":960,"height":640,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/soldi.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/reddito-e-pensione-di-cittadinanza-superata-la-soglia-di-un-milione-di-domande-accolte\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/reddito-e-pensione-di-cittadinanza-superata-la-soglia-di-un-milione-di-domande-accolte\/","name":"Reddito e Pensione di cittadinanza: superata la soglia di un milione di domande accolte -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/reddito-e-pensione-di-cittadinanza-superata-la-soglia-di-un-milione-di-domande-accolte\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/reddito-e-pensione-di-cittadinanza-superata-la-soglia-di-un-milione-di-domande-accolte\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/soldi.jpg","datePublished":"2019-11-06T10:47:49+00:00","dateModified":"2019-11-06T10:47:49+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/reddito-e-pensione-di-cittadinanza-superata-la-soglia-di-un-milione-di-domande-accolte\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/reddito-e-pensione-di-cittadinanza-superata-la-soglia-di-un-milione-di-domande-accolte\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/reddito-e-pensione-di-cittadinanza-superata-la-soglia-di-un-milione-di-domande-accolte\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/soldi.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/soldi.jpg","width":960,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/reddito-e-pensione-di-cittadinanza-superata-la-soglia-di-un-milione-di-domande-accolte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Reddito e Pensione di cittadinanza: superata la soglia di un milione di domande accolte"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/2013"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=2013"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/2013\/revisions"}],"predecessor-version":[{"id":2017,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/2013\/revisions\/2017"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/2016"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=2013"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=2013"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=2013"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}