{"id":2151,"date":"2019-12-05T16:45:17","date_gmt":"2019-12-05T15:45:17","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=2151"},"modified":"2019-12-05T16:45:17","modified_gmt":"2019-12-05T15:45:17","slug":"rapporto-ocsel-2017-2018-il-55-degli-accordi-nel-nord-solo-il-2-al-sud","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/rapporto-ocsel-2017-2018-il-55-degli-accordi-nel-nord-solo-il-2-al-sud\/","title":{"rendered":"Rapporto OCSEL 2017-2018: \u00a0Il 55% degli accordi nel Nord, solo il 2% al Sud"},"content":{"rendered":"<div align=\"left\"><span style=\"color: #000000; font-family: Geneva;\"><span class=\"dropcap dropcap3\">I<\/span>l 5\u00b0 rapporto Ocsel (Osservatorio Contrattazione di Secondo Livello) curato e presentato <a class=\"matchTooltip\">oggi<\/a> dalla Cisl raccoglie ed analizza 2.182 accordi aziendali negoziati negli anni 2017 e 2018 (di cui 1.236 per il primo anno e 946 nel secondo) \u00a0in 1.363 aziende che occupano 928.260 lavoratori. <\/span><\/div>\n<div align=\"left\"><\/div>\n<div align=\"left\"><span style=\"color: #000000; font-family: Geneva;\">Si tratta non di un campione statistico, ma in ogni caso del rapporto sulla contrattazione aziendale con la pi\u00f9 grande raccolta di accordi esistente nel nostro paese. Ocsel \u00e8 una banca dati della Cisl che ad <a class=\"matchTooltip\">oggi<\/a> registra in totale 12.160 accordi siglati negli ultimi 10 anni. Ecco i contenuti principali emersi dal rapporto:<\/span><\/div>\n<p>&nbsp;<\/p>\n<div align=\"left\"><span style=\"color: #000000; font-family: Geneva;\">Nel panorama delle relazioni sindacali \u00e8 tornata a svolgersi una contrattazione pi\u00f9 strutturata e meno episodica rispetto agli anni della crisi; il 54% degli accordi sono rinnovi di contratti precedenti, il 19% sono accordi integrativi degli stessi; <\/span><\/div>\n<div align=\"left\"><\/div>\n<div align=\"left\"><span style=\"color: #000000; font-family: Geneva;\">La contrattazione di secondo livello si estende e sviluppa ad altri settori oltre al Metalmeccanico con il 31% \u00a0al \u00a0commercio 10%, Servizi (13%)Trasporti (11%);<\/span><\/div>\n<div align=\"left\"><\/div>\n<div align=\"left\"><span style=\"color: #000000; font-family: Geneva;\">Resta un deciso squilibrio territoriale che vede la contrattazione aziendale diffusa nel nord (55% del totale) e nel centro (20%), mentre scarsa \u00e8 la diffusione nel sud del paese (2%)<\/span><\/div>\n<div align=\"left\"><span style=\"color: #000000; font-family: Geneva;\">Diffusa la contrattazione nelle piccole (fra 20 e 49 addetti) e micro imprese sotto i 19 dipendenti. La partecipazione delle piccole aziende alla crescita della contrattazione aziendale \u00e8 un dato significativo perch\u00e9 smentisce la convinzione diffusa che la contrattazione sia uno strumento applicabile solo alle aziende medio grandi.<\/span><\/div>\n<div align=\"left\"><\/div>\n<div align=\"left\"><span style=\"color: #000000; font-family: Geneva;\">Il salario costituisce l\u2019argomento maggiormente trattato nella contrattazione, presente nel 51% degli accordi analizzati con un avanzo di 7 punti percentuali rispetto alla contrattazione del biennio precedente. E\u2019 questo certamente il principale indicatore della ripresa. \u00a0<\/span><\/div>\n<div align=\"left\"><\/div>\n<div align=\"left\"><span style=\"color: #000000; font-family: Geneva;\">Salario e welfare sono i temi pi\u00f9 vivaci e in crescita, segno di una ripresa di buon andamento delle imprese in generale, mentre calano fortemente gli accordi legati a situazioni di crisi<\/span><\/div>\n<div align=\"left\"><span style=\"color: #000000; font-family: Geneva;\">Il valore del premio per lavoratore supera mediamente una mensilit\u00e0 (1534,38 euro pro capite). I dati sul valore medio dei premi di risultato rilevati dalla nostra ricerca sono in linea con quanto rilevato da altre ricerche e hanno trovato conferma dai dati elaborati dal Ministero delle finanze sulle denunce dei redditi per gli anni 2016 e 2017. \u00a0<\/span><\/div>\n<div align=\"left\"><\/div>\n<div align=\"left\"><span style=\"color: #000000; font-family: Geneva;\">La recensione degli accordi che definiscono un premio variabile segnala come il 13% degli accordi preveda premi che possono arrivare a 500 euro, il 26% da 501 a 1000 euro, il 19% da 1001 a 1500 euro e il 20% premi che vanno da 1501 a 2000 euro. Significativo e quantitativamente rilevante il fatto che ben il 23% degli accordi preveda premi superiori ai 2000 euro. <\/span><\/div>\n<div align=\"left\"><\/div>\n<div align=\"left\"><span style=\"color: #000000; font-family: Geneva;\">In tema di orari di lavoro il 22% degli accordi relativi si occupano della distribuzione degli stessi, tema centrale di fronte a mercati sempre pi\u00f9 difficilmente prevedibili, mentre spicca anche il fatto che in tema di flessibilit\u00e0, la stessa viene negoziata sia relativamente alle esigenze produttive ma sempre pi\u00f9 anche verso le flessibilit\u00e0 richieste dai lavoratori (in entrata e uscita nonch\u00e9 meccanismi di banca ore). <\/span><\/div>\n<div align=\"left\"><\/div>\n<div align=\"left\"><span style=\"color: #000000; font-family: Geneva;\">Gli accordi relativi alla organizzazione del lavoro vedono al centro a) la crescita degli accordi indirizzati a governare il cambiamento tecnologico (39%), \u00a0b) la diffusione nei settori del Terziario e dei Servizi (33%) di queste problematiche che precedentemente interessavano esclusivamente il settore manifatturiero; c) l\u2019emergere di nuove necessit\u00e0 e nuove opportunit\u00e0: numerosi accordi (54%) prevedono di utilizzare lo Smart-Working; riconoscono la necessit\u00e0 di modalit\u00e0 per classificare le professionalit\u00e0 e le competenze (20%) e di adeguare anche qualitativamente gli organici aziendali (21% accordi); e) ed il coinvolgimento del sindacato nel processo del cambiamento (26% degli accordi).<\/span><\/div>\n<div align=\"left\"><\/div>\n<div align=\"left\"><span style=\"color: #000000; font-family: Geneva;\">Anche in tema di professionalit\u00e0 la contrattazione aziendale sta molto innovandosi: si superano i terreni tradizionali dei passaggi di categoria e ci si concentra nella regolazione di nuovi profili professionali (46%) e nella valutazione e riconoscimento delle nuove professionalit\u00e0 (20%)<\/span><\/div>\n<div align=\"left\"><\/div>\n<div align=\"left\"><span style=\"color: #000000; font-family: Geneva;\">Anche il welfare sembra svilupparsi ulteriormente. Gli accordi censiti da OCSEL mostrano una crescita impressionante della contrattazione sul welfare. Infatti se nel 2015-16 il 23% degli accordi prevedeva interventi sul welfare nel 2018 tale percentuale \u00e8 salita al 38%. E\u2019 indubbio, come molte volte indicato negli stessi accordi, che tale crescita sia stata favorita dai vantaggi fiscali e contributivi. <\/span><\/div>\n<div align=\"left\"><\/div>\n<div align=\"left\"><span style=\"color: #000000; font-family: Geneva;\">Nella maggioranza degli accordi si sono privilegiate le soluzioni a livello aziendale tramite l\u2019erogazione di sevizi o la stipula di convenzioni (67%), o attraverso l\u2019estensione e il miglioramento dei Fondi Integrativi (40%) e infine attraverso il miglioramento delle disposizioni normative e legislative (32%). <\/span><\/div>\n<div align=\"left\"><\/div>\n<div align=\"left\"><span style=\"color: #000000; font-family: Geneva;\">Fra le pratiche di welfare in crescita la tematica dell\u2019assistenza familiare (materia in crescita dall1% al 7% nel raffronto fra i due bienni), di prevedere servizi a supporto del dipendente (2% degli accordi), il sostegno del potere di acquisto (dal 5% al 15%), la formazione e l\u2019istruzione (dal 2 al 9%), i servizi ricreativi (dall\u20191 al 9%).<\/span><\/div>\n<div align=\"left\"><\/div>\n<div align=\"left\"><span style=\"color: #000000; font-family: Geneva;\">Anche in tema di formazione, mercato del lavoro, partecipazione, ambiente e sicurezza la contrattazione aziendale non cerca di replicare semplici adempimenti di legge ma di caratterizzarsi verso misure nuove che aumentano il grado di coinvolgimento e responsabilit\u00e0 delle RSU e del sindacato in azienda. Comincia ad esserci attenzione per la formazione orientata a facilitare l\u2019introduzione di nuove tecnologie (20%) come anche quella relativa alla riqualificazione per nuova organizzazione del lavoro (11%). <\/span><\/div>\n<div align=\"left\"><\/div>\n<div align=\"left\"><span style=\"color: #000000; font-family: Geneva;\">\u00a0\u201cI dati del nostro osservatorio restituiscono alla Cisl ed a tutte le parti sociali una contrattazione aziendale evolutiva nella forma e nei contenuti, dinamica, costruttiva di soluzioni e tutele sempre pi\u00f9 ricche. \u00a0Ma la contrattazione aziendale per sviluppare tutte le sue potenzialit\u00e0 ha bisogno di sostegno, sia di natura fiscale che di normativa di legge non invasiva, valore erga omnes dei contratti , sostegno alla conclusione della misurazione della rappresentanza, sostegno alla partecipazione\u201d. <\/span><\/div>\n<div align=\"left\"><\/div>\n<div align=\"left\"><span style=\"color: #000000; font-family: Geneva;\">La fotografia del nostro Osservatorio evidenzia l\u2019importanza di una contrattazione aziendale sempre pi\u00f9 plurale e innovativa, un motore di crescita sostenuta, ben distribuita, partecipata, capace di elevare il benessere della persona, di rafforzare la qualit\u00e0 del lavoro e di incrementare performance e competitivit\u00e0 d\u2019impresa. Un patrimonio insostituibile di relazioni industriali reattive, flessibili, in presa diretta con i bisogni reali di ogni azienda e di ogni territorio\u201d.~<\/span><\/div>\n<div align=\"left\"><\/div>\n<div align=\"left\"><span style=\"color: #000000; font-family: Geneva;\">Questo sistema offre gi\u00e0 tanto allo sviluppo e alla coesione, ma va ulteriormente sostenuto e promosso con maggiori affidamenti e responsabilit\u00e0 tra le parti sociali e adeguate politiche fiscali che ne stimolino diffusione e crescita, specialmente nelle aree dove il tessuto produttivo \u00e8 pi\u00f9 debole e disgregato e le aziende sono pi\u00f9 piccole e isolate, come nel Mezzogiorno. Per questo crediamo che i frutti degli accordi di secondo livello, sia economici che di welfare, vadano del tutto detassati, insieme anche agli aumenti dei prossimi rinnovi contrattuali di primo livello&#8221;, sottolinea.<\/span><\/div>\n<div align=\"left\"><\/div>\n<div align=\"left\"><span style=\"color: #000000; font-family: Geneva;\">\u201cL\u2019adattivit\u00e0 e la dinamicit\u00e0 dell\u2019incontro~contrattuale &#8211; evidenzia ancora il sindacalista &#8211; mal si conciliano con leggi-precetto che entrano in materie tipicamente negoziali come il Decreto Dignit\u00e0, di cui esigiamo la modifica con un forte affidamento alla contrattazione aziendale sulle causali per i rinnovi dei rapporti a tempo determinato. Va poi scongiurata l\u2019adozione del salario minimo legale: per elevare salari, tutele e produttivit\u00e0 non serve una~ retribuzione oraria \u2018di Stato\u2019, ma l&#8217;estensione dei contratti leader in ogni comparto, con una lotta senza quartiere al dumping negoziale, alle rappresentanze di comodo e ai contratti pirata\u201d.<\/span><\/div>\n<div align=\"left\"><\/div>\n<div align=\"left\"><span style=\"color: #000000; font-family: Geneva;\">\u201cAl Governo chiediamo un impegno su questi fronti e, pi\u00f9 in generale, su un modello di sviluppo maggiormente partecipativo, che esalti l\u2019apporto sussidiario della contrattazione e valorizzi il ruolo delle rappresentanze sociali nel disegno delle strategie di crescita. Pensiamo che i tempi siano maturi anche per varare una legge quadro sulla partecipazione e sulla democrazia economica che sostenga il coinvolgimento dei lavoratori alla vita d\u2019impresa,~un provvedimento legislativo che deleghi alla contrattazione il compito di declinare in ogni realt\u00e0 le forme pi\u00f9 idonee di partecipazione\u201d, conclude Sbarra.<\/span><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Il 5\u00b0 rapporto Ocsel (Osservatorio Contrattazione di Secondo Livello) curato e presentato oggi dalla Cisl raccoglie ed analizza 2.182 accordi aziendali negoziati negli anni 2017 e 2018 (di cui 1.236 per il primo anno e 946 nel secondo) \u00a0in 1.363 aziende che occupano 928.260 lavoratori. Si tratta non di un campione statistico, ma in ogni [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1042,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Rapporto OCSEL 2017-2018: \u00a0Il 55% degli accordi nel Nord, solo il 2% al Sud -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/rapporto-ocsel-2017-2018-il-55-degli-accordi-nel-nord-solo-il-2-al-sud\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rapporto OCSEL 2017-2018: \u00a0Il 55% degli accordi nel Nord, solo il 2% al Sud -\" \/>\n<meta property=\"og:description\" content=\"Il 5\u00b0 rapporto Ocsel (Osservatorio Contrattazione di Secondo Livello) curato e presentato oggi dalla Cisl raccoglie ed analizza 2.182 accordi aziendali negoziati negli anni 2017 e 2018 (di cui 1.236 per il primo anno e 946 nel secondo) \u00a0in 1.363 aziende che occupano 928.260 lavoratori. Si tratta non di un campione statistico, ma in ogni [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/rapporto-ocsel-2017-2018-il-55-degli-accordi-nel-nord-solo-il-2-al-sud\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-05T15:45:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/laptop-3196481_960_720.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/rapporto-ocsel-2017-2018-il-55-degli-accordi-nel-nord-solo-il-2-al-sud\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/rapporto-ocsel-2017-2018-il-55-degli-accordi-nel-nord-solo-il-2-al-sud\/\",\"name\":\"Rapporto OCSEL 2017-2018: \u00a0Il 55% degli accordi nel Nord, solo il 2% al Sud -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/rapporto-ocsel-2017-2018-il-55-degli-accordi-nel-nord-solo-il-2-al-sud\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/rapporto-ocsel-2017-2018-il-55-degli-accordi-nel-nord-solo-il-2-al-sud\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/laptop-3196481_960_720.jpg\",\"datePublished\":\"2019-12-05T15:45:17+00:00\",\"dateModified\":\"2019-12-05T15:45:17+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/rapporto-ocsel-2017-2018-il-55-degli-accordi-nel-nord-solo-il-2-al-sud\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/rapporto-ocsel-2017-2018-il-55-degli-accordi-nel-nord-solo-il-2-al-sud\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/rapporto-ocsel-2017-2018-il-55-degli-accordi-nel-nord-solo-il-2-al-sud\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/laptop-3196481_960_720.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/laptop-3196481_960_720.jpg\",\"width\":960,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/rapporto-ocsel-2017-2018-il-55-degli-accordi-nel-nord-solo-il-2-al-sud\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rapporto OCSEL 2017-2018: \u00a0Il 55% degli accordi nel Nord, solo il 2% al Sud\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rapporto OCSEL 2017-2018: \u00a0Il 55% degli accordi nel Nord, solo il 2% al Sud -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/rapporto-ocsel-2017-2018-il-55-degli-accordi-nel-nord-solo-il-2-al-sud\/","og_locale":"it_IT","og_type":"article","og_title":"Rapporto OCSEL 2017-2018: \u00a0Il 55% degli accordi nel Nord, solo il 2% al Sud -","og_description":"Il 5\u00b0 rapporto Ocsel (Osservatorio Contrattazione di Secondo Livello) curato e presentato oggi dalla Cisl raccoglie ed analizza 2.182 accordi aziendali negoziati negli anni 2017 e 2018 (di cui 1.236 per il primo anno e 946 nel secondo) \u00a0in 1.363 aziende che occupano 928.260 lavoratori. Si tratta non di un campione statistico, ma in ogni [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/rapporto-ocsel-2017-2018-il-55-degli-accordi-nel-nord-solo-il-2-al-sud\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2019-12-05T15:45:17+00:00","og_image":[{"width":960,"height":640,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/laptop-3196481_960_720.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/rapporto-ocsel-2017-2018-il-55-degli-accordi-nel-nord-solo-il-2-al-sud\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/rapporto-ocsel-2017-2018-il-55-degli-accordi-nel-nord-solo-il-2-al-sud\/","name":"Rapporto OCSEL 2017-2018: \u00a0Il 55% degli accordi nel Nord, solo il 2% al Sud -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/rapporto-ocsel-2017-2018-il-55-degli-accordi-nel-nord-solo-il-2-al-sud\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/rapporto-ocsel-2017-2018-il-55-degli-accordi-nel-nord-solo-il-2-al-sud\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/laptop-3196481_960_720.jpg","datePublished":"2019-12-05T15:45:17+00:00","dateModified":"2019-12-05T15:45:17+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/rapporto-ocsel-2017-2018-il-55-degli-accordi-nel-nord-solo-il-2-al-sud\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/rapporto-ocsel-2017-2018-il-55-degli-accordi-nel-nord-solo-il-2-al-sud\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/rapporto-ocsel-2017-2018-il-55-degli-accordi-nel-nord-solo-il-2-al-sud\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/laptop-3196481_960_720.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/laptop-3196481_960_720.jpg","width":960,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/rapporto-ocsel-2017-2018-il-55-degli-accordi-nel-nord-solo-il-2-al-sud\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Rapporto OCSEL 2017-2018: \u00a0Il 55% degli accordi nel Nord, solo il 2% al Sud"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/2151"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=2151"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/2151\/revisions"}],"predecessor-version":[{"id":2152,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/2151\/revisions\/2152"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/1042"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=2151"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=2151"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=2151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}