{"id":2178,"date":"2019-12-11T16:06:35","date_gmt":"2019-12-11T15:06:35","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=2178"},"modified":"2019-12-11T16:06:35","modified_gmt":"2019-12-11T15:06:35","slug":"claudia-merlino-e-il-nuovo-direttore-generale-di-cia-agricoltori-italiani","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/claudia-merlino-e-il-nuovo-direttore-generale-di-cia-agricoltori-italiani\/","title":{"rendered":"Claudia Merlino \u00e8 il nuovo direttore generale di Cia-Agricoltori Italiani"},"content":{"rendered":"<p><strong><span class=\"dropcap dropcap3\">C<\/span>laudia Merlino \u00e8 il nuovo direttore generale di Cia-Agricoltori Italiani<\/strong>. <strong>Nominata dalla Giunta<\/strong>, <strong>riunita a Roma<\/strong>, arriva all\u2019incarico dopo aver ricoperto prima il ruolo di responsabile Lavoro e Relazioni sindacali e poi di capo del settore Organizzazione.<\/p>\n<p>Claudia Merlino <strong>subentra a Rossana Zambelli<\/strong>,<strong> in carica dal 2010<\/strong>, che lascia la guida amministrativa di Cia per la raggiunta maturit\u00e0 previdenziale.<\/p>\n<p>\u201c<strong>A nome di tutta la Cia, esprimiamo a Rossana Zambelli i pi\u00f9 vivi ringraziamenti per il lavoro e l\u2019impegno svolto per la nostra organizzazione<\/strong> e per l\u2019agricoltura del nostro Paese -ha dichiarato il presidente Cia, <strong>Dino Scanavino<\/strong>, in rappresentanza della Giunta nazionale-. Nei suoi tanti anni di attivit\u00e0, Zambelli <strong>ha contribuito in maniera fattiva alla crescita dell\u2019organizzazione dedicata alla tutela degli imprenditori agricoli<\/strong>\u201d. Allo stesso tempo, ha continuato Scanavino, \u201c<strong>facciamo i nostri migliori auguri a Claudia Merlino per questo nuovo importante incarico<\/strong>, sicuri che sapr\u00e0 garantire a Cia passione e professionalit\u00e0\u201d.<\/p>\n<p>Claudia Merlino \u00e8 la seconda donna a ricoprire il ruolo di direttore generale di Cia-Agricoltori Italiani.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Claudia Merlino \u00e8 il nuovo direttore generale di Cia-Agricoltori Italiani. Nominata dalla Giunta, riunita a Roma, arriva all\u2019incarico dopo aver ricoperto prima il ruolo di responsabile Lavoro e Relazioni sindacali e poi di capo del settore Organizzazione. Claudia Merlino subentra a Rossana Zambelli, in carica dal 2010, che lascia la guida amministrativa di Cia per [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2179,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[537],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Claudia Merlino \u00e8 il nuovo direttore generale di Cia-Agricoltori Italiani -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/claudia-merlino-e-il-nuovo-direttore-generale-di-cia-agricoltori-italiani\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Claudia Merlino \u00e8 il nuovo direttore generale di Cia-Agricoltori Italiani -\" \/>\n<meta property=\"og:description\" content=\"Claudia Merlino \u00e8 il nuovo direttore generale di Cia-Agricoltori Italiani. Nominata dalla Giunta, riunita a Roma, arriva all\u2019incarico dopo aver ricoperto prima il ruolo di responsabile Lavoro e Relazioni sindacali e poi di capo del settore Organizzazione. Claudia Merlino subentra a Rossana Zambelli, in carica dal 2010, che lascia la guida amministrativa di Cia per [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/claudia-merlino-e-il-nuovo-direttore-generale-di-cia-agricoltori-italiani\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-11T15:06:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/12\/Schermata-2019-12-11-alle-16.05.55.png\" \/>\n\t<meta property=\"og:image:width\" content=\"691\" \/>\n\t<meta property=\"og:image:height\" content=\"487\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/claudia-merlino-e-il-nuovo-direttore-generale-di-cia-agricoltori-italiani\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/claudia-merlino-e-il-nuovo-direttore-generale-di-cia-agricoltori-italiani\/\",\"name\":\"Claudia Merlino \u00e8 il nuovo direttore generale di Cia-Agricoltori Italiani -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/claudia-merlino-e-il-nuovo-direttore-generale-di-cia-agricoltori-italiani\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/claudia-merlino-e-il-nuovo-direttore-generale-di-cia-agricoltori-italiani\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/12\/Schermata-2019-12-11-alle-16.05.55.png\",\"datePublished\":\"2019-12-11T15:06:35+00:00\",\"dateModified\":\"2019-12-11T15:06:35+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/claudia-merlino-e-il-nuovo-direttore-generale-di-cia-agricoltori-italiani\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/claudia-merlino-e-il-nuovo-direttore-generale-di-cia-agricoltori-italiani\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/claudia-merlino-e-il-nuovo-direttore-generale-di-cia-agricoltori-italiani\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/12\/Schermata-2019-12-11-alle-16.05.55.png\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/12\/Schermata-2019-12-11-alle-16.05.55.png\",\"width\":691,\"height\":487},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/claudia-merlino-e-il-nuovo-direttore-generale-di-cia-agricoltori-italiani\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Claudia Merlino \u00e8 il nuovo direttore generale di Cia-Agricoltori Italiani\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Claudia Merlino \u00e8 il nuovo direttore generale di Cia-Agricoltori Italiani -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/claudia-merlino-e-il-nuovo-direttore-generale-di-cia-agricoltori-italiani\/","og_locale":"it_IT","og_type":"article","og_title":"Claudia Merlino \u00e8 il nuovo direttore generale di Cia-Agricoltori Italiani -","og_description":"Claudia Merlino \u00e8 il nuovo direttore generale di Cia-Agricoltori Italiani. Nominata dalla Giunta, riunita a Roma, arriva all\u2019incarico dopo aver ricoperto prima il ruolo di responsabile Lavoro e Relazioni sindacali e poi di capo del settore Organizzazione. Claudia Merlino subentra a Rossana Zambelli, in carica dal 2010, che lascia la guida amministrativa di Cia per [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/claudia-merlino-e-il-nuovo-direttore-generale-di-cia-agricoltori-italiani\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2019-12-11T15:06:35+00:00","og_image":[{"width":691,"height":487,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/12\/Schermata-2019-12-11-alle-16.05.55.png","type":"image\/png"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/claudia-merlino-e-il-nuovo-direttore-generale-di-cia-agricoltori-italiani\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/claudia-merlino-e-il-nuovo-direttore-generale-di-cia-agricoltori-italiani\/","name":"Claudia Merlino \u00e8 il nuovo direttore generale di Cia-Agricoltori Italiani -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/claudia-merlino-e-il-nuovo-direttore-generale-di-cia-agricoltori-italiani\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/claudia-merlino-e-il-nuovo-direttore-generale-di-cia-agricoltori-italiani\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/12\/Schermata-2019-12-11-alle-16.05.55.png","datePublished":"2019-12-11T15:06:35+00:00","dateModified":"2019-12-11T15:06:35+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/claudia-merlino-e-il-nuovo-direttore-generale-di-cia-agricoltori-italiani\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/claudia-merlino-e-il-nuovo-direttore-generale-di-cia-agricoltori-italiani\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/claudia-merlino-e-il-nuovo-direttore-generale-di-cia-agricoltori-italiani\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/12\/Schermata-2019-12-11-alle-16.05.55.png","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/12\/Schermata-2019-12-11-alle-16.05.55.png","width":691,"height":487},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/claudia-merlino-e-il-nuovo-direttore-generale-di-cia-agricoltori-italiani\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Claudia Merlino \u00e8 il nuovo direttore generale di Cia-Agricoltori Italiani"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/2178"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=2178"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/2178\/revisions"}],"predecessor-version":[{"id":2180,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/2178\/revisions\/2180"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/2179"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=2178"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=2178"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=2178"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}