{"id":234,"date":"2018-09-25T16:55:02","date_gmt":"2018-09-25T14:55:02","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=234"},"modified":"2018-09-26T10:29:02","modified_gmt":"2018-09-26T08:29:02","slug":"lindustria-conciaria-conferma-la-leadership-mondiale-domani-la-novantacinquesima-edizione-di-lineapelle","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/lindustria-conciaria-conferma-la-leadership-mondiale-domani-la-novantacinquesima-edizione-di-lineapelle\/","title":{"rendered":"L\u2019industria conciaria conferma la leadership mondiale"},"content":{"rendered":"<p><span style=\"font-family: garamond, serif; font-size: large;\"><span class=\"dropcap dropcap3\">C<\/span>ontinua a crescere la produzione conciaria italiana (+5% nel primo semestre 2018 rispetto al corrispondente 2017), trainando il comparto a livello europeo insieme a Francia, Spagna e Germania. La pelle italiana consolida il suo primato mondiale per qualit\u00e0 delle produzioni e fatturati. I suoi ricavi complessivi rappresentano il 65% del totale Ue e il 19% di quello mondiale.\u00a0<\/span><\/p>\n<div><span style=\"font-family: garamond, serif; font-size: large;\">Questi alcuni dei dati sul settore resi noti questa mattina a Milano a Piazza Affari nella sede di Borsa Italiana nel corso della conferenza stampa di presentazione della novantacinquesima edizione di <a href=\"http:\/\/r.media.theghostteam.com\/mk\/cl\/1MGnWe_0rJAo1e8NaWyhdkFVNzLCw-PjtvaGaQwCDFTK8MjpKFfZiBVC_vcpneILPVINNefw5u-tUB20-wysXrdVB1og7-ILs8_CgeHec1m9uuLJl34\" target=\"_blank\" rel=\"noopener\">Lineapelle<\/a>, il pi\u00f9 importante salone mondiale della pelle e di tutto il settore della fornitura di materiali, componenti e accessori, promosso da Unic in programma da <a class=\"matchTooltip\">domani<\/a>, marted\u00ec 25 a gioved\u00ec 27 settembre a Fiera Milano Rho.<\/span><\/div>\n<div><\/div>\n<blockquote class=\"td_quote_box td_box_left\">\n<div><span style=\"font-family: garamond, serif; font-size: large;\"><br \/>\nLa conferenza stampa \u00e8 stata l\u2019occasione per fare il punto su congiuntura e prospettive del comparto.\u00a0<\/span><\/div>\n<\/blockquote>\n<div>\n<p><span style=\"font-family: garamond, serif; font-size: large;\">\u201cInnovazione, qualit\u00e0 e sostenibilit\u00e0 sono i parametri con cui confermiamo la nostra leadership internazionale. Il nostro \u00e8 un settore che ha saputo anticipare le sfide dell&#8217;Industria 4.0 per essere sempre pi\u00f9 competitivo\u201d, ha dichiarato in occasione della conferenza di presentazione il Presidente di Unic e Lineapelle, Gianni Russo. \u201cPer cogliere l\u2019obiettivo lavoriamo ogni giorno per anticipare tempi e tendenze, contribuendo a costruire anche percorsi formativi adeguati all\u2019evoluzione tecnologica in atto, pur senza sradicarci dalla nostra grande, prestigiosa tradizione manifatturiera e artigianale\u201d.<\/span><\/p>\n<p>All\u2019incontro \u00e8 intervenuto in video il Presidente di Confindustria, <strong>Vincenzo Boccia<\/strong>, che ha sottolineato, fra l\u2019altro, la strategicit\u00e0 del settore. \u201c\u00c8 un momento importante per un settore &#8211; ha dichiarato Boccia &#8211; che \u00e8 una delle dimensioni dell\u2019eccellenza del Made in Italy. \u00a0Quando entrano in gioco bellezza ed equilibro, entra in gioco l\u2019Italia.<\/p>\n<\/div>\n<div><\/div>\n<div>\n<p><span style=\"font-family: garamond, serif; font-size: large;\">Lo abbiamo celebrato anche nell\u2019occasione di Milano XL con la suggestiva installazione alla Galleria di Arte Moderna di Via Palestro. Lineapelle rappresenta uno specchio dell\u2019eccellenza dell\u2019Italia nel mondo. Un mondo fatto di mercati globali, e i mercati globali sono mercati di nicchia e i mercati di nicchia sono mercati per noi italiani. Le aziende del vostro settore esportano oltre il 70% del loro fatturato. Un\u2019immagine dell\u2019Italia: un Paese che troppo spesso si appiattisce sul presente, si convince delle critiche e ha una percezione di s\u00e9 peggiore di quella che il mondo ha di noi stessi.<\/span><\/p>\n<p>Lineapelle- ha detto Boccia- mette in tutti noi una dimensione di ottimismo della volont\u00e0 e ci spiega perch\u00e9 siamo la seconda manifattura d\u2019Europa. Basta frequentare quella che sar\u00e0 Lineapelle per capire cos\u2019\u00e8 l\u2019Italia nel mondo. Noi siamo orgogliosi di rappresentare quest\u2019industria, il futuro dell\u2019Italia. Un\u2019Italia senza materie prime che deve all\u2019industria e all\u2019export gran parte della sua ricchezza. E faremo la nostra parte nelle nostre fabbriche, nei nostri settori ma anche con una capacit\u00e0 di proposte nell\u2019interesse del Paese perch\u00e9 abbiamo deciso di rappresentare interessi ed essere ponte tra gli interessi delle imprese e del Paese\u201d.<\/p>\n<p>Oltre ai Presidenti <strong>Russo e Boccia<\/strong>, alla conferenza di presentazione sono intervenuti il Direttore Generale di Lineapelle <strong>Fulvia Bacchi<\/strong> , il Responsabile Ufficio Economico Lineapelle <strong>Luca Boltri<\/strong>, il responsabile dell\u2019Innovation Square<strong> Federico Brugnoli<\/strong> e il Direttore Artistico Milano XL <strong>Luca Stoppini.<\/strong><\/p>\n<\/div>\n<div><span style=\"font-family: garamond, serif; font-size: large;\"><span style=\"font-family: garamond, serif; font-size: large;\"><br \/>\nLa conferenza stampa si \u00e8 conclusa con l\u2019intervento di Valentina Sidoti (Head of institutional Investors, Markets Analysis e Regulation presso Borsa Italiana &#8211; London Stock Exchange Group e Responsabile del Progetto Rivelazioni) che, insieme con il presidente di Unic e Lineapelle Gianni Russo, ha annunciato l\u2019adesione di Unic-Concerie Italiane al progetto Rivelazioni-Finance for Fine Arts, promosso da Borsa Italiana grazie alla quale \u00e8 stato restaurata l\u2019opera &#8220;Giuditta&#8221; di Nicolas R\u00e9gnier delle Gallerie dell\u2019Accademia di Venezia \u00a0che sar\u00e0 in mostra nei prossimi giorni nella BIG \u2013 Borsa Italiana Gallery, lo spazio espositivo all\u2019interno di Palazzo Mezzanotte.<\/span><\/span>&#8220;Rivelazioni \u2013 Finance for Fine Arts- ha commentato Valentina Sidoti- \u00a0\u00e8 un progetto rivolto alla valorizzazione del patrimonio artistico italiano attraverso il restauro di opere dei principali musei del Paese, un modo per sostenere il patrimonio di creativit\u00e0 e competenza alla base del successo del Made in Italy nel mondo. Consente di ottimizzare il meccanismo di raccolta fondi attraverso la proposta di pi\u00f9 opere con costi di restauro differenti, facilitando la relazione tra mecenate e museo e semplificando le modalit\u00e0 di donazione. Borsa Italiana, inoltre, promuove il progetto presso il proprio network nazionale e internazionale.<br \/>\nUNIC ha risposto con generosit\u00e0 al nostro invito a partecipare al progetto. Questa collaborazione \u00e8 un bellissimo esempio di affinit\u00e0 di intenti e di valori nel promuovere il Sistema Italia e che <a class=\"matchTooltip\">oggi<\/a> celebriamo qui in Borsa Italiana\u201d.<\/p>\n<p>&#8220;Lineapelle95- ha spiegato Russo nel suo intervento- inizier\u00e0 <a class=\"matchTooltip\">domani<\/a> ed ha gi\u00e0 segnato dei record. Dal numero degli espositori (1.306) alla dimensione dell\u2019allestimento (oltre 48.500 metri quadrati). Oltre 20 mila i visitatori attesi, provenienti da 110 Paesi. Su scala mondiale, il settore \u00e8 formato da circa 50 mila aziende, per pi\u00f9 di un milione di occupati e un giro d\u2019affari superiore a 150 miliardi di dollari.<br \/>\nNel corso della tre giorni saranno presentate le tendenze stilistiche autunno\/inverno 2019-2020, elaborate dal Comitato Moda di Lineapelle.<br \/>\nGrande novit\u00e0 di Lineapelle95 sar\u00e0 un focus permanente sull\u2019innovazione. Un hub all\u2019interno del quale 40 relatori di altissimo profilo provenienti da tutto il mondo, istituti di R&amp;S specializzati, aziende altamente innovative, presenteranno lavori, competenze, prodotti, dalla ricerca in laboratorio a soluzioni gi\u00e0 completamente industrializzate. Un\u2019opportunit\u00e0 straordinaria per approfondire temi di sempre pi\u00f9 stringente attualit\u00e0 come il rapporto tra moda e biotech, i materiali del futuro, l\u2019economia circolare, l\u2019industria 4.0, le capacit\u00e0 e le competenze necessarie per l\u2019impresa rivoluzionata dall\u2019integrazione digitale nei suoi processi, nei suoi prodotti, nei suoi assetti organizzativi.&#8221;<\/p>\n<p>Tra le novit\u00e0 di Lineapelle95, l\u2019incontro con la citt\u00e0 di Milano, attraverso due allestimenti aperti al pubblico. Presso la Villa Reale di Milano \u00e8 possibile visitare fino a venerd\u00ec 28 settembre il Cubo a specchio dedicato all\u2019eccellenza e alla sostenibilit\u00e0 della pelle italiana, promosso all\u2019interno della seconda edizione di Milano XL. Presso lo Spazio Lineapelle di Palazzo Gorani (alle spalle di Piazza Affari) \u00e8 invece aperta la mostra Leather in Everyday Life, che racconta il viscerale e quotidiano rapporto dell\u2019uomo con la pelle.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Continua a crescere la produzione conciaria italiana (+5% nel primo semestre 2018 rispetto al corrispondente 2017), trainando il comparto a livello europeo insieme a Francia, Spagna e Germania. La pelle italiana consolida il suo primato mondiale per qualit\u00e0 delle produzioni e fatturati. I suoi ricavi complessivi rappresentano il 65% del totale Ue e il 19% [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":235,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>L\u2019industria conciaria conferma la leadership mondiale -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/lindustria-conciaria-conferma-la-leadership-mondiale-domani-la-novantacinquesima-edizione-di-lineapelle\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019industria conciaria conferma la leadership mondiale -\" \/>\n<meta property=\"og:description\" content=\"Continua a crescere la produzione conciaria italiana (+5% nel primo semestre 2018 rispetto al corrispondente 2017), trainando il comparto a livello europeo insieme a Francia, Spagna e Germania. La pelle italiana consolida il suo primato mondiale per qualit\u00e0 delle produzioni e fatturati. I suoi ricavi complessivi rappresentano il 65% del totale Ue e il 19% [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/lindustria-conciaria-conferma-la-leadership-mondiale-domani-la-novantacinquesima-edizione-di-lineapelle\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-25T14:55:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-09-26T08:29:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/09\/Una-foto-della-conferenza-stampa-durante-lintervento-di-Vincenzo-Boccia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"4656\" \/>\n\t<meta property=\"og:image:height\" content=\"2620\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/lindustria-conciaria-conferma-la-leadership-mondiale-domani-la-novantacinquesima-edizione-di-lineapelle\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/lindustria-conciaria-conferma-la-leadership-mondiale-domani-la-novantacinquesima-edizione-di-lineapelle\/\",\"name\":\"L\u2019industria conciaria conferma la leadership mondiale -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/lindustria-conciaria-conferma-la-leadership-mondiale-domani-la-novantacinquesima-edizione-di-lineapelle\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/lindustria-conciaria-conferma-la-leadership-mondiale-domani-la-novantacinquesima-edizione-di-lineapelle\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/09\/Una-foto-della-conferenza-stampa-durante-lintervento-di-Vincenzo-Boccia.jpg\",\"datePublished\":\"2018-09-25T14:55:02+00:00\",\"dateModified\":\"2018-09-26T08:29:02+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/lindustria-conciaria-conferma-la-leadership-mondiale-domani-la-novantacinquesima-edizione-di-lineapelle\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/lindustria-conciaria-conferma-la-leadership-mondiale-domani-la-novantacinquesima-edizione-di-lineapelle\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/lindustria-conciaria-conferma-la-leadership-mondiale-domani-la-novantacinquesima-edizione-di-lineapelle\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/09\/Una-foto-della-conferenza-stampa-durante-lintervento-di-Vincenzo-Boccia.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/09\/Una-foto-della-conferenza-stampa-durante-lintervento-di-Vincenzo-Boccia.jpg\",\"width\":4656,\"height\":2620},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/lindustria-conciaria-conferma-la-leadership-mondiale-domani-la-novantacinquesima-edizione-di-lineapelle\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u2019industria conciaria conferma la leadership mondiale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u2019industria conciaria conferma la leadership mondiale -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/lindustria-conciaria-conferma-la-leadership-mondiale-domani-la-novantacinquesima-edizione-di-lineapelle\/","og_locale":"it_IT","og_type":"article","og_title":"L\u2019industria conciaria conferma la leadership mondiale -","og_description":"Continua a crescere la produzione conciaria italiana (+5% nel primo semestre 2018 rispetto al corrispondente 2017), trainando il comparto a livello europeo insieme a Francia, Spagna e Germania. La pelle italiana consolida il suo primato mondiale per qualit\u00e0 delle produzioni e fatturati. I suoi ricavi complessivi rappresentano il 65% del totale Ue e il 19% [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/lindustria-conciaria-conferma-la-leadership-mondiale-domani-la-novantacinquesima-edizione-di-lineapelle\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2018-09-25T14:55:02+00:00","article_modified_time":"2018-09-26T08:29:02+00:00","og_image":[{"width":4656,"height":2620,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/09\/Una-foto-della-conferenza-stampa-durante-lintervento-di-Vincenzo-Boccia.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/lindustria-conciaria-conferma-la-leadership-mondiale-domani-la-novantacinquesima-edizione-di-lineapelle\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/lindustria-conciaria-conferma-la-leadership-mondiale-domani-la-novantacinquesima-edizione-di-lineapelle\/","name":"L\u2019industria conciaria conferma la leadership mondiale -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/lindustria-conciaria-conferma-la-leadership-mondiale-domani-la-novantacinquesima-edizione-di-lineapelle\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/lindustria-conciaria-conferma-la-leadership-mondiale-domani-la-novantacinquesima-edizione-di-lineapelle\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/09\/Una-foto-della-conferenza-stampa-durante-lintervento-di-Vincenzo-Boccia.jpg","datePublished":"2018-09-25T14:55:02+00:00","dateModified":"2018-09-26T08:29:02+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/lindustria-conciaria-conferma-la-leadership-mondiale-domani-la-novantacinquesima-edizione-di-lineapelle\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/lindustria-conciaria-conferma-la-leadership-mondiale-domani-la-novantacinquesima-edizione-di-lineapelle\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/lindustria-conciaria-conferma-la-leadership-mondiale-domani-la-novantacinquesima-edizione-di-lineapelle\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/09\/Una-foto-della-conferenza-stampa-durante-lintervento-di-Vincenzo-Boccia.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/09\/Una-foto-della-conferenza-stampa-durante-lintervento-di-Vincenzo-Boccia.jpg","width":4656,"height":2620},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/lindustria-conciaria-conferma-la-leadership-mondiale-domani-la-novantacinquesima-edizione-di-lineapelle\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"L\u2019industria conciaria conferma la leadership mondiale"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/234"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=234"}],"version-history":[{"count":2,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/234\/revisions"}],"predecessor-version":[{"id":245,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/234\/revisions\/245"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/235"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=234"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=234"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}