{"id":2381,"date":"2020-01-27T22:43:19","date_gmt":"2020-01-27T21:43:19","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=2381"},"modified":"2020-01-27T22:44:47","modified_gmt":"2020-01-27T21:44:47","slug":"conti-correnti-online-aumentano-i-costi-ma-la-convenienza-rimane","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/conti-correnti-online-aumentano-i-costi-ma-la-convenienza-rimane\/","title":{"rendered":"Conti correnti online: aumentano i costi, ma la convenienza rimane"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">L<\/span>\u2019analisi di <b>SosTariffe<\/b>\u00a0ha preso in esame le condizioni dei <a href=\"https:\/\/www.sostariffe.it\/conto-corrente\/\">conti correnti <\/a>online e tradizionali in Italia, mettendo in evidenza un <b>palese aumento dei costi<\/b> per entrambi.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>I rincari maggiori hanno toccato le <b>banche online<\/b>, dove si registrano <b>aumenti medi del 29%,<\/b> ma la situazione delle banche tradizionali non differisce di molto, nella misura in cui il confronto tra il 2019 e il 2020 ha messo in luce un <b>aumento fino al 27%.<\/b> Nonostante ci\u00f2, l\u2019analisi delle varie voci che contribuiscono al costo totale dei conti correnti chiarisce che quelli online rappresentano ancora oggi lo <b>strumento pi\u00f9 economico<\/b> per depositare e gestire i propri risparmi.<\/p>\n<p>Lo studio comparativo di SosTariffe.it ha scandagliato ad uno ad uno tutti i costi di gestione che gravano sul titolare di un conto corrente.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p><b>Conti correnti telematici: le coppie colpite dai rincari maggiori<span class=\"Apple-converted-space\">\u00a0<\/span><\/b><\/p>\n<p>Lo studio \u00e8 partito dall\u2019analisi di <b>tre profili differenti di consumatori<\/b>, attraverso i quali \u00e8 stato possibile mettere in luce quali sono stati i cambiamenti pi\u00f9 significativi che hanno caratterizzato l\u2019ultimo anno a proposito dei <b>costi dei conti correnti online<\/b>: il single, la coppia e la famiglia. La base dell\u2019analisi \u00e8 stata invece costituita da <b>17 banche italiane<\/b> e da tutti i costi di gestione tipici di un conto corrente.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Il <b>costo di un conto corrente online<\/b> tra gennaio 2019 e gennaio 2020 \u00e8 passato da 45,26 euro a 58,58 euro, comportando cos\u00ec una <b>variazione nella spesa del 29,44%<\/b> nell\u2019arco di soli 12 mesi. Si tratta di una percentuale di non poco conto, considerato che le banche online si affidano spesso a istituti di credito con poche o nessuna filale fisica, quindi in grado di ammortizzare i costi tipici dei conti correnti tradizionali.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Scendendo maggiormente nel dettaglio, sono <b>le coppie a dover sostenere una spessa maggiore<\/b> con l\u2019inizio del nuovo anno: dal confronto con gennaio 2019 si nota infatti il passaggio dai 45,31 euro dello scorso gennaio ai 60,23 di quest\u2019anno, segnando cos\u00ec un <b>+32,92%. <\/b>Risulta leggermente meno colpito dal rincaro l\u2019esborso mensile spettante ai <b>single<\/b>, per i quali c\u2019\u00e8 stato un <b>aumento di una decina di euro<\/b>: si va infatti dai 35,03 euro di gennaio 2019 ai 45,14 euro di gennaio 2020 <b>(+28,85%).<\/b> I soggetti ai quali \u00e8 andata meglio, nonostante gli aumenti, sono invece le<b> famiglie<\/b>, per le quali si riscontra una <b>variazione del 26,96%<\/b>, con cifre in aumento da 55,44 euro a 70,38 euro.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p><b>Banche online: le operazioni pi\u00f9 costose riguardano i bonifici, i prelievi di contante allo sportello e il costo dell\u2019assegno singolo<\/b><\/p>\n<p>Quali sono i fattori che hanno avuto un peso maggiore nell\u2019aumento del costo totale dei conti correnti online? Tra le operazioni pi\u00f9 incisive si annoverano i <b>bonifici disposti allo sportello<\/b>, il cui prezzo \u00e8 passato dai 2,91 euro dello scorso anno ai 3,94 euro attuali, registrando un <b>rincaro pari al 29%.<\/b> Ma ci sono altre operazioni che hanno subito un aumento notevole nel corso degli ultimi 12 mesi.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Se i bonifici disposti allo sportello occupano il primo posto, al secondo troviamo il costo relativo al <b>prelievo di contante allo sportello<\/b>, con un <b>rialzo del 27%,<\/b> che da 2,31 euro \u00e8 passata a 2,93 euro, seguito da un\u2019altra voce di spesa, ovvero il <b>costo dell\u2019assegno singolo<\/b>, <b>cresciuto del 21%,<\/b> con cifre che in aumento da 0,16 euro a 0,19 euro<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Sono <b>aumentati del 10%<\/b> anche il <b>prelievo ATM presso un\u2019altra banca e il prelievo in uno dei Paesi dell\u2019Unione europea<\/b>, saliti entrambi da 1,02 euro a 1,12 euro. L\u2019unica voce per la quale \u00e8 stata individuata una riduzione rispetto allo stesso periodo del 2019 \u00e8 quella relativa al <b>canone annuo della carta di credito<\/b>: il risparmio ha visto un <b>calo dei costi pari al 5%,<\/b> con una relativa diminuzione da 22,77 euro a 21,66 euro.<\/p>\n<p><b>Banche tradizionali: le operazioni pi\u00f9 costose sono quelle allo sportello e in filiale<\/b><\/p>\n<p>SosTariffe.it ha indagato anche sulla seconda tipologia di conto corrente, ovvero quella tradizionale che si affida a istituti di credito dotati di diverse filiali fisiche distribuite sul territorio. I profili di utente presi in considerazione per l\u2019analisi sono tre, ovvero: il gestore di conto corrente tradizionale che <b>svolge operazioni soltanto allo sportello e in filiale, <\/b>l\u2019utente che fa <b>un uso misto del suo conto<\/b>, quindi effettua operazioni sia allo sportello sia online, e un utente che <b>fa un uso esclusivamente telematico del conto<\/b>, nonostante i suoi risparmi siano depositati in una banca tradizionale.<\/p>\n<p>I dati ricavati permettono di evidenziare un <b>rincaro maggiore per i clienti che si limitano ad effettuare esclusivamente operazioni allo sportello<\/b> e in filiale, pur potendo disporre dei servizi dell\u2019Internet banking.<b> <\/b>Si tratta di un trend in controtendenza rispetto all\u2019analisi comparativa effettuata tra il 2018 e il 2019, dalla quale era emerso proprio il risultato opposto.<\/p>\n<p>Ci\u00f2 permette quindi di confermare la <b>convenienza nell\u2019utilizzo dell\u2019Internet banking<\/b> anche per i possessori di un conto tradizionale, che ha subito in misura meno rilevante l\u2019aumento del costo: si \u00e8 infatti passati dai 100,68 euro del 2019 ai 123,46 euro del 2020, con un <b>aumento del 22,62%<\/b>. In questo caso specifico, sono state proprio le <b>coppie<\/b> a sentire meno il rialzo: da 126,28 euro dello scorso anno, oggi spendono 128,81 euro (<b>+22,14%<\/b>). Maggiore, anche se di poco, <b>l\u2019impatto sui single<\/b> <b>(+22,77%)<\/b> che passano da 73,62 euro a 90,39 euro, e <b>sulle famiglie<\/b> (<b>+22,96%<\/b>), per le quali la spesa \u00e8 aumentata di quasi 30 euro, passando da 122,14 euro a 150,17 euro.<\/p>\n<p>Per quanto riguarda l\u2019<b>utilizzo misto<\/b>, gli aumenti medi in un anno si sono attestati intorno al <b>22,68%<\/b>. I correntisti colpiti dal rincaro pi\u00f9 elevato in termini percentuali sono <b>stati i single<\/b>, che lo scorso anno pagavano 92,56 euro, mentre oggi devono sostenere una spesa di 117,70 euro (<b>+27,16%<\/b>)<b>.<\/b> Le <b>coppie <\/b>risentono di un <b>aumento del 23,78%<\/b>, passando da 128,37 euro a 158,89 euro, mentre la situazione migliore \u00e8 quella vissuta dalle famiglie che hanno subito un cambiamento al rialzo del <b>18,97%<\/b>, con una spesa che \u00e8 slittata da 149,45 euro a 177,80 euro.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Restano, dunque, i clienti che scelgono tuttora di effettuare ogni singola operazione allo sportello o in filiale quelli per i quali sono stati rilevati <b>i maggiori aumenti<\/b>, che sono stati in media <b>pari al 28,89%<\/b>, con una variazione che ha portato a dover spendere 194,47 euro rispetto ai 153,25 euro dell\u2019anno precedente. <b>I single sono i soggetti maggiormente colpiti dal rincaro<\/b>, con una spesa che a gennaio 2019 era pari a 126,76 euro, mentre oggi tocca i 174,59 euro (<b>+37,73%<\/b>). <b>Le coppie subiscono un aumento del 24,76%<\/b>: se lo scorso anno spendevano 149,57 euro, oggi pagano 186,59 euro. Infine, per le famiglie il costo del conto corrente tradizionale corrisponde a 222,21 euro, mentre a gennaio 2019 erano pari a 183,42 euro (<b>+21,15%<\/b>).<\/p>\n<p><b>Banche tradizionali: aumenta il canone annuo della carta di debito, ma scende il prelievo ATM presso la propria banca<\/b><\/p>\n<p>Ci sono alcune voci che sono cresciute particolarmente nel corso dell\u2019ultimo anno e che hanno avuto una certa incidenza per i possessori di un conto corrente tradizionale, ovvero il <b>canone annuo della carta di debito, che \u00e8 schizzato alle stelle con un aumento del 467%<\/b> <b>e il costo dell\u2019assegno singolo, con un rialzo del 25%.<span class=\"Apple-converted-space\">\u00a0<\/span><\/b><\/p>\n<p>Un altro servizio che nel 2020 ha un costo pi\u00f9 alto rispetto al 2019 \u00e8 quello dei <b>bonifici online, che ha subito un rialzo del 16%<\/b>. Aumentano del <b>2% anche il prelievo in un altro paese dell\u2019Unione europea<\/b> e quello presso l\u2019ATM di un\u2019altra banca.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Una buona notizia riguarda il <b>costo del prelievo presso l\u2019ATM della propria banca, che \u00e8 stato praticamente azzerato rispetto allo scorso anno<\/b>. Risparmi previsti anche su altre operazioni, ovvero i <b>movimenti allo sportello (-4%), il canone annuo della carta di credito (-1%) e i bonifici disposti allo sportello (-1%).<span class=\"Apple-converted-space\">\u00a0<\/span><\/b><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019analisi di SosTariffe\u00a0ha preso in esame le condizioni dei conti correnti online e tradizionali in Italia, mettendo in evidenza un palese aumento dei costi per entrambi.\u00a0 I rincari maggiori hanno toccato le banche online, dove si registrano aumenti medi del 29%, ma la situazione delle banche tradizionali non differisce di molto, nella misura in cui [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1733,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[162],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Conti correnti online: aumentano i costi, ma la convenienza rimane -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/conti-correnti-online-aumentano-i-costi-ma-la-convenienza-rimane\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conti correnti online: aumentano i costi, ma la convenienza rimane -\" \/>\n<meta property=\"og:description\" content=\"L\u2019analisi di SosTariffe\u00a0ha preso in esame le condizioni dei conti correnti online e tradizionali in Italia, mettendo in evidenza un palese aumento dei costi per entrambi.\u00a0 I rincari maggiori hanno toccato le banche online, dove si registrano aumenti medi del 29%, ma la situazione delle banche tradizionali non differisce di molto, nella misura in cui [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/conti-correnti-online-aumentano-i-costi-ma-la-convenienza-rimane\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-27T21:43:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-01-27T21:44:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/09\/SFONDO.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1254\" \/>\n\t<meta property=\"og:image:height\" content=\"836\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/conti-correnti-online-aumentano-i-costi-ma-la-convenienza-rimane\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/conti-correnti-online-aumentano-i-costi-ma-la-convenienza-rimane\/\",\"name\":\"Conti correnti online: aumentano i costi, ma la convenienza rimane -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/conti-correnti-online-aumentano-i-costi-ma-la-convenienza-rimane\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/conti-correnti-online-aumentano-i-costi-ma-la-convenienza-rimane\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/09\/SFONDO.jpg\",\"datePublished\":\"2020-01-27T21:43:19+00:00\",\"dateModified\":\"2020-01-27T21:44:47+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/conti-correnti-online-aumentano-i-costi-ma-la-convenienza-rimane\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/conti-correnti-online-aumentano-i-costi-ma-la-convenienza-rimane\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/conti-correnti-online-aumentano-i-costi-ma-la-convenienza-rimane\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/09\/SFONDO.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/09\/SFONDO.jpg\",\"width\":1254,\"height\":836},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/conti-correnti-online-aumentano-i-costi-ma-la-convenienza-rimane\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conti correnti online: aumentano i costi, ma la convenienza rimane\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conti correnti online: aumentano i costi, ma la convenienza rimane -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/conti-correnti-online-aumentano-i-costi-ma-la-convenienza-rimane\/","og_locale":"it_IT","og_type":"article","og_title":"Conti correnti online: aumentano i costi, ma la convenienza rimane -","og_description":"L\u2019analisi di SosTariffe\u00a0ha preso in esame le condizioni dei conti correnti online e tradizionali in Italia, mettendo in evidenza un palese aumento dei costi per entrambi.\u00a0 I rincari maggiori hanno toccato le banche online, dove si registrano aumenti medi del 29%, ma la situazione delle banche tradizionali non differisce di molto, nella misura in cui [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/conti-correnti-online-aumentano-i-costi-ma-la-convenienza-rimane\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2020-01-27T21:43:19+00:00","article_modified_time":"2020-01-27T21:44:47+00:00","og_image":[{"width":1254,"height":836,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/09\/SFONDO.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/conti-correnti-online-aumentano-i-costi-ma-la-convenienza-rimane\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/conti-correnti-online-aumentano-i-costi-ma-la-convenienza-rimane\/","name":"Conti correnti online: aumentano i costi, ma la convenienza rimane -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/conti-correnti-online-aumentano-i-costi-ma-la-convenienza-rimane\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/conti-correnti-online-aumentano-i-costi-ma-la-convenienza-rimane\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/09\/SFONDO.jpg","datePublished":"2020-01-27T21:43:19+00:00","dateModified":"2020-01-27T21:44:47+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/conti-correnti-online-aumentano-i-costi-ma-la-convenienza-rimane\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/conti-correnti-online-aumentano-i-costi-ma-la-convenienza-rimane\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/conti-correnti-online-aumentano-i-costi-ma-la-convenienza-rimane\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/09\/SFONDO.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/09\/SFONDO.jpg","width":1254,"height":836},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/conti-correnti-online-aumentano-i-costi-ma-la-convenienza-rimane\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Conti correnti online: aumentano i costi, ma la convenienza rimane"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/2381"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=2381"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/2381\/revisions"}],"predecessor-version":[{"id":2382,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/2381\/revisions\/2382"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/1733"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=2381"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=2381"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=2381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}