{"id":2470,"date":"2020-02-05T11:25:58","date_gmt":"2020-02-05T10:25:58","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=2470"},"modified":"2020-02-05T11:25:58","modified_gmt":"2020-02-05T10:25:58","slug":"cnr-e-grant-thornton-siglano-accordo-quadro-per-le-aziende-italiane","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/cnr-e-grant-thornton-siglano-accordo-quadro-per-le-aziende-italiane\/","title":{"rendered":"Cnr e Grant Thornton siglano accordo quadro per le aziende italiane"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">C<\/span>onsiglio nazionale delle ricerche (Cnr) e<b> <\/b>Bernoni Grant Thornton hanno recentemente siglato un accordo quadro a livello nazionale della durata di tre anni per favorire lo sviluppo delle piccole e medie imprese italiane.<\/p>\n<p>I due soggetti firmatari sono rispettivamente il maggior Ente pubblico di ricerca italiano, a vocazione spiccatamente multidisciplinare, e la member firm italiana di Grant Thornton International Ltd, uno dei principali network a livello mondiale che fornisce servizi di consulenza tributaria, societaria, advisory, IT e outsourcing.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>L\u2019accordo prevede che le parti, ognuna per i propri ambiti di competenza, collaborino per ideare e sviluppare iniziative, eventi e progetti di ricerca, formazione, innovazione tecnologica, presso start up e piccole e medie imprese (Pmi) innovative, istituti finanziari, societ\u00e0 di venture capital e business angel.<\/p>\n<p>La collaborazione, da definire a seconda dei diversi progetti e iniziative, \u00e8 orientata allo sviluppo delle start up e Pmi innovative su tutto il territorio nazionale e potr\u00e0 prevedere il coinvolgimento e il supporto di altri soggetti pubblici come Ministeri, Regioni ed altri enti interessati, e\/o privati. A titolo di esempio, potr\u00e0 riguardare le seguenti linee di attivit\u00e0:<\/p>\n<ul>\n<li>diffusione delle agevolazioni per attivit\u00e0 di ricerca e innovazione (rivolte in particolare alle Pmi innovative);<\/li>\n<li>formazione congiunta alle imprese sui seguenti temi: ricerca, innovazione tecnologica e valorizzazione dei propri asset (per favorirne lo sviluppo e quello del Paese);<\/li>\n<li>definizione di proposte strategiche per il miglioramento di realt\u00e0 imprenditoriali gi\u00e0 consolidate (orientate a sbloccare il potenziale di crescita);<\/li>\n<li>analisi e sperimentazione di servizi innovativi per il finanziamento e la crescita degli spin off del Cnr, delle start up e delle Pmi innovative.<\/li>\n<\/ul>\n<p>L\u2019accordo prevede l\u2019istituzione di un Comitato di indirizzo strategico composto da quattro membri, due in rappresentanza di Bernoni Grant Thornton e due del Cnr, con il compito di sviluppare e integrare le linee di attivit\u00e0, di valutare i temi strategici di intervento e di approvare i progetti di ricerca da sviluppare attraverso specifiche convenzioni operative.<\/p>\n<p>Ogni anno il Comitato predisporr\u00e0 una relazione sullo stato di attuazione dell\u2019accordo. Per ogni specifico progetto approvato, le parti provvederanno alla stesura e sottoscrizione di una convenzione operativa.<\/p>\n<p>Obiettivo comune sar\u00e0 quello di integrare pubblico e privato per dare vita ad una collaborazione incentrata sulla promozione della formazione come driver di sviluppo per i progetti con ampio potenziale di crescita.<\/p>\n<p>\u201cSiamo molto soddisfatti e orgogliosi dell\u2019accordo quadro siglato con il Cnr e non vediamo l\u2019ora di iniziare a collaborare su un progetto cos\u00ec ambizioso. La nostra attivit\u00e0 di consulenza si svolge, da sempre, al fianco delle Pmi italiane ed estere accompagnando le stesse nel processo di crescita e di sviluppo.<\/p>\n<p>L\u2019esperienza maturata ci ha consentito di osservare le enormi potenzialit\u00e0 di crescita delle imprese italiane e soprattutto di quelle improntate all\u2019innovazione tecnologica. Abbiamo l\u2019ambizione, con il Cnr, di fornire alle Pmi la formazione e l\u2019informazione specializzata in modo da liberare il loro potenziale di crescita e permettere alle stesse di affermarsi a livello italiano ed internazionale e, quindi, favorire lo sviluppo del nostro Paese\u201d, afferma Federico Feroci, Tax partner di Grant Thornton.<\/p>\n<blockquote class=\"td_pull_quote td_pull_center\"><p>Il Cnr, firmando questo accordo, conferma il suo impegno e la sua volont\u00e0 di collaborare con soggetti qualificati per trasferire le conoscenze e tecnologie sviluppate dai suoi gruppi di ricerca al settore produttivo e accrescere cos\u00ec la competitivit\u00e0 delle aziende<\/p><\/blockquote>\n<p>dichiara <strong>Cristina Battaglia<\/strong>, responsabile Unit\u00e0 valorizzazione della ricerca del Cnr.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Consiglio nazionale delle ricerche (Cnr) e Bernoni Grant Thornton hanno recentemente siglato un accordo quadro a livello nazionale della durata di tre anni per favorire lo sviluppo delle piccole e medie imprese italiane. I due soggetti firmatari sono rispettivamente il maggior Ente pubblico di ricerca italiano, a vocazione spiccatamente multidisciplinare, e la member firm italiana [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2032,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[311],"tags":[887,889,890,888],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cnr e Grant Thornton siglano accordo quadro per le aziende italiane -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/cnr-e-grant-thornton-siglano-accordo-quadro-per-le-aziende-italiane\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cnr e Grant Thornton siglano accordo quadro per le aziende italiane -\" \/>\n<meta property=\"og:description\" content=\"Consiglio nazionale delle ricerche (Cnr) e Bernoni Grant Thornton hanno recentemente siglato un accordo quadro a livello nazionale della durata di tre anni per favorire lo sviluppo delle piccole e medie imprese italiane. I due soggetti firmatari sono rispettivamente il maggior Ente pubblico di ricerca italiano, a vocazione spiccatamente multidisciplinare, e la member firm italiana [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/cnr-e-grant-thornton-siglano-accordo-quadro-per-le-aziende-italiane\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-05T10:25:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/impresa-lavoro-ufficio-banca.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/cnr-e-grant-thornton-siglano-accordo-quadro-per-le-aziende-italiane\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/cnr-e-grant-thornton-siglano-accordo-quadro-per-le-aziende-italiane\/\",\"name\":\"Cnr e Grant Thornton siglano accordo quadro per le aziende italiane -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/cnr-e-grant-thornton-siglano-accordo-quadro-per-le-aziende-italiane\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/cnr-e-grant-thornton-siglano-accordo-quadro-per-le-aziende-italiane\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/impresa-lavoro-ufficio-banca.jpg\",\"datePublished\":\"2020-02-05T10:25:58+00:00\",\"dateModified\":\"2020-02-05T10:25:58+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/cnr-e-grant-thornton-siglano-accordo-quadro-per-le-aziende-italiane\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/cnr-e-grant-thornton-siglano-accordo-quadro-per-le-aziende-italiane\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/cnr-e-grant-thornton-siglano-accordo-quadro-per-le-aziende-italiane\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/impresa-lavoro-ufficio-banca.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/impresa-lavoro-ufficio-banca.jpg\",\"width\":960,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/cnr-e-grant-thornton-siglano-accordo-quadro-per-le-aziende-italiane\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cnr e Grant Thornton siglano accordo quadro per le aziende italiane\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cnr e Grant Thornton siglano accordo quadro per le aziende italiane -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/cnr-e-grant-thornton-siglano-accordo-quadro-per-le-aziende-italiane\/","og_locale":"it_IT","og_type":"article","og_title":"Cnr e Grant Thornton siglano accordo quadro per le aziende italiane -","og_description":"Consiglio nazionale delle ricerche (Cnr) e Bernoni Grant Thornton hanno recentemente siglato un accordo quadro a livello nazionale della durata di tre anni per favorire lo sviluppo delle piccole e medie imprese italiane. I due soggetti firmatari sono rispettivamente il maggior Ente pubblico di ricerca italiano, a vocazione spiccatamente multidisciplinare, e la member firm italiana [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/cnr-e-grant-thornton-siglano-accordo-quadro-per-le-aziende-italiane\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2020-02-05T10:25:58+00:00","og_image":[{"width":960,"height":640,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/impresa-lavoro-ufficio-banca.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/cnr-e-grant-thornton-siglano-accordo-quadro-per-le-aziende-italiane\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/cnr-e-grant-thornton-siglano-accordo-quadro-per-le-aziende-italiane\/","name":"Cnr e Grant Thornton siglano accordo quadro per le aziende italiane -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/cnr-e-grant-thornton-siglano-accordo-quadro-per-le-aziende-italiane\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/cnr-e-grant-thornton-siglano-accordo-quadro-per-le-aziende-italiane\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/impresa-lavoro-ufficio-banca.jpg","datePublished":"2020-02-05T10:25:58+00:00","dateModified":"2020-02-05T10:25:58+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/cnr-e-grant-thornton-siglano-accordo-quadro-per-le-aziende-italiane\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/cnr-e-grant-thornton-siglano-accordo-quadro-per-le-aziende-italiane\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/cnr-e-grant-thornton-siglano-accordo-quadro-per-le-aziende-italiane\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/impresa-lavoro-ufficio-banca.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/impresa-lavoro-ufficio-banca.jpg","width":960,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/cnr-e-grant-thornton-siglano-accordo-quadro-per-le-aziende-italiane\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Cnr e Grant Thornton siglano accordo quadro per le aziende italiane"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/2470"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=2470"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/2470\/revisions"}],"predecessor-version":[{"id":2471,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/2470\/revisions\/2471"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/2032"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=2470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=2470"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=2470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}