{"id":2591,"date":"2020-03-02T15:53:43","date_gmt":"2020-03-02T14:53:43","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=2591"},"modified":"2020-03-02T15:53:43","modified_gmt":"2020-03-02T14:53:43","slug":"coronavirus-sul-sito-di-confindustria-la-sezione-dedicata-allemergenza","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-sul-sito-di-confindustria-la-sezione-dedicata-allemergenza\/","title":{"rendered":"Coronavirus, sul sito di Confindustria la sezione dedicata all&#8217;emergenza"},"content":{"rendered":"<div class=\"itemHeader\"><span class=\"dropcap dropcap3\">N<\/span>ella homepage del sito di Confindustria, al <a href=\"https:\/\/www.confindustria.it\/coronavirus\">link<\/a>, \u00e8 stata creata una sezione specifica dedicata all&#8217;emergenza Coronavirus.<\/div>\n<div class=\"itemBody\">\n<div class=\"itemFullText\">\n<p>&nbsp;<\/p>\n<p>All&#8217;interno della pagina si trovano:<\/p>\n<p>\u2022 una <span id=\"cloake6045a7dafd2733e498f79a8e744904d\"><a href=\"mailto:info.coronavirus@confindustria.it\">casella di posta elettronica<\/a><\/span> dedicata alla segnalazione, d&#8217;ora in poi, di tutte le problematiche che stanno emergendo in queste ore;<\/p>\n<p>\u2022 i contatti diretti della task force di Confindustria che stanno seguendo le principali emergenze che vengono segnalate dalle imprese;<\/p>\n<p>\u2022 una sezione &#8220;aggiornamenti per le imprese&#8221; che raccoglie tutte le informative sul tema inviate alle imprese;<\/p>\n<p>\u2022 una sezione &#8220;<a href=\"https:\/\/www.confindustria.it\/coronavirus\/info\" target=\"_blank\" rel=\"noopener noreferrer\">info utili<\/a>&#8221; che raccoglie tutti i provvedimenti normativi, le Ordinanze, le linee guida e i leaflet rilasciati dai vari Ministeri.<\/p>\n<p>Inoltre, sempre sulla pagina &#8211; alla quale indirizzare le imprese &#8211; potete trovare il link diretto alla compilazione del questionario sull&#8217;impatto del fenomeno Coronavirus sul sistema produttivo italiano.<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Nella homepage del sito di Confindustria, al link, \u00e8 stata creata una sezione specifica dedicata all&#8217;emergenza Coronavirus. &nbsp; All&#8217;interno della pagina si trovano: \u2022 una casella di posta elettronica dedicata alla segnalazione, d&#8217;ora in poi, di tutte le problematiche che stanno emergendo in queste ore; \u2022 i contatti diretti della task force di Confindustria che [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2592,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[311],"tags":[180,877,928],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Coronavirus, sul sito di Confindustria la sezione dedicata all&#039;emergenza -<\/title>\n<meta name=\"description\" content=\"Nella homepage del sito di Confindustria, al link, \u00e8 stata creata una sezione specifica dedicata all&#039;emergenza Coronavirus.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-sul-sito-di-confindustria-la-sezione-dedicata-allemergenza\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coronavirus, sul sito di Confindustria la sezione dedicata all&#039;emergenza -\" \/>\n<meta property=\"og:description\" content=\"Nella homepage del sito di Confindustria, al link, \u00e8 stata creata una sezione specifica dedicata all&#039;emergenza Coronavirus.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-sul-sito-di-confindustria-la-sezione-dedicata-allemergenza\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-02T14:53:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/03\/Schermata-2020-03-02-alle-15.51.12.png\" \/>\n\t<meta property=\"og:image:width\" content=\"882\" \/>\n\t<meta property=\"og:image:height\" content=\"354\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-sul-sito-di-confindustria-la-sezione-dedicata-allemergenza\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-sul-sito-di-confindustria-la-sezione-dedicata-allemergenza\/\",\"name\":\"Coronavirus, sul sito di Confindustria la sezione dedicata all'emergenza -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-sul-sito-di-confindustria-la-sezione-dedicata-allemergenza\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-sul-sito-di-confindustria-la-sezione-dedicata-allemergenza\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/03\/Schermata-2020-03-02-alle-15.51.12.png\",\"datePublished\":\"2020-03-02T14:53:43+00:00\",\"dateModified\":\"2020-03-02T14:53:43+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"description\":\"Nella homepage del sito di Confindustria, al link, \u00e8 stata creata una sezione specifica dedicata all'emergenza Coronavirus.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-sul-sito-di-confindustria-la-sezione-dedicata-allemergenza\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-sul-sito-di-confindustria-la-sezione-dedicata-allemergenza\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-sul-sito-di-confindustria-la-sezione-dedicata-allemergenza\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/03\/Schermata-2020-03-02-alle-15.51.12.png\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/03\/Schermata-2020-03-02-alle-15.51.12.png\",\"width\":882,\"height\":354},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-sul-sito-di-confindustria-la-sezione-dedicata-allemergenza\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coronavirus, sul sito di Confindustria la sezione dedicata all&#8217;emergenza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Coronavirus, sul sito di Confindustria la sezione dedicata all'emergenza -","description":"Nella homepage del sito di Confindustria, al link, \u00e8 stata creata una sezione specifica dedicata all'emergenza Coronavirus.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-sul-sito-di-confindustria-la-sezione-dedicata-allemergenza\/","og_locale":"it_IT","og_type":"article","og_title":"Coronavirus, sul sito di Confindustria la sezione dedicata all'emergenza -","og_description":"Nella homepage del sito di Confindustria, al link, \u00e8 stata creata una sezione specifica dedicata all'emergenza Coronavirus.","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-sul-sito-di-confindustria-la-sezione-dedicata-allemergenza\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2020-03-02T14:53:43+00:00","og_image":[{"width":882,"height":354,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/03\/Schermata-2020-03-02-alle-15.51.12.png","type":"image\/png"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-sul-sito-di-confindustria-la-sezione-dedicata-allemergenza\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-sul-sito-di-confindustria-la-sezione-dedicata-allemergenza\/","name":"Coronavirus, sul sito di Confindustria la sezione dedicata all'emergenza -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-sul-sito-di-confindustria-la-sezione-dedicata-allemergenza\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-sul-sito-di-confindustria-la-sezione-dedicata-allemergenza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/03\/Schermata-2020-03-02-alle-15.51.12.png","datePublished":"2020-03-02T14:53:43+00:00","dateModified":"2020-03-02T14:53:43+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"description":"Nella homepage del sito di Confindustria, al link, \u00e8 stata creata una sezione specifica dedicata all'emergenza Coronavirus.","breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-sul-sito-di-confindustria-la-sezione-dedicata-allemergenza\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-sul-sito-di-confindustria-la-sezione-dedicata-allemergenza\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-sul-sito-di-confindustria-la-sezione-dedicata-allemergenza\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/03\/Schermata-2020-03-02-alle-15.51.12.png","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/03\/Schermata-2020-03-02-alle-15.51.12.png","width":882,"height":354},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-sul-sito-di-confindustria-la-sezione-dedicata-allemergenza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Coronavirus, sul sito di Confindustria la sezione dedicata all&#8217;emergenza"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/2591"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=2591"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/2591\/revisions"}],"predecessor-version":[{"id":2593,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/2591\/revisions\/2593"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/2592"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=2591"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=2591"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=2591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}