{"id":2636,"date":"2020-03-06T16:49:47","date_gmt":"2020-03-06T15:49:47","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=2636"},"modified":"2020-03-06T16:50:22","modified_gmt":"2020-03-06T15:50:22","slug":"entrate-tributarie-a-gennaio-2020-pari-a-377-miliardi-31","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/entrate-tributarie-a-gennaio-2020-pari-a-377-miliardi-31\/","title":{"rendered":"Entrate tributarie: a gennaio 2020 pari a 37,7 miliardi (+3,1%)"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">N<\/span>el mese di gennaio 2020, le entrate tributarie erariali accertate in base al criterio della competenza giuridica ammontano a 37.687 milioni di euro, segnando un incremento di 1.140 milioni di euro rispetto allo stesso mese dell\u2019anno precedente (+3,1%).<\/p>\n<p><strong>IMPOSTE DIRETTE<\/strong><br \/>\nLe imposte dirette ammontano a 26.219 milioni di euro, con una crescita di 829 milioni di euro (+3,3%) rispetto al mese di gennaio 2019. La crescita \u00e8 riconducibile all\u2019andamento delle ritenute IRPEF sui lavoratori dipendenti e i pensionati (+726 milioni di euro, +3,2%).<br \/>\nL\u2019IRES registra una diminuzione di 15 milioni di euro (-4,8%).<\/p>\n<p><strong>IMPOSTE INDIRETTE<\/strong><br \/>\nLe imposte indirette ammontano a 11.468 milioni di euro e registrano una variazione positiva di 311 milioni di euro (+2,8%). Il risultato \u00e8 dovuto al gettito dell\u2019IVA (+312 milioni di euro, +5,2%) sia per la componente dell\u2019imposta legata agli scambi interni che registra un incremento di 244 milioni di euro, (+5,1%) che per la componente relativa alle importazioni (+68 milioni di euro, pari a +5,4%), che riflette il notevole incremento del prezzo del petrolio.<br \/>\nTra le altre imposte indirette si segnala l\u2019incremento del gettito relativo all\u2019imposta di bollo (+34 milioni di euro, pari a +6,1%), e dell\u2019accisa sui prodotti energetici, loro derivati e prodotti analoghi (+49 milioni di euro, pari a +4,5).<\/p>\n<p><strong>ENTRATE DA ACCERTAMENTO E CONTROLLO<\/strong><br \/>\nLe entrate tributarie erariali derivanti da attivit\u00e0 di accertamento e controllo si sono attestate a 824 milioni (+58 milioni di euro, +7,6%) di cui: 348 milioni di euro (-29 milioni di euro, -7,7%) sono affluiti dalle imposte dirette e 476 milioni di euro (+87 milioni di euro, +22,4%) dalle imposte indirette.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nel mese di gennaio 2020, le entrate tributarie erariali accertate in base al criterio della competenza giuridica ammontano a 37.687 milioni di euro, segnando un incremento di 1.140 milioni di euro rispetto allo stesso mese dell\u2019anno precedente (+3,1%). IMPOSTE DIRETTE Le imposte dirette ammontano a 26.219 milioni di euro, con una crescita di 829 milioni [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1528,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Entrate tributarie: a gennaio 2020 pari a 37,7 miliardi (+3,1%) -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/entrate-tributarie-a-gennaio-2020-pari-a-377-miliardi-31\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Entrate tributarie: a gennaio 2020 pari a 37,7 miliardi (+3,1%) -\" \/>\n<meta property=\"og:description\" content=\"Nel mese di gennaio 2020, le entrate tributarie erariali accertate in base al criterio della competenza giuridica ammontano a 37.687 milioni di euro, segnando un incremento di 1.140 milioni di euro rispetto allo stesso mese dell\u2019anno precedente (+3,1%). IMPOSTE DIRETTE Le imposte dirette ammontano a 26.219 milioni di euro, con una crescita di 829 milioni [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/entrate-tributarie-a-gennaio-2020-pari-a-377-miliardi-31\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-06T15:49:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-06T15:50:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/fisco-tasse.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"678\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/entrate-tributarie-a-gennaio-2020-pari-a-377-miliardi-31\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/entrate-tributarie-a-gennaio-2020-pari-a-377-miliardi-31\/\",\"name\":\"Entrate tributarie: a gennaio 2020 pari a 37,7 miliardi (+3,1%) -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/entrate-tributarie-a-gennaio-2020-pari-a-377-miliardi-31\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/entrate-tributarie-a-gennaio-2020-pari-a-377-miliardi-31\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/fisco-tasse.jpg\",\"datePublished\":\"2020-03-06T15:49:47+00:00\",\"dateModified\":\"2020-03-06T15:50:22+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/entrate-tributarie-a-gennaio-2020-pari-a-377-miliardi-31\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/entrate-tributarie-a-gennaio-2020-pari-a-377-miliardi-31\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/entrate-tributarie-a-gennaio-2020-pari-a-377-miliardi-31\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/fisco-tasse.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/fisco-tasse.jpg\",\"width\":960,\"height\":678},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/entrate-tributarie-a-gennaio-2020-pari-a-377-miliardi-31\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Entrate tributarie: a gennaio 2020 pari a 37,7 miliardi (+3,1%)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Entrate tributarie: a gennaio 2020 pari a 37,7 miliardi (+3,1%) -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/entrate-tributarie-a-gennaio-2020-pari-a-377-miliardi-31\/","og_locale":"it_IT","og_type":"article","og_title":"Entrate tributarie: a gennaio 2020 pari a 37,7 miliardi (+3,1%) -","og_description":"Nel mese di gennaio 2020, le entrate tributarie erariali accertate in base al criterio della competenza giuridica ammontano a 37.687 milioni di euro, segnando un incremento di 1.140 milioni di euro rispetto allo stesso mese dell\u2019anno precedente (+3,1%). IMPOSTE DIRETTE Le imposte dirette ammontano a 26.219 milioni di euro, con una crescita di 829 milioni [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/entrate-tributarie-a-gennaio-2020-pari-a-377-miliardi-31\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2020-03-06T15:49:47+00:00","article_modified_time":"2020-03-06T15:50:22+00:00","og_image":[{"width":960,"height":678,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/fisco-tasse.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/entrate-tributarie-a-gennaio-2020-pari-a-377-miliardi-31\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/entrate-tributarie-a-gennaio-2020-pari-a-377-miliardi-31\/","name":"Entrate tributarie: a gennaio 2020 pari a 37,7 miliardi (+3,1%) -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/entrate-tributarie-a-gennaio-2020-pari-a-377-miliardi-31\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/entrate-tributarie-a-gennaio-2020-pari-a-377-miliardi-31\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/fisco-tasse.jpg","datePublished":"2020-03-06T15:49:47+00:00","dateModified":"2020-03-06T15:50:22+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/entrate-tributarie-a-gennaio-2020-pari-a-377-miliardi-31\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/entrate-tributarie-a-gennaio-2020-pari-a-377-miliardi-31\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/entrate-tributarie-a-gennaio-2020-pari-a-377-miliardi-31\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/fisco-tasse.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/fisco-tasse.jpg","width":960,"height":678},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/entrate-tributarie-a-gennaio-2020-pari-a-377-miliardi-31\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Entrate tributarie: a gennaio 2020 pari a 37,7 miliardi (+3,1%)"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/2636"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=2636"}],"version-history":[{"count":2,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/2636\/revisions"}],"predecessor-version":[{"id":2638,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/2636\/revisions\/2638"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/1528"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=2636"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=2636"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=2636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}