{"id":2664,"date":"2020-03-09T17:05:01","date_gmt":"2020-03-09T16:05:01","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=2664"},"modified":"2020-03-09T17:05:01","modified_gmt":"2020-03-09T16:05:01","slug":"coronavirus-iss-pubblicato-oggi-il-vademecum-cosa-fare-in-caso-di-dubbi","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-iss-pubblicato-oggi-il-vademecum-cosa-fare-in-caso-di-dubbi\/","title":{"rendered":"Coronavirus ISS, pubblicato oggi il vademecum \u201cCosa fare in caso di dubbi\u201d"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">I<\/span> sintomi a cui fare attenzione, i numeri da chiamare, come proteggere i familiari, dove fare il test. Sono questi i contenuti della breve guida pubblicata oggi dall\u2019<strong>Istituto Superiore di Sanit\u00e0<\/strong> e realizzata in collaborazione con lo <strong>European Centre for Disease Control e il Ministero della Salute<\/strong><\/p>\n<p>Il documento \u00e8 dedicato in particolare alle persone cha hanno sintomi tali da suscitare il sospetto di contagio da COVID-19 e che possono trovare in questa guida tutte le informazioni per avere assistenza.<\/p>\n<p><span class=\"td_btn td_btn_lg td_default_btn\">NUOVO CORONAVIRUS IL VADEMECUM<\/span><\/p>\n<div class=\"textLayer\"><strong>Quali sono i sintomi a cui devo fare attenzione?<\/strong><\/div>\n<div><\/div>\n<div class=\"textLayer\">1) Febbre e sintomi simil-influenzali come tosse, mal di gola, respiro corto, dolore ai muscoli, stanchezza sono segnali di una possibile infezione da nuovo coronavirus.<\/div>\n<div><\/div>\n<div class=\"textLayer\">2) Ho febbre e\/o sintomi influenzali, cosa devo fare?Se negli ultimi 14 giorni sei stato a stretto contatto con una persona infetta da COVID-19 o sei stato in un&#8217;area a rischio oppure hai lavorato in una struttura sanitaria con pazienti COVID-19, resta in casa e chiama il medico di famiglia, il pediatra o la guardia medica.<\/div>\n<div><\/div>\n<div class=\"textLayer\">3) Dopo quanto tempo devo chiamare il medico?Subito. Se ritieni di essere contagiato, chiama appena avverti i sintomi di infezione respiratoria, spiegando i sintomi e i contatti a rischio.<\/div>\n<div><\/div>\n<div class=\"textLayer\">4) Non riesco a contattare il mio medico di famiglia, cosa devo fare? Chiama uno dei numeri di emergenza indicati sul <a href=\"http:\/\/www.salute.gov.it\/nuovocoronavirus\"><strong>sito<\/strong><\/a><\/div>\n<div><\/div>\n<div class=\"textLayer\">5) Posso andare direttamente al pronto soccorso o dal mio medicodi famiglia?No. Se accedi al pronto soccorso o vai in un ambulatorio senza prima averlo concordato con il medico potresti contagiare altre persone.<\/div>\n<div><\/div>\n<div class=\"textLayer\">6) Come posso proteggere i miei familiari?Segui sempre i comportamenti di igiene personale (lavati regolarmente le mani con acqua e sapone o usa un gel a base alcolica) e mantieni pulito l&#8217;ambiente. Se pensi di essere infetto indossa una mascherina chirurgica, resta a distanza dai tuoi familiari e disinfetta spesso gli oggetti di uso comune.<\/div>\n<div><\/div>\n<div class=\"textLayer\">7) Dove posso fare il test?I test vengono eseguiti unicamente in laboratori del Servizio Sanitario Nazionale selezionati. Se il tuo medico ritiene che sia necessario un testti fornir\u00e0 indicazioni su come procedere.<\/div>\n<div><\/div>\n<div class=\"textLayer\">8) Dove trovo altre informazioni attendibili? Segui solo le indicazioni specifiche e aggiornate dei siti web ufficiali,delle autorit\u00e0 locali e della Protezione<\/div>\n<div><\/div>\n<div><a href=\"http:\/\/www.piemonteconomia.it\/web\/wp-content\/uploads\/2020\/03\/VADEMECUM_ISS_ECDC_9marzo.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">SCARICA IL VADEMECUM ISS<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>I sintomi a cui fare attenzione, i numeri da chiamare, come proteggere i familiari, dove fare il test. Sono questi i contenuti della breve guida pubblicata oggi dall\u2019Istituto Superiore di Sanit\u00e0 e realizzata in collaborazione con lo European Centre for Disease Control e il Ministero della Salute Il documento \u00e8 dedicato in particolare alle persone [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2665,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[128],"tags":[877,946,947],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Coronavirus ISS, pubblicato oggi il vademecum \u201cCosa fare in caso di dubbi\u201d -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-iss-pubblicato-oggi-il-vademecum-cosa-fare-in-caso-di-dubbi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coronavirus ISS, pubblicato oggi il vademecum \u201cCosa fare in caso di dubbi\u201d -\" \/>\n<meta property=\"og:description\" content=\"I sintomi a cui fare attenzione, i numeri da chiamare, come proteggere i familiari, dove fare il test. Sono questi i contenuti della breve guida pubblicata oggi dall\u2019Istituto Superiore di Sanit\u00e0 e realizzata in collaborazione con lo European Centre for Disease Control e il Ministero della Salute Il documento \u00e8 dedicato in particolare alle persone [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-iss-pubblicato-oggi-il-vademecum-cosa-fare-in-caso-di-dubbi\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-09T16:05:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/03\/Schermata-2020-03-09-alle-16.05.58.png\" \/>\n\t<meta property=\"og:image:width\" content=\"851\" \/>\n\t<meta property=\"og:image:height\" content=\"477\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-iss-pubblicato-oggi-il-vademecum-cosa-fare-in-caso-di-dubbi\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-iss-pubblicato-oggi-il-vademecum-cosa-fare-in-caso-di-dubbi\/\",\"name\":\"Coronavirus ISS, pubblicato oggi il vademecum \u201cCosa fare in caso di dubbi\u201d -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-iss-pubblicato-oggi-il-vademecum-cosa-fare-in-caso-di-dubbi\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-iss-pubblicato-oggi-il-vademecum-cosa-fare-in-caso-di-dubbi\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/03\/Schermata-2020-03-09-alle-16.05.58.png\",\"datePublished\":\"2020-03-09T16:05:01+00:00\",\"dateModified\":\"2020-03-09T16:05:01+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-iss-pubblicato-oggi-il-vademecum-cosa-fare-in-caso-di-dubbi\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-iss-pubblicato-oggi-il-vademecum-cosa-fare-in-caso-di-dubbi\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-iss-pubblicato-oggi-il-vademecum-cosa-fare-in-caso-di-dubbi\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/03\/Schermata-2020-03-09-alle-16.05.58.png\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/03\/Schermata-2020-03-09-alle-16.05.58.png\",\"width\":851,\"height\":477},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-iss-pubblicato-oggi-il-vademecum-cosa-fare-in-caso-di-dubbi\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coronavirus ISS, pubblicato oggi il vademecum \u201cCosa fare in caso di dubbi\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Coronavirus ISS, pubblicato oggi il vademecum \u201cCosa fare in caso di dubbi\u201d -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-iss-pubblicato-oggi-il-vademecum-cosa-fare-in-caso-di-dubbi\/","og_locale":"it_IT","og_type":"article","og_title":"Coronavirus ISS, pubblicato oggi il vademecum \u201cCosa fare in caso di dubbi\u201d -","og_description":"I sintomi a cui fare attenzione, i numeri da chiamare, come proteggere i familiari, dove fare il test. Sono questi i contenuti della breve guida pubblicata oggi dall\u2019Istituto Superiore di Sanit\u00e0 e realizzata in collaborazione con lo European Centre for Disease Control e il Ministero della Salute Il documento \u00e8 dedicato in particolare alle persone [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-iss-pubblicato-oggi-il-vademecum-cosa-fare-in-caso-di-dubbi\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2020-03-09T16:05:01+00:00","og_image":[{"width":851,"height":477,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/03\/Schermata-2020-03-09-alle-16.05.58.png","type":"image\/png"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-iss-pubblicato-oggi-il-vademecum-cosa-fare-in-caso-di-dubbi\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-iss-pubblicato-oggi-il-vademecum-cosa-fare-in-caso-di-dubbi\/","name":"Coronavirus ISS, pubblicato oggi il vademecum \u201cCosa fare in caso di dubbi\u201d -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-iss-pubblicato-oggi-il-vademecum-cosa-fare-in-caso-di-dubbi\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-iss-pubblicato-oggi-il-vademecum-cosa-fare-in-caso-di-dubbi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/03\/Schermata-2020-03-09-alle-16.05.58.png","datePublished":"2020-03-09T16:05:01+00:00","dateModified":"2020-03-09T16:05:01+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-iss-pubblicato-oggi-il-vademecum-cosa-fare-in-caso-di-dubbi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-iss-pubblicato-oggi-il-vademecum-cosa-fare-in-caso-di-dubbi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-iss-pubblicato-oggi-il-vademecum-cosa-fare-in-caso-di-dubbi\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/03\/Schermata-2020-03-09-alle-16.05.58.png","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/03\/Schermata-2020-03-09-alle-16.05.58.png","width":851,"height":477},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-iss-pubblicato-oggi-il-vademecum-cosa-fare-in-caso-di-dubbi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Coronavirus ISS, pubblicato oggi il vademecum \u201cCosa fare in caso di dubbi\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/2664"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=2664"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/2664\/revisions"}],"predecessor-version":[{"id":2666,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/2664\/revisions\/2666"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/2665"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=2664"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=2664"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=2664"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}