{"id":2694,"date":"2020-03-16T09:50:07","date_gmt":"2020-03-16T08:50:07","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=2694"},"modified":"2020-03-16T09:50:07","modified_gmt":"2020-03-16T08:50:07","slug":"le-richieste-di-adiconsum-a-mef-abi-e-consob-per-aiutare-i-cittadini-consumatori","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/le-richieste-di-adiconsum-a-mef-abi-e-consob-per-aiutare-i-cittadini-consumatori\/","title":{"rendered":"Le richieste di Adiconsum a MEF, ABI e CONSOB per aiutare i cittadini-consumatori"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">L<\/span>e ricadute dell\u2019effetto COVID-19 anche sulla condizione economica delle famiglie, rischiano di aggravare la gi\u00e0 preoccupante situazione sanitaria. \u00c8 per questo che Adiconsum, fin dai primi giorni del manifestarsi dell\u2019emergenza, ha sollecitato le istituzioni per agevolare e rendere meno pesanti le condizioni di vita dei cittadini-consumatori.<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>Al MEF, \u00e8 stata sollecitata l\u2019introduzione di un provvedimento finalizzato a concedere pi\u00f9 tempo (almeno 3 mesi oltre l\u2019attuale scadenza del 18 aprile), ai risparmiatori danneggiati dalle banche messe in liquidazione per fare domanda al Fondo Indennizzo Risparmiatori (FIR).<\/li>\n<li>Ad ABI, \u00e8 stato richiesto di rinnovare e semplificare la possibilit\u00e0 di chiedere la sospensione delle rate dei mutui prima casa e dei prestiti, utilizzando il Fondo di solidariet\u00e0 \u201cGasparrini\u201d che prevede la sospensione delle stesse fino a 18 mesi.<\/li>\n<li>All\u2019Autorit\u00e0 di Vigilanza (CONSOB), \u00e8 stato inoltre richiesto di assumere le necessarie iniziative atte a inibire le speculazioni sui nostri mercati, attuate attraverso le vendite allo scoperto di ordini dati su titoli che non si possiedono, intervenendo anche presso l&#8217;Autorit\u00e0 europea Esma, al fine di avviare un coordinamento per la gestione della crisi che sta investendo le piazze europee con l&#8217;emergenza Covid-19.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Raccomandiamo infine ai risparmiatori, a maggior ragione in momenti turbolenti come quelli attuali, di non farsi prendere dal panico, ma che \u00e8 indispensabile avere un progetto d\u2019investimento.<\/p>\n<p>Un progetto di investimento pu\u00f2 essere quello di destinare una parte del patrimonio ad un obiettivo di vita per il quale si \u00e8 profondamente interessati, ad es. un progetto legato ai nostri figli per garantire loro l\u2019istruzione universitaria, oppure legato ad un bisogno quale quello di\u00a0 l\u2019integrare il reddito da pensione. L\u2019importante \u00e8 che sia un obiettivo definito e veramente importante.<\/p>\n<p>Quindi, se si ha un progetto di investimento, questo momento pu\u00f2 rappresentare un\u2019opportunit\u00e0, non un problema. Ma l\u2019occasione arriva per coloro che si preoccupano di essere ben informati. Fare scelte finanziarie, per la massima parte dei risparmiatori, non \u00e8 un discorso tecnico (certo esiste anche questa componente) e men che meno riguarda la capacit\u00e0 di prevedere dove andranno i mercati. Fare scelte finanziarie significa prima di tutto fare chiarezza su cosa \u00e8 veramente importante per ciascuno di noi, quindi cosa realmente vogliamo dal nostro patrimonio.<\/p>\n<p>La chiarezza aiuta enormemente le scelte finanziarie.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<table width=\"100%\">\n<tbody>\n<tr>\n<td>\n<table width=\"100%\">\n<tbody>\n<tr>\n<td><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Le ricadute dell\u2019effetto COVID-19 anche sulla condizione economica delle famiglie, rischiano di aggravare la gi\u00e0 preoccupante situazione sanitaria. \u00c8 per questo che Adiconsum, fin dai primi giorni del manifestarsi dell\u2019emergenza, ha sollecitato le istituzioni per agevolare e rendere meno pesanti le condizioni di vita dei cittadini-consumatori. &nbsp; Al MEF, \u00e8 stata sollecitata l\u2019introduzione di un [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":703,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[162],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Le richieste di Adiconsum a MEF, ABI e CONSOB per aiutare i cittadini-consumatori -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/le-richieste-di-adiconsum-a-mef-abi-e-consob-per-aiutare-i-cittadini-consumatori\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le richieste di Adiconsum a MEF, ABI e CONSOB per aiutare i cittadini-consumatori -\" \/>\n<meta property=\"og:description\" content=\"Le ricadute dell\u2019effetto COVID-19 anche sulla condizione economica delle famiglie, rischiano di aggravare la gi\u00e0 preoccupante situazione sanitaria. \u00c8 per questo che Adiconsum, fin dai primi giorni del manifestarsi dell\u2019emergenza, ha sollecitato le istituzioni per agevolare e rendere meno pesanti le condizioni di vita dei cittadini-consumatori. &nbsp; Al MEF, \u00e8 stata sollecitata l\u2019introduzione di un [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/le-richieste-di-adiconsum-a-mef-abi-e-consob-per-aiutare-i-cittadini-consumatori\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-16T08:50:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/05\/lavoro.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"606\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/le-richieste-di-adiconsum-a-mef-abi-e-consob-per-aiutare-i-cittadini-consumatori\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/le-richieste-di-adiconsum-a-mef-abi-e-consob-per-aiutare-i-cittadini-consumatori\/\",\"name\":\"Le richieste di Adiconsum a MEF, ABI e CONSOB per aiutare i cittadini-consumatori -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/le-richieste-di-adiconsum-a-mef-abi-e-consob-per-aiutare-i-cittadini-consumatori\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/le-richieste-di-adiconsum-a-mef-abi-e-consob-per-aiutare-i-cittadini-consumatori\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/05\/lavoro.jpg\",\"datePublished\":\"2020-03-16T08:50:07+00:00\",\"dateModified\":\"2020-03-16T08:50:07+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/le-richieste-di-adiconsum-a-mef-abi-e-consob-per-aiutare-i-cittadini-consumatori\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/le-richieste-di-adiconsum-a-mef-abi-e-consob-per-aiutare-i-cittadini-consumatori\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/le-richieste-di-adiconsum-a-mef-abi-e-consob-per-aiutare-i-cittadini-consumatori\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/05\/lavoro.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/05\/lavoro.jpg\",\"width\":960,\"height\":606},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/le-richieste-di-adiconsum-a-mef-abi-e-consob-per-aiutare-i-cittadini-consumatori\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le richieste di Adiconsum a MEF, ABI e CONSOB per aiutare i cittadini-consumatori\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le richieste di Adiconsum a MEF, ABI e CONSOB per aiutare i cittadini-consumatori -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/le-richieste-di-adiconsum-a-mef-abi-e-consob-per-aiutare-i-cittadini-consumatori\/","og_locale":"it_IT","og_type":"article","og_title":"Le richieste di Adiconsum a MEF, ABI e CONSOB per aiutare i cittadini-consumatori -","og_description":"Le ricadute dell\u2019effetto COVID-19 anche sulla condizione economica delle famiglie, rischiano di aggravare la gi\u00e0 preoccupante situazione sanitaria. \u00c8 per questo che Adiconsum, fin dai primi giorni del manifestarsi dell\u2019emergenza, ha sollecitato le istituzioni per agevolare e rendere meno pesanti le condizioni di vita dei cittadini-consumatori. &nbsp; Al MEF, \u00e8 stata sollecitata l\u2019introduzione di un [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/le-richieste-di-adiconsum-a-mef-abi-e-consob-per-aiutare-i-cittadini-consumatori\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2020-03-16T08:50:07+00:00","og_image":[{"width":960,"height":606,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/05\/lavoro.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/le-richieste-di-adiconsum-a-mef-abi-e-consob-per-aiutare-i-cittadini-consumatori\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/le-richieste-di-adiconsum-a-mef-abi-e-consob-per-aiutare-i-cittadini-consumatori\/","name":"Le richieste di Adiconsum a MEF, ABI e CONSOB per aiutare i cittadini-consumatori -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/le-richieste-di-adiconsum-a-mef-abi-e-consob-per-aiutare-i-cittadini-consumatori\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/le-richieste-di-adiconsum-a-mef-abi-e-consob-per-aiutare-i-cittadini-consumatori\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/05\/lavoro.jpg","datePublished":"2020-03-16T08:50:07+00:00","dateModified":"2020-03-16T08:50:07+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/le-richieste-di-adiconsum-a-mef-abi-e-consob-per-aiutare-i-cittadini-consumatori\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/le-richieste-di-adiconsum-a-mef-abi-e-consob-per-aiutare-i-cittadini-consumatori\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/le-richieste-di-adiconsum-a-mef-abi-e-consob-per-aiutare-i-cittadini-consumatori\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/05\/lavoro.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/05\/lavoro.jpg","width":960,"height":606},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/le-richieste-di-adiconsum-a-mef-abi-e-consob-per-aiutare-i-cittadini-consumatori\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Le richieste di Adiconsum a MEF, ABI e CONSOB per aiutare i cittadini-consumatori"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/2694"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=2694"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/2694\/revisions"}],"predecessor-version":[{"id":2695,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/2694\/revisions\/2695"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/703"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=2694"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=2694"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=2694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}