{"id":2749,"date":"2020-03-25T10:06:02","date_gmt":"2020-03-25T09:06:02","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=2749"},"modified":"2020-03-25T10:06:02","modified_gmt":"2020-03-25T09:06:02","slug":"coronavirus-bper-banca-mette-in-campo-un-miliardo-per-la-liquidita-delle-imprese","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-bper-banca-mette-in-campo-un-miliardo-per-la-liquidita-delle-imprese\/","title":{"rendered":"Coronavirus, BPER Banca mette in campo un miliardo per la liquidit\u00e0 delle imprese"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">S<\/span>i intensificano gli interventi di BPER Banca a sostegno dell\u2019economia reale per fare fronte all\u2019emergenza Covid-19. L\u2019Istituto ha infatti stanziato, nell\u2019ambito del progetto \u201cBPER Banca per l\u2019Italia\u201d, un nuovo plafond di un miliardo di euro a sostegno delle imprese clienti, per consentire loro di fare fronte alle esigenze di liquidit\u00e0.<\/p>\n<p>Le aziende possono scegliere tra due forme tecniche: il\u00a0prestito aziendale\u00a0o\u00a0l\u2019affidamento di conto corrente. Il prestito aziendale prevede una durata massima di 18 mesi, con preammortamento di 6 mesi senza spese di istruttoria, mentre l\u2019affidamento di conto corrente ha una durata massima di 12 mesi e sar\u00e0 messo a disposizione su un conto senza commissioni.<\/p>\n<p>La nuova iniziativa si aggiunge alla prima tranche di 100 milioni di euro di un plafond rivolto al sostegno di privati, liberi professionisti, artigiani, commercianti e piccoli operatori economici, che la Banca ha stanziato nei giorni scorsi. Questi finanziamenti hanno una durata di 36 mesi, con condizioni particolarmente agevolate e senza spese di istruttoria.<\/p>\n<p>Il Vice Direttore Generale Vicario di BPER Banca Stefano Rossetti dichiara: \u201cIn queste settimane di emergenza stiamo seguendo molto da vicino la situazione delle imprese, con un\u2019attenzione particolare a quelle di piccole e medie dimensioni, che a fronte di una pesante riduzione dei ricavi devono continuare a sostenere costi di esercizio non differibili. C\u2019\u00e8 dunque l\u2019esigenza di strumenti concreti e flessibili, come quelli che abbiamo messo in campo, per supportare le esigenze di liquidit\u00e0 delle aziende e per aiutarle ad attraversare questa fase delicata\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si intensificano gli interventi di BPER Banca a sostegno dell\u2019economia reale per fare fronte all\u2019emergenza Covid-19. L\u2019Istituto ha infatti stanziato, nell\u2019ambito del progetto \u201cBPER Banca per l\u2019Italia\u201d, un nuovo plafond di un miliardo di euro a sostegno delle imprese clienti, per consentire loro di fare fronte alle esigenze di liquidit\u00e0. Le aziende possono scegliere tra [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2750,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[162],"tags":[445,877,968],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Coronavirus, BPER Banca mette in campo un miliardo per la liquidit\u00e0 delle imprese -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-bper-banca-mette-in-campo-un-miliardo-per-la-liquidita-delle-imprese\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coronavirus, BPER Banca mette in campo un miliardo per la liquidit\u00e0 delle imprese -\" \/>\n<meta property=\"og:description\" content=\"Si intensificano gli interventi di BPER Banca a sostegno dell\u2019economia reale per fare fronte all\u2019emergenza Covid-19. L\u2019Istituto ha infatti stanziato, nell\u2019ambito del progetto \u201cBPER Banca per l\u2019Italia\u201d, un nuovo plafond di un miliardo di euro a sostegno delle imprese clienti, per consentire loro di fare fronte alle esigenze di liquidit\u00e0. Le aziende possono scegliere tra [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-bper-banca-mette-in-campo-un-miliardo-per-la-liquidita-delle-imprese\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-25T09:06:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/03\/Stefano-Rossetti_Vdg-vicario-BPER-Banca.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-bper-banca-mette-in-campo-un-miliardo-per-la-liquidita-delle-imprese\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-bper-banca-mette-in-campo-un-miliardo-per-la-liquidita-delle-imprese\/\",\"name\":\"Coronavirus, BPER Banca mette in campo un miliardo per la liquidit\u00e0 delle imprese -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-bper-banca-mette-in-campo-un-miliardo-per-la-liquidita-delle-imprese\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-bper-banca-mette-in-campo-un-miliardo-per-la-liquidita-delle-imprese\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/03\/Stefano-Rossetti_Vdg-vicario-BPER-Banca.jpg\",\"datePublished\":\"2020-03-25T09:06:02+00:00\",\"dateModified\":\"2020-03-25T09:06:02+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-bper-banca-mette-in-campo-un-miliardo-per-la-liquidita-delle-imprese\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-bper-banca-mette-in-campo-un-miliardo-per-la-liquidita-delle-imprese\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-bper-banca-mette-in-campo-un-miliardo-per-la-liquidita-delle-imprese\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/03\/Stefano-Rossetti_Vdg-vicario-BPER-Banca.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/03\/Stefano-Rossetti_Vdg-vicario-BPER-Banca.jpg\",\"width\":1000,\"height\":667},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-bper-banca-mette-in-campo-un-miliardo-per-la-liquidita-delle-imprese\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coronavirus, BPER Banca mette in campo un miliardo per la liquidit\u00e0 delle imprese\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Coronavirus, BPER Banca mette in campo un miliardo per la liquidit\u00e0 delle imprese -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-bper-banca-mette-in-campo-un-miliardo-per-la-liquidita-delle-imprese\/","og_locale":"it_IT","og_type":"article","og_title":"Coronavirus, BPER Banca mette in campo un miliardo per la liquidit\u00e0 delle imprese -","og_description":"Si intensificano gli interventi di BPER Banca a sostegno dell\u2019economia reale per fare fronte all\u2019emergenza Covid-19. L\u2019Istituto ha infatti stanziato, nell\u2019ambito del progetto \u201cBPER Banca per l\u2019Italia\u201d, un nuovo plafond di un miliardo di euro a sostegno delle imprese clienti, per consentire loro di fare fronte alle esigenze di liquidit\u00e0. Le aziende possono scegliere tra [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-bper-banca-mette-in-campo-un-miliardo-per-la-liquidita-delle-imprese\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2020-03-25T09:06:02+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/03\/Stefano-Rossetti_Vdg-vicario-BPER-Banca.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-bper-banca-mette-in-campo-un-miliardo-per-la-liquidita-delle-imprese\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-bper-banca-mette-in-campo-un-miliardo-per-la-liquidita-delle-imprese\/","name":"Coronavirus, BPER Banca mette in campo un miliardo per la liquidit\u00e0 delle imprese -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-bper-banca-mette-in-campo-un-miliardo-per-la-liquidita-delle-imprese\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-bper-banca-mette-in-campo-un-miliardo-per-la-liquidita-delle-imprese\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/03\/Stefano-Rossetti_Vdg-vicario-BPER-Banca.jpg","datePublished":"2020-03-25T09:06:02+00:00","dateModified":"2020-03-25T09:06:02+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-bper-banca-mette-in-campo-un-miliardo-per-la-liquidita-delle-imprese\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-bper-banca-mette-in-campo-un-miliardo-per-la-liquidita-delle-imprese\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-bper-banca-mette-in-campo-un-miliardo-per-la-liquidita-delle-imprese\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/03\/Stefano-Rossetti_Vdg-vicario-BPER-Banca.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/03\/Stefano-Rossetti_Vdg-vicario-BPER-Banca.jpg","width":1000,"height":667},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-bper-banca-mette-in-campo-un-miliardo-per-la-liquidita-delle-imprese\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Coronavirus, BPER Banca mette in campo un miliardo per la liquidit\u00e0 delle imprese"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/2749"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=2749"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/2749\/revisions"}],"predecessor-version":[{"id":2751,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/2749\/revisions\/2751"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/2750"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=2749"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=2749"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=2749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}