{"id":2812,"date":"2020-04-03T22:51:16","date_gmt":"2020-04-03T20:51:16","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=2812"},"modified":"2020-04-03T22:51:16","modified_gmt":"2020-04-03T20:51:16","slug":"agenzia-entrate-5-per-mille-2018-anticipata-la-pubblicazione-degli-elenchi","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/agenzia-entrate-5-per-mille-2018-anticipata-la-pubblicazione-degli-elenchi\/","title":{"rendered":"Agenzia entrate: 5 per mille 2018 Anticipata la pubblicazione degli elenchi"},"content":{"rendered":"<div class=\"page\" title=\"Page 1\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p><span class=\"dropcap dropcap3\">L<\/span>\u2019Agenzia delle Entrate ha pubblicato in anticipo gli elenchi per la destinazione del 5 per mille 2018, con i dati relativi alle preferenze espresse dai contribuenti nella propria dichiarazione dei redditi, per venire incontro alle richieste degli 8.029 Comuni e quasi 57mila enti tra volontariato, ricerca sanitaria e scientifica, associazioni sportive dilettantistiche, beni culturali e paesaggistici ed enti gestori delle aree protette.<\/p>\n<p>L\u2019elenco degli enti ammessi e di quelli esclusi e\u0300 online insieme agli importi attribuiti agli enti che hanno chiesto di accedere al beneficio ed e\u0300 consultabile sul sito dell\u2019Agenzia delle Entrate, nella sezione \u201c5 per mille\u201d.<\/p>\n<p>5 per mille: i numeri del 2018 \u2013 L\u2019elenco degli ammessi comprende in totale 56.908 enti, suddivisi per categoria: in cima alla classifica gli enti del volontariato (46.312), a seguire le associazioni sportive dilettantistiche (9.892), gli enti impegnati nella ricerca scientifica (480), quelli che operano nel settore della sanita\u0300 (106), gli enti dei beni culturali e paesaggistici (94) e gli enti gestori delle aree protette (24). Sono presenti anche i Comuni (in tutto 8.029) ai quali, per il 2018, sono destinati 14,9 milioni di euro.<\/p>\n<p>Le preferenze dei contribuenti: ricerca in testa &#8211; L\u2019Associazione italiana per la ricerca sul cancro (Airc) occupa anche per il 2018 il primo posto sia tra gli enti impegnati nel settore della ricerca sanitaria sia tra quelli che operano in quello della ricerca scientifica. Per il primo ambito, sono oltre 400mila le scelte espresse con un importo totale che supera i 18,2 milioni di euro. Per quanto riguarda, invece, la ricerca scientifica i contribuenti che hanno espresso la preferenza per l\u2019Airc superano 1 milione, con oltre 39 milioni di euro di beneficio.<\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019Agenzia delle Entrate ha pubblicato in anticipo gli elenchi per la destinazione del 5 per mille 2018, con i dati relativi alle preferenze espresse dai contribuenti nella propria dichiarazione dei redditi, per venire incontro alle richieste degli 8.029 Comuni e quasi 57mila enti tra volontariato, ricerca sanitaria e scientifica, associazioni sportive dilettantistiche, beni culturali e [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1076,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Agenzia entrate: 5 per mille 2018 Anticipata la pubblicazione degli elenchi -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/agenzia-entrate-5-per-mille-2018-anticipata-la-pubblicazione-degli-elenchi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Agenzia entrate: 5 per mille 2018 Anticipata la pubblicazione degli elenchi -\" \/>\n<meta property=\"og:description\" content=\"L\u2019Agenzia delle Entrate ha pubblicato in anticipo gli elenchi per la destinazione del 5 per mille 2018, con i dati relativi alle preferenze espresse dai contribuenti nella propria dichiarazione dei redditi, per venire incontro alle richieste degli 8.029 Comuni e quasi 57mila enti tra volontariato, ricerca sanitaria e scientifica, associazioni sportive dilettantistiche, beni culturali e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/agenzia-entrate-5-per-mille-2018-anticipata-la-pubblicazione-degli-elenchi\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-03T20:51:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/tasse.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/agenzia-entrate-5-per-mille-2018-anticipata-la-pubblicazione-degli-elenchi\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/agenzia-entrate-5-per-mille-2018-anticipata-la-pubblicazione-degli-elenchi\/\",\"name\":\"Agenzia entrate: 5 per mille 2018 Anticipata la pubblicazione degli elenchi -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/agenzia-entrate-5-per-mille-2018-anticipata-la-pubblicazione-degli-elenchi\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/agenzia-entrate-5-per-mille-2018-anticipata-la-pubblicazione-degli-elenchi\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/tasse.jpg\",\"datePublished\":\"2020-04-03T20:51:16+00:00\",\"dateModified\":\"2020-04-03T20:51:16+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/agenzia-entrate-5-per-mille-2018-anticipata-la-pubblicazione-degli-elenchi\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/agenzia-entrate-5-per-mille-2018-anticipata-la-pubblicazione-degli-elenchi\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/agenzia-entrate-5-per-mille-2018-anticipata-la-pubblicazione-degli-elenchi\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/tasse.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/tasse.jpg\",\"width\":960,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/agenzia-entrate-5-per-mille-2018-anticipata-la-pubblicazione-degli-elenchi\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Agenzia entrate: 5 per mille 2018 Anticipata la pubblicazione degli elenchi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Agenzia entrate: 5 per mille 2018 Anticipata la pubblicazione degli elenchi -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/agenzia-entrate-5-per-mille-2018-anticipata-la-pubblicazione-degli-elenchi\/","og_locale":"it_IT","og_type":"article","og_title":"Agenzia entrate: 5 per mille 2018 Anticipata la pubblicazione degli elenchi -","og_description":"L\u2019Agenzia delle Entrate ha pubblicato in anticipo gli elenchi per la destinazione del 5 per mille 2018, con i dati relativi alle preferenze espresse dai contribuenti nella propria dichiarazione dei redditi, per venire incontro alle richieste degli 8.029 Comuni e quasi 57mila enti tra volontariato, ricerca sanitaria e scientifica, associazioni sportive dilettantistiche, beni culturali e [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/agenzia-entrate-5-per-mille-2018-anticipata-la-pubblicazione-degli-elenchi\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2020-04-03T20:51:16+00:00","og_image":[{"width":960,"height":640,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/tasse.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/agenzia-entrate-5-per-mille-2018-anticipata-la-pubblicazione-degli-elenchi\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/agenzia-entrate-5-per-mille-2018-anticipata-la-pubblicazione-degli-elenchi\/","name":"Agenzia entrate: 5 per mille 2018 Anticipata la pubblicazione degli elenchi -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/agenzia-entrate-5-per-mille-2018-anticipata-la-pubblicazione-degli-elenchi\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/agenzia-entrate-5-per-mille-2018-anticipata-la-pubblicazione-degli-elenchi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/tasse.jpg","datePublished":"2020-04-03T20:51:16+00:00","dateModified":"2020-04-03T20:51:16+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/agenzia-entrate-5-per-mille-2018-anticipata-la-pubblicazione-degli-elenchi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/agenzia-entrate-5-per-mille-2018-anticipata-la-pubblicazione-degli-elenchi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/agenzia-entrate-5-per-mille-2018-anticipata-la-pubblicazione-degli-elenchi\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/tasse.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/tasse.jpg","width":960,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/agenzia-entrate-5-per-mille-2018-anticipata-la-pubblicazione-degli-elenchi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Agenzia entrate: 5 per mille 2018 Anticipata la pubblicazione degli elenchi"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/2812"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=2812"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/2812\/revisions"}],"predecessor-version":[{"id":2813,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/2812\/revisions\/2813"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/1076"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=2812"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=2812"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=2812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}