{"id":3043,"date":"2020-05-02T16:57:39","date_gmt":"2020-05-02T14:57:39","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=3043"},"modified":"2020-05-02T16:58:34","modified_gmt":"2020-05-02T14:58:34","slug":"i-paradossi-della-fase-2-tornano-al-lavoro-piu-over-50-che-giovani","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/i-paradossi-della-fase-2-tornano-al-lavoro-piu-over-50-che-giovani\/","title":{"rendered":"I paradossi della Fase 2: tornano al lavoro piu\u0300 over 50 che giovani"},"content":{"rendered":"<div class=\"page\" title=\"Page 1\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p><span class=\"dropcap dropcap3\">D<\/span>ei 4,4 milioni di italiani che riprenderanno le attivita\u0300 dal 4 maggio la maggior parte e\u0300 dipendente, over 50 e occupato al Nord-Italia: la fotografia scattata dalla Fondazione Studi Consulenti del Lavoro sulla ripresa e gli effetti inattesi<\/p>\n<p>Roma, 2 maggio 2020 \u2013 Sono 4,4 milioni i lavoratori che dal 4 maggio, secondo quanto stabilito dal DPCM del 26 aprile, riprenderanno la propria attivita\u0300 lavorativa; mentre 2,7 milioni continueranno a restare a casa in attesa di successive misure governative. Su 100 rimasti a casa per effetto dei provvedimenti di sospensione delle attivita\u0300, ben il 62,2% potra\u0300 tornare al lavoro.<\/p>\n<p>La ripresa pero\u0300 avra\u0300 effetti inattesi. Coinvolgera\u0300 soprattutto lavoratori over 50, rispetto ai giovani, interessera\u0300 maggiormente il Nord Italia, piu\u0300 esposto al contagio in questi due mesi di emergenza da Covid-19, e favorira\u0300 i lavoratori dipendenti a discapito degli autonomi. Ad approfondire le caratteristiche di chi da lunedi\u0300 riprendera\u0300 la propria attivita\u0300 e\u0300 la nuova indagine della Fondazione Studi Consulenti del Lavoro, a partire dai microdati delle Forze Lavoro Istat, intitolata \u201cRitorno al lavoro per 4,4 milioni di italiani.<\/p>\n<p>Al Nord prima che al Sud, anziani piu\u0300 dei giovani\u201d. La ripresa interessera\u0300 principalmente i lavoratori dell\u2019industria, dove l\u2019attivita\u0300 potra\u0300 ritornare a pieno regime (100% dei settori riaperti): su 100 lavoratori che rientreranno al lavoro il 60,7% lavora nel settore manifatturiero; il 15,1% nelle costruzioni; il 12,7% nel commercio e l\u201911,4% in altre attivita\u0300 di servizio.<\/p>\n<p>Dunque, principalmente occupazione maschile piu\u0300 presente in tale comparto. Saranno, infatti, 3,3 milioni gli uomini che torneranno al lavoro (il 74,8% del totale), mentre \u201csolo\u201d 1,1 mln le donne (25,2%). In generale, saranno soprattutto lavoratori dipendenti (3,5 mln, pari al 79,4% di chi riprendera\u0300 a lavorare) mentre gli autonomi (il restante 20,6%) dovranno ancora aspettare: solo il 49% di quanti sono stati interessati dai provvedimenti di sospensione potra\u0300 riaprire gia\u0300 dal 4 maggio.<\/p>\n<p>Tra i paradossi legati alla riapertura delle attivita\u0300 produttive prevista dalla Fase 2, nonostante il dibattito nazionale sull\u2019opportunita\u0300 di prevedere rientri differenziati per tutelare maggiormente la popolazione piu\u0300 adulta, c\u2019e\u0300 l\u2019aspetto legato all\u2019eta\u0300 dei lavoratori coinvolti.<\/p>\n<p>Gli over 50 riprenderanno a lavorare prima dei giovani. Su 100 occupati in settori \u201csospesi\u201d, a rientrare saranno il 68,7% dei 50-59enni; il 67,1% dei 40-49enni; il 59% dei 30-39enni e il 48,8% degli under 30. Alta anche la percentuale degli over 60 (pari al 60,1% di quanti sono rimasti a casa per effetto del blocco delle attivita\u0300).<\/p>\n<p>Anche la \u201csettorialita\u0300\u201d delle aperture delinea un quadro non coerente rispetto alla diffusione della pandemia. La ripresa, infatti, si concentrera\u0300 proprio nelle aree piu\u0300 interessate dal virus: a fronte di 2,8 mln di lavoratori al Nord Italia, saranno 812 mila al Centro e 822 mila al Sud gli occupati che rientreranno al lavoro.<\/p>\n<p>Tra le regioni interessate: Emilia-Romagna, Piemonte, Veneto, Marche e Lombardia, dove il tasso di rientro oscilla intorno al 69%; di contro in Val d\u2019Aosta (49,3%), Lazio (46,7%), Sicilia (43,4%), Calabria (42,5%) e Sardegna (39,2%), la ripresa interessera\u0300 meno di un lavoratore su due tra quelli \u201csospesi\u201d.<\/p>\n<p>Ovviamente la riapertura dei settori non comportera\u0300 necessariamente la presenza in sede dei lavoratori, ma seguendo le indicazioni ribadite negli stessi ultimi provvedimenti governativi, dovra\u0300 essere promosso il piu\u0300 possibile il lavoro agile. Da questo punto di vista, tuttavia, l\u2019indagine evidenzia come solo nel 36,6% dei casi i lavoratori chiamati a riprendere le proprie attivita\u0300 potranno farlo in smart working; mentre la maggior parte (63,4%), per le caratteristiche del proprio lavoro, non potra\u0300 che farlo in sede.<\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Dei 4,4 milioni di italiani che riprenderanno le attivita\u0300 dal 4 maggio la maggior parte e\u0300 dipendente, over 50 e occupato al Nord-Italia: la fotografia scattata dalla Fondazione Studi Consulenti del Lavoro sulla ripresa e gli effetti inattesi Roma, 2 maggio 2020 \u2013 Sono 4,4 milioni i lavoratori che dal 4 maggio, secondo quanto stabilito [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1600,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>I paradossi della Fase 2: tornano al lavoro piu\u0300 over 50 che giovani -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/i-paradossi-della-fase-2-tornano-al-lavoro-piu-over-50-che-giovani\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"I paradossi della Fase 2: tornano al lavoro piu\u0300 over 50 che giovani -\" \/>\n<meta property=\"og:description\" content=\"Dei 4,4 milioni di italiani che riprenderanno le attivita\u0300 dal 4 maggio la maggior parte e\u0300 dipendente, over 50 e occupato al Nord-Italia: la fotografia scattata dalla Fondazione Studi Consulenti del Lavoro sulla ripresa e gli effetti inattesi Roma, 2 maggio 2020 \u2013 Sono 4,4 milioni i lavoratori che dal 4 maggio, secondo quanto stabilito [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/i-paradossi-della-fase-2-tornano-al-lavoro-piu-over-50-che-giovani\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-02T14:57:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-02T14:58:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/Lavoro5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"510\" \/>\n\t<meta property=\"og:image:height\" content=\"340\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/i-paradossi-della-fase-2-tornano-al-lavoro-piu-over-50-che-giovani\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/i-paradossi-della-fase-2-tornano-al-lavoro-piu-over-50-che-giovani\/\",\"name\":\"I paradossi della Fase 2: tornano al lavoro piu\u0300 over 50 che giovani -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/i-paradossi-della-fase-2-tornano-al-lavoro-piu-over-50-che-giovani\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/i-paradossi-della-fase-2-tornano-al-lavoro-piu-over-50-che-giovani\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/Lavoro5.jpg\",\"datePublished\":\"2020-05-02T14:57:39+00:00\",\"dateModified\":\"2020-05-02T14:58:34+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/i-paradossi-della-fase-2-tornano-al-lavoro-piu-over-50-che-giovani\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/i-paradossi-della-fase-2-tornano-al-lavoro-piu-over-50-che-giovani\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/i-paradossi-della-fase-2-tornano-al-lavoro-piu-over-50-che-giovani\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/Lavoro5.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/Lavoro5.jpg\",\"width\":510,\"height\":340},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/i-paradossi-della-fase-2-tornano-al-lavoro-piu-over-50-che-giovani\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"I paradossi della Fase 2: tornano al lavoro piu\u0300 over 50 che giovani\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"I paradossi della Fase 2: tornano al lavoro piu\u0300 over 50 che giovani -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/i-paradossi-della-fase-2-tornano-al-lavoro-piu-over-50-che-giovani\/","og_locale":"it_IT","og_type":"article","og_title":"I paradossi della Fase 2: tornano al lavoro piu\u0300 over 50 che giovani -","og_description":"Dei 4,4 milioni di italiani che riprenderanno le attivita\u0300 dal 4 maggio la maggior parte e\u0300 dipendente, over 50 e occupato al Nord-Italia: la fotografia scattata dalla Fondazione Studi Consulenti del Lavoro sulla ripresa e gli effetti inattesi Roma, 2 maggio 2020 \u2013 Sono 4,4 milioni i lavoratori che dal 4 maggio, secondo quanto stabilito [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/i-paradossi-della-fase-2-tornano-al-lavoro-piu-over-50-che-giovani\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2020-05-02T14:57:39+00:00","article_modified_time":"2020-05-02T14:58:34+00:00","og_image":[{"width":510,"height":340,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/Lavoro5.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/i-paradossi-della-fase-2-tornano-al-lavoro-piu-over-50-che-giovani\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/i-paradossi-della-fase-2-tornano-al-lavoro-piu-over-50-che-giovani\/","name":"I paradossi della Fase 2: tornano al lavoro piu\u0300 over 50 che giovani -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/i-paradossi-della-fase-2-tornano-al-lavoro-piu-over-50-che-giovani\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/i-paradossi-della-fase-2-tornano-al-lavoro-piu-over-50-che-giovani\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/Lavoro5.jpg","datePublished":"2020-05-02T14:57:39+00:00","dateModified":"2020-05-02T14:58:34+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/i-paradossi-della-fase-2-tornano-al-lavoro-piu-over-50-che-giovani\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/i-paradossi-della-fase-2-tornano-al-lavoro-piu-over-50-che-giovani\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/i-paradossi-della-fase-2-tornano-al-lavoro-piu-over-50-che-giovani\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/Lavoro5.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/Lavoro5.jpg","width":510,"height":340},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/i-paradossi-della-fase-2-tornano-al-lavoro-piu-over-50-che-giovani\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"I paradossi della Fase 2: tornano al lavoro piu\u0300 over 50 che giovani"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/3043"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=3043"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/3043\/revisions"}],"predecessor-version":[{"id":3044,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/3043\/revisions\/3044"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/1600"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=3043"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=3043"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=3043"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}