{"id":3054,"date":"2020-05-05T09:52:18","date_gmt":"2020-05-05T07:52:18","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=3054"},"modified":"2020-05-05T09:52:18","modified_gmt":"2020-05-05T07:52:18","slug":"mini-prestiti-fino-a-25mila-sono-stati-un-flop","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/mini-prestiti-fino-a-25mila-sono-stati-un-flop\/","title":{"rendered":"Mini prestiti fino a 25mila sono stati un flop"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">I<\/span> mini prestiti fino a 25 mila euro introdotti dal \u201cdecreto liquidit\u00e0\u201d a sostegno dei liberi professionisti, dei lavoratori autonomi e delle Pmi non hanno riscosso l\u2019interesse sperato. Almeno sino ad ora.<\/p>\n<p>A dirlo \u00e8 la CGIA che ha riscontrato che fino allo scorso 30 aprile le banche hanno fatto pervenire al Fondo di garanzia del Mediocredito Centrale 45.703 domande. Ebbene, se teniamo conto che la platea delle imprese e dei liberi professionisti interessati per legge da questa misura \u00e8 costituita da oltre 5.250.000 attivit\u00e0, vuol dire che solo lo 0,9 per cento di queste ultime ha fatto ricorso a questa misura.<\/p>\n<p>\u201cQuesto flop \u2013 segnala il coordinatore dell\u2019Ufficio studi Paolo Zabeo \u2013 era prevedibile. Tantissime partite Iva sono state obbligate a chiudere temporaneamente per legge e successivamente, a seguito delle richieste di credito sollevate dalle stesse, il Governo gli ha teso una mano con il decreto liquidit\u00e0, costringendole a indebitarsi con le banche. Una soluzione che, ovviamente, non poteva riscuotere l\u2019entusiasmo degli interessati.<\/p>\n<p>A nostro avviso, invece, in questo momento particolare le piccole imprese dovrebbero essere sorrette con contributi a fondo perduto. In altre parole, ad indebitarsi \u00e8 bene che lo faccia lo Stato e non le imprese che con troppi debiti, purtroppo, rischiano di implodere\u201d.<\/p>\n<p>Tornando ai dati sulla presentazione delle domande al Fondo di garanzia, non \u00e8 da escludere che il numero ufficiale (45.703) pervenuto al Fondo di garanzia sia sottostimato. Molte richieste, infatti, sono ancora in fase di lavorazione presso gli istituti di credito.<\/p>\n<p>Tanti imprenditori, infatti, hanno inviato la domanda non correttamente e sono stati invitati a modificarla\/integrarla. Pertanto, se conteggiassimo anche le richieste che sono \u201cbloccate\u201d presso gli sportelli bancari che, secondo indiscrezioni giornalistiche, ammonterebbero a circa 250 mila, l\u2019incidenza percentuale delle aziende interessate dal micro prestito fino a 25 mila euro rimarrebbe comunque bassissima. Una misera percentuale del 5,6 per cento.<\/p>\n<div class=\"page\" title=\"Page 2\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>\u201cIn un momento di emergenza nazionale non e\u0300 il caso di fare polemiche \u2013 dichiara il segretario della CGIA Renato Mason &#8211; tuttavia, e\u0300 necessario consentire alle Pmi di accedere alle risorse con piu\u0300 facilita\u0300. A nostro avviso il modello da seguire e\u0300 quello tedesco. A parita\u0300 di costi, o quasi, ma con fatturati in caduta libera, se nelle prossime settimane le aziende non avranno a disposizione la liquidita\u0300 necessaria per far fronte alle esigenze di ogni giorno, nel giro di qualche mese molte di queste saranno costrette a chiudere definitivamente i battenti\u201d.<\/p>\n<p>Come riportato piu\u0300 sopra, la CGIA auspica che anche in Italia si riproduca l\u2019esperienza maturata in Germania in queste ultime settimane. Per sostenere le piccole imprese, infatti, il governo federale e i la\u0308nder tedeschi hanno erogato, alle realta\u0300 con meno di 15 addetti, fino a 15 mila euro a fondo perduto. Una misura di grande attenzione alle piccolissime attivita\u0300 che sia la Banca d\u2019Italia (nell\u2019audizione alla Camera dei Deputati di lunedi\u0300 27 aprile 2020) sia il Commissario Europeo al Mercato Interno e ai Servizi, Thierry Breton1, hanno suggerito al nostro Governo di adottare anche in Italia.<\/p>\n<p>Le piccole e micro imprese, comunque, sono da sempre fortemente indebitate e a corto di liquidita\u0300. Nel 2019, infatti, registravano livelli di indebitamento che non possono essere ritoccati ulteriormente all\u2019insu\u0300, come invece \u201csuggerito\u201d dal \u201cdecreto liquidita\u0300\u201d. Quelle con meno di 5<\/p>\n<div class=\"page\" title=\"Page 3\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>addetti, ad esempio, presentavano una esposizione bancaria media (in bonis) di 115 mila euro per affidato. Un importo che se aumentato rischia di rendere insolvibili moltissime attivita\u0300.<\/p>\n<p>Tuttavia, non e\u0300 solo la mancanza di credito a preoccupare la CGIA, ma anche le previsioni dei consumi delle famiglie italiane per l\u2019anno in corso. Secondo il Def 2020, infatti, la caduta sara\u0300 pari al 7,2 per cento; in termini assoluti il crollo degli acquisti rispetto al 2019 sara\u0300 di circa 75 miliardi e a farne le spese saranno soprattutto gli artigiani, i piccoli commercianti e i lavoratori autonomi che vivono quasi esclusivamente dei consumi delle famiglie. Insomma, i fatturati di queste piccole attivita\u0300 sono destinati a cadere rovinosamente, trascinando verso la chiusura definitiva tantissimi negozi di vicinato.<\/p>\n<p>Sul fronte della proteste che stanno montando in tutto il Paese, la CGIA denuncia i gravi errori di comunicazione compiuti dal Premier Conte domenica scorsa (26 aprile 2020). Solo due giorni dopo la pubblicazione del DPCM, gli italiani sono venuti a conoscenza dell\u2019esistenza di un dossier dell\u2019Istituto Superiore della Sanita\u0300 che, tramite una serie di proiezioni, allertava che una riapertura totale delle attivita\u0300 a inizio maggio avrebbe potuto causare oltre 150 mila ricoveri nei reparti di terapia intensiva gia\u0300 a partire dal prossimo 8 giugno.<\/p>\n<p>Siamo certi che se il Presidente del Consiglio avesse citato i risultati di questo studio durante la conferenza stampa, nessuno avrebbe criticato la decisione di scaglionare le aperture delle aziende artigianali e commerciali. Tutti avrebbero capito, invece, il Premier ha fatto solo una grande confusione, alimentando ulteriormente il senso di sconforto che attanaglia moltissimi piccoli imprenditori che, loro malgrado, ritorneranno al lavoro, forse, solo fra un mese.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I mini prestiti fino a 25 mila euro introdotti dal \u201cdecreto liquidit\u00e0\u201d a sostegno dei liberi professionisti, dei lavoratori autonomi e delle Pmi non hanno riscosso l\u2019interesse sperato. Almeno sino ad ora. A dirlo \u00e8 la CGIA che ha riscontrato che fino allo scorso 30 aprile le banche hanno fatto pervenire al Fondo di garanzia [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1596,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[162],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mini prestiti fino a 25mila sono stati un flop -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/mini-prestiti-fino-a-25mila-sono-stati-un-flop\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mini prestiti fino a 25mila sono stati un flop -\" \/>\n<meta property=\"og:description\" content=\"I mini prestiti fino a 25 mila euro introdotti dal \u201cdecreto liquidit\u00e0\u201d a sostegno dei liberi professionisti, dei lavoratori autonomi e delle Pmi non hanno riscosso l\u2019interesse sperato. Almeno sino ad ora. A dirlo \u00e8 la CGIA che ha riscontrato che fino allo scorso 30 aprile le banche hanno fatto pervenire al Fondo di garanzia [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/mini-prestiti-fino-a-25mila-sono-stati-un-flop\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-05T07:52:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/soldi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"638\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/mini-prestiti-fino-a-25mila-sono-stati-un-flop\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/mini-prestiti-fino-a-25mila-sono-stati-un-flop\/\",\"name\":\"Mini prestiti fino a 25mila sono stati un flop -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/mini-prestiti-fino-a-25mila-sono-stati-un-flop\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/mini-prestiti-fino-a-25mila-sono-stati-un-flop\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/soldi.jpg\",\"datePublished\":\"2020-05-05T07:52:18+00:00\",\"dateModified\":\"2020-05-05T07:52:18+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/mini-prestiti-fino-a-25mila-sono-stati-un-flop\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/mini-prestiti-fino-a-25mila-sono-stati-un-flop\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/mini-prestiti-fino-a-25mila-sono-stati-un-flop\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/soldi.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/soldi.jpg\",\"width\":960,\"height\":638},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/mini-prestiti-fino-a-25mila-sono-stati-un-flop\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mini prestiti fino a 25mila sono stati un flop\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mini prestiti fino a 25mila sono stati un flop -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/mini-prestiti-fino-a-25mila-sono-stati-un-flop\/","og_locale":"it_IT","og_type":"article","og_title":"Mini prestiti fino a 25mila sono stati un flop -","og_description":"I mini prestiti fino a 25 mila euro introdotti dal \u201cdecreto liquidit\u00e0\u201d a sostegno dei liberi professionisti, dei lavoratori autonomi e delle Pmi non hanno riscosso l\u2019interesse sperato. Almeno sino ad ora. A dirlo \u00e8 la CGIA che ha riscontrato che fino allo scorso 30 aprile le banche hanno fatto pervenire al Fondo di garanzia [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/mini-prestiti-fino-a-25mila-sono-stati-un-flop\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2020-05-05T07:52:18+00:00","og_image":[{"width":960,"height":638,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/soldi.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/mini-prestiti-fino-a-25mila-sono-stati-un-flop\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/mini-prestiti-fino-a-25mila-sono-stati-un-flop\/","name":"Mini prestiti fino a 25mila sono stati un flop -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/mini-prestiti-fino-a-25mila-sono-stati-un-flop\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/mini-prestiti-fino-a-25mila-sono-stati-un-flop\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/soldi.jpg","datePublished":"2020-05-05T07:52:18+00:00","dateModified":"2020-05-05T07:52:18+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/mini-prestiti-fino-a-25mila-sono-stati-un-flop\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/mini-prestiti-fino-a-25mila-sono-stati-un-flop\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/mini-prestiti-fino-a-25mila-sono-stati-un-flop\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/soldi.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/soldi.jpg","width":960,"height":638},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/mini-prestiti-fino-a-25mila-sono-stati-un-flop\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Mini prestiti fino a 25mila sono stati un flop"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/3054"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=3054"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/3054\/revisions"}],"predecessor-version":[{"id":3055,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/3054\/revisions\/3055"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/1596"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=3054"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=3054"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=3054"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}