{"id":3194,"date":"2020-05-26T11:36:28","date_gmt":"2020-05-26T09:36:28","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=3194"},"modified":"2020-05-26T11:36:28","modified_gmt":"2020-05-26T09:36:28","slug":"fase-2-unimpresa-serve-oltre-1-miliardo-per-rifinanziare-impresa-sicura","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/fase-2-unimpresa-serve-oltre-1-miliardo-per-rifinanziare-impresa-sicura\/","title":{"rendered":"Fase 2, Unimpresa: serve oltre 1 miliardo per rifinanziare\u00a0\u201cImpresa Sicura\u201d"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">C<\/span><em>hiediamo che il Governo provveda a un immediato rifinanziamento, di oltre 1 miliardo di euro, del bando per \u201cImpresa Sicura\u201d tenendo conto delle esigenze reali delle imprese colpite da una crisi economica che non conosce precedenti e che ora devono far fronte a spese ingenti per acquistare i dispositivi di protezione individuale, fondamentali per ripartire e contenere i rischi legati all\u2019epidemia Covid-19<\/em>.<\/p>\n<p>\u00c8 quanto dichiara il vicepresidente di Unimpresa, Salvo Politino, spiegando che \u00aba fronte di una dotazione finanziaria di 50 milioni di euro, sono state presentate richieste, da parte delle imprese, per un totale di oltre 1,2 miliardi e ci\u00f2 dimostra come vi sia la necessit\u00e0 di reperire risorse a fondo perduto per fare fronte alle disposizioni di sicurezza previste dalla Fase 2 del Covid-19. Purtroppo, ancora una volta, su una misura che doveva rappresentare un aiuto concreto per le imprese, sono state stanziate somme irrisorie. Occorre soddisfare tutte le richieste presentate\u00bb.<\/p>\n<p>I fondi inizialmente destinati a \u201cImpresa Sicura\u201d, l\u2019incentivo del governo destinato alle aziende per gli acquisti di dispositivi di protezione individuale (Dpi) sono esauriti in un minuto, lo scorso 11 maggio.<\/p>\n<p>\u00abIl bando \u00e8 stato aperto alle ore 9.00 e alle 9.01 i soldi erano gi\u00e0 finiti\u00bb spiega Politino. Il totale delle domande presentate \u00e8 stato 249.681 di cui 208.826 valide per un importo complessivo richiesto di 1.207.561.075 euro. Il numero eccessivo delle domande presentate ha esaurito rapidamente l\u2019intero\u00a0<em>plafond<\/em>\u00a0delle risorse finanziarie previste dalla misura. La percentuale di domande accolte sul totale di quelle presentate \u00e8 pari all\u20191,26%.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chiediamo che il Governo provveda a un immediato rifinanziamento, di oltre 1 miliardo di euro, del bando per \u201cImpresa Sicura\u201d tenendo conto delle esigenze reali delle imprese colpite da una crisi economica che non conosce precedenti e che ora devono far fronte a spese ingenti per acquistare i dispositivi di protezione individuale, fondamentali per ripartire [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2032,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[162],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fase 2, Unimpresa: serve oltre 1 miliardo per rifinanziare\u00a0\u201cImpresa Sicura\u201d -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/fase-2-unimpresa-serve-oltre-1-miliardo-per-rifinanziare-impresa-sicura\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fase 2, Unimpresa: serve oltre 1 miliardo per rifinanziare\u00a0\u201cImpresa Sicura\u201d -\" \/>\n<meta property=\"og:description\" content=\"Chiediamo che il Governo provveda a un immediato rifinanziamento, di oltre 1 miliardo di euro, del bando per \u201cImpresa Sicura\u201d tenendo conto delle esigenze reali delle imprese colpite da una crisi economica che non conosce precedenti e che ora devono far fronte a spese ingenti per acquistare i dispositivi di protezione individuale, fondamentali per ripartire [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/fase-2-unimpresa-serve-oltre-1-miliardo-per-rifinanziare-impresa-sicura\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-26T09:36:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/impresa-lavoro-ufficio-banca.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/fase-2-unimpresa-serve-oltre-1-miliardo-per-rifinanziare-impresa-sicura\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/fase-2-unimpresa-serve-oltre-1-miliardo-per-rifinanziare-impresa-sicura\/\",\"name\":\"Fase 2, Unimpresa: serve oltre 1 miliardo per rifinanziare\u00a0\u201cImpresa Sicura\u201d -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/fase-2-unimpresa-serve-oltre-1-miliardo-per-rifinanziare-impresa-sicura\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/fase-2-unimpresa-serve-oltre-1-miliardo-per-rifinanziare-impresa-sicura\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/impresa-lavoro-ufficio-banca.jpg\",\"datePublished\":\"2020-05-26T09:36:28+00:00\",\"dateModified\":\"2020-05-26T09:36:28+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/fase-2-unimpresa-serve-oltre-1-miliardo-per-rifinanziare-impresa-sicura\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/fase-2-unimpresa-serve-oltre-1-miliardo-per-rifinanziare-impresa-sicura\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/fase-2-unimpresa-serve-oltre-1-miliardo-per-rifinanziare-impresa-sicura\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/impresa-lavoro-ufficio-banca.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/impresa-lavoro-ufficio-banca.jpg\",\"width\":960,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/fase-2-unimpresa-serve-oltre-1-miliardo-per-rifinanziare-impresa-sicura\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fase 2, Unimpresa: serve oltre 1 miliardo per rifinanziare\u00a0\u201cImpresa Sicura\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fase 2, Unimpresa: serve oltre 1 miliardo per rifinanziare\u00a0\u201cImpresa Sicura\u201d -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/fase-2-unimpresa-serve-oltre-1-miliardo-per-rifinanziare-impresa-sicura\/","og_locale":"it_IT","og_type":"article","og_title":"Fase 2, Unimpresa: serve oltre 1 miliardo per rifinanziare\u00a0\u201cImpresa Sicura\u201d -","og_description":"Chiediamo che il Governo provveda a un immediato rifinanziamento, di oltre 1 miliardo di euro, del bando per \u201cImpresa Sicura\u201d tenendo conto delle esigenze reali delle imprese colpite da una crisi economica che non conosce precedenti e che ora devono far fronte a spese ingenti per acquistare i dispositivi di protezione individuale, fondamentali per ripartire [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/fase-2-unimpresa-serve-oltre-1-miliardo-per-rifinanziare-impresa-sicura\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2020-05-26T09:36:28+00:00","og_image":[{"width":960,"height":640,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/impresa-lavoro-ufficio-banca.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/fase-2-unimpresa-serve-oltre-1-miliardo-per-rifinanziare-impresa-sicura\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/fase-2-unimpresa-serve-oltre-1-miliardo-per-rifinanziare-impresa-sicura\/","name":"Fase 2, Unimpresa: serve oltre 1 miliardo per rifinanziare\u00a0\u201cImpresa Sicura\u201d -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/fase-2-unimpresa-serve-oltre-1-miliardo-per-rifinanziare-impresa-sicura\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/fase-2-unimpresa-serve-oltre-1-miliardo-per-rifinanziare-impresa-sicura\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/impresa-lavoro-ufficio-banca.jpg","datePublished":"2020-05-26T09:36:28+00:00","dateModified":"2020-05-26T09:36:28+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/fase-2-unimpresa-serve-oltre-1-miliardo-per-rifinanziare-impresa-sicura\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/fase-2-unimpresa-serve-oltre-1-miliardo-per-rifinanziare-impresa-sicura\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/fase-2-unimpresa-serve-oltre-1-miliardo-per-rifinanziare-impresa-sicura\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/impresa-lavoro-ufficio-banca.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/impresa-lavoro-ufficio-banca.jpg","width":960,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/fase-2-unimpresa-serve-oltre-1-miliardo-per-rifinanziare-impresa-sicura\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Fase 2, Unimpresa: serve oltre 1 miliardo per rifinanziare\u00a0\u201cImpresa Sicura\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/3194"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=3194"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/3194\/revisions"}],"predecessor-version":[{"id":3195,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/3194\/revisions\/3195"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/2032"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=3194"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=3194"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=3194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}