{"id":3251,"date":"2020-06-01T17:26:35","date_gmt":"2020-06-01T15:26:35","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=3251"},"modified":"2020-06-01T17:26:35","modified_gmt":"2020-06-01T15:26:35","slug":"mef-e-cdp-firmano-convenzione-per-anticipazioni-di-liquidita","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/mef-e-cdp-firmano-convenzione-per-anticipazioni-di-liquidita\/","title":{"rendered":"Mef e Cdp firmano convenzione per anticipazioni di liquidit\u00e0"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">I<\/span>l Ministero dell\u2019economia e delle Finanze e la Cassa Depositi e Prestiti hanno sottoscritto la Convenzione prevista dall\u2019articolo 115 del DL n. 34\/2020 (c.d. Decreto Rilancio) per il pagamento dei debiti certi, liquidi ed esigibili degli Enti locali, delle Regioni e delle Province Autonome, maturati alla data del 31 dicembre 2019, relativi a somministrazioni, forniture, appalti e a obbligazioni per prestazioni professionali. Sono stati altres\u00ec approvati i \u201cContratti tipo\u201d per la concessione delle relative anticipazioni di liquidit\u00e0 in favore degli Enti.<\/p>\n<p>Le richieste delle anticipazioni, che avranno durata fino ad un massimo di trenta anni e saranno regolate ad un tasso fisso dell\u20191,226%, dovranno pervenire a Cassa Depositi e Prestiti nel periodo compreso tra il 15 giugno e il 7 luglio 2020.<\/p>\n<p>La misura si affianca alle ulteriori iniziative governative varate per rispondere alle esigenze dei territori, nell\u2019attuale contesto di crisi sanitaria. A beneficiare dell\u2019accelerazione del pagamento dei debiti degli enti territoriali saranno le imprese e gli altri creditori della P.A, che potranno cos\u00ec ottenere un significativo importo di risorse (12 miliardi di euro): 8 miliardi saranno destinati al pagamento di debiti commerciali degli Enti locali, delle Regioni e delle Province Autonome e i restanti 4 miliardi serviranno per i debiti degli enti del servizio sanitario nazionale. Cassa Depositi e Prestiti comunicher\u00e0 all\u2019ente beneficiario la concessione dell\u2019anticipazione entro il 24 luglio 2020.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Ministero dell\u2019economia e delle Finanze e la Cassa Depositi e Prestiti hanno sottoscritto la Convenzione prevista dall\u2019articolo 115 del DL n. 34\/2020 (c.d. Decreto Rilancio) per il pagamento dei debiti certi, liquidi ed esigibili degli Enti locali, delle Regioni e delle Province Autonome, maturati alla data del 31 dicembre 2019, relativi a somministrazioni, forniture, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":164,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[162],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mef e Cdp firmano convenzione per anticipazioni di liquidit\u00e0 -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/mef-e-cdp-firmano-convenzione-per-anticipazioni-di-liquidita\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mef e Cdp firmano convenzione per anticipazioni di liquidit\u00e0 -\" \/>\n<meta property=\"og:description\" content=\"Il Ministero dell\u2019economia e delle Finanze e la Cassa Depositi e Prestiti hanno sottoscritto la Convenzione prevista dall\u2019articolo 115 del DL n. 34\/2020 (c.d. Decreto Rilancio) per il pagamento dei debiti certi, liquidi ed esigibili degli Enti locali, delle Regioni e delle Province Autonome, maturati alla data del 31 dicembre 2019, relativi a somministrazioni, forniture, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/mef-e-cdp-firmano-convenzione-per-anticipazioni-di-liquidita\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-01T15:26:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/07\/soldi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/mef-e-cdp-firmano-convenzione-per-anticipazioni-di-liquidita\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/mef-e-cdp-firmano-convenzione-per-anticipazioni-di-liquidita\/\",\"name\":\"Mef e Cdp firmano convenzione per anticipazioni di liquidit\u00e0 -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/mef-e-cdp-firmano-convenzione-per-anticipazioni-di-liquidita\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/mef-e-cdp-firmano-convenzione-per-anticipazioni-di-liquidita\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/07\/soldi.jpg\",\"datePublished\":\"2020-06-01T15:26:35+00:00\",\"dateModified\":\"2020-06-01T15:26:35+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/mef-e-cdp-firmano-convenzione-per-anticipazioni-di-liquidita\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/mef-e-cdp-firmano-convenzione-per-anticipazioni-di-liquidita\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/mef-e-cdp-firmano-convenzione-per-anticipazioni-di-liquidita\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/07\/soldi.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/07\/soldi.jpg\",\"width\":960,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/mef-e-cdp-firmano-convenzione-per-anticipazioni-di-liquidita\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mef e Cdp firmano convenzione per anticipazioni di liquidit\u00e0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mef e Cdp firmano convenzione per anticipazioni di liquidit\u00e0 -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/mef-e-cdp-firmano-convenzione-per-anticipazioni-di-liquidita\/","og_locale":"it_IT","og_type":"article","og_title":"Mef e Cdp firmano convenzione per anticipazioni di liquidit\u00e0 -","og_description":"Il Ministero dell\u2019economia e delle Finanze e la Cassa Depositi e Prestiti hanno sottoscritto la Convenzione prevista dall\u2019articolo 115 del DL n. 34\/2020 (c.d. Decreto Rilancio) per il pagamento dei debiti certi, liquidi ed esigibili degli Enti locali, delle Regioni e delle Province Autonome, maturati alla data del 31 dicembre 2019, relativi a somministrazioni, forniture, [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/mef-e-cdp-firmano-convenzione-per-anticipazioni-di-liquidita\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2020-06-01T15:26:35+00:00","og_image":[{"width":960,"height":600,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/07\/soldi.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/mef-e-cdp-firmano-convenzione-per-anticipazioni-di-liquidita\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/mef-e-cdp-firmano-convenzione-per-anticipazioni-di-liquidita\/","name":"Mef e Cdp firmano convenzione per anticipazioni di liquidit\u00e0 -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/mef-e-cdp-firmano-convenzione-per-anticipazioni-di-liquidita\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/mef-e-cdp-firmano-convenzione-per-anticipazioni-di-liquidita\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/07\/soldi.jpg","datePublished":"2020-06-01T15:26:35+00:00","dateModified":"2020-06-01T15:26:35+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/mef-e-cdp-firmano-convenzione-per-anticipazioni-di-liquidita\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/mef-e-cdp-firmano-convenzione-per-anticipazioni-di-liquidita\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/mef-e-cdp-firmano-convenzione-per-anticipazioni-di-liquidita\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/07\/soldi.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/07\/soldi.jpg","width":960,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/mef-e-cdp-firmano-convenzione-per-anticipazioni-di-liquidita\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Mef e Cdp firmano convenzione per anticipazioni di liquidit\u00e0"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/3251"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=3251"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/3251\/revisions"}],"predecessor-version":[{"id":3252,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/3251\/revisions\/3252"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/164"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=3251"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=3251"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=3251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}