{"id":3260,"date":"2020-06-03T12:49:23","date_gmt":"2020-06-03T10:49:23","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=3260"},"modified":"2020-06-03T18:48:11","modified_gmt":"2020-06-03T16:48:11","slug":"le-imprese-hanno-bisogno-di-credito-piu-che-raddoppiate-le-richieste","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/le-imprese-hanno-bisogno-di-credito-piu-che-raddoppiate-le-richieste\/","title":{"rendered":"Le imprese hanno bisogno di credito, pi\u00f9 che raddoppiate le richieste"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">D<\/span>alle elaborazioni effettuate sul patrimonio informativo di EURISC &#8211; il Sistema di Informazioni Creditizie gestito da CRIF \u2013 emergono chiari segnali della voglia di ripartire da parte delle imprese italiane.<\/p>\n<p>Nello specifico il numero delle richieste di credito presentate nelle ultime settimane rispetto a quella compresa tra il 9 e il 15 marzo, quando sono entrate in vigore le misure di lockdown per contenere la diffisione della pandemia, hanno fatto registrare una violenta impennata, con un +290% in quella compresa tra il 27 aprile e il 3 maggio e rispettivamente un +247% e un +249% nelle due successive.<\/p>\n<p>Del resto, da una recente analisi condotta da CRIF Ratings \u00e8 emerso che il 37% delle imprese si sta trovando ad affrontare questa fase di emergenza partendo da situazioni di liquidit\u00e0 gi\u00e0 delicate, mentre un ulteriore 7% non ha particolari margini di manovra, determinando un fabbisogno di liquidit\u00e0 pari a 60 miliardi di Euro, di cui solo 15 miliardi potranno essere coperti dai flussi di cassa a fronte di 45 miliardi che dovranno arrivare dal mercato bancario e\/o dei capitali.<\/p>\n<p>Prendendo come valore di riferimento (100%) la settimana compresa tra il 9 e il 15 marzo scorso, che ancora beneficiava delle istruttorie imbastite nelle settimane precedenti il lockdown, la debolezza delle richieste \u00e8 perdurata ininterrottamente da met\u00e0 marzo a met\u00e0 aprile, con il picco negativo registrato nella settimana compresa tra il 13 e il 19 aprile, quando i volumi si sono attestati ial 70% di quelli pre-lockdown. Dalla settimana successiva \u00e8 iniziato un percorso di deciso recupero, seppur con intensit\u00e0 differenti a seconda delle diverse forme tecniche considerate nell\u2019analisi di CRIF.<\/p>\n<p>Tornando all\u2019analisi sull\u2019andamento delle richieste di credito presentate dalle imprese italiane nelle ultime 10 settimane, dal grafico seguente si evince chiaramente come nelle prime settimane a seguito del blocco del Paese si sia registrata una frenata, pi\u00f9 o meno accentuata a seconda delle diverse forme tecniche considerate, cui \u00e8 seguita una sostanziale stabilizzazione dei volumi per alcune settimane, con le imprese che hanno adottato un atteggiamento prudente in attesa anche di pi\u00f9 chiare disposizioni da parte del Governo sulle iniziative disposte per favorire la ripresa.<\/p>\n<p>A partire dalla settimana del 20 aprile, per\u00f2, si registra una brusca inversione di tendenza che porta a una impennata delle richieste presentate agli istituti di credito, con volumi ben al di sopra di quelli pre-lockdown.<\/p>\n<p>La dinamica registrata non \u00e8 per\u00f2 omogenea e mostra accentuazioni differenti sia per quanto riguarda l\u2019entit\u00e0 sia la velocit\u00e0 di recupero.<\/p>\n<p>Un altro dato interessante che emerge dall\u2019analisi prodotta da CRIF riguarda la tipologia di intermediario finanziario al quale le imprese si sono maggiormente rivolti in queste settimane. Nello specifico, anche nelle settimane immediatamente successive al lockdown le Banche maggiori, quelle minori e i Confidi hanno mostrato volumi di richieste non troppo dissimili da quelli considerati nella settimana indice, ritornando sui valori precedenti abbastanza velocemente e arrivando a superarli abbondantemente nelle ultime 4 settimane.<\/p>\n<p>Decisamente pi\u00f9 graduale ed articolato il percorso di recupero evidenziato dalle societ\u00e0 di renting, dalle finanziarie auto e, soprattutto, dalle societ\u00e0 finanziarie e da quelle di leasing, con queste ultime due che ancora mostrano un gap rispetto alla settimana indice seppur con volumi in costante recupero.<\/p>\n<p>Per quanto riguarda invece i prestiti personali, l\u2019andamento mostra un recupero pi\u00f9 veloce e organico, con volumi di richieste che gi\u00e0 nella settimana del 30 marzo erano tornati sui valori precedenti il lockdown, salvo poi andare ben oltre il 150% nelle ultime 3 settimane di osservazione.<\/p>\n<p>Dinamica molto diversa dalle precedenti, invece, \u00e8 quella fatta registrare dai prestiti finalizzati all\u2019acquisto di beni e servizi. Nello specifico, questa forma tecnica \u00e8 quella che pi\u00f9 di tutte ha risentito della chiusura delle attivit\u00e0 disposta dal Governo per fronteggiare la diffusione dell\u2019epidemia, con una evidente debolezza perdurata per oltre un mese e facendo segnare un picco negativo del 19%. La dinamica in atta fa per\u00f2 emergere un chiaro recupero, con i volumi che nelle ultime settimane di osservazione si sono attestati rispettivamente al 150% e al 213% rispetto a quelli della settimana indice.<\/p>\n<p>Segnali meno incoraggianti arrivano dal fronte delle richieste di carte di credito, che dopo la il lockdown per diverse settimane si sono attestate su volumi pari a circa la met\u00e0 di quelli precedenti pur facendo segnare un lento seppur continuo recupero a partire da fine aprile.<\/p>\n<p>Tra tutte le forme tecniche di credito alle imprese che sono state considerate nell\u2019analisi di CRIF sono per\u00f2 le richieste di fidi ad essere risultate la tipologia che ha meno risentito degli impatti dell\u2019emergenza Coronavirus, avendo contenuto la flessione nelle settimane immediatamente successive al lockdown ed avendo mostrato una significativa accelerazione gi\u00e0 a partire dalla settimana compresa tra il 20 e il 26 aprile, attestandosi su livelli 2\/3 volte superiori a quelli precedenti il lockdown di inizio marzo.<\/p>\n<p>\u201cIn Italia quasi la met\u00e0 delle imprese si sta trovando ad affrontare la crisi causata dalla pandemia globale partendo da condizioni finanziarie gi\u00e0 precarie e nei prossimi mesi avranno bisogno di robuste iniezioni di liquidit\u00e0 per ripartire. Questo spiega le ragioni per cui, dopo una fase di fisiologico stallo successivo al varo del lockdown da parte del Governo, abbiano ripreso a rivolgersi in modo vigoroso agli intermefiari finanziari \u2013 commenta Antonio Deledda, Direttore Credit Bureau di CRIF -.<\/p>\n<p>Uno dei fattori cruciali in grado di sostenere la propensione a richiedere credito \u00e8 rappresentato dalla concreta possibilit\u00e0 di vederselo erogare per cui \u00e8 fondamenmtale che le aziende di credito coninuino a disporre degli strumenti e delle informazioni in grado di attestare la sostenibilit\u00e0 del finanziamento, scongiurando il rischio che irrigidiscano i processi di erogazione e le condizioni di offerta\u201d.<\/p>\n<p>Il dato realmente ecltatante \u00e8 per\u00f2 quello relativo alle societ\u00e0 di factoring, che dopo aver fatto registrare un picco di richieste nelle due settimane successive al lockdown cui era seguito un picco negativo tra il 6 e il 14 aprile, nelle ultime due settimane osservate hanno evidenziato volumi pari rispettivamente 649% e 895% rispetto alla settimana indice.<\/p>\n<p>L\u2019analisi di dettaglio per tipologia di creditI richiestI dalle imprese<br \/>\nEntrando maggiormente nel dettaglio, per quanto riguarda i Mutui immobiliari, dopo aver visto le richieste delle imprese quasi dimezzarsi nella 13^ settimana dell\u2019anno, quando i volumi si sono attestati al 57% rispetto a quelli che si registravano prima del lockdown, a partire dalla settimana iniziata il 20 aprile le richieste sono balzate al 285% rispetto alla settimana di riferimento, per arrivare poi ad un picco pari a 826% in quella compresa tra il 27 aprile e il 3 maggio e riipiegare parzialmente nelle due successive (rispettivamente al 608% e al 505%).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dalle elaborazioni effettuate sul patrimonio informativo di EURISC &#8211; il Sistema di Informazioni Creditizie gestito da CRIF \u2013 emergono chiari segnali della voglia di ripartire da parte delle imprese italiane. Nello specifico il numero delle richieste di credito presentate nelle ultime settimane rispetto a quella compresa tra il 9 e il 15 marzo, quando sono [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":21,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Le imprese hanno bisogno di credito, pi\u00f9 che raddoppiate le richieste -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/le-imprese-hanno-bisogno-di-credito-piu-che-raddoppiate-le-richieste\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le imprese hanno bisogno di credito, pi\u00f9 che raddoppiate le richieste -\" \/>\n<meta property=\"og:description\" content=\"Dalle elaborazioni effettuate sul patrimonio informativo di EURISC &#8211; il Sistema di Informazioni Creditizie gestito da CRIF \u2013 emergono chiari segnali della voglia di ripartire da parte delle imprese italiane. Nello specifico il numero delle richieste di credito presentate nelle ultime settimane rispetto a quella compresa tra il 9 e il 15 marzo, quando sono [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/le-imprese-hanno-bisogno-di-credito-piu-che-raddoppiate-le-richieste\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-03T10:49:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-03T16:48:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/07\/p2-e1531909427362.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1065\" \/>\n\t<meta property=\"og:image:height\" content=\"782\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/le-imprese-hanno-bisogno-di-credito-piu-che-raddoppiate-le-richieste\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/le-imprese-hanno-bisogno-di-credito-piu-che-raddoppiate-le-richieste\/\",\"name\":\"Le imprese hanno bisogno di credito, pi\u00f9 che raddoppiate le richieste -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/le-imprese-hanno-bisogno-di-credito-piu-che-raddoppiate-le-richieste\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/le-imprese-hanno-bisogno-di-credito-piu-che-raddoppiate-le-richieste\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/07\/p2-e1531909427362.jpg\",\"datePublished\":\"2020-06-03T10:49:23+00:00\",\"dateModified\":\"2020-06-03T16:48:11+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/le-imprese-hanno-bisogno-di-credito-piu-che-raddoppiate-le-richieste\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/le-imprese-hanno-bisogno-di-credito-piu-che-raddoppiate-le-richieste\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/le-imprese-hanno-bisogno-di-credito-piu-che-raddoppiate-le-richieste\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/07\/p2-e1531909427362.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/07\/p2-e1531909427362.jpg\",\"width\":1065,\"height\":782},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/le-imprese-hanno-bisogno-di-credito-piu-che-raddoppiate-le-richieste\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le imprese hanno bisogno di credito, pi\u00f9 che raddoppiate le richieste\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le imprese hanno bisogno di credito, pi\u00f9 che raddoppiate le richieste -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/le-imprese-hanno-bisogno-di-credito-piu-che-raddoppiate-le-richieste\/","og_locale":"it_IT","og_type":"article","og_title":"Le imprese hanno bisogno di credito, pi\u00f9 che raddoppiate le richieste -","og_description":"Dalle elaborazioni effettuate sul patrimonio informativo di EURISC &#8211; il Sistema di Informazioni Creditizie gestito da CRIF \u2013 emergono chiari segnali della voglia di ripartire da parte delle imprese italiane. Nello specifico il numero delle richieste di credito presentate nelle ultime settimane rispetto a quella compresa tra il 9 e il 15 marzo, quando sono [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/le-imprese-hanno-bisogno-di-credito-piu-che-raddoppiate-le-richieste\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2020-06-03T10:49:23+00:00","article_modified_time":"2020-06-03T16:48:11+00:00","og_image":[{"width":1065,"height":782,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/07\/p2-e1531909427362.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/le-imprese-hanno-bisogno-di-credito-piu-che-raddoppiate-le-richieste\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/le-imprese-hanno-bisogno-di-credito-piu-che-raddoppiate-le-richieste\/","name":"Le imprese hanno bisogno di credito, pi\u00f9 che raddoppiate le richieste -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/le-imprese-hanno-bisogno-di-credito-piu-che-raddoppiate-le-richieste\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/le-imprese-hanno-bisogno-di-credito-piu-che-raddoppiate-le-richieste\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/07\/p2-e1531909427362.jpg","datePublished":"2020-06-03T10:49:23+00:00","dateModified":"2020-06-03T16:48:11+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/le-imprese-hanno-bisogno-di-credito-piu-che-raddoppiate-le-richieste\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/le-imprese-hanno-bisogno-di-credito-piu-che-raddoppiate-le-richieste\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/le-imprese-hanno-bisogno-di-credito-piu-che-raddoppiate-le-richieste\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/07\/p2-e1531909427362.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/07\/p2-e1531909427362.jpg","width":1065,"height":782},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/le-imprese-hanno-bisogno-di-credito-piu-che-raddoppiate-le-richieste\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Le imprese hanno bisogno di credito, pi\u00f9 che raddoppiate le richieste"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/3260"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=3260"}],"version-history":[{"count":2,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/3260\/revisions"}],"predecessor-version":[{"id":3263,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/3260\/revisions\/3263"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/21"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=3260"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=3260"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=3260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}