{"id":3266,"date":"2020-06-03T18:52:14","date_gmt":"2020-06-03T16:52:14","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=3266"},"modified":"2020-06-03T18:52:14","modified_gmt":"2020-06-03T16:52:14","slug":"dai-professionisti-10-proposte-per-far-ripartire-il-paese","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/dai-professionisti-10-proposte-per-far-ripartire-il-paese\/","title":{"rendered":"Dai professionisti 10 proposte per far ripartire il Paese"},"content":{"rendered":"<div class=\"page\" title=\"Page 1\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p><span class=\"dropcap dropcap3\">D<\/span>omani gli Stati Generali delle Professioni italiane per ribadire il loro ruolo sussidiario e presentare il \u201cManifesto per la Rinascita dell\u2019Italia\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>23 ordini professionali italiani uniti per dire basta alle discriminazioni nei loro confronti e per ribadire al Governo il loro ruolo economico, sociale e sussidiario. E\u0301 quanto avverra\u0300 domani, 4 giugno, in occasione degli Stati Generali delle Professioni italiane: la piu\u0300 grande manifestazione online di protesta e proposta, che verra\u0300 trasmessa in diretta streaming, dalle 10.30 alle 12.30, sul<a href=\"http:\/\/www.professionitaliane.it\"> sito<\/a>\u00a0 e sul canale Youtube Professioni italiane.<\/p>\n<p>I 2,3 milioni di professionisti chiederanno al decisore politico la pari dignita\u0300 del lavoro in tutte le sue forme, il riconoscimento concreto dell&#8217;essenzialita\u0300 delle attivita\u0300 esercitate dagli iscritti agli ordini e il rispetto del principio di equiparazione tra attivita\u0300 di impresa e libero professionale, gia\u0300 sancito a livello europeo e nazionale.<\/p>\n<p>L\u2019obiettivo dell\u2019evento e\u0300, infatti, quello di sollecitare l\u2019Esecutivo ad approvare le proposte di modifica al decreto Rilancio presentate dagli ordini e che riguardano, in particolar modo, la possibilita\u0300 di fruire del bonus di 600\/1000 euro e dei contributi a fondo perduto, da cui sono stati esclusi; la semplificazione normativa; l\u2019autonomia della Casse nel sostegno agli iscritti; l\u2019alleggerimento degli oneri fiscali a loro carico e l\u2019introduzione di uno scudo penale per la responsabilita\u0300 penale di chi abbia posto in essere tutte le misure necessarie per contrastare e contenere la diffusione del Covid-19 nei luoghi di lavoro.<\/p>\n<p>La manifestazione sara\u0300 anche l\u2019occasione per ascoltare il parere della classe politica e riaffermare l\u2019alleanza tra le Professioni italiane che, con voce unitaria e forte, presenteranno il loro \u201cManifesto per la Rinascita dell\u2019Italia\u201d. Un documento per la ripartenza economica dei professionisti e di tutte le attivita\u0300 produttive, contenente 10 suggerimenti e sollecitazioni in campo sanitario, tecnico ed economico, tra cui il sostegno alle attivita\u0300 professionali, che non si sono mai fermate durante l\u2019emergenza sanitaria, ma che oggi necessitano di aiuti ad hoc per sopravvivere.<\/p>\n<ol>\n<li>Garantire il diritto alla salute, alla prevenzione ed alla sicurezza delle cure<\/li>\n<li>Garantire la parita\u0300 di accesso dei professionisti alle misure di incentivo al<\/li>\n<\/ol>\n<p>lavoro e di sostegno nella fase di emergenza<br \/>\n3. Rafforzare le misure in materia di politiche di investimento, programmi industriali sostenibili e innovazione<\/p>\n<ol start=\"4\">\n<li>Realizzare un piano credibile di semplificazione normativa<\/li>\n<li>Garantire l\u2019applicazione del principio di sussidiarieta\u0300<\/li>\n<\/ol>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"page\" title=\"Page 2\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<ol start=\"6\">\n<li>Ridurre la pressione fiscale<\/li>\n<li>Avviare un Green New Deal per progettare opere innovative e sostenibili e promuovere un fondo per lo sviluppo professionale sostenibile<\/li>\n<li>\u00a0Avviare un piano di catalogazione dei patrimoni ambientali e culturali del Paese, di riprogettazione e manutenzione, di investimento nella rigenerazione urbana e di mitigazione del rischio sismico e idrogeologico del territorio e delle opere<\/li>\n<li>Valorizzare e tutelare il patrimonio ambientale, artistico, paesaggistico e culturale per nuovi percorsi di crescita<\/li>\n<li>Garantire affidabilita\u0300 e sicurezza nel settore ICT, delle informazioni e delle telecomunicazioni, accelerando un processo di digitalizzazione del Paese<\/li>\n<\/ol>\n<p>Le idee contenute nel Manifesto sono frutto di quel bagaglio di valori, conoscenze e competenze che contraddistinguono da sempre i professionisti ordinistici italiani e che si esprimono nella loro attivita\u0300 quotidiana di tutela dello Stato.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Domani gli Stati Generali delle Professioni italiane per ribadire il loro ruolo sussidiario e presentare il \u201cManifesto per la Rinascita dell\u2019Italia\u201d. &nbsp; 23 ordini professionali italiani uniti per dire basta alle discriminazioni nei loro confronti e per ribadire al Governo il loro ruolo economico, sociale e sussidiario. E\u0301 quanto avverra\u0300 domani, 4 giugno, in occasione [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2032,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dai professionisti 10 proposte per far ripartire il Paese -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/dai-professionisti-10-proposte-per-far-ripartire-il-paese\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dai professionisti 10 proposte per far ripartire il Paese -\" \/>\n<meta property=\"og:description\" content=\"Domani gli Stati Generali delle Professioni italiane per ribadire il loro ruolo sussidiario e presentare il \u201cManifesto per la Rinascita dell\u2019Italia\u201d. &nbsp; 23 ordini professionali italiani uniti per dire basta alle discriminazioni nei loro confronti e per ribadire al Governo il loro ruolo economico, sociale e sussidiario. E\u0301 quanto avverra\u0300 domani, 4 giugno, in occasione [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/dai-professionisti-10-proposte-per-far-ripartire-il-paese\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-03T16:52:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/impresa-lavoro-ufficio-banca.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/dai-professionisti-10-proposte-per-far-ripartire-il-paese\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/dai-professionisti-10-proposte-per-far-ripartire-il-paese\/\",\"name\":\"Dai professionisti 10 proposte per far ripartire il Paese -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/dai-professionisti-10-proposte-per-far-ripartire-il-paese\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/dai-professionisti-10-proposte-per-far-ripartire-il-paese\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/impresa-lavoro-ufficio-banca.jpg\",\"datePublished\":\"2020-06-03T16:52:14+00:00\",\"dateModified\":\"2020-06-03T16:52:14+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/dai-professionisti-10-proposte-per-far-ripartire-il-paese\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/dai-professionisti-10-proposte-per-far-ripartire-il-paese\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/dai-professionisti-10-proposte-per-far-ripartire-il-paese\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/impresa-lavoro-ufficio-banca.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/impresa-lavoro-ufficio-banca.jpg\",\"width\":960,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/dai-professionisti-10-proposte-per-far-ripartire-il-paese\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dai professionisti 10 proposte per far ripartire il Paese\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dai professionisti 10 proposte per far ripartire il Paese -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/dai-professionisti-10-proposte-per-far-ripartire-il-paese\/","og_locale":"it_IT","og_type":"article","og_title":"Dai professionisti 10 proposte per far ripartire il Paese -","og_description":"Domani gli Stati Generali delle Professioni italiane per ribadire il loro ruolo sussidiario e presentare il \u201cManifesto per la Rinascita dell\u2019Italia\u201d. &nbsp; 23 ordini professionali italiani uniti per dire basta alle discriminazioni nei loro confronti e per ribadire al Governo il loro ruolo economico, sociale e sussidiario. E\u0301 quanto avverra\u0300 domani, 4 giugno, in occasione [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/dai-professionisti-10-proposte-per-far-ripartire-il-paese\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2020-06-03T16:52:14+00:00","og_image":[{"width":960,"height":640,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/impresa-lavoro-ufficio-banca.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/dai-professionisti-10-proposte-per-far-ripartire-il-paese\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/dai-professionisti-10-proposte-per-far-ripartire-il-paese\/","name":"Dai professionisti 10 proposte per far ripartire il Paese -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/dai-professionisti-10-proposte-per-far-ripartire-il-paese\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/dai-professionisti-10-proposte-per-far-ripartire-il-paese\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/impresa-lavoro-ufficio-banca.jpg","datePublished":"2020-06-03T16:52:14+00:00","dateModified":"2020-06-03T16:52:14+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/dai-professionisti-10-proposte-per-far-ripartire-il-paese\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/dai-professionisti-10-proposte-per-far-ripartire-il-paese\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/dai-professionisti-10-proposte-per-far-ripartire-il-paese\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/impresa-lavoro-ufficio-banca.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/impresa-lavoro-ufficio-banca.jpg","width":960,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/dai-professionisti-10-proposte-per-far-ripartire-il-paese\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Dai professionisti 10 proposte per far ripartire il Paese"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/3266"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=3266"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/3266\/revisions"}],"predecessor-version":[{"id":3267,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/3266\/revisions\/3267"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/2032"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=3266"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=3266"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=3266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}