{"id":3268,"date":"2020-06-04T23:28:06","date_gmt":"2020-06-04T21:28:06","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=3268"},"modified":"2020-06-04T23:28:06","modified_gmt":"2020-06-04T21:28:06","slug":"bollette-della-luce-gonfiate-cinque-consigli-per-evitare-fatture-elevate","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/bollette-della-luce-gonfiate-cinque-consigli-per-evitare-fatture-elevate\/","title":{"rendered":"Bollette della luce gonfiate: cinque consigli per evitare fatture elevate"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">L<\/span>e fatture dell\u2019energia elettrica potrebbero riservare delle sorprese: dai consumi presunti, all\u2019applicazione di clausole contrattuali errate, fino alla pretesa di arretrati oltre i due anni. Come farsi rispettare? Una guida con i consigli pratici degli esperti SOStariffe.it per pagare il giusto e pretendere, nel caso, il rimborso delle cifre ingiustamente versate<\/p>\n<p>A partire dal primo aprile l&#8217;Arera, l&#8217;Authority di settore, ha rivisto al ribasso le tariffe della luce per il secondo trimestre del 2020 (-18,3%) per i clienti in regime di maggior tutela. Dunque almeno per il mercato tutelato, le bollette dell&#8217;energia elettrica dovrebbero essere pi\u00f9 leggere. Ma ci\u00f2 non sempre accade. Come mai? La fattura della luce potrebbe essere gonfiata rispetto ai consumi reali. SOStariffe.it ha stilato un elenco di cinque regole d&#8217;oro per smascherare i costi aggiuntivi e accertarci cos\u00ec di star pagando il giusto.<\/p>\n<p>I consumi si controllano cos\u00ec<br \/>\nAnzitutto \u00e8 buona norma imparare a leggere con attenzione la bolletta, per evitare di pagare ci\u00f2 che non si deve, anche se siamo passati al mercato libero e abbiamo sottoscritto un&#8217;offerta luce conveniente. Teniamo conto che tra le voci di costo riportate sulla fattura ce ne sono alcune fisse:<br \/>\n&#8211; il costo della materia prima, deciso dal fornitore di energia e indicato sul contratto firmato;\u2028- la spesa per trasportare l&#8217;energia dalle centrali a casa;\u2028- quella per lettura e gestione del contatore, che cambia con i consumi;\u2028- gli oneri di sistema.<br \/>\nA queste voci costanti si aggiungono poi diverse imposte, come l&#8217;IVA e le accise a cui di recente si \u00e8 aggiunto il canone RAI che costa 90 euro all&#8217;anno, ma si paga 9 euro per volta in 10 mesi. Le bollette hanno un genere una periodicit\u00e0 bimestrale. I consumi riportati devono essere effettivi, cio\u00e8 corrispondere ai valori riportati dal contatore.<\/p>\n<p>Ricordarsi di comunicare l&#8217;autolettura<br \/>\nLe fatture potrebbero non essere &#8216;fedeli&#8217; all&#8217;energia effettivamente consumata, ma basarsi invece su un calcolo presuntivo dell&#8217;energia stimata nel periodo considerato. I consumi riportati in bolletta infatti, possono comprendere sia i kWh effettivamente impiegati che quelli solo stimati.<\/p>\n<p>Per scoprirlo dobbiamo tenere sotto controllo il contatore. Il modo per farlo \u00e8 l&#8217;autolettura: ovvero comunicare al fornitore i dati riportati volta per volta sul nostro contatore. Controllare ogni bimestre il contatore ci aiuter\u00e0 ad accorgerci se i valori riportati in bolletta non corrispondono al consumo reale. Se dovessimo notare delle difformit\u00e0, rivolgiamoci al servizio clienti del nostro fornitore per farci inviare una nuova bolletta con i consumi effettivi. Pretendiamo inoltre il rimborso delle somme versate per errore.<\/p>\n<p>Ad oggi i contatori della luce sono in molti casi smart meter, cio\u00e8 contatori elettronici tele-gestiti, letti a distanza dal fornitore. Ce ne sono in servizio oltre 35 milioni. Se disponiamo di un contatore elettrico telegestito non dobbiamo comunicare nessuna lettura, poich\u00e9 lo smart meter trasmette i dati rilevati in tempo reale ogni quarto d\u2019ora e le fatture sono emesse in base ai consumi effettivi.<\/p>\n<p>Ad ogni modo se vogliamo leggere quanto stiamo consumando, la gran parte dei modelli di contatore elettronico dispongono di un tasto grigio vicino al display, premendo il quale si potranno visualizzare il codice cliente, la potenza massima del contatore, e i dati di consumo in corrispondenza dei simboli A1, A2 e A3 che indicano la quantit\u00e0 di energia usata nelle varie fasce orarie (rispettivamente F1, F2 ed F3).<br \/>\nSe in casa abbiamo ancora il vecchio contatore tradizionale, invece, \u00e8 importante ricordarsi di comunicare le cifre prima della virgola. Tutti i gestori mettono a disposizione appositi canali per trasmettere i dati rilevati: un numero telefonico, un\u2019app per tablet e smartphone oppure un\u2019area del proprio sito.<\/p>\n<p>\u00c8 la tariffa giusta per noi? Verificare il profilo di consumo<br \/>\nAl momento della firma del contratto ci viene assegnato un profilo di consumo, che poi ritroveremo riportato in bolletta, insieme al tipo di offerta sottoscritta, alla tensione della fornitura elettrica e alla potenza impegnata.<\/p>\n<p>In genere si distingue tra uso domestico residente e non residente. Tuttavia il profilo che \u00e8 stato selezionato in fase di firma del contratto potrebbe non essere applicato correttamente. Se le condizioni non vengono rispettate dobbiamo inviare un reclamo al fornitore. Al reclamo si dovranno allegare i documenti che attestano l&#8217;assegnazione del profilo a cui facciamo riferimento. Potremmo inoltre anche esigere un eventuale rimborso del prezzo ingiustamente pagato per l&#8217;errore del fornitore.<\/p>\n<p>Come scoprire il fornitore non sta ai patti<br \/>\nAl pari del profilo di consumo, \u00e8 importante controllare anche l&#8217;applicazione di tutte le altre clausole del contratto. Se ad esempio abbiamo stipulato un contratto di fornitura di energia con tariffa monoraria e nella bolletta ritroviamo la ripartizione dei consumi su due fasce orarie, allora c&#8217;\u00e8 evidentemente un errore di applicazione delle clausole del contratto. Non ci resta che rivolgerci al servizio clienti del nostro fornitore o inoltrare un reclamo.<br \/>\nBollette prescritte in 2 anni<\/p>\n<p>A partire dal 2019 le bollette della luce si prescrivono in due anni e non pi\u00f9 in cinque. Il diritto al pagamento del corrispettivo da parte del fornitore dunque viene meno passati i due anni dall\u2019emissione. Se il fornitore ci richiede arretrati pi\u00f9 vecchi di 24 mesi non siamo tenuti a pagare, n\u00e9 la compagnia potr\u00e0 sospendere l&#8217;erogazione dell&#8217;energia per morosit\u00e0. In caso in cui si riceva in bolletta la richiesta di pagare un importo caduto in prescrizione, bisogner\u00e0 inviare un reclamo tramite raccomandata con ricevuta di ritorno.<br \/>\nUsare un comparatore per passare al mercato libero<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le fatture dell\u2019energia elettrica potrebbero riservare delle sorprese: dai consumi presunti, all\u2019applicazione di clausole contrattuali errate, fino alla pretesa di arretrati oltre i due anni. Come farsi rispettare? Una guida con i consigli pratici degli esperti SOStariffe.it per pagare il giusto e pretendere, nel caso, il rimborso delle cifre ingiustamente versate A partire dal primo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2192,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[35],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Bollette della luce gonfiate: cinque consigli per evitare fatture elevate -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/bollette-della-luce-gonfiate-cinque-consigli-per-evitare-fatture-elevate\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bollette della luce gonfiate: cinque consigli per evitare fatture elevate -\" \/>\n<meta property=\"og:description\" content=\"Le fatture dell\u2019energia elettrica potrebbero riservare delle sorprese: dai consumi presunti, all\u2019applicazione di clausole contrattuali errate, fino alla pretesa di arretrati oltre i due anni. Come farsi rispettare? Una guida con i consigli pratici degli esperti SOStariffe.it per pagare il giusto e pretendere, nel caso, il rimborso delle cifre ingiustamente versate A partire dal primo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/bollette-della-luce-gonfiate-cinque-consigli-per-evitare-fatture-elevate\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-04T21:28:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/12\/lampadina.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"540\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/bollette-della-luce-gonfiate-cinque-consigli-per-evitare-fatture-elevate\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/bollette-della-luce-gonfiate-cinque-consigli-per-evitare-fatture-elevate\/\",\"name\":\"Bollette della luce gonfiate: cinque consigli per evitare fatture elevate -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/bollette-della-luce-gonfiate-cinque-consigli-per-evitare-fatture-elevate\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/bollette-della-luce-gonfiate-cinque-consigli-per-evitare-fatture-elevate\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/12\/lampadina.jpg\",\"datePublished\":\"2020-06-04T21:28:06+00:00\",\"dateModified\":\"2020-06-04T21:28:06+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/bollette-della-luce-gonfiate-cinque-consigli-per-evitare-fatture-elevate\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/bollette-della-luce-gonfiate-cinque-consigli-per-evitare-fatture-elevate\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/bollette-della-luce-gonfiate-cinque-consigli-per-evitare-fatture-elevate\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/12\/lampadina.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/12\/lampadina.jpg\",\"width\":960,\"height\":540},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/bollette-della-luce-gonfiate-cinque-consigli-per-evitare-fatture-elevate\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bollette della luce gonfiate: cinque consigli per evitare fatture elevate\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bollette della luce gonfiate: cinque consigli per evitare fatture elevate -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/bollette-della-luce-gonfiate-cinque-consigli-per-evitare-fatture-elevate\/","og_locale":"it_IT","og_type":"article","og_title":"Bollette della luce gonfiate: cinque consigli per evitare fatture elevate -","og_description":"Le fatture dell\u2019energia elettrica potrebbero riservare delle sorprese: dai consumi presunti, all\u2019applicazione di clausole contrattuali errate, fino alla pretesa di arretrati oltre i due anni. Come farsi rispettare? Una guida con i consigli pratici degli esperti SOStariffe.it per pagare il giusto e pretendere, nel caso, il rimborso delle cifre ingiustamente versate A partire dal primo [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/bollette-della-luce-gonfiate-cinque-consigli-per-evitare-fatture-elevate\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2020-06-04T21:28:06+00:00","og_image":[{"width":960,"height":540,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/12\/lampadina.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/bollette-della-luce-gonfiate-cinque-consigli-per-evitare-fatture-elevate\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/bollette-della-luce-gonfiate-cinque-consigli-per-evitare-fatture-elevate\/","name":"Bollette della luce gonfiate: cinque consigli per evitare fatture elevate -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/bollette-della-luce-gonfiate-cinque-consigli-per-evitare-fatture-elevate\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/bollette-della-luce-gonfiate-cinque-consigli-per-evitare-fatture-elevate\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/12\/lampadina.jpg","datePublished":"2020-06-04T21:28:06+00:00","dateModified":"2020-06-04T21:28:06+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/bollette-della-luce-gonfiate-cinque-consigli-per-evitare-fatture-elevate\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/bollette-della-luce-gonfiate-cinque-consigli-per-evitare-fatture-elevate\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/bollette-della-luce-gonfiate-cinque-consigli-per-evitare-fatture-elevate\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/12\/lampadina.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/12\/lampadina.jpg","width":960,"height":540},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/bollette-della-luce-gonfiate-cinque-consigli-per-evitare-fatture-elevate\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Bollette della luce gonfiate: cinque consigli per evitare fatture elevate"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/3268"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=3268"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/3268\/revisions"}],"predecessor-version":[{"id":3269,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/3268\/revisions\/3269"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/2192"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=3268"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=3268"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=3268"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}