{"id":3375,"date":"2020-06-17T09:01:32","date_gmt":"2020-06-17T07:01:32","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=3375"},"modified":"2020-06-17T09:01:32","modified_gmt":"2020-06-17T07:01:32","slug":"stati-generali-uecoop-265-peso-buracrazia-sulle-imprese","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/stati-generali-uecoop-265-peso-buracrazia-sulle-imprese\/","title":{"rendered":"Stati generali, UECOOP: +26,5% peso buracrazia sulle imprese"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">L<\/span>\u2019Unione europea delle Cooperative chiede procedure pi\u00f9 snelle e stop appalti al massimo ribasso<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>Nell\u2019ultimo anno \u00e8 aumentato del +26,5% il peso della burocrazia sul lavoro delle imprese. E\u2019 quanto emerge da una analisi presentata dall\u2019Unione europea delle cooperative (Uecoop) nel corso della partecipazione agli Stati Generali in corso a Villa Pamphili con il Presidente del consiglio Giuseppe Conte. Per la competitivit\u00e0 delle imprese e per una ripartenza dell\u2019economia \u00e8 necessario \u2013 ha evidenziato durante l\u2019incontro il Presidente di Uecoop Gherardo Colombo \u2013 alleggerire il carico burocratico che rallenta l\u2019attivit\u00e0 e quindi la reattivit\u00e0 del sistema produttivo: basti pensare ai ritardi registrati relativamente alle misure che il Governo ha varato in materia di liquidit\u00e0 e cassa integrazione.<\/p>\n<p>&nbsp;<\/p>\n<p>Una situazione che frena la capacit\u00e0 di imprese e cooperative a crescere e a sviluppare economia e occupazione anche per i giovani e per le donne in un momento in cui il Paese \u2013 continua Colombo \u2013 ha bisogno di servizi sempre pi\u00f9 qualificati che privilegino la dimensione comunitaria e di prossimit\u00e0: dalla sanit\u00e0 ai trasporti, dall\u2019assistenza agli anziani e alle persone con problemi di inclusione, fino ai i servizi educativi e scolastici. Per queste necessit\u00e0 le cooperative svolgono da sempre un importante ruolo ma c\u2019\u00e8 bisogno di superare la logica dei grandi appalti al massimo ribasso che \u2013 sottolinea Uecoop \u2013 oltre a comportare un carico burocratico e di procedure non indifferente tagliano fuori una fetta importante di piccole e medie imprese che da sempre rappresentano l\u2019ossatura economica dell\u2019Italia.<\/p>\n<p>&nbsp;<\/p>\n<p>Le cooperative potrebbero essere coinvolte nel dare risposta ad ulteriori bisogni sociali di prossimit\u00e0 con particolare attenzione alle situazioni di fragilit\u00e0, disagio sociale, economico e abitativo che non trovano soddisfazione nella rete dei servizi pubblico-istituzionali gi\u00e0 attivi sul territorio. In questi ambiti \u2013 ha spiegato Gherardo Colombo \u2013 operano gi\u00e0 migliaia di cooperative sociali che supportano le necessit\u00e0 di oltre 7milioni di famiglie e che, nonostante la pandemia da coronavirus, hanno continuato a prendersi cura degli anziani e dei soggetti pi\u00f9 deboli anche in collaborazione con gli enti locali. Per questo \u2013 ha proseguito Colombo \u2013 \u00e8 necessario incrementare i fondi statali per assicurare la liquidit\u00e0 a comuni, province e regioni migliorando ancora di pi\u00f9 i tempi di pagamento della Pubblica Amministrazione per non mettere a repentaglio i bilanci delle imprese e i posti di lavoro.<\/p>\n<p>&nbsp;<\/p>\n<p>Il rilancio dell\u2019Italia non pu\u00f2 per\u00f2 prescindere da trasparenza e correttezza che possono essere incentivate attraverso una formazione continua di tutti gli interpreti del sistema, finalizzata \u2013 conclude Colombo \u2013 alla comprensione e alla condivisione delle regole e delle procedure.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019Unione europea delle Cooperative chiede procedure pi\u00f9 snelle e stop appalti al massimo ribasso \u00a0 Nell\u2019ultimo anno \u00e8 aumentato del +26,5% il peso della burocrazia sul lavoro delle imprese. E\u2019 quanto emerge da una analisi presentata dall\u2019Unione europea delle cooperative (Uecoop) nel corso della partecipazione agli Stati Generali in corso a Villa Pamphili con il [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":21,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Stati generali, UECOOP: +26,5% peso buracrazia sulle imprese -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/stati-generali-uecoop-265-peso-buracrazia-sulle-imprese\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Stati generali, UECOOP: +26,5% peso buracrazia sulle imprese -\" \/>\n<meta property=\"og:description\" content=\"L\u2019Unione europea delle Cooperative chiede procedure pi\u00f9 snelle e stop appalti al massimo ribasso \u00a0 Nell\u2019ultimo anno \u00e8 aumentato del +26,5% il peso della burocrazia sul lavoro delle imprese. E\u2019 quanto emerge da una analisi presentata dall\u2019Unione europea delle cooperative (Uecoop) nel corso della partecipazione agli Stati Generali in corso a Villa Pamphili con il [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/stati-generali-uecoop-265-peso-buracrazia-sulle-imprese\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-17T07:01:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/07\/p2-e1531909427362.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1065\" \/>\n\t<meta property=\"og:image:height\" content=\"782\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/stati-generali-uecoop-265-peso-buracrazia-sulle-imprese\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/stati-generali-uecoop-265-peso-buracrazia-sulle-imprese\/\",\"name\":\"Stati generali, UECOOP: +26,5% peso buracrazia sulle imprese -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/stati-generali-uecoop-265-peso-buracrazia-sulle-imprese\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/stati-generali-uecoop-265-peso-buracrazia-sulle-imprese\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/07\/p2-e1531909427362.jpg\",\"datePublished\":\"2020-06-17T07:01:32+00:00\",\"dateModified\":\"2020-06-17T07:01:32+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/stati-generali-uecoop-265-peso-buracrazia-sulle-imprese\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/stati-generali-uecoop-265-peso-buracrazia-sulle-imprese\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/stati-generali-uecoop-265-peso-buracrazia-sulle-imprese\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/07\/p2-e1531909427362.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/07\/p2-e1531909427362.jpg\",\"width\":1065,\"height\":782},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/stati-generali-uecoop-265-peso-buracrazia-sulle-imprese\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Stati generali, UECOOP: +26,5% peso buracrazia sulle imprese\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Stati generali, UECOOP: +26,5% peso buracrazia sulle imprese -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/stati-generali-uecoop-265-peso-buracrazia-sulle-imprese\/","og_locale":"it_IT","og_type":"article","og_title":"Stati generali, UECOOP: +26,5% peso buracrazia sulle imprese -","og_description":"L\u2019Unione europea delle Cooperative chiede procedure pi\u00f9 snelle e stop appalti al massimo ribasso \u00a0 Nell\u2019ultimo anno \u00e8 aumentato del +26,5% il peso della burocrazia sul lavoro delle imprese. E\u2019 quanto emerge da una analisi presentata dall\u2019Unione europea delle cooperative (Uecoop) nel corso della partecipazione agli Stati Generali in corso a Villa Pamphili con il [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/stati-generali-uecoop-265-peso-buracrazia-sulle-imprese\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2020-06-17T07:01:32+00:00","og_image":[{"width":1065,"height":782,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/07\/p2-e1531909427362.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/stati-generali-uecoop-265-peso-buracrazia-sulle-imprese\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/stati-generali-uecoop-265-peso-buracrazia-sulle-imprese\/","name":"Stati generali, UECOOP: +26,5% peso buracrazia sulle imprese -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/stati-generali-uecoop-265-peso-buracrazia-sulle-imprese\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/stati-generali-uecoop-265-peso-buracrazia-sulle-imprese\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/07\/p2-e1531909427362.jpg","datePublished":"2020-06-17T07:01:32+00:00","dateModified":"2020-06-17T07:01:32+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/stati-generali-uecoop-265-peso-buracrazia-sulle-imprese\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/stati-generali-uecoop-265-peso-buracrazia-sulle-imprese\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/stati-generali-uecoop-265-peso-buracrazia-sulle-imprese\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/07\/p2-e1531909427362.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/07\/p2-e1531909427362.jpg","width":1065,"height":782},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/stati-generali-uecoop-265-peso-buracrazia-sulle-imprese\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Stati generali, UECOOP: +26,5% peso buracrazia sulle imprese"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/3375"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=3375"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/3375\/revisions"}],"predecessor-version":[{"id":3376,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/3375\/revisions\/3376"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/21"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=3375"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=3375"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=3375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}