{"id":3411,"date":"2020-06-19T08:17:01","date_gmt":"2020-06-19T06:17:01","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=3411"},"modified":"2020-06-19T08:21:57","modified_gmt":"2020-06-19T06:21:57","slug":"coronavirus-aumentano-i-casi-nellultima-settimana","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-aumentano-i-casi-nellultima-settimana\/","title":{"rendered":"Coronavirus, aumentano i casi nell&#8217;ultima settimana"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">N<\/span>ella settimana 11-17 giugno il monitoraggio indipendente della Fondazione GIMBE \u2013 afferma il Presidente <strong>Nino Cartabellotta<\/strong> \u2013 conferma rispetto alla settimana precedente la costante riduzione dei pazienti ricoverati con sintomi e in terapia intensiva e l\u2019ulteriore rallentamento sul fronte dei decessi. Relativamente ai casi totali, si rileva un lieve incremento percentuale rispetto alla settimana precedente\u00bb. In sintesi:<\/p>\n<ul>\n<li>Casi totali: +2.065 (+0,9%)<\/li>\n<li>Decessi: + 334 (+1,0%)<\/li>\n<li>Ricoverati con sintomi: -1.207 (-27,9%)<\/li>\n<li>Terapia intensiva -86 (-34,5%)<\/li>\n<\/ul>\n<p>\u00abConsiderato il maggior incremento dei casi totali negli ultimi 7 giorni rispetto alla settimana precedente \u2013 spiega Cartabellotta \u2013 la nostra analisi si \u00e8 concentrata su due aspetti: la variazione regionale dei nuovi casi e dei tamponi diagnostici, ovvero i cosiddetti \u201ccasi testati\u201d secondo la denominazione utilizzata dalla Protezione Civile\u00bb.<\/p>\n<p><b>Variazione dei nuovi casi<\/b>. Negli ultimi 7 giorni si registra un incremento di 2.294 nuovi casi, rispetto ai 1.927 della settimana precedente. 11 Regioni hanno un incremento complessivo di 461 casi di cui 384 (83%) in Lombardia; a seguire Piemonte (33), Toscana (18), Emilia Romagna (13), Prov. Aut. di Trento (4), Friuli Venezia Giulia (3), Calabria (2), Prov. Aut. di Bolzano (1), Abruzzo (1), Sardegna (1), Veneto (1). Le altre 10 Regioni fanno registrare complessivamente 94 nuovi casi in meno rispetto alla settimana precedente con minime variazioni negative, ad eccezione della Liguria (-61 casi). Le variazioni dei nuovi casi per 100.000 abitanti oscillano da +3,8 della Lombardia a -3,9 della Liguria (figura 1).<\/p>\n<p><b>Relazione n\u00b0 tamponi diagnostici e incidenza nuovi casi<\/b>. Nell\u2019ultima settimana, rispetto alla precedente, i tamponi per diagnosticare nuovi casi (cd. \u201ccasi testati\u201d) sono aumentati solo in Emilia Romagna (+7.819), Lombardia (+1.821),<b> <\/b>Lazio (+1.389), Campania (+1.087), Prov. Aut. di Trento (+834) e Valle D\u2019Aosta (+76). Nelle rimanenti Regioni sono invece diminuiti, auspicabilmente per la situazione epidemiologica e per l\u2019utilizzo sempre pi\u00f9 esteso di test sierologici di screening (figura 2).<\/p>\n<p>\u00abConsiderato che in questa fase dell\u2019epidemia \u2013 continua il Presidente \u2013 \u00e8 indispensabile uno stretto monitoraggio la Fondazione GIMBE ha verificato la disponibilit\u00e0 pubblica dei 21 indicatori che le Regioni dovrebbero trasmettere secondo quanto previsto dal Decreto del Ministero della Salute 30 aprile 2020\u00bb. Nessuno dei 12 indicatori di processo (6 relativi alla capacit\u00e0 di monitoraggio, 6 a quella di accertamento diagnostico, indagine e di gestione dei contatti) \u00e8 pubblicamente disponibile per cittadini e ricercatori. Dei 9 indicatori di esito solo 3 vengono pubblicati (tabella).<\/p>\n<p><a href=\"http:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/06\/Schermata-2020-06-19-alle-08.14.59.png\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-3412\" src=\"http:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/06\/Schermata-2020-06-19-alle-08.14.59.png\" alt=\"\" width=\"1226\" height=\"880\" srcset=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/06\/Schermata-2020-06-19-alle-08.14.59.png 1226w, https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/06\/Schermata-2020-06-19-alle-08.14.59-300x215.png 300w, https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/06\/Schermata-2020-06-19-alle-08.14.59-1024x735.png 1024w, https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/06\/Schermata-2020-06-19-alle-08.14.59-768x551.png 768w, https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/06\/Schermata-2020-06-19-alle-08.14.59-696x500.png 696w, https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/06\/Schermata-2020-06-19-alle-08.14.59-1068x767.png 1068w, https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/06\/Schermata-2020-06-19-alle-08.14.59-585x420.png 585w\" sizes=\"(max-width: 1226px) 100vw, 1226px\" \/><\/a><\/p>\n<p>\u00abI dati forniti dalla Protezione Civile \u2013 conclude Cartabellotta \u2013 documentano un lieve incremento dei casi nell\u2019ultima settimana rispetto alla precedente, ma non permettono alcun monitoraggio accurato in questa fase dell\u2019epidemia. Considerato che le fonti ufficiali riportano solo 3 dei 21 indicatori previsti dal sistema di monitoraggio nazionale, la Fondazione GIMBE invita le Regioni a trasmettere tutti i dati richiesti e chiede al Ministero della Salute di renderli pubblici, sia in formato open per i ricercatori, sia in un formato di facile comprensione per i cittadini\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nella settimana 11-17 giugno il monitoraggio indipendente della Fondazione GIMBE \u2013 afferma il Presidente Nino Cartabellotta \u2013 conferma rispetto alla settimana precedente la costante riduzione dei pazienti ricoverati con sintomi e in terapia intensiva e l\u2019ulteriore rallentamento sul fronte dei decessi. Relativamente ai casi totali, si rileva un lieve incremento percentuale rispetto alla settimana precedente\u00bb. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2665,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[128],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Coronavirus, aumentano i casi nell&#039;ultima settimana -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-aumentano-i-casi-nellultima-settimana\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coronavirus, aumentano i casi nell&#039;ultima settimana -\" \/>\n<meta property=\"og:description\" content=\"Nella settimana 11-17 giugno il monitoraggio indipendente della Fondazione GIMBE \u2013 afferma il Presidente Nino Cartabellotta \u2013 conferma rispetto alla settimana precedente la costante riduzione dei pazienti ricoverati con sintomi e in terapia intensiva e l\u2019ulteriore rallentamento sul fronte dei decessi. Relativamente ai casi totali, si rileva un lieve incremento percentuale rispetto alla settimana precedente\u00bb. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-aumentano-i-casi-nellultima-settimana\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-19T06:17:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-19T06:21:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/03\/Schermata-2020-03-09-alle-16.05.58.png\" \/>\n\t<meta property=\"og:image:width\" content=\"851\" \/>\n\t<meta property=\"og:image:height\" content=\"477\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-aumentano-i-casi-nellultima-settimana\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-aumentano-i-casi-nellultima-settimana\/\",\"name\":\"Coronavirus, aumentano i casi nell'ultima settimana -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-aumentano-i-casi-nellultima-settimana\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-aumentano-i-casi-nellultima-settimana\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/03\/Schermata-2020-03-09-alle-16.05.58.png\",\"datePublished\":\"2020-06-19T06:17:01+00:00\",\"dateModified\":\"2020-06-19T06:21:57+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-aumentano-i-casi-nellultima-settimana\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-aumentano-i-casi-nellultima-settimana\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-aumentano-i-casi-nellultima-settimana\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/03\/Schermata-2020-03-09-alle-16.05.58.png\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/03\/Schermata-2020-03-09-alle-16.05.58.png\",\"width\":851,\"height\":477},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-aumentano-i-casi-nellultima-settimana\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coronavirus, aumentano i casi nell&#8217;ultima settimana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Coronavirus, aumentano i casi nell'ultima settimana -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-aumentano-i-casi-nellultima-settimana\/","og_locale":"it_IT","og_type":"article","og_title":"Coronavirus, aumentano i casi nell'ultima settimana -","og_description":"Nella settimana 11-17 giugno il monitoraggio indipendente della Fondazione GIMBE \u2013 afferma il Presidente Nino Cartabellotta \u2013 conferma rispetto alla settimana precedente la costante riduzione dei pazienti ricoverati con sintomi e in terapia intensiva e l\u2019ulteriore rallentamento sul fronte dei decessi. Relativamente ai casi totali, si rileva un lieve incremento percentuale rispetto alla settimana precedente\u00bb. [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-aumentano-i-casi-nellultima-settimana\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2020-06-19T06:17:01+00:00","article_modified_time":"2020-06-19T06:21:57+00:00","og_image":[{"width":851,"height":477,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/03\/Schermata-2020-03-09-alle-16.05.58.png","type":"image\/png"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-aumentano-i-casi-nellultima-settimana\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-aumentano-i-casi-nellultima-settimana\/","name":"Coronavirus, aumentano i casi nell'ultima settimana -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-aumentano-i-casi-nellultima-settimana\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-aumentano-i-casi-nellultima-settimana\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/03\/Schermata-2020-03-09-alle-16.05.58.png","datePublished":"2020-06-19T06:17:01+00:00","dateModified":"2020-06-19T06:21:57+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-aumentano-i-casi-nellultima-settimana\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-aumentano-i-casi-nellultima-settimana\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-aumentano-i-casi-nellultima-settimana\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/03\/Schermata-2020-03-09-alle-16.05.58.png","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/03\/Schermata-2020-03-09-alle-16.05.58.png","width":851,"height":477},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-aumentano-i-casi-nellultima-settimana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Coronavirus, aumentano i casi nell&#8217;ultima settimana"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/3411"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=3411"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/3411\/revisions"}],"predecessor-version":[{"id":3413,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/3411\/revisions\/3413"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/2665"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=3411"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=3411"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=3411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}