{"id":3418,"date":"2020-06-20T19:15:29","date_gmt":"2020-06-20T17:15:29","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=3418"},"modified":"2020-06-20T19:15:29","modified_gmt":"2020-06-20T17:15:29","slug":"i-debiti-della-pa-sono-in-aumento","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/i-debiti-della-pa-sono-in-aumento\/","title":{"rendered":"CGIA Mestre: i debiti della PA sono in aumento"},"content":{"rendered":"<div class=\"page\" title=\"Page 1\">\n<div class=\"section\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\"><\/div>\n<\/div>\n<\/div>\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p><span class=\"dropcap dropcap3\">S<\/span>econdo l\u2019Eurostat, fa sapere l\u2019Ufficio studi della CGIA, i debiti commerciali della nostra Pubblica Amministrazioni (PA) sono in aumento. Sebbene questi dati non contengono la componente in conto capitale, che secondo alcune stime ammonterebbe tra i 7-8 miliardi di euro all\u2019anno, i mancati pagamenti di parte corrente hanno toccato, il 31 dicembre scorso, i 49,4 miliardi di euro.<\/p>\n<p>\u201cIn attesa che il ministero dell\u2019Economia certifichi ufficialmente a quanto ammonta il debito commerciale della nostra PA \u2013 dichiara il coordinatore dell\u2019Ufficio studi <strong>Paolo Zabeo<\/strong> \u2013 la situazione e\u0300 destinata a peggiorare.<\/p>\n<p>Se le difficolta\u0300 degli enti locali sono sotto gli occhi di tutti, nulla lasciava presagire che avessero problemi perfino le amministrazioni centrali. Oltre ai ministeri, in questo primo trimestre dell\u2019anno anche una parte dell\u2019Amministrazione finanziaria non ha rispettato i tempi di pagamento. Ancorche\u0301 la Giustizia tributaria e tre Agenzie fiscali abbiano saldato i propri fornitori in anticipo, il Demanio, invece, ha liquidato le imprese dopo 7 giorni dalla scadenza prevista per legge, il ministero delle Finanze dopo 8 e la Guardia di Finanza addirittura dopo 136\u201d .<\/p>\n<p>Ci riferiamo agli Indicatori di Tempestivita\u0300 dei Pagamenti (ITP) che in questo caso sono stati estrapolati dai rispettivi siti internet dei ministeri. Questi ultimi, come tutte le altre Amministrazioni pubbliche, oltre all\u2019 ITP (calcolato ai sensi dell\u2019art. 9 del D.P.C.M. del 22 settembre 2014) hanno l\u2019obbligo di pubblicare sul proprio sito anche il numero dei creditori e l\u2019ammontare complessivo dei debiti (art. 33 comma 1 del D.Lgs n. 33\/2013 cosi\u0300 come modificato dall\u2019art. 29 del D.Lgs. 97\/2016) maturati ogni trimestre e alla fine di ciascun anno per le seguenti voci di spesa: somministrazioni, forniture, appalti e prestazioni professionali.<\/p>\n<p>Le cifre riportate dall\u2019Eurostat evidenziano, inoltre, che negli ultimi 4 anni lo stock complessivo e\u0300 in costante crescita. Se nel 2016 i debiti di parte corrente erano 44,3, nel 2017 sono saliti a 45,6, nel 2018 hanno toccato i 47,8 per arrivare, come abbiamo appena riportato piu\u0300 sopra, a 49,4 miliardi nel 2019 . L\u2019anno scorso, il dato assoluto era pari al 2,8 per cento del Pil: tra i 27 paesi Ue monitorati, solo la Croazia, con il 2,9 per cento, ha registrato una incidenza piu\u0300 elevata della nostra.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"page\" title=\"Page 2\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>\u201cSebbene la nostra PA sia tra le peggiori pagatrici d\u2019Europa \u2013 segnala il Segretario Renato Mason &#8211; molti si erano convinti che i tempi di pagamento si sarebbero drasticamente ridotti grazie all\u2019introduzione, avviata nel luglio del 2017, dell\u2019obbligo da parte di tutti gli enti pubblici di trasmettere le informazioni relative ai singoli pagamenti attraverso il sistema Siope+ .<\/p>\n<p>Questa modalita\u0300 doveva consentire a regime la quantificazione dell\u2019ammontare delle passivita\u0300 commerciali e il monitoraggio continuo dei tempi di pagamento delle Amministrazioni pubbliche. Purtroppo, tutto cio\u0300 non e\u0300 ancora avvenuto per l\u2019avversione di moltissimi enti a rispettare le disposizioni di legge, con il risultato che lo stock del debito rimane ancora spaventosamente elevato. Non solo. Il mancato saldo delle fatture sta innescando degli effetti negativi su intere filiere produttive, diffondendo questa anomalia tutta italiana anche nel settore privato\u201d.<\/p>\n<p>L\u2019aspetto paradossale di questa vicenda e\u0300 che nessuno e\u0300 in grado di affermare a quanto ammonta esattamente il debito commerciale della nostra PA, nonostante le imprese che lavorano per quest\u2019ultima abbiano da parecchi anni l\u2019obbligo, per essere liquidate, di emettere la fattura elettronica.<\/p>\n<p>Sistema di rilevazione telematica degli incassi e dei pagamenti effettuati dai tesorieri di tutte le Amministrazioni pubbliche. Questa piattaforma e\u0300 gestita dal Ministero dell&#8217;Economia e delle Finanze<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"page\" title=\"Page 3\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Come funzionano i pagamenti in queste transazioni commerciali ? Una volta che il fornitore emette la fattura elettronica, questa transita attraverso una piattaforma controllata dal Ministero dell\u2019Economia e delle Finanze detta SdI (Sistema di Interscambio) che la smista all\u2019ente o alla struttura pubblica a cui e\u0300 indirizzata. I dati della fattura elettronica vengono acquisiti dalla Piattaforma dei Crediti Commerciali (PCC) che dovrebbe registrare tutti i pagamenti riconducibili alle transazioni commerciali della PA. Per cercare di intercettare la totalita\u0300 delle transazioni e\u0300 stato istituito il Siope+, un sistema di rilevazione telematica degli incassi e dei pagamenti degli enti pubblici. Per alimentare il Siope+ tutte le amministrazioni pubbliche devono ordinare gli incassi e i pagamenti esclusivamente con modalita\u0300 informatica.<\/p>\n<p>Sebbene questa prassi sia partita gradualmente dal luglio del 2017, lo Stato non e\u0300 ancora in grado di dimensionare il debito complessivo contratto da tutte le Amministrazioni pubbliche con i propri fornitori, per il semplice fatto che una parte importante delle Amministrazioni pubbliche non hanno ancora aderito alla piattaforma Siope+. Pertanto, possono saldare i propri fornitori con scadenze ben oltre quelle stabilite dalla legge .<\/p>\n<p>Con il decreto Rilancio, l\u2019Esecutivo ha messo a disposizione di Regioni, Asl ed enti locali 12 miliardi di euro per liquidare i debiti commerciali maturati entro della fine del 2019. Una somma che dovrebbe contribuire ad abbassare lo stock, anche se la soluzione piu\u0300 efficace per azzerare o quasi i mancati pagamenti potrebbe essere quella di ricorrere al cosiddetto Fondo salva Stati (MES).<\/p>\n<p>4 Dal 2013, a seguito del recepimento nel nostro ordinamento della normativa europea contro i ritardi di pagamento (Direttiva UE\/2011\/7), i tempi di pagamento nelle transazioni commerciali tra enti pubblici italiani e aziende private non possono superare di norma i 30 giorni (60 per alcune tipologie di forniture, in particolare quelle sanitarie)<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"page\" title=\"Page 4\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Considerando che circa la meta\u0300 dei debiti commerciali della nostra PA sono ad appannaggio della sanita\u0300, il ricorso al fondo per 36-37 miliardi di euro potrebbe consentire all\u2019Amministrazione pubblica di erogare una buona parte di queste risorse ai fornitori delle aziende sanitarie che da sempre subiscono i ritardi di pagamento piu\u0300 pesanti.<\/p>\n<p>Con la sentenza n\u00b0 4, depositata il 28 gennaio 2020, lo stesso giorno in cui la Corte di Giustizia Europea ha bocciato l\u2019Italia per i ritardi dei pagamenti della nostra PA, la Corte Costituzionale ha stabilito che le anticipazioni di liquidita\u0300 ottenute dagli enti locali per onorare le passivita\u0300 pregresse sono prestiti di carattere eccezionale che devono essere utilizzati per la finalita\u0300 per cui sono stati erogati e non per migliorare i risultati di bilancio.<\/p>\n<p>I giudici della Consulta, quindi, hanno chiuso definitivamente una controversia sollevata dalla Corte dei Conti nei confronti del Comune di Napoli. Nel recente passato, infatti, non sono stati pochi i Sindaci e anche i Governatori che hanno utilizzato i prestiti statali sblocca-debiti erogati dal 2013 per assestare i bilanci di Comuni\/Regioni, anziche\u0301 per liquidare le vecchie fatture dei propri fornitori.<\/p>\n<p>Una condotta che la Corte Costituzionale ha finalmente chiarito che non puo\u0300 piu\u0300 essere praticata. Un principio, ovviamente, che dovra\u0300 valere anche per questa tranche da 12 miliardi che il Governo Conte, attraverso la Cassa Depositi e Prestiti, sta mettendo a disposizione di Regioni, aziende sanitarie ed enti locali che, finalmente, potranno saldare i propri creditori.<\/p>\n<\/div>\n<\/div>\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Secondo l\u2019Eurostat, fa sapere l\u2019Ufficio studi della CGIA, i debiti commerciali della nostra Pubblica Amministrazioni (PA) sono in aumento. Sebbene questi dati non contengono la componente in conto capitale, che secondo alcune stime ammonterebbe tra i 7-8 miliardi di euro all\u2019anno, i mancati pagamenti di parte corrente hanno toccato, il 31 dicembre scorso, i 49,4 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3378,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[162],"tags":[190,380],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>CGIA Mestre: i debiti della PA sono in aumento -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/i-debiti-della-pa-sono-in-aumento\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CGIA Mestre: i debiti della PA sono in aumento -\" \/>\n<meta property=\"og:description\" content=\"Secondo l\u2019Eurostat, fa sapere l\u2019Ufficio studi della CGIA, i debiti commerciali della nostra Pubblica Amministrazioni (PA) sono in aumento. Sebbene questi dati non contengono la componente in conto capitale, che secondo alcune stime ammonterebbe tra i 7-8 miliardi di euro all\u2019anno, i mancati pagamenti di parte corrente hanno toccato, il 31 dicembre scorso, i 49,4 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/i-debiti-della-pa-sono-in-aumento\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-20T17:15:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/06\/Schermata-2020-06-17-alle-15.57.33.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1396\" \/>\n\t<meta property=\"og:image:height\" content=\"942\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/i-debiti-della-pa-sono-in-aumento\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/i-debiti-della-pa-sono-in-aumento\/\",\"name\":\"CGIA Mestre: i debiti della PA sono in aumento -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/i-debiti-della-pa-sono-in-aumento\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/i-debiti-della-pa-sono-in-aumento\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/06\/Schermata-2020-06-17-alle-15.57.33.png\",\"datePublished\":\"2020-06-20T17:15:29+00:00\",\"dateModified\":\"2020-06-20T17:15:29+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/i-debiti-della-pa-sono-in-aumento\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/i-debiti-della-pa-sono-in-aumento\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/i-debiti-della-pa-sono-in-aumento\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/06\/Schermata-2020-06-17-alle-15.57.33.png\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/06\/Schermata-2020-06-17-alle-15.57.33.png\",\"width\":1396,\"height\":942},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/i-debiti-della-pa-sono-in-aumento\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CGIA Mestre: i debiti della PA sono in aumento\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CGIA Mestre: i debiti della PA sono in aumento -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/i-debiti-della-pa-sono-in-aumento\/","og_locale":"it_IT","og_type":"article","og_title":"CGIA Mestre: i debiti della PA sono in aumento -","og_description":"Secondo l\u2019Eurostat, fa sapere l\u2019Ufficio studi della CGIA, i debiti commerciali della nostra Pubblica Amministrazioni (PA) sono in aumento. Sebbene questi dati non contengono la componente in conto capitale, che secondo alcune stime ammonterebbe tra i 7-8 miliardi di euro all\u2019anno, i mancati pagamenti di parte corrente hanno toccato, il 31 dicembre scorso, i 49,4 [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/i-debiti-della-pa-sono-in-aumento\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2020-06-20T17:15:29+00:00","og_image":[{"width":1396,"height":942,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/06\/Schermata-2020-06-17-alle-15.57.33.png","type":"image\/png"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/i-debiti-della-pa-sono-in-aumento\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/i-debiti-della-pa-sono-in-aumento\/","name":"CGIA Mestre: i debiti della PA sono in aumento -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/i-debiti-della-pa-sono-in-aumento\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/i-debiti-della-pa-sono-in-aumento\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/06\/Schermata-2020-06-17-alle-15.57.33.png","datePublished":"2020-06-20T17:15:29+00:00","dateModified":"2020-06-20T17:15:29+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/i-debiti-della-pa-sono-in-aumento\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/i-debiti-della-pa-sono-in-aumento\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/i-debiti-della-pa-sono-in-aumento\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/06\/Schermata-2020-06-17-alle-15.57.33.png","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/06\/Schermata-2020-06-17-alle-15.57.33.png","width":1396,"height":942},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/i-debiti-della-pa-sono-in-aumento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"CGIA Mestre: i debiti della PA sono in aumento"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/3418"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=3418"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/3418\/revisions"}],"predecessor-version":[{"id":3419,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/3418\/revisions\/3419"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/3378"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=3418"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=3418"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=3418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}