{"id":3449,"date":"2020-06-22T17:12:36","date_gmt":"2020-06-22T15:12:36","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=3449"},"modified":"2020-06-22T17:13:19","modified_gmt":"2020-06-22T15:13:19","slug":"100-milioni-per-la-digital-transformation-delle-pmi","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/100-milioni-per-la-digital-transformation-delle-pmi\/","title":{"rendered":"100 milioni per la Digital Transformation delle PMI\u00a0"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">E\u2019<\/span> stato registrato dalla Corte dei Conti ed \u00e8 in corso di pubblicazione nella Gazzetta Ufficiale il decreto attuativo del Ministero dello Sviluppo economico che favorisce la trasformazione tecnologica e digitale dei processi produttivi delle micro, piccole e medie imprese, attraverso l\u2019applicazione di tecnologie avanzate previste nell\u2019ambito di Impresa 4.0 e di quelle relative a soluzioni tecnologiche digitali di filiera.<\/p>\n<p>Per questa misura agevolativa sono stati stanziati 100 milioni di euro dal Decreto Crescita, con l\u2019obiettivo di sostenere la <strong>Digital Transformation delle PMI<\/strong> nel settore manifatturiero e in quello dei servizi diretti alle imprese, nel settore turistico per le imprese impegnate nella digitalizzazione della fruizione dei beni culturali e nel settore del commercio, contribuendo cos\u00ec agli obiettivi di innovazione e di crescita di competitivit\u00e0 dell\u2019intero tessuto produttivo del Paese.<\/p>\n<p>In particolare sono agevolati progetti per un importo non inferiore a 50 mila euro e non superiore a 500 mila euro, che possono essere presentati sia da imprese singole che associate, fino a 10 soggetti aderenti, mediante contratti di rete o altre forme di collaborazione in cui figuri, come capofila, un DIH- Digital Innovation Hub o un EDI-ecosistema digitale per l\u2019innovazione.<\/p>\n<p>La Digital Transformation riguarda tutte le tecnologie pi\u00f9 avanzate quali advanced manufacturing solutions, additive manufacturing, realt\u00e0 aumentata, simulation, integrazione orizzontale e verticale, industrial internet, cloud, cybersecurity, big data e analytics, software, piattaforme e applicazioni digitali per la gestione e il coordinamento della logistica, e-commerce, sistemi di pagamento mobile e via internet, fintech, sistemi elettronici per lo scambio di dati geolocalizzazione, tecnologie per l\u2019in-store customer experience, system integration applicata all\u2019automazione dei processi, blockchain, intelligenza artificiale, internet of things.<\/p>\n<p>Le modalit\u00e0 e i termini di presentazione delle domande saranno disciplinate da un successivo provvedimento ministeriale.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>E\u2019 stato registrato dalla Corte dei Conti ed \u00e8 in corso di pubblicazione nella Gazzetta Ufficiale il decreto attuativo del Ministero dello Sviluppo economico che favorisce la trasformazione tecnologica e digitale dei processi produttivi delle micro, piccole e medie imprese, attraverso l\u2019applicazione di tecnologie avanzate previste nell\u2019ambito di Impresa 4.0 e di quelle relative a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1921,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[970],"tags":[366,1052,1058,1060,137,1061,31],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>100 milioni per la Digital Transformation delle PMI\u00a0 -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/100-milioni-per-la-digital-transformation-delle-pmi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"100 milioni per la Digital Transformation delle PMI\u00a0 -\" \/>\n<meta property=\"og:description\" content=\"E\u2019 stato registrato dalla Corte dei Conti ed \u00e8 in corso di pubblicazione nella Gazzetta Ufficiale il decreto attuativo del Ministero dello Sviluppo economico che favorisce la trasformazione tecnologica e digitale dei processi produttivi delle micro, piccole e medie imprese, attraverso l\u2019applicazione di tecnologie avanzate previste nell\u2019ambito di Impresa 4.0 e di quelle relative a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/100-milioni-per-la-digital-transformation-delle-pmi\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-22T15:12:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-22T15:13:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/10\/innovazione-tecnologia-internet.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"601\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/100-milioni-per-la-digital-transformation-delle-pmi\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/100-milioni-per-la-digital-transformation-delle-pmi\/\",\"name\":\"100 milioni per la Digital Transformation delle PMI\u00a0 -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/100-milioni-per-la-digital-transformation-delle-pmi\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/100-milioni-per-la-digital-transformation-delle-pmi\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/10\/innovazione-tecnologia-internet.jpg\",\"datePublished\":\"2020-06-22T15:12:36+00:00\",\"dateModified\":\"2020-06-22T15:13:19+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/100-milioni-per-la-digital-transformation-delle-pmi\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/100-milioni-per-la-digital-transformation-delle-pmi\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/100-milioni-per-la-digital-transformation-delle-pmi\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/10\/innovazione-tecnologia-internet.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/10\/innovazione-tecnologia-internet.jpg\",\"width\":960,\"height\":601},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/100-milioni-per-la-digital-transformation-delle-pmi\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"100 milioni per la Digital Transformation delle PMI\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"100 milioni per la Digital Transformation delle PMI\u00a0 -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/100-milioni-per-la-digital-transformation-delle-pmi\/","og_locale":"it_IT","og_type":"article","og_title":"100 milioni per la Digital Transformation delle PMI\u00a0 -","og_description":"E\u2019 stato registrato dalla Corte dei Conti ed \u00e8 in corso di pubblicazione nella Gazzetta Ufficiale il decreto attuativo del Ministero dello Sviluppo economico che favorisce la trasformazione tecnologica e digitale dei processi produttivi delle micro, piccole e medie imprese, attraverso l\u2019applicazione di tecnologie avanzate previste nell\u2019ambito di Impresa 4.0 e di quelle relative a [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/100-milioni-per-la-digital-transformation-delle-pmi\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2020-06-22T15:12:36+00:00","article_modified_time":"2020-06-22T15:13:19+00:00","og_image":[{"width":960,"height":601,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/10\/innovazione-tecnologia-internet.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/100-milioni-per-la-digital-transformation-delle-pmi\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/100-milioni-per-la-digital-transformation-delle-pmi\/","name":"100 milioni per la Digital Transformation delle PMI\u00a0 -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/100-milioni-per-la-digital-transformation-delle-pmi\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/100-milioni-per-la-digital-transformation-delle-pmi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/10\/innovazione-tecnologia-internet.jpg","datePublished":"2020-06-22T15:12:36+00:00","dateModified":"2020-06-22T15:13:19+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/100-milioni-per-la-digital-transformation-delle-pmi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/100-milioni-per-la-digital-transformation-delle-pmi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/100-milioni-per-la-digital-transformation-delle-pmi\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/10\/innovazione-tecnologia-internet.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/10\/innovazione-tecnologia-internet.jpg","width":960,"height":601},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/100-milioni-per-la-digital-transformation-delle-pmi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"100 milioni per la Digital Transformation delle PMI\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/3449"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=3449"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/3449\/revisions"}],"predecessor-version":[{"id":3450,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/3449\/revisions\/3450"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/1921"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=3449"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=3449"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=3449"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}