{"id":3522,"date":"2020-06-29T08:47:36","date_gmt":"2020-06-29T06:47:36","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=3522"},"modified":"2020-06-29T08:47:36","modified_gmt":"2020-06-29T06:47:36","slug":"i-prestiti-ismea-passano-da-25-a-30-000-euro","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/i-prestiti-ismea-passano-da-25-a-30-000-euro\/","title":{"rendered":"I prestiti ISMEA passano da 25 a 30.000 euro"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">C<\/span>on la conversione in legge del \u201cdecreto liquidit\u00e0\u201d (legge 40\/2020) sono stati apportati correttivi al sistema dei prestiti agevolati per le imprese agricole colpite dalla pandemia di Covid-19 volti ad ampliare la portata della misura che prevede una copertura al 100% del Fondo ISMEA per finanziamenti fino a 25mila euro.<\/p>\n<p>Pi\u00f9 precisamente:<br \/>\n&#8211; il limite di 25.000 euro \u00e8 elevato a 30.000 euro;<br \/>\n&#8211; la durata \u00e8 stata allungata da 6 a 10 anni;<br \/>\n&#8211; \u00e8 previsto che l\u2019ammontare del finanziamento possa essere parametrato, alternativamente, al 25% del fatturato o al doppio della spesa salariale;<br \/>\n&#8211; la garanzia al 100% \u00e8 altres\u00ec concessa in favore di beneficiari finali che presentano esposizioni che, anche prima del 31 gennaio 2020, sono state classificate come inadempienze probabili o esposizioni scadute e\/o sconfinanti deteriorate, a condizione che le predette esposizioni alla data della richiesta del finanziamento non siano pi\u00f9 classificabili come esposizioni deteriorate. La disposizione si applica a tutte le richieste di garanzia pervenute dalla data di entrata in vigore della legge di conversione del decreto liquidit\u00e0 (7 giugno 2020).<\/p>\n<p>I nuovi modelli per le domande sono disponibili sul portale L25 e sul sito dell\u2019<a href=\"http:\/\/www.ismea.it\/flex\/cm\/pages\/ServeBLOB.php\/L\/IT\/IDPagina\/11028\">ISMEA<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con la conversione in legge del \u201cdecreto liquidit\u00e0\u201d (legge 40\/2020) sono stati apportati correttivi al sistema dei prestiti agevolati per le imprese agricole colpite dalla pandemia di Covid-19 volti ad ampliare la portata della misura che prevede una copertura al 100% del Fondo ISMEA per finanziamenti fino a 25mila euro. Pi\u00f9 precisamente: &#8211; il limite [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3339,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[162],"tags":[1092,20,1091,229],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>I prestiti ISMEA passano da 25 a 30.000 euro -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/i-prestiti-ismea-passano-da-25-a-30-000-euro\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"I prestiti ISMEA passano da 25 a 30.000 euro -\" \/>\n<meta property=\"og:description\" content=\"Con la conversione in legge del \u201cdecreto liquidit\u00e0\u201d (legge 40\/2020) sono stati apportati correttivi al sistema dei prestiti agevolati per le imprese agricole colpite dalla pandemia di Covid-19 volti ad ampliare la portata della misura che prevede una copertura al 100% del Fondo ISMEA per finanziamenti fino a 25mila euro. Pi\u00f9 precisamente: &#8211; il limite [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/i-prestiti-ismea-passano-da-25-a-30-000-euro\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-29T06:47:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/06\/Schermata-2020-06-15-alle-10.11.48.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1550\" \/>\n\t<meta property=\"og:image:height\" content=\"968\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/i-prestiti-ismea-passano-da-25-a-30-000-euro\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/i-prestiti-ismea-passano-da-25-a-30-000-euro\/\",\"name\":\"I prestiti ISMEA passano da 25 a 30.000 euro -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/i-prestiti-ismea-passano-da-25-a-30-000-euro\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/i-prestiti-ismea-passano-da-25-a-30-000-euro\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/06\/Schermata-2020-06-15-alle-10.11.48.png\",\"datePublished\":\"2020-06-29T06:47:36+00:00\",\"dateModified\":\"2020-06-29T06:47:36+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/i-prestiti-ismea-passano-da-25-a-30-000-euro\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/i-prestiti-ismea-passano-da-25-a-30-000-euro\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/i-prestiti-ismea-passano-da-25-a-30-000-euro\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/06\/Schermata-2020-06-15-alle-10.11.48.png\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/06\/Schermata-2020-06-15-alle-10.11.48.png\",\"width\":1550,\"height\":968},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/i-prestiti-ismea-passano-da-25-a-30-000-euro\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"I prestiti ISMEA passano da 25 a 30.000 euro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"I prestiti ISMEA passano da 25 a 30.000 euro -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/i-prestiti-ismea-passano-da-25-a-30-000-euro\/","og_locale":"it_IT","og_type":"article","og_title":"I prestiti ISMEA passano da 25 a 30.000 euro -","og_description":"Con la conversione in legge del \u201cdecreto liquidit\u00e0\u201d (legge 40\/2020) sono stati apportati correttivi al sistema dei prestiti agevolati per le imprese agricole colpite dalla pandemia di Covid-19 volti ad ampliare la portata della misura che prevede una copertura al 100% del Fondo ISMEA per finanziamenti fino a 25mila euro. Pi\u00f9 precisamente: &#8211; il limite [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/i-prestiti-ismea-passano-da-25-a-30-000-euro\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2020-06-29T06:47:36+00:00","og_image":[{"width":1550,"height":968,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/06\/Schermata-2020-06-15-alle-10.11.48.png","type":"image\/png"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/i-prestiti-ismea-passano-da-25-a-30-000-euro\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/i-prestiti-ismea-passano-da-25-a-30-000-euro\/","name":"I prestiti ISMEA passano da 25 a 30.000 euro -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/i-prestiti-ismea-passano-da-25-a-30-000-euro\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/i-prestiti-ismea-passano-da-25-a-30-000-euro\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/06\/Schermata-2020-06-15-alle-10.11.48.png","datePublished":"2020-06-29T06:47:36+00:00","dateModified":"2020-06-29T06:47:36+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/i-prestiti-ismea-passano-da-25-a-30-000-euro\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/i-prestiti-ismea-passano-da-25-a-30-000-euro\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/i-prestiti-ismea-passano-da-25-a-30-000-euro\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/06\/Schermata-2020-06-15-alle-10.11.48.png","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/06\/Schermata-2020-06-15-alle-10.11.48.png","width":1550,"height":968},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/i-prestiti-ismea-passano-da-25-a-30-000-euro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"I prestiti ISMEA passano da 25 a 30.000 euro"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/3522"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=3522"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/3522\/revisions"}],"predecessor-version":[{"id":3523,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/3522\/revisions\/3523"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/3339"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=3522"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=3522"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=3522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}