{"id":3532,"date":"2020-06-30T15:15:21","date_gmt":"2020-06-30T13:15:21","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=3532"},"modified":"2020-06-30T15:15:21","modified_gmt":"2020-06-30T13:15:21","slug":"differito-al-30-settembre-il-termine-di-comunicazione-ad-agenzia-entrate-di-informazioni-su-conti-finanziari","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/differito-al-30-settembre-il-termine-di-comunicazione-ad-agenzia-entrate-di-informazioni-su-conti-finanziari\/","title":{"rendered":"Differito al 30 settembre il termine di comunicazione ad Agenzia Entrate di informazioni su conti finanziari"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">\u00c8<\/span> in via di predisposizione il decreto del Ministro dell\u2019Economia e delle Finanze che, a causa dell\u2019emergenza sanitaria connessa alla pandemia COVID-19, dispone il\u00a0<strong>differimento dal 30 giugno 2020 al 30 settembre<\/strong>\u00a0<strong>2020 del termine per la comunicazione all\u2019Agenzia delle Entrate delle informazioni sui conti finanziari\u00a0<\/strong><strong>(DAC2\/MCAA\/IGA)\u00a0per l\u2019anno 2020<\/strong>\u00a0(relative al periodo di\u00a0<em>reporting<\/em>\u00a02019) da parte delle istituzioni finanziarie italiane.<\/p>\n<p>Il differimento riguarda l\u2019obbligo di comunicazione delle informazioni da scambiare con gli altri Stati membri UE (sulla base della direttiva 2014\/107\/UE, c.d. DAC2), con gli altri Paesi non UE (sulla base del\u00a0<em>Multilateral Competent Authority Agreement<\/em>\u00a0firmato il 29 ottobre 2014), con gli Stati Uniti (nell\u2019ambito dell\u2019accordo intergovernativo ratificato con legge 18 giugno 2015, n. 95 relativo alla implementazione della legislazione FATCA).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c8 in via di predisposizione il decreto del Ministro dell\u2019Economia e delle Finanze che, a causa dell\u2019emergenza sanitaria connessa alla pandemia COVID-19, dispone il\u00a0differimento dal 30 giugno 2020 al 30 settembre\u00a02020 del termine per la comunicazione all\u2019Agenzia delle Entrate delle informazioni sui conti finanziari\u00a0(DAC2\/MCAA\/IGA)\u00a0per l\u2019anno 2020\u00a0(relative al periodo di\u00a0reporting\u00a02019) da parte delle istituzioni finanziarie italiane. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3378,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41],"tags":[393,42,115,43],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Differito al 30 settembre il termine di comunicazione ad Agenzia Entrate di informazioni su conti finanziari -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/differito-al-30-settembre-il-termine-di-comunicazione-ad-agenzia-entrate-di-informazioni-su-conti-finanziari\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Differito al 30 settembre il termine di comunicazione ad Agenzia Entrate di informazioni su conti finanziari -\" \/>\n<meta property=\"og:description\" content=\"\u00c8 in via di predisposizione il decreto del Ministro dell\u2019Economia e delle Finanze che, a causa dell\u2019emergenza sanitaria connessa alla pandemia COVID-19, dispone il\u00a0differimento dal 30 giugno 2020 al 30 settembre\u00a02020 del termine per la comunicazione all\u2019Agenzia delle Entrate delle informazioni sui conti finanziari\u00a0(DAC2\/MCAA\/IGA)\u00a0per l\u2019anno 2020\u00a0(relative al periodo di\u00a0reporting\u00a02019) da parte delle istituzioni finanziarie italiane. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/differito-al-30-settembre-il-termine-di-comunicazione-ad-agenzia-entrate-di-informazioni-su-conti-finanziari\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-30T13:15:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/06\/Schermata-2020-06-17-alle-15.57.33.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1396\" \/>\n\t<meta property=\"og:image:height\" content=\"942\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/differito-al-30-settembre-il-termine-di-comunicazione-ad-agenzia-entrate-di-informazioni-su-conti-finanziari\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/differito-al-30-settembre-il-termine-di-comunicazione-ad-agenzia-entrate-di-informazioni-su-conti-finanziari\/\",\"name\":\"Differito al 30 settembre il termine di comunicazione ad Agenzia Entrate di informazioni su conti finanziari -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/differito-al-30-settembre-il-termine-di-comunicazione-ad-agenzia-entrate-di-informazioni-su-conti-finanziari\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/differito-al-30-settembre-il-termine-di-comunicazione-ad-agenzia-entrate-di-informazioni-su-conti-finanziari\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/06\/Schermata-2020-06-17-alle-15.57.33.png\",\"datePublished\":\"2020-06-30T13:15:21+00:00\",\"dateModified\":\"2020-06-30T13:15:21+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/differito-al-30-settembre-il-termine-di-comunicazione-ad-agenzia-entrate-di-informazioni-su-conti-finanziari\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/differito-al-30-settembre-il-termine-di-comunicazione-ad-agenzia-entrate-di-informazioni-su-conti-finanziari\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/differito-al-30-settembre-il-termine-di-comunicazione-ad-agenzia-entrate-di-informazioni-su-conti-finanziari\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/06\/Schermata-2020-06-17-alle-15.57.33.png\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/06\/Schermata-2020-06-17-alle-15.57.33.png\",\"width\":1396,\"height\":942},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/differito-al-30-settembre-il-termine-di-comunicazione-ad-agenzia-entrate-di-informazioni-su-conti-finanziari\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Differito al 30 settembre il termine di comunicazione ad Agenzia Entrate di informazioni su conti finanziari\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Differito al 30 settembre il termine di comunicazione ad Agenzia Entrate di informazioni su conti finanziari -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/differito-al-30-settembre-il-termine-di-comunicazione-ad-agenzia-entrate-di-informazioni-su-conti-finanziari\/","og_locale":"it_IT","og_type":"article","og_title":"Differito al 30 settembre il termine di comunicazione ad Agenzia Entrate di informazioni su conti finanziari -","og_description":"\u00c8 in via di predisposizione il decreto del Ministro dell\u2019Economia e delle Finanze che, a causa dell\u2019emergenza sanitaria connessa alla pandemia COVID-19, dispone il\u00a0differimento dal 30 giugno 2020 al 30 settembre\u00a02020 del termine per la comunicazione all\u2019Agenzia delle Entrate delle informazioni sui conti finanziari\u00a0(DAC2\/MCAA\/IGA)\u00a0per l\u2019anno 2020\u00a0(relative al periodo di\u00a0reporting\u00a02019) da parte delle istituzioni finanziarie italiane. [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/differito-al-30-settembre-il-termine-di-comunicazione-ad-agenzia-entrate-di-informazioni-su-conti-finanziari\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2020-06-30T13:15:21+00:00","og_image":[{"width":1396,"height":942,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/06\/Schermata-2020-06-17-alle-15.57.33.png","type":"image\/png"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/differito-al-30-settembre-il-termine-di-comunicazione-ad-agenzia-entrate-di-informazioni-su-conti-finanziari\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/differito-al-30-settembre-il-termine-di-comunicazione-ad-agenzia-entrate-di-informazioni-su-conti-finanziari\/","name":"Differito al 30 settembre il termine di comunicazione ad Agenzia Entrate di informazioni su conti finanziari -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/differito-al-30-settembre-il-termine-di-comunicazione-ad-agenzia-entrate-di-informazioni-su-conti-finanziari\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/differito-al-30-settembre-il-termine-di-comunicazione-ad-agenzia-entrate-di-informazioni-su-conti-finanziari\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/06\/Schermata-2020-06-17-alle-15.57.33.png","datePublished":"2020-06-30T13:15:21+00:00","dateModified":"2020-06-30T13:15:21+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/differito-al-30-settembre-il-termine-di-comunicazione-ad-agenzia-entrate-di-informazioni-su-conti-finanziari\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/differito-al-30-settembre-il-termine-di-comunicazione-ad-agenzia-entrate-di-informazioni-su-conti-finanziari\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/differito-al-30-settembre-il-termine-di-comunicazione-ad-agenzia-entrate-di-informazioni-su-conti-finanziari\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/06\/Schermata-2020-06-17-alle-15.57.33.png","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/06\/Schermata-2020-06-17-alle-15.57.33.png","width":1396,"height":942},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/differito-al-30-settembre-il-termine-di-comunicazione-ad-agenzia-entrate-di-informazioni-su-conti-finanziari\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Differito al 30 settembre il termine di comunicazione ad Agenzia Entrate di informazioni su conti finanziari"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/3532"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=3532"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/3532\/revisions"}],"predecessor-version":[{"id":3533,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/3532\/revisions\/3533"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/3378"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=3532"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=3532"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=3532"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}