{"id":3569,"date":"2020-07-03T14:52:23","date_gmt":"2020-07-03T12:52:23","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=3569"},"modified":"2020-07-03T14:52:23","modified_gmt":"2020-07-03T12:52:23","slug":"il-fondo-per-linnovazione-finanziera-tecnologie-innovative-per-le-energie-rinnovabili","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/il-fondo-per-linnovazione-finanziera-tecnologie-innovative-per-le-energie-rinnovabili\/","title":{"rendered":"Il Fondo per l&#8217;innovazione finanzier\u00e0 tecnologie innovative per le energie rinnovabili"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">L<\/span>a Commissione pubblica oggi il primo invito a presentare proposte nell&#8217;ambito del <a href=\"https:\/\/ec.europa.eu\/clima\/policies\/innovation-fund_en\">Fondo per l&#8217;innovazione<\/a>, uno dei principali programmi a livello mondiale per la dimostrazione di tecnologie innovative a basse emissioni di carbonio, finanziato con i proventi della vendita all&#8217;asta di quote del sistema di scambio delle quote di emissione dell&#8217;UE.<\/p>\n<p>Il Fondo per l&#8217;innovazione finanzier\u00e0 tecnologie innovative per le energie rinnovabili, le industrie ad alta intensit\u00e0 energetica, lo stoccaggio di energia e la cattura, l&#8217;uso e lo stoccaggio del carbonio. Il Fondo dar\u00e0 impulso alla ripresa verde attraverso la creazione di posti di lavoro locali e adeguati alle esigenze future, preparando il terreno per la neutralit\u00e0 climatica e rafforzando la leadership tecnologica europea su scala mondiale.<\/p>\n<p><strong>Frans Timmermans<\/strong>, Vicepresidente esecutivo della Commissione europea, ha dichiarato: &#8220;<em>L&#8217;invito a presentare proposte arriva al momento giusto. L&#8217;UE investir\u00e0 un\u00a0miliardo di \u20ac in progetti promettenti e maturi per il mercato, quali l&#8217;idrogeno pulito o altre soluzioni a basse emissioni di carbonio per industrie ad alta intensit\u00e0 energetica come l&#8217;acciaio, il cemento e i prodotti chimici. L&#8217;UE sosterr\u00e0 inoltre lo stoccaggio dell&#8217;energia, le soluzioni di rete e la cattura e lo stoccaggio del carbonio. Si tratta di investimenti di grande portata che contribuiranno a rilanciare l&#8217;economia dell&#8217;UE e a creare una ripresa verde che ci permetta di conseguire la neutralit\u00e0 climatica nel 2050.&#8221;<\/em><\/p>\n<p>Nel periodo 2020-2030, il Fondo per l&#8217;innovazione erogher\u00e0 <a href=\"https:\/\/ec.europa.eu\/commission\/presscorner\/detail\/en\/IP_19_1381\">circa 10\u00a0miliardi di \u20ac<\/a>, provenienti dalla vendita all&#8217;asta di quote nell&#8217;ambito del <a href=\"https:\/\/ec.europa.eu\/clima\/policies\/ets\/revision_en\">sistema di scambio delle quote di emissione dell&#8217;UE<\/a>, in aggiunta agli importi inutilizzati del predecessore del Fondo per l&#8217;innovazione, <a href=\"https:\/\/ec.europa.eu\/clima\/policies\/lowcarbon\/ner300_en\">il programma\u00a0NER 300<\/a>.<\/p>\n<p>Il primo invito a presentare proposte permetter\u00e0 di erogare finanziamenti per 1\u00a0miliardo di \u20ac a progetti di grande portata sulle tecnologie pulite per contribuire a sormontare i rischi legati alla commercializzazione e alla dimostrazione su vasta scala.<\/p>\n<p>Questi finanziamenti aiuteranno le nuove tecnologie a raggiungere il mercato. Per i progetti promettenti ma non ancora maturi per il mercato \u00e8 previsto un bilancio separato di 8\u00a0milioni di \u20ac per l&#8217;assistenza allo sviluppo dei progetti.<\/p>\n<p>L&#8217;invito \u00e8 aperto a progetti in settori ammissibili di tutti gli Stati membri dell&#8217;UE, dell&#8217;Islanda e della Norvegia. I finanziamenti possono essere utilizzati in combinazione con altre iniziative di finanziamento pubblico, quali gli aiuti di Stato o altri programmi di finanziamento dell&#8217;UE.<\/p>\n<p>I progetti saranno valutati in funzione del loro potenziale per evitare le emissioni di gas a effetto serra, del potenziale di innovazione e della maturit\u00e0 finanziaria e tecnica, come pure del potenziale di espansione e di efficienza sotto il profilo dei costi.<\/p>\n<p>Il termine ultimo di presentazione delle domande \u00e8 il 29\u00a0ottobre 2020.<\/p>\n<p>Le domande di finanziamento per i progetti possono essere presentate sul <a href=\"https:\/\/ec.europa.eu\/info\/funding-tenders\/opportunities\/portal\/screen\/opportunities\/topic-details\/innovfund-lsc-2020-two-stage\"> EU Funding and Tenders portal<\/a> (portale UE delle opportunit\u00e0 di finanziamento e di appalto), sul quale sono disponibili ulteriori informazioni sulla procedura nel suo complesso.<\/p>\n<p>Il Fondo per l&#8217;innovazione si propone di fornire i giusti incentivi finanziari per incoraggiare le imprese e le autorit\u00e0 pubbliche a investire nelle tecnologie a basse emissioni di carbonio di prossima generazione e di garantire alle imprese dell&#8217;UE una posizione pionieristica che le ponga all&#8217;avanguardia mondiale in queste tecnologie.<\/p>\n<p>Il Fondo per l&#8217;innovazione sar\u00e0 attuato dall&#8217;<a href=\"https:\/\/ec.europa.eu\/inea\/en\">Agenzia esecutiva per l&#8217;innovazione e le reti (INEA)<\/a>, mentre la <a href=\"https:\/\/www.eib.org\/en\/index.htm\"> Banca europea per gli investimenti<\/a> fornir\u00e0 assistenza per lo sviluppo di progetti promettenti ma non ancora maturi per una piena applicazione.<\/p>\n<ul>\n<li><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>La Commissione pubblica oggi il primo invito a presentare proposte nell&#8217;ambito del Fondo per l&#8217;innovazione, uno dei principali programmi a livello mondiale per la dimostrazione di tecnologie innovative a basse emissioni di carbonio, finanziato con i proventi della vendita all&#8217;asta di quote del sistema di scambio delle quote di emissione dell&#8217;UE. Il Fondo per l&#8217;innovazione [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3339,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[130],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Il Fondo per l&#039;innovazione finanzier\u00e0 tecnologie innovative per le energie rinnovabili -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.italiaeconomiaonline.it\/web\/il-fondo-per-linnovazione-finanziera-tecnologie-innovative-per-le-energie-rinnovabili\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il Fondo per l&#039;innovazione finanzier\u00e0 tecnologie innovative per le energie rinnovabili -\" \/>\n<meta property=\"og:description\" content=\"La Commissione pubblica oggi il primo invito a presentare proposte nell&#8217;ambito del Fondo per l&#8217;innovazione, uno dei principali programmi a livello mondiale per la dimostrazione di tecnologie innovative a basse emissioni di carbonio, finanziato con i proventi della vendita all&#8217;asta di quote del sistema di scambio delle quote di emissione dell&#8217;UE. Il Fondo per l&#8217;innovazione [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.italiaeconomiaonline.it\/web\/il-fondo-per-linnovazione-finanziera-tecnologie-innovative-per-le-energie-rinnovabili\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-03T12:52:23+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/06\/Schermata-2020-06-15-alle-10.11.48.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1550\" \/>\n\t<meta property=\"og:image:height\" content=\"968\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.italiaeconomiaonline.it\/web\/il-fondo-per-linnovazione-finanziera-tecnologie-innovative-per-le-energie-rinnovabili\/\",\"url\":\"http:\/\/www.italiaeconomiaonline.it\/web\/il-fondo-per-linnovazione-finanziera-tecnologie-innovative-per-le-energie-rinnovabili\/\",\"name\":\"Il Fondo per l'innovazione finanzier\u00e0 tecnologie innovative per le energie rinnovabili -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/www.italiaeconomiaonline.it\/web\/il-fondo-per-linnovazione-finanziera-tecnologie-innovative-per-le-energie-rinnovabili\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/www.italiaeconomiaonline.it\/web\/il-fondo-per-linnovazione-finanziera-tecnologie-innovative-per-le-energie-rinnovabili\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/06\/Schermata-2020-06-15-alle-10.11.48.png\",\"datePublished\":\"2020-07-03T12:52:23+00:00\",\"dateModified\":\"2020-07-03T12:52:23+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"http:\/\/www.italiaeconomiaonline.it\/web\/il-fondo-per-linnovazione-finanziera-tecnologie-innovative-per-le-energie-rinnovabili\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.italiaeconomiaonline.it\/web\/il-fondo-per-linnovazione-finanziera-tecnologie-innovative-per-le-energie-rinnovabili\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\/\/www.italiaeconomiaonline.it\/web\/il-fondo-per-linnovazione-finanziera-tecnologie-innovative-per-le-energie-rinnovabili\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/06\/Schermata-2020-06-15-alle-10.11.48.png\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/06\/Schermata-2020-06-15-alle-10.11.48.png\",\"width\":1550,\"height\":968},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/www.italiaeconomiaonline.it\/web\/il-fondo-per-linnovazione-finanziera-tecnologie-innovative-per-le-energie-rinnovabili\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il Fondo per l&#8217;innovazione finanzier\u00e0 tecnologie innovative per le energie rinnovabili\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il Fondo per l'innovazione finanzier\u00e0 tecnologie innovative per le energie rinnovabili -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.italiaeconomiaonline.it\/web\/il-fondo-per-linnovazione-finanziera-tecnologie-innovative-per-le-energie-rinnovabili\/","og_locale":"it_IT","og_type":"article","og_title":"Il Fondo per l'innovazione finanzier\u00e0 tecnologie innovative per le energie rinnovabili -","og_description":"La Commissione pubblica oggi il primo invito a presentare proposte nell&#8217;ambito del Fondo per l&#8217;innovazione, uno dei principali programmi a livello mondiale per la dimostrazione di tecnologie innovative a basse emissioni di carbonio, finanziato con i proventi della vendita all&#8217;asta di quote del sistema di scambio delle quote di emissione dell&#8217;UE. Il Fondo per l&#8217;innovazione [&hellip;]","og_url":"http:\/\/www.italiaeconomiaonline.it\/web\/il-fondo-per-linnovazione-finanziera-tecnologie-innovative-per-le-energie-rinnovabili\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2020-07-03T12:52:23+00:00","og_image":[{"width":1550,"height":968,"url":"http:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/06\/Schermata-2020-06-15-alle-10.11.48.png","type":"image\/png"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/www.italiaeconomiaonline.it\/web\/il-fondo-per-linnovazione-finanziera-tecnologie-innovative-per-le-energie-rinnovabili\/","url":"http:\/\/www.italiaeconomiaonline.it\/web\/il-fondo-per-linnovazione-finanziera-tecnologie-innovative-per-le-energie-rinnovabili\/","name":"Il Fondo per l'innovazione finanzier\u00e0 tecnologie innovative per le energie rinnovabili -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.italiaeconomiaonline.it\/web\/il-fondo-per-linnovazione-finanziera-tecnologie-innovative-per-le-energie-rinnovabili\/#primaryimage"},"image":{"@id":"http:\/\/www.italiaeconomiaonline.it\/web\/il-fondo-per-linnovazione-finanziera-tecnologie-innovative-per-le-energie-rinnovabili\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/06\/Schermata-2020-06-15-alle-10.11.48.png","datePublished":"2020-07-03T12:52:23+00:00","dateModified":"2020-07-03T12:52:23+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"http:\/\/www.italiaeconomiaonline.it\/web\/il-fondo-per-linnovazione-finanziera-tecnologie-innovative-per-le-energie-rinnovabili\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.italiaeconomiaonline.it\/web\/il-fondo-per-linnovazione-finanziera-tecnologie-innovative-per-le-energie-rinnovabili\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/www.italiaeconomiaonline.it\/web\/il-fondo-per-linnovazione-finanziera-tecnologie-innovative-per-le-energie-rinnovabili\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/06\/Schermata-2020-06-15-alle-10.11.48.png","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/06\/Schermata-2020-06-15-alle-10.11.48.png","width":1550,"height":968},{"@type":"BreadcrumbList","@id":"http:\/\/www.italiaeconomiaonline.it\/web\/il-fondo-per-linnovazione-finanziera-tecnologie-innovative-per-le-energie-rinnovabili\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Il Fondo per l&#8217;innovazione finanzier\u00e0 tecnologie innovative per le energie rinnovabili"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/3569"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=3569"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/3569\/revisions"}],"predecessor-version":[{"id":3570,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/3569\/revisions\/3570"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/3339"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=3569"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=3569"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=3569"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}